{"id":13044,"date":"2022-11-23T10:00:00","date_gmt":"2022-11-23T09:00:00","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=13044"},"modified":"2022-11-24T11:06:31","modified_gmt":"2022-11-24T10:06:31","slug":"reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/23\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\/","title":{"rendered":"Reggio Calabria: l&#8217;associazione Le Muse cambia l&#8217;argomento domenicale"},"content":{"rendered":"<p style=\"text-align: justify\">L\u2019associazione culturale <strong>Le Muse \u201cLaboratorio delle Arti e delle Lettere\u201d<\/strong> di Reggio Calabria cambia argomento domenicale e lo fa ponendo all\u2019attenzione il territorio metropolitano. Nascono cos\u00ec ha ricordato il presidente Muse prof. <strong>Giuseppe Livoti<\/strong> in apertura di serata i \u201c<strong>Dialoghi metropolitani\u201d<\/strong> ovvero il voler confrontarsi con alte personalit\u00e0 che operano all\u2019interno dell\u2019area metropolitana dello <strong>Stretto<\/strong>. <strong>Livoti<\/strong> nella sua premessa ha chiarito come nella programmazione annuale di volta in volta, verranno chiamati presidenti o referenti di istituzioni importanti all\u2019interno dell\u2019area metropolitana proprio per capire lo stato dell\u2019arte, ci\u00f2 che \u00e8 stato fatto o ci\u00f2 che \u00e8 un diritto sapere. \u00a0\u00a0La Citt\u00e0 metropolitana di Reggio Calabria e la sua conseguente area \u00e8 stata individuata e riconosciuta per legge solo a partire dal 5 maggio 2009 grazie alla legge delega n 42 in materia di federalismo fiscale in attuazione dell&#8217;articolo 119 della Costituzione. In base a quella legge il <strong>Governo<\/strong> era delegato ad adottare entro 36 mesi dalla data in entrata in vigore della legge (entro il 21 maggio 2012) un decreto legislativo per l&#8217;istituzione delle 10 citt\u00e0 metropolitane individuate dalla legislazione italiana, tra le quali la citt\u00e0 di<strong> Reggio Calabria<\/strong>. La <strong>Citt\u00e0 metropolitana di Reggio Calabria<\/strong> \u00e8 stata istituita dall&#8217;ordinamento giuridico nazionale con il Decreto legge 5 novembre 2012, n. 188 &#8220;Disposizioni urgenti in materia di Province e Citt\u00e0 metropolitane&#8221;.<\/p>\n<p style=\"text-align: justify\">Si \u00e8 ricordato inoltre come dell&#8217;area metropolitana di<strong> Reggio Calabria,<\/strong> si discute sin dagli anni settanta, principalmente in funzione della conurbazione con la corrispondente area metropolitana di Messina e per la istituzione dell&#8217;area metropolitana dello Stretto. Ed ancora il territorio definito <strong>dall&#8217;Aspromonte<\/strong> ai due fronti costieri del basso ionio reggino e del tirreno fino alla sua conformazione lineare dal comune di Rosarno a nord al comune di Melito di Porto Salvo a sud. In evidenza i comuni di Villa San Giovanni, Campo Calabro, Montebello Ionico e Motta San Giovanni mentre \u00a0l\u2019 area di gravitazione principale \u00e8 formata da otto comuni: Calanna, Cardeto, Fiumara, Laganadi, San Roberto, Scilla, Bagnara Calabra e Melito Porto Salvo mentre i rimanenti comuni formano i &#8220;sistemi secondari aggregati&#8221; che fanno riferimento per i servizi di livello inferiore principalmente su Palmi e Gioia Tauro.\u00a0 Due confronti dunque e due ospiti importanti alle Muse ovvero il presidente di Confcommercio Lorenzo Labate ed il vicepresidente di Confindustria Giuseppe Febert. La Confcommercio di Reggio Calabria \u00e8 oggi una moderna Associazione che ha come propria mission rappresentare gli interessi gli operatori del commercio, del turismo, dei servizi e delle professioni.<\/p>\n<p style=\"text-align: justify\">I principali obiettivi <strong>dell\u2019Associazione<\/strong> ha chiarito subito il presidente Labate sono promuovere e tutelare gli interessi morali, sociali ed economici degli associati nei confronti di qualunque organismo pubblico o privato, in armonia con gli indirizzi della <strong>Confcommercio nazionale<\/strong> e delle organizzazioni nazionali di categoria, dare identit\u00e0 e voce ai settori rappresentati come soggetti collettivi, organizzare le relazioni tra gli associati per la risoluzione di problemi comuni, promuovere la formazione professionale, tecnica e sindacale degli imprenditori e degli aspiranti imprenditori, fornire assistenza e consulenza alle imprese, servizi e opportunit\u00e0 esclusive di risparmio nella gestione aziendale. Labate chiamato ad intervenire sulle ultime posizioni della citt\u00e0 sull\u2019indagine realizzata da Italia Oggi con <strong>l\u2019Universit\u00e0<\/strong> <strong>La<\/strong> <strong>Sapienza<\/strong> vede <strong>Reggio Calabria<\/strong> al 95 \u00b0 posto e al 101\u00b0 nel pi\u00f9 recente rapporto del Sole 24 ore sulla qualit\u00e0 della vita, ha ribadito come i sondaggi non sono mai delle verit\u00e0 assolute perch\u00e9 dipendono da vari parametri richiesti agli intervistati ed occorre sempre considerare altri riferimenti quali (sanit\u00e0, pericolosit\u00e0, servizi sociali ecc &#8230;).<\/p>\n<p style=\"text-align: justify\">Dunque esaminare un territorio vuol dire avere molteplici parametri di riferimento ed attribuibili a pi\u00f9 fasce d\u2019et\u00e0 cosa che effettivamente non viene mai fatta e da questo ne scaturisce che la polemica anche nel caso di Reggio ha sempre un successo mediatico. \u00a0Occorre tornare e parlare alla politica, occorre che la politica faccia parte della vita di impresa non dimenticando che dal 2021 hanno chiuso 320 mila tra aziende e societ\u00e0. Nella nostra citt\u00e0 e provincia poi manca proprio l\u2019educazione all\u2019impresa ed occorre una strategia comune, una scelta comune che regioni magari come la Sicilia gestiscono meglio e con pi\u00f9 facilit\u00e0 per forma mentis. Tra le iniziative che far\u00e0 per la citt\u00e0 per <strong>Natale Confcommercio<\/strong> offrir\u00e0 \u201cVia per Via\u201d ovvero 10 mila euro per una pubblica illuminazione ad una zona della citt\u00e0 (lo scorso anno fu il Viale Aldo Moro),\u00a0 e poi una novit\u00e0 ovvero la nascita di una applicazione da scaricare sul cellulare denominata Movibel utile ai turisti \u00a0per fare scaturire informazioni del territorio ed orientarli alla conoscenza dei siti storico-artistici e non solo ed infine si sta pensando ad istituire un<strong> Festival Internazionale<\/strong> dedicato al Bergamotto con chef da tutto il mondo. Per Confindustria ha conversato il vice presidente <strong>Giuseppe Febert. <\/strong><\/p>\n<p style=\"text-align: justify\">Rappresento la principale associazione di rappresentanza delle imprese manifatturiere e di servizi in Italia a cui aderiscono volontariamente oltre 150 mila imprese di dimensioni piccole, medie e grandi, per un totale di 5.382.382 addetti ha subito chiarito Febert. La mission dell\u2019associazione \u00e8 favorire l\u2019affermazione dell\u2019impresa quale motore della crescita economica, sociale e civile del Paese. In questo senso, definisce percorsi comuni e condivide &#8211; nel rispetto degli ambiti di autonomia e influenza &#8211; obiettivi e iniziative con il mondo dell\u2019economia e della finanza, delle Istituzioni nazionali, europee e internazionali, della PA, delle Parti Sociali, della cultura e della ricerca, della scienza e della tecnologia, della politica, dell\u2019informazione e della societ\u00e0 civile. Noi \u00a0puntiamo alla politica del -rimani al Sud- magari divenendo una regione attrattiva per i ragazzi del nord,\u00a0 poich\u00e9 la nostra citt\u00e0 con le sue ottime condizioni meteo climatiche e la sua predisposizione al turismo potrebbe essere la California dell\u2019Italia.<\/p>\n<p style=\"text-align: justify\">Strategico il <strong>Porto di Gioia Tauro<\/strong> unico per la sua conformazione geografica e strutturale, ecco perch\u00e9 <strong>Msc<\/strong> opera in questa importante realt\u00e0 che \u00e8 l\u2019area portuale che non dovrebbe essere solo un importante riferimento per il tracking. Per Confindustria sar\u00e0 decisiva la costruzione del ponte sullo Stretto che va vista non in una ottica di scelta politica ma di aspetto economico, di sviluppo del territorio, basti pensare che sarebbero impegnate alla sua realizzazione circa 120 mila persone e si creerebbe una sinergia continua con la vicina <strong>Sicilia<\/strong> al centro del <strong>Mediterraneo<\/strong>. Tra gli interventi si segnala quello del vice sindaco di <strong>Bova Gianfranco Marino,<\/strong> il quale ha sostenuto che le scelte politiche devono essere sempre fatte ad ampio raggio, non limitandosi al tempo attuale, ma verificando i benefici negli anni, e questo lo si evince anche da precise volont\u00e0 che storicamente hanno visto rinascere centri come <strong>Roccella<\/strong> o ancora lo storico borgo di Bova, esempio rappresentativo delle buone pratiche della politica.\u00a0 Dunque un riscatto emotivo, sociale, economico ed umano per un\u2019area metropolitana che ancora non ha una sua identit\u00e0 precisa ed unitaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019associazione culturale Le Muse \u201cLaboratorio delle Arti e delle Lettere\u201d di Reggio Calabria cambia argomento domenicale e lo fa ponendo all\u2019attenzione il territorio metropolitano. Nascono cos\u00ec ha ricordato il presidente&hellip;<\/p>\n","protected":false},"author":8,"featured_media":13047,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[921,196,140],"tags":[4986,988,236],"class_list":["post-13044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-news","category-reggio-calabria","tag-le-muse-laboratorio-delle-arti-e-delle-lettere","tag-porto-di-gioia-tauro","tag-reggio-calabria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;associazione Le Muse cambia l&#039;argomento domenicale<\/title>\n<meta name=\"description\" content=\"L&#039;associazione culturale Le Muse di Reggio Calabria cambier\u00e0 argomento domenicale mettendo il territorio metropolitano come priorit\u00e0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/23\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;associazione Le Muse cambia l&#039;argomento domenicale\" \/>\n<meta property=\"og:description\" content=\"L&#039;associazione culturale Le Muse di Reggio Calabria cambier\u00e0 argomento domenicale mettendo il territorio metropolitano come priorit\u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/23\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-23T09:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-24T10:06:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/11\/Il-presidente-Muse-Giuseppe-Livoti-con-Lorenzo-Labate-e-Giuseppe-Febert.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"858\" \/>\n\t<meta property=\"og:image:height\" content=\"572\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Filippo Francesco Idone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Filippo Francesco Idone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/23\\\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/23\\\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\\\/\"},\"author\":{\"name\":\"Filippo Francesco Idone\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\"},\"headline\":\"Reggio Calabria: l&#8217;associazione Le Muse cambia l&#8217;argomento domenicale\",\"datePublished\":\"2022-11-23T09:00:00+00:00\",\"dateModified\":\"2022-11-24T10:06:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/23\\\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\\\/\"},\"wordCount\":1107,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/23\\\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/11\\\/Il-presidente-Muse-Giuseppe-Livoti-con-Lorenzo-Labate-e-Giuseppe-Febert.jpg\",\"keywords\":[\"Le Muse \u2013 Laboratorio delle Arti e delle Lettere\",\"porto di Gioia Tauro\",\"reggio calabria\"],\"articleSection\":[\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/23\\\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/23\\\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/23\\\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\\\/\",\"name\":\"L'associazione Le Muse cambia l'argomento domenicale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/23\\\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/23\\\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/11\\\/Il-presidente-Muse-Giuseppe-Livoti-con-Lorenzo-Labate-e-Giuseppe-Febert.jpg\",\"datePublished\":\"2022-11-23T09:00:00+00:00\",\"dateModified\":\"2022-11-24T10:06:31+00:00\",\"description\":\"L'associazione culturale Le Muse di Reggio Calabria cambier\u00e0 argomento domenicale mettendo il territorio metropolitano come priorit\u00e0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/23\\\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/23\\\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/23\\\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/11\\\/Il-presidente-Muse-Giuseppe-Livoti-con-Lorenzo-Labate-e-Giuseppe-Febert.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/11\\\/Il-presidente-Muse-Giuseppe-Livoti-con-Lorenzo-Labate-e-Giuseppe-Febert.jpg\",\"width\":858,\"height\":572},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/23\\\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reggio Calabria: l&#8217;associazione Le Muse cambia l&#8217;argomento domenicale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\",\"name\":\"Filippo Francesco Idone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"caption\":\"Filippo Francesco Idone\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/filippoidone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'associazione Le Muse cambia l'argomento domenicale","description":"L'associazione culturale Le Muse di Reggio Calabria cambier\u00e0 argomento domenicale mettendo il territorio metropolitano come priorit\u00e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/23\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\/","og_locale":"it_IT","og_type":"article","og_title":"L'associazione Le Muse cambia l'argomento domenicale","og_description":"L'associazione culturale Le Muse di Reggio Calabria cambier\u00e0 argomento domenicale mettendo il territorio metropolitano come priorit\u00e0","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/23\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\/","og_site_name":"Radio Touring 104","article_published_time":"2022-11-23T09:00:00+00:00","article_modified_time":"2022-11-24T10:06:31+00:00","og_image":[{"width":858,"height":572,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/11\/Il-presidente-Muse-Giuseppe-Livoti-con-Lorenzo-Labate-e-Giuseppe-Febert.jpg","type":"image\/jpeg"}],"author":"Filippo Francesco Idone","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Filippo Francesco Idone","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/23\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/23\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\/"},"author":{"name":"Filippo Francesco Idone","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b"},"headline":"Reggio Calabria: l&#8217;associazione Le Muse cambia l&#8217;argomento domenicale","datePublished":"2022-11-23T09:00:00+00:00","dateModified":"2022-11-24T10:06:31+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/23\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\/"},"wordCount":1107,"commentCount":0,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/23\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/11\/Il-presidente-Muse-Giuseppe-Livoti-con-Lorenzo-Labate-e-Giuseppe-Febert.jpg","keywords":["Le Muse \u2013 Laboratorio delle Arti e delle Lettere","porto di Gioia Tauro","reggio calabria"],"articleSection":["Home","News","Reggio Calabria"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/23\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/23\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/23\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\/","name":"L'associazione Le Muse cambia l'argomento domenicale","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/23\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/23\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/11\/Il-presidente-Muse-Giuseppe-Livoti-con-Lorenzo-Labate-e-Giuseppe-Febert.jpg","datePublished":"2022-11-23T09:00:00+00:00","dateModified":"2022-11-24T10:06:31+00:00","description":"L'associazione culturale Le Muse di Reggio Calabria cambier\u00e0 argomento domenicale mettendo il territorio metropolitano come priorit\u00e0","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/23\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/23\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/23\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/11\/Il-presidente-Muse-Giuseppe-Livoti-con-Lorenzo-Labate-e-Giuseppe-Febert.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/11\/Il-presidente-Muse-Giuseppe-Livoti-con-Lorenzo-Labate-e-Giuseppe-Febert.jpg","width":858,"height":572},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/23\/reggio-calabria-lassociazione-le-muse-cambia-largomento-domenicale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Reggio Calabria: l&#8217;associazione Le Muse cambia l&#8217;argomento domenicale"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b","name":"Filippo Francesco Idone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","caption":"Filippo Francesco Idone"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/filippoidone\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/11\/Il-presidente-Muse-Giuseppe-Livoti-con-Lorenzo-Labate-e-Giuseppe-Febert.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/13044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=13044"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/13044\/revisions"}],"predecessor-version":[{"id":13048,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/13044\/revisions\/13048"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/13047"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=13044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=13044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=13044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}