{"id":13463,"date":"2022-11-26T18:59:56","date_gmt":"2022-11-26T17:59:56","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=13463"},"modified":"2022-11-28T11:03:13","modified_gmt":"2022-11-28T10:03:13","slug":"villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/26\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\/","title":{"rendered":"Villa San Giovanni: criticit\u00e0 verso l&#8217;Autorit\u00e0 Portuale di Sistema dello Stretto"},"content":{"rendered":"<div dir=\"auto\" style=\"text-align: justify\">Registriamo anche noi, amministrazione comunale, il silenzio assordante dell\u2019<strong>Autorit\u00e0 Portuale<\/strong> di<strong> Sistema dello Stretto<\/strong> dopo la delibera consiliare assunta all\u2019unanimit\u00e0 lo scorso 13 settembre e trasmessa alla stessa Autorit\u00e0 entro la scadenza indicata: lo registriamo con preoccupazione perch\u00e9 mai <strong>Villa<\/strong> accetter\u00e0 di essere seduta ad una mensa gi\u00e0 imbandita da chicchessia. Del resto, abbiamo registrato con amarezza la visita del presidente Mega nel mese di ottobre alla banchina portuale, senza che lo stesso abbia sentito la necessit\u00e0, a posizioni assunte, di approfittare di quella stessa visita per confrontarsi con i rappresentati dell\u2019esecutivo e del consiglio comunale. Al presidente Mega avremmo spiegato il nostro punto di vista sull\u2019accusa di immobilismo decennale mossa da lui a mezzo social: quell\u2019immobilismo \u00e8 certamente attribuibile a un vecchio modo di fare politica che non ci appartiene, perch\u00e9 non siamo noi a voler mantenere uno status quo che mortifica la Citt\u00e0 e arreca danno ambientale e danno alla salute dei villesi.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\" style=\"text-align: justify\">L<strong>\u2019Autorit\u00e0 Portuale dello Stretto<\/strong> non pu\u00f2 sacrificare gli interessi di Villa con la giustificazione di decisioni non assunte nel corso di decenni: deve essere questa comunit\u00e0 a pagare il prezzo per ci\u00f2 che non \u00e8 stato preteso dalla politica nel passato? Finalmente anche per Villa \u00e8 arrivato il momento di decidere nel suo esclusivo interesse, a maggior ragione se questo non compromette in alcun modo il sistema della mobilit\u00e0 dinamica dello Stretto. Le colpe del passato (individuate dal presidente Mega) non devono ricadere ancora su questa comunit\u00e0. Questa Citt\u00e0 vuole respirare, vivere e svilupparsi.\u00a0Il consiglio comunale ha dettato una posizione condivisa anche da quanti hanno interloquito (prima e dopo il 13 settembre) con quest\u2019Amministrazione: no a nuovi ormeggi all\u2019interno del porto storico; no ai 20mila metri quadrati di banchina per ospitare i mezzi veloci ma s\u00ec all\u2019ottimizzazione degli attracchi dei mezzi veloci per implementare i servizi ai passeggeri; immediata realizzazione, con i fondi gi\u00e0 a disposizione dell\u2019Autorit\u00e0 di Sistema Portuale dello Stretto, di una passerella coperta sulla banchina attuale prospiciente via Marinai d\u2019Italia e distinzione, ai fini della sicurezza, dei flussi pedonale e veicolare; interventi urgenti sui quattro terrenti che sfociano nelle aree di competenza dell\u2019Autorit\u00e0 (Solaro, Lupina, Immacolata e Campanella).<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\" style=\"text-align: justify\">L\u2019Unico progetto della Citt\u00e0, su cui investire i fondi del <strong>PNRR<\/strong>, rimane quello unanimemente voluto dal civico consesso: autoporto di Castelluccio (con i fondi residui del DPCM), bretella di collegamento, nuovi banchinamenti-piazzali operativi-stazione marittima-nuovi approdi a sud dell\u2019attuale porto storico ferroviario, ripascimento della spiaggia di Acciarello, restituzione alla Citt\u00e0 degli approdi dismessi dalle societ\u00e0 private da convertire in porto turistico comunale per la nautica da diporto, realizzazione da parte dell\u2019ente degli approdi turistici in localit\u00e0 <strong>Croce<\/strong> <strong>Rossa<\/strong>. E\u2019 alto l\u2019interesse della comunit\u00e0 rispetto a questo tema e rimaniamo disponibili a una continua interlocuzione: partiti politici, movimenti, associazioni e cittadini si intendano chiamati ad un tavolo permanente di confronto. L\u2019interesse della nostra Citt\u00e0 prima di tutto!<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Registriamo anche noi, amministrazione comunale, il silenzio assordante dell\u2019Autorit\u00e0 Portuale di Sistema dello Stretto dopo la delibera consiliare assunta all\u2019unanimit\u00e0 lo scorso 13 settembre e trasmessa alla stessa Autorit\u00e0 entro&hellip;<\/p>\n","protected":false},"author":8,"featured_media":9177,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[142,921,196],"tags":[6519,2467,1034,6520,364],"class_list":["post-13463","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-home","category-news","tag-autorita-portuale-dello-stretto","tag-croce-rossa","tag-pnrr","tag-sistema-dello-stretto","tag-villa-san-giovanni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Villa San Giovanni: criticit\u00e0 verso l&#039;Autorit\u00e0 Portuale di Sistema dello Stretto - Radio Touring 104<\/title>\n<meta name=\"description\" content=\"Dopo la delibera, l&#039;amministrazione di Villa San Giovanni, ha comunicato varie criticit\u00e0 verso l&#039;Autorit\u00e0 Portuale di Sistema dello Stretto\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/26\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Villa San Giovanni: criticit\u00e0 verso l&#039;Autorit\u00e0 Portuale di Sistema dello Stretto - Radio Touring 104\" \/>\n<meta property=\"og:description\" content=\"Dopo la delibera, l&#039;amministrazione di Villa San Giovanni, ha comunicato varie criticit\u00e0 verso l&#039;Autorit\u00e0 Portuale di Sistema dello Stretto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/26\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-26T17:59:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-28T10:03:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/08\/villa-san-giovanni.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Filippo Francesco Idone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Filippo Francesco Idone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/26\\\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/26\\\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\\\/\"},\"author\":{\"name\":\"Filippo Francesco Idone\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\"},\"headline\":\"Villa San Giovanni: criticit\u00e0 verso l&#8217;Autorit\u00e0 Portuale di Sistema dello Stretto\",\"datePublished\":\"2022-11-26T17:59:56+00:00\",\"dateModified\":\"2022-11-28T10:03:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/26\\\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\\\/\"},\"wordCount\":495,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/26\\\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/08\\\/villa-san-giovanni.jpg\",\"keywords\":[\"Autorit\u00e0 Portuale dello Stretto\",\"Croce Rossa\",\"pnrr\",\"Sistema dello Stretto\",\"villa san giovanni\"],\"articleSection\":[\"Calabria\",\"Home\",\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/26\\\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/26\\\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/26\\\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\\\/\",\"name\":\"Villa San Giovanni: criticit\u00e0 verso l'Autorit\u00e0 Portuale di Sistema dello Stretto - Radio Touring 104\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/26\\\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/26\\\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/08\\\/villa-san-giovanni.jpg\",\"datePublished\":\"2022-11-26T17:59:56+00:00\",\"dateModified\":\"2022-11-28T10:03:13+00:00\",\"description\":\"Dopo la delibera, l'amministrazione di Villa San Giovanni, ha comunicato varie criticit\u00e0 verso l'Autorit\u00e0 Portuale di Sistema dello Stretto\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/26\\\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/26\\\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/26\\\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/08\\\/villa-san-giovanni.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/08\\\/villa-san-giovanni.jpg\",\"width\":960,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2022\\\/11\\\/26\\\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Villa San Giovanni: criticit\u00e0 verso l&#8217;Autorit\u00e0 Portuale di Sistema dello Stretto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\",\"name\":\"Filippo Francesco Idone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"caption\":\"Filippo Francesco Idone\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/filippoidone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Villa San Giovanni: criticit\u00e0 verso l'Autorit\u00e0 Portuale di Sistema dello Stretto - Radio Touring 104","description":"Dopo la delibera, l'amministrazione di Villa San Giovanni, ha comunicato varie criticit\u00e0 verso l'Autorit\u00e0 Portuale di Sistema dello Stretto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/26\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\/","og_locale":"it_IT","og_type":"article","og_title":"Villa San Giovanni: criticit\u00e0 verso l'Autorit\u00e0 Portuale di Sistema dello Stretto - Radio Touring 104","og_description":"Dopo la delibera, l'amministrazione di Villa San Giovanni, ha comunicato varie criticit\u00e0 verso l'Autorit\u00e0 Portuale di Sistema dello Stretto","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/26\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\/","og_site_name":"Radio Touring 104","article_published_time":"2022-11-26T17:59:56+00:00","article_modified_time":"2022-11-28T10:03:13+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/08\/villa-san-giovanni.jpg","type":"image\/jpeg"}],"author":"Filippo Francesco Idone","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Filippo Francesco Idone","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/26\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/26\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\/"},"author":{"name":"Filippo Francesco Idone","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b"},"headline":"Villa San Giovanni: criticit\u00e0 verso l&#8217;Autorit\u00e0 Portuale di Sistema dello Stretto","datePublished":"2022-11-26T17:59:56+00:00","dateModified":"2022-11-28T10:03:13+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/26\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\/"},"wordCount":495,"commentCount":0,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/26\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/08\/villa-san-giovanni.jpg","keywords":["Autorit\u00e0 Portuale dello Stretto","Croce Rossa","pnrr","Sistema dello Stretto","villa san giovanni"],"articleSection":["Calabria","Home","News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/26\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/26\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/26\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\/","name":"Villa San Giovanni: criticit\u00e0 verso l'Autorit\u00e0 Portuale di Sistema dello Stretto - Radio Touring 104","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/26\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/26\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/08\/villa-san-giovanni.jpg","datePublished":"2022-11-26T17:59:56+00:00","dateModified":"2022-11-28T10:03:13+00:00","description":"Dopo la delibera, l'amministrazione di Villa San Giovanni, ha comunicato varie criticit\u00e0 verso l'Autorit\u00e0 Portuale di Sistema dello Stretto","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/26\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/26\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/26\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/08\/villa-san-giovanni.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/08\/villa-san-giovanni.jpg","width":960,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2022\/11\/26\/villa-san-giovanni-criticita-verso-lautorita-portuale-di-sistema-dello-stretto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Villa San Giovanni: criticit\u00e0 verso l&#8217;Autorit\u00e0 Portuale di Sistema dello Stretto"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b","name":"Filippo Francesco Idone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","caption":"Filippo Francesco Idone"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/filippoidone\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/08\/villa-san-giovanni.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/13463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=13463"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/13463\/revisions"}],"predecessor-version":[{"id":13464,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/13463\/revisions\/13464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/9177"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=13463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=13463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=13463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}