{"id":17078,"date":"2023-01-19T10:10:49","date_gmt":"2023-01-19T09:10:49","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=17078"},"modified":"2023-01-19T10:11:03","modified_gmt":"2023-01-19T09:11:03","slug":"17078","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/19\/17078\/","title":{"rendered":"31 enne arrestato per detenzione di sostanze stupefacenti"},"content":{"rendered":"<p>A Reggio Calabria, i Carabinieri hanno arrestato per detenzione di sostanze stupefacenti, un 31enne del posto, coniugato, disoccupato, con precedenti di polizia.<\/p>\n<p>Nello specifico, i militari dell\u2019Arma, nell\u2019ambito di servizi di controllo a largo raggio del territorio, a seguito di perquisizione domiciliare presso l\u2019abitazione dell\u2019uomo, hanno rinvenuto nascosti all\u2019interno di un armadio, oltre 400 grammi di sostanza stupefacente del tipo marijuana, un bilancino di precisione e vario materiale per il confezionamento della sostanza stupefacente.<\/p>\n<p>Lo stupefacente rinvenuto \u00e8 stato sottoposto a sequestro, a disposizione dell\u2019Autorit\u00e0 Giudiziaria mentre l\u2019uomo, a seguito della convalida dell\u2019arresto \u00e8 stato sottoposto agli arresti domiciliari.<\/p>\n<p>Rimane sempre alta l\u2019attenzione dell\u2019Arma per i crimini in materia di detenzione illecita e spaccio di sostanze stupefacenti, al fine di contrastare un fenomeno dilagante specie tra i giovani.<\/p>\n<p>Trattandosi di procedimento in fase di indagini preliminari, rimangono salve le successive determinazioni in fase processuale.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Reggio Calabria, i Carabinieri hanno arrestato per detenzione di sostanze stupefacenti, un 31enne del posto, coniugato, disoccupato, con precedenti di polizia. Nello specifico, i militari dell\u2019Arma, nell\u2019ambito di servizi&hellip;<\/p>\n","protected":false},"author":12,"featured_media":17083,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[921,196,140],"tags":[8672,8671,8674,8673],"class_list":["post-17078","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-news","category-reggio-calabria","tag-31-enne-arrestato-per-detenzione-di-sostanze-stupefacenti","tag-carabinieri-reggio-calabria","tag-droga-e-materiale-di-confezionamento","tag-possesso-di-bilancino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>31 enne arrestato per detenzione di sostanze stupefacenti<\/title>\n<meta name=\"description\" content=\"I Carabinieri hanno arrestato un 31enne con precedenti per possesso di 400 gr di stupefacente, bilancino e materiale di confezionamento\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/19\/17078\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"31 enne arrestato per detenzione di sostanze stupefacenti\" \/>\n<meta property=\"og:description\" content=\"I Carabinieri hanno arrestato un 31enne con precedenti per possesso di 400 gr di stupefacente, bilancino e materiale di confezionamento\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/19\/17078\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-19T09:10:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-19T09:11:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/01\/stupefacenti-carabinieri-reggio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"882\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sebastiano Plutino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastiano Plutino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/19\\\/17078\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/19\\\/17078\\\/\"},\"author\":{\"name\":\"Sebastiano Plutino\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\"},\"headline\":\"31 enne arrestato per detenzione di sostanze stupefacenti\",\"datePublished\":\"2023-01-19T09:10:49+00:00\",\"dateModified\":\"2023-01-19T09:11:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/19\\\/17078\\\/\"},\"wordCount\":159,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/19\\\/17078\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/01\\\/stupefacenti-carabinieri-reggio.jpg\",\"keywords\":[\"31 enne arrestato per detenzione di sostanze stupefacenti\",\"carabinieri Reggio Calabria\",\"droga e materiale di confezionamento\",\"possesso di bilancino\"],\"articleSection\":[\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/19\\\/17078\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/19\\\/17078\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/19\\\/17078\\\/\",\"name\":\"31 enne arrestato per detenzione di sostanze stupefacenti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/19\\\/17078\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/19\\\/17078\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/01\\\/stupefacenti-carabinieri-reggio.jpg\",\"datePublished\":\"2023-01-19T09:10:49+00:00\",\"dateModified\":\"2023-01-19T09:11:03+00:00\",\"description\":\"I Carabinieri hanno arrestato un 31enne con precedenti per possesso di 400 gr di stupefacente, bilancino e materiale di confezionamento\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/19\\\/17078\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/19\\\/17078\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/19\\\/17078\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/01\\\/stupefacenti-carabinieri-reggio.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/01\\\/stupefacenti-carabinieri-reggio.jpg\",\"width\":882,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/19\\\/17078\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"31 enne arrestato per detenzione di sostanze stupefacenti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\",\"name\":\"Sebastiano Plutino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"caption\":\"Sebastiano Plutino\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/sebastiano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"31 enne arrestato per detenzione di sostanze stupefacenti","description":"I Carabinieri hanno arrestato un 31enne con precedenti per possesso di 400 gr di stupefacente, bilancino e materiale di confezionamento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/19\/17078\/","og_locale":"it_IT","og_type":"article","og_title":"31 enne arrestato per detenzione di sostanze stupefacenti","og_description":"I Carabinieri hanno arrestato un 31enne con precedenti per possesso di 400 gr di stupefacente, bilancino e materiale di confezionamento","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/19\/17078\/","og_site_name":"Radio Touring 104","article_published_time":"2023-01-19T09:10:49+00:00","article_modified_time":"2023-01-19T09:11:03+00:00","og_image":[{"width":882,"height":700,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/01\/stupefacenti-carabinieri-reggio.jpg","type":"image\/jpeg"}],"author":"Sebastiano Plutino","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Sebastiano Plutino","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/19\/17078\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/19\/17078\/"},"author":{"name":"Sebastiano Plutino","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e"},"headline":"31 enne arrestato per detenzione di sostanze stupefacenti","datePublished":"2023-01-19T09:10:49+00:00","dateModified":"2023-01-19T09:11:03+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/19\/17078\/"},"wordCount":159,"commentCount":0,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/19\/17078\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/01\/stupefacenti-carabinieri-reggio.jpg","keywords":["31 enne arrestato per detenzione di sostanze stupefacenti","carabinieri Reggio Calabria","droga e materiale di confezionamento","possesso di bilancino"],"articleSection":["Home","News","Reggio Calabria"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/19\/17078\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/19\/17078\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/19\/17078\/","name":"31 enne arrestato per detenzione di sostanze stupefacenti","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/19\/17078\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/19\/17078\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/01\/stupefacenti-carabinieri-reggio.jpg","datePublished":"2023-01-19T09:10:49+00:00","dateModified":"2023-01-19T09:11:03+00:00","description":"I Carabinieri hanno arrestato un 31enne con precedenti per possesso di 400 gr di stupefacente, bilancino e materiale di confezionamento","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/19\/17078\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/19\/17078\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/19\/17078\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/01\/stupefacenti-carabinieri-reggio.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/01\/stupefacenti-carabinieri-reggio.jpg","width":882,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/19\/17078\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"31 enne arrestato per detenzione di sostanze stupefacenti"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e","name":"Sebastiano Plutino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","caption":"Sebastiano Plutino"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/sebastiano\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/01\/stupefacenti-carabinieri-reggio.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/17078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=17078"}],"version-history":[{"count":2,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/17078\/revisions"}],"predecessor-version":[{"id":17085,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/17078\/revisions\/17085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/17083"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=17078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=17078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=17078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}