{"id":17824,"date":"2023-01-27T19:48:15","date_gmt":"2023-01-27T18:48:15","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=17824"},"modified":"2023-01-28T16:48:35","modified_gmt":"2023-01-28T15:48:35","slug":"gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/27\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\/","title":{"rendered":"Gelatiere dell&#8217;Anno: il titolo a Carmelo Caratozzolo, di Oppido Mamertina"},"content":{"rendered":"<p style=\"text-align: justify;\">&#8220;<em>\u00c8 calabrese di Oppido Mamertina il Gelatiere dell\u2019Anno<\/em>\u201d, dichiara con orgoglio il Consigliere regionale Domenico Giannetta (FI). \u201c<em>Carmelo Caratozzolo, calabrese di Oppido Mamertina \u00e8 stato insignito Gelatiere dell\u2019Anno alla 44\u00b0edizione del Salone internazionale del Sigep di Rimini dalla prestigiosa Associazione Italiana Gelatieri. Con la pasticceria artigianale di Carmelo Caratozzolo<\/em> &#8211; dichiara il consigliere Giannetta &#8211; <em>vince la migliore tradizione dolciaria della Calabria e di Oppido Mamertina. Sono particolarmente orgoglioso del riconoscimento, perch\u00e9 conosco la cura e l\u2019amore che Carmelo mette nel proprio lavoro e quanto la sua pasticceria sia attenta alla tradizione e alle eccellenze del territorio. <\/em><br \/>\n<em>Carmelo ha scelto di rimanere in Calabria<\/em> &#8211; continua Giannetta &#8211; <em>e conduce la sua attivit\u00e0 dove \u00e8 nato, a Oppido. Cosa che, per lui, non ha mai rappresentato un limite, ma semmai un punto di forza per la sua proposta. Al Sigep (Salone internazionale della Gelateria, Pasticceria, Panificazione Artigianali e Caff\u00e8), non a caso, ha vinto con il gusto \u201ctradizioni\u201d, un gelato gianduia e arachidi che ricorda il croccante dei nostri torroni apprezzati in tutto il mondo. Nella cornice internazionale del Sigep<\/em> &#8211; dice ancora il consigliere forzista &#8211; <em>in un clima effervescente di grande competizione, che ha visto la partecipazione di oltre 250 pasticceri di tutto il mondo, Carmelo Caratozzolo si \u00e8 aggiudicato anche il primo premio per l\u2019eccellenza della sua torta gelato artigianale. Una vittoria che gli vale la finale della Coppa Italiana che si terr\u00e0 a Roma in autunno. Una bella storia, ancora da scrivere<\/em> &#8211; conclude Giannetta &#8211;<em> che spero possa essere da esempio ai tanti giovani calabresi appassionati del mestiere perch\u00e9 scelgano di investire in Calabria il proprio futuro di successo<\/em>\u201d.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>&#8220;\u00c8 calabrese di Oppido Mamertina il Gelatiere dell\u2019Anno\u201d, dichiara con orgoglio il Consigliere regionale Domenico Giannetta (FI). \u201cCarmelo Caratozzolo, calabrese di Oppido Mamertina \u00e8 stato insignito Gelatiere dell\u2019Anno alla 44\u00b0edizione&hellip;<\/p>\n","protected":false},"author":5,"featured_media":17825,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[142,921,196],"tags":[9177,2074,9176,2052],"class_list":["post-17824","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-home","category-news","tag-carmelo-caratozzolo","tag-domenico-giannetta","tag-gelatiere-dellanno","tag-oppido-mamertina"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gelatiere dell&#039;Anno: il titolo al calabrese Carmelo Caratozzolo<\/title>\n<meta name=\"description\" content=\"Carmelo Caratozzolo \u00e8 stato insignito Gelatiere dell\u2019Anno alla 44\u00b0edizione del Salone internazionale del Sigep di Rimini\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/27\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gelatiere dell&#039;Anno: il titolo al calabrese Carmelo Caratozzolo\" \/>\n<meta property=\"og:description\" content=\"Carmelo Caratozzolo \u00e8 stato insignito Gelatiere dell\u2019Anno alla 44\u00b0edizione del Salone internazionale del Sigep di Rimini\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/27\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-27T18:48:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-28T15:48:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/01\/gelatiere.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1104\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/27\\\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/27\\\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\\\/\"},\"author\":{\"name\":\"redazione\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/1b3eb3c07c47136bc44c785c543e635f\"},\"headline\":\"Gelatiere dell&#8217;Anno: il titolo a Carmelo Caratozzolo, di Oppido Mamertina\",\"datePublished\":\"2023-01-27T18:48:15+00:00\",\"dateModified\":\"2023-01-28T15:48:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/27\\\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\\\/\"},\"wordCount\":283,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/27\\\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/01\\\/gelatiere.jpg\",\"keywords\":[\"carmelo caratozzolo\",\"domenico giannetta\",\"gelatiere dell'anno\",\"Oppido Mamertina\"],\"articleSection\":[\"Calabria\",\"Home\",\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/27\\\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/27\\\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/27\\\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\\\/\",\"name\":\"Gelatiere dell'Anno: il titolo al calabrese Carmelo Caratozzolo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/27\\\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/27\\\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/01\\\/gelatiere.jpg\",\"datePublished\":\"2023-01-27T18:48:15+00:00\",\"dateModified\":\"2023-01-28T15:48:35+00:00\",\"description\":\"Carmelo Caratozzolo \u00e8 stato insignito Gelatiere dell\u2019Anno alla 44\u00b0edizione del Salone internazionale del Sigep di Rimini\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/27\\\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/27\\\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/27\\\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/01\\\/gelatiere.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/01\\\/gelatiere.jpg\",\"width\":1104,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/01\\\/27\\\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gelatiere dell&#8217;Anno: il titolo a Carmelo Caratozzolo, di Oppido Mamertina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/1b3eb3c07c47136bc44c785c543e635f\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gelatiere dell'Anno: il titolo al calabrese Carmelo Caratozzolo","description":"Carmelo Caratozzolo \u00e8 stato insignito Gelatiere dell\u2019Anno alla 44\u00b0edizione del Salone internazionale del Sigep di Rimini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/27\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\/","og_locale":"it_IT","og_type":"article","og_title":"Gelatiere dell'Anno: il titolo al calabrese Carmelo Caratozzolo","og_description":"Carmelo Caratozzolo \u00e8 stato insignito Gelatiere dell\u2019Anno alla 44\u00b0edizione del Salone internazionale del Sigep di Rimini","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/27\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\/","og_site_name":"Radio Touring 104","article_published_time":"2023-01-27T18:48:15+00:00","article_modified_time":"2023-01-28T15:48:35+00:00","og_image":[{"width":1104,"height":900,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/01\/gelatiere.jpg","type":"image\/jpeg"}],"author":"redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/27\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/27\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\/"},"author":{"name":"redazione","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/1b3eb3c07c47136bc44c785c543e635f"},"headline":"Gelatiere dell&#8217;Anno: il titolo a Carmelo Caratozzolo, di Oppido Mamertina","datePublished":"2023-01-27T18:48:15+00:00","dateModified":"2023-01-28T15:48:35+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/27\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\/"},"wordCount":283,"commentCount":0,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/27\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/01\/gelatiere.jpg","keywords":["carmelo caratozzolo","domenico giannetta","gelatiere dell'anno","Oppido Mamertina"],"articleSection":["Calabria","Home","News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/27\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/27\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/27\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\/","name":"Gelatiere dell'Anno: il titolo al calabrese Carmelo Caratozzolo","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/27\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/27\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/01\/gelatiere.jpg","datePublished":"2023-01-27T18:48:15+00:00","dateModified":"2023-01-28T15:48:35+00:00","description":"Carmelo Caratozzolo \u00e8 stato insignito Gelatiere dell\u2019Anno alla 44\u00b0edizione del Salone internazionale del Sigep di Rimini","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/27\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/27\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/27\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/01\/gelatiere.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/01\/gelatiere.jpg","width":1104,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/01\/27\/gelatiere-dellanno-il-titolo-a-carmelo-caratozzolo-di-oppido-mamertina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Gelatiere dell&#8217;Anno: il titolo a Carmelo Caratozzolo, di Oppido Mamertina"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/1b3eb3c07c47136bc44c785c543e635f","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g","caption":"redazione"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/redazione\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/01\/gelatiere.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/17824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=17824"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/17824\/revisions"}],"predecessor-version":[{"id":17826,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/17824\/revisions\/17826"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/17825"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=17824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=17824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=17824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}