{"id":18503,"date":"2023-02-08T09:30:03","date_gmt":"2023-02-08T08:30:03","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=18503"},"modified":"2023-02-08T09:30:03","modified_gmt":"2023-02-08T08:30:03","slug":"villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2023\/02\/08\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\/","title":{"rendered":"Villa S.G., comunicato su ipotesi bilancio stabilmente riequilibrato"},"content":{"rendered":"<div dir=\"auto\">Le prescrizioni sollevate dal ministero dell\u2019Interno sull\u2019ipotesi di bilancio stabilmente riequilibrato approvato da questa maggioranza consiliare non rappresentano la \u201cbocciatura\u201d e tanto meno certificano la \u201cinefficienza\u201d nella gestione e nell\u2019amministrazione della Citt\u00e0.<\/div>\n<div dir=\"auto\">La minoranza consiliare e le forze politiche di opposizione di cdx, come ormai \u00e8 consuetudine, tentano di screditare un operato trasparente e che ha avuto ed ha il solo fine di dare risposte alla Comunit\u00e0, come deve essere in un corretto rapporto tra amministratori ed amministrati.<\/div>\n<div dir=\"auto\">Il ministero, infatti, esamina il documento contabile (del settembre 2022) nel 2023 e, in estrema sintesi, chiede a quest\u2019ente di rimodulare l\u2019ipotesi di bilancio non pi\u00f9 come una previsione sul 2021\/2023, ma di redigere per gli anni 2021 e 2022 un pre consuntivo, estendendo l\u2019ipotesi fino al 2025.<\/div>\n<div dir=\"auto\">Ma la minoranza non entra nel merito, come ci si sarebbe aspettati da chi \u00e8 chiamato a svolgere il ruolo di controllo e garanzia, limitandosi ad esprimere frettolose quanto imprecise valutazioni in relazione alla nota ministeriale, rispetto alle quali<\/div>\n<div dir=\"auto\">occorre offrire noi, ancora una volta, le corrette ed autentiche interpretazioni per evitare che si possano ingenerare confusioni.<\/div>\n<div dir=\"auto\">Di fronte al disastro economico finanziario cui quelle stesse forze politiche di minoranza hanno portato la Citt\u00e0, questa maggioranza ha deciso di approvare una nuova ipotesi di bilancio stabilmente riequilibrato, sulla traccia lasciata dai commissari prefettizi, nel pieno rispetto del dettato dell\u2019art. 261 del TUEL (Testo Unico Enti Locali) che disciplina la procedura di formazione del documento: \u201c 1. L&#8217;ipotesi di bilancio di previsione stabilmente riequilibrato \u00e8 istruita dalla Commissione per la finanza e gli organici degli enti locali, che formula eventuali rilievi o richieste istruttorie, cui l&#8217;ente locale fornisce risposta entro sessanta giorni.<\/div>\n<div dir=\"auto\">2.\u00a0 \u00a0 \u00a0Entro il termine di quattro mesi la Commissione esprime un parere sulla validit\u00e0 delle misure disposte dall&#8217;ente per consolidare la propria situazione finanziaria e sulla capacit\u00e0 delle misure stesse di assicurare stabilit\u00e0 alla gestione finanziaria dell&#8217;ente medesimo. La formulazione di rilievi o richieste di cui al comma 1 sospende il decorso del termine\u201d.<\/div>\n<div dir=\"auto\">Nel merito dei rilievi formulati, dunque, la struttura economico finanziaria fornir\u00e0 tutte le informazioni richieste, formulando un\u2019ipotesi ancor pi\u00f9 strutturata a valere fino all\u2019annualit\u00e0 2025.<\/div>\n<div dir=\"auto\">Di siffatta nuova elaborazione si dar\u00e0 dovuta contezza ai consiglieri tutti nelle sedi preposte quando i tempi saranno maturi, ovvero quando la proposta sar\u00e0 pronta per l\u2019esame da parte della commissione bilancio e del consiglio comunale.<\/div>\n<div dir=\"auto\">Il documento, infatti, discusso solo per cortesia istituzionale con l\u2019ufficio di presidenza (assente il vice presidente Lucisano) ed i capigruppo consiliari, non \u00e8 un atto di competenza dei consiglieri ma un provvedimento di istruttoria ammnistrativa: ci\u00f2 al fine di non ingenerare confusione in ordine alle competenze di gestione ed a quelle politiche, che inducono a presumere di addebitare responsabilit\u00e0 impropriamente, nonostante la delicatezza che la vicenda richiede.<\/div>\n<div dir=\"auto\">Uno fra tutti, il presunto peggioramento della situazione finanziaria dell\u2019ente che, appunto, non risulta assolutamente intaccata da un documento previsionale ereditato dalla precedente struttura economico finanziaria.<\/div>\n<div dir=\"auto\">Non sono le presunte carenze di \u201cdocumentazione giustificativa\u201d a indurre il Ministero a richiedere ulteriore istruttoria per il via libera del documento, piuttosto analisi, complessi elaborati, attestazioni e verifiche ben differenti.<\/div>\n<div dir=\"auto\">Le presunte \u201cintraprendenti\u201d ed \u201ceccessive\u201d variazioni di bilancio, strumentalmente richiamate dalla minoranza come causa di aumento della spesa, non costituiscono invece alcun aggravio della situazione economica, ma sono richiamate nella nota del Ministero come possibili (e peraltro segnalate!) produttrici di un paventato disequilibrio che, in realt\u00e0, non sussiste. Questo sar\u00e0 dimostrato per tabulas dall\u2019assessorato competente.<\/div>\n<div dir=\"auto\">Nessun imbarazzo di questa amministrazione, ma tutt\u2019al pi\u00f9 una concentrata riservatezza proprio al fine di non creare turbativa alcuna in una fase istruttoria delicata per il licenziamento del documento finale.<\/div>\n<div dir=\"auto\">Certo \u00e8 singolare che chi ha portato la Citt\u00e0 nel baratro in cui si trova, chi ne ha determinato il dissesto negando per anni difficolt\u00e0 economiche e nascondendosi dietro problemi \u201cdi sola cassa\u201d, chi ha deciso privatizzazioni nella gestione dei servizi e nella riscossione dei tributi, chi ha prodotto errori su errori nella gestione economico finanziario e nell\u2019amministrazione di questa Citt\u00e0, adesso additi mancanze e inefficienze a questa maggioranza, che ha consapevolmente ereditato le macerie e lavora, a testa bassa, per risollevare le sorti di Villa.<\/div>\n<div dir=\"auto\">Sono l\u00ec, in quelle \u201cforze politiche\u201d, non i partiti ma le tre amministrazioni che dal 2010 al 2021 hanno governato: quelle stesse amministrazioni di cui oggi paghiamo scelte amministrative, economiche e sociali pi\u00f9 che discutibili. Altro che invocato<\/div>\n<div dir=\"auto\">dialogo istituzionale finalizzato alla ricerca di soluzioni per la Citt\u00e0!<\/div>\n<div dir=\"auto\">Quest\u2019amministrazione ha fatto ci\u00f2 che doveva, rimodulando alcune spese per interventi a favore della citt\u00e0 senza alcuno spreco o aggravio, non \u201cper fare qualcosa\u201d ma per dare quelle risposte che tutti noi villesi aspettiamo da anni. Evidentemente questo ai precedenti amministratori non \u00e8 per nulla gradito. Del resto, se lo fosse stato, quelle risposte le avrebbero date loro quando erano alla guida di Villa!<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le prescrizioni sollevate dal ministero dell\u2019Interno sull\u2019ipotesi di bilancio stabilmente riequilibrato approvato da questa maggioranza consiliare non rappresentano la \u201cbocciatura\u201d e tanto meno certificano la \u201cinefficienza\u201d nella gestione e nell\u2019amministrazione&hellip;<\/p>\n","protected":false},"author":12,"featured_media":15591,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[921,196,140],"tags":[9615,9616],"class_list":["post-18503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-news","category-reggio-calabria","tag-comune-di-villa-s-g","tag-ipotesi-bilancio-stabilmente-riequilibrato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Villa S.G., comunicato su ipotesi bilancio stabilmente riequilibrato<\/title>\n<meta name=\"description\" content=\"Comunicato stampa della maggioranza di Villa S.G., dopo le prescrizioni sollevate dal ministero dell\u2019Interno su bilancio: &quot;Non \u00e8 bocciatura&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2023\/02\/08\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Villa S.G., comunicato su ipotesi bilancio stabilmente riequilibrato\" \/>\n<meta property=\"og:description\" content=\"Comunicato stampa della maggioranza di Villa S.G., dopo le prescrizioni sollevate dal ministero dell\u2019Interno su bilancio: &quot;Non \u00e8 bocciatura&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2023\/02\/08\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-08T08:30:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/12\/Comune-di-Villa-S.G.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"857\" \/>\n\t<meta property=\"og:image:height\" content=\"857\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sebastiano Plutino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastiano Plutino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/02\\\/08\\\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/02\\\/08\\\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\\\/\"},\"author\":{\"name\":\"Sebastiano Plutino\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\"},\"headline\":\"Villa S.G., comunicato su ipotesi bilancio stabilmente riequilibrato\",\"datePublished\":\"2023-02-08T08:30:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/02\\\/08\\\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\\\/\"},\"wordCount\":804,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/02\\\/08\\\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/12\\\/Comune-di-Villa-S.G.jpg\",\"keywords\":[\"Comune di Villa S.G.\",\"ipotesi bilancio stabilmente riequilibrato\"],\"articleSection\":[\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/02\\\/08\\\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/02\\\/08\\\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/02\\\/08\\\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\\\/\",\"name\":\"Villa S.G., comunicato su ipotesi bilancio stabilmente riequilibrato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/02\\\/08\\\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/02\\\/08\\\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/12\\\/Comune-di-Villa-S.G.jpg\",\"datePublished\":\"2023-02-08T08:30:03+00:00\",\"description\":\"Comunicato stampa della maggioranza di Villa S.G., dopo le prescrizioni sollevate dal ministero dell\u2019Interno su bilancio: \\\"Non \u00e8 bocciatura\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/02\\\/08\\\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/02\\\/08\\\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/02\\\/08\\\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/12\\\/Comune-di-Villa-S.G.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/12\\\/Comune-di-Villa-S.G.jpg\",\"width\":857,\"height\":857},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/02\\\/08\\\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Villa S.G., comunicato su ipotesi bilancio stabilmente riequilibrato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\",\"name\":\"Sebastiano Plutino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"caption\":\"Sebastiano Plutino\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/sebastiano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Villa S.G., comunicato su ipotesi bilancio stabilmente riequilibrato","description":"Comunicato stampa della maggioranza di Villa S.G., dopo le prescrizioni sollevate dal ministero dell\u2019Interno su bilancio: \"Non \u00e8 bocciatura\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2023\/02\/08\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\/","og_locale":"it_IT","og_type":"article","og_title":"Villa S.G., comunicato su ipotesi bilancio stabilmente riequilibrato","og_description":"Comunicato stampa della maggioranza di Villa S.G., dopo le prescrizioni sollevate dal ministero dell\u2019Interno su bilancio: \"Non \u00e8 bocciatura\"","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2023\/02\/08\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\/","og_site_name":"Radio Touring 104","article_published_time":"2023-02-08T08:30:03+00:00","og_image":[{"width":857,"height":857,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/12\/Comune-di-Villa-S.G.jpg","type":"image\/jpeg"}],"author":"Sebastiano Plutino","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Sebastiano Plutino","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/02\/08\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/02\/08\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\/"},"author":{"name":"Sebastiano Plutino","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e"},"headline":"Villa S.G., comunicato su ipotesi bilancio stabilmente riequilibrato","datePublished":"2023-02-08T08:30:03+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/02\/08\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\/"},"wordCount":804,"commentCount":0,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/02\/08\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/12\/Comune-di-Villa-S.G.jpg","keywords":["Comune di Villa S.G.","ipotesi bilancio stabilmente riequilibrato"],"articleSection":["Home","News","Reggio Calabria"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/progettotouring.it\/radiotouring104\/2023\/02\/08\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/02\/08\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2023\/02\/08\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\/","name":"Villa S.G., comunicato su ipotesi bilancio stabilmente riequilibrato","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/02\/08\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/02\/08\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/12\/Comune-di-Villa-S.G.jpg","datePublished":"2023-02-08T08:30:03+00:00","description":"Comunicato stampa della maggioranza di Villa S.G., dopo le prescrizioni sollevate dal ministero dell\u2019Interno su bilancio: \"Non \u00e8 bocciatura\"","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/02\/08\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2023\/02\/08\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/02\/08\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/12\/Comune-di-Villa-S.G.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/12\/Comune-di-Villa-S.G.jpg","width":857,"height":857},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/02\/08\/villa-s-g-comunicato-su-ipotesi-bilancio-stabilmente-riequilibrato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Villa S.G., comunicato su ipotesi bilancio stabilmente riequilibrato"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e","name":"Sebastiano Plutino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","caption":"Sebastiano Plutino"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/sebastiano\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/12\/Comune-di-Villa-S.G.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/18503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=18503"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/18503\/revisions"}],"predecessor-version":[{"id":18506,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/18503\/revisions\/18506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/15591"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=18503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=18503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=18503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}