{"id":20941,"date":"2023-03-15T12:56:49","date_gmt":"2023-03-15T11:56:49","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=20941"},"modified":"2023-03-15T12:56:49","modified_gmt":"2023-03-15T11:56:49","slug":"loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2023\/03\/15\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\/","title":{"rendered":"L&#8217;Oro del Precipizio, i Plastic Farm Animals raccontano album e s\u00e8 stessi"},"content":{"rendered":"<p>1) <strong>Siete la mia prima intervista di musica, mi auguro di essere all&#8217;altezza, non siete di certo la band pi\u00f9 facile da intervistare alla prima esperienza. Come prima cosa vi chiedo com&#8217;\u00e8 nato questo nome &#8220;<img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-20942\" src=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.40.19-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.40.19-300x200.jpeg 300w, https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.40.19-585x390.jpeg 585w, https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.40.19-263x175.jpeg 263w, https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.40.19.jpeg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignnone size-medium wp-image-20943\" src=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-3-300x246.jpeg\" alt=\"\" width=\"300\" height=\"246\" srcset=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-3-300x246.jpeg 300w, https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-3.jpeg 585w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignnone size-medium wp-image-20944\" src=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-2-300x295.jpeg\" alt=\"\" width=\"300\" height=\"295\" srcset=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-2-300x295.jpeg 300w, https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-2.jpeg 407w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-20945\" src=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-1-300x224.jpeg\" alt=\"\" width=\"300\" height=\"224\" srcset=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-1-300x224.jpeg 300w, https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-1-1024x764.jpeg 1024w, https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-1-768x573.jpeg 768w, https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-1-1536x1145.jpeg 1536w, https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-1-1170x872.jpeg 1170w, https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-1-585x436.jpeg 585w, https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-1.jpeg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-20946\" src=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-300x200.jpeg 300w, https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-1024x682.jpeg 1024w, https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-768x512.jpeg 768w, https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-1536x1023.jpeg 1536w, https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-1170x780.jpeg 1170w, https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-585x390.jpeg 585w, https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-263x175.jpeg 263w, https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47.jpeg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><em>\u00a0E&#8217; un piacere essere proprio noi ad inaugurare i problemi con le interviste musicali.<\/em><\/p>\n<p><em>Per tanto tempo abbiamo cercato un nome adatto, magari anche in italiano, ma ci siamo resi conto che \u00e8 diventato davvero complicato trovare un nome che non sia gi\u00e0 stato utilizzato in passato. Non eravamo e non siamo alla ricerca del colpo ad effetto a tutti i costi, ci piaceva l&#8217;idea che il nome rispecchiasse in qualche maniera un certo immaginario definito ma che lascia spazio a tante possibili interpretazioni.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>2) <strong>Su quali presupposti, sensazioni nasce l&#8217;album &#8220;L&#8217;Oro del Precipizio&#8221;? Perch\u00e9 proprio questo nome e qual \u00e8\/sono i messaggi che si pone di trasmettere al pubblico?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><em>Scegliere il titolo dell&#8217;album \u00e8 stato pi\u00f9 semplice. L&#8217;immagine \u00e8 chiara, racconta di provvisoriet\u00e0, qualcosa di precario, un confine sul quale viviamo ed entro il quale cerchiamo costantemente il bello, qualcosa che luccichi. Serve cercare tanto, molto probabilmente serve bestemmiare tanto, ma siamo sicuri ci sia sempre qualcosa che luccica e giustifichi la ricerca.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>3) <strong>Non vorrei fare una figura barbina, Diluvio Universale tratta la fine di un amore? La cui rottura con la partner per il protagonista \u00e8 triste al punto di non essere molto distante dalla bruttezza della realt\u00e0 del mondo moderno. Quasi si voglia lasciare andare &#8220;rimanere in equilibrio non \u00e8 poi cos\u00ec fondamentale&#8221;?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><em>Devo dirti che non l&#8217;avevo mai \u201cletta\u201d da questo punto di vista. Il focus del testo \u00e8 sulla realt\u00e0 e non ti nascondo che mi piace l&#8217;idea che ci si possa innamorare della realt\u00e0, con tutte le conseguenze che l&#8217;innamoramento si porta in dote. E ti confermo senza dubbi che \u201crimanere in equilibrio non \u00e8 poi cos\u00ec fondamentale\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>4) <strong>L&#8217;Oro del Precipizio mi ha davvero colpito molto: tratta di un amore assai intenso, passionale, simbiotico, irrequieto, irrinunciabile come un bisogno, burrascoso, che manda al diavolo regole logiche basilari ed i pi\u00f9 grandi che hanno provato a spiegare razionalmente l&#8217;Amore. Che sembrava eterno per il fuoco da cui era alimentato. Fino a quando hanno dovuto affrontare il mare. Che li ha allontanati, risucchiandoli. Sbaglio?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><em>\u00c8 la chiave di lettura corretta, certo. E proprio perch\u00e9 l&#8217;interpretazione \u00e8 giusta, mi piace sottolineare l&#8217;importanza della musica che in tutti i pezzi, ma qui in particolare, gioca un ruolo fondamentale nell&#8217;accompagnare le parole dentro la burrasca in cui \u201cChi \u00e8 chi?\u201d. Il tema \u00e8 cos\u00ec personale che non c\u2019\u00e8 da aggiungere molto, possiamo solo sperare di aver trasmesso bene il senso di ci\u00f2 che avevamo in testa, di aver toccato e fatto risuonare le corde giuste.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>5)<strong> &#8220;Cara la notte&#8221; mi ha dato l&#8217;impressione di un bilancio di un protagonista che vive inquieto.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><em>Mi fa piacere che d&#8217;impatto i pezzi si presentino per quello che sono e non si nascondano. I ritmi sono molto serrati e il testo vuole raccontarla tutta quell&#8217;inquietudine nei modi che furono campo di sfida e riflessione di alcuni grandi scrittori del passato. In questo caso mi piace pensare che ci sia un sottile filo che lega questo pezzo al Mastro Bruno Pelaggi, poeta scalpellino delle Serre di fine ottocento, e alle sue lettere \u201cAlla Luna\u201d, \u201cA Umberto I\u00b0\u201d e \u201cAllu Patritiernu\u201d, che se non conoscete vi invitiamo a scoprire.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>6)<strong> &#8220;Il Magnifico&#8221;\u00a0sembra raccontare una storia fragile come certe questioni esistenziali, ma dura come solo la cruda e a volte opprimente realt\u00e0 riesce ad essere.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><em>Anche in questo caso, il tempo del brano scandisce un mood ideale alla narrazione. Raccontiamo sempre il reale anche quando si presenta in forma di ipotesi, quasi razionalmente. \u201cHo desiderato cos\u00ec tanto dirtelo, che il desiderio di dirtelo ha soverchiato le gerachie\u201d, in questo incipit c&#8217;\u00e8 una voglia di attenzionare la frenesia che ha fatto perdere la buona educazione di capire che c&#8217;\u00e8 momento e momento, che dire certe cose, fossero anche giuste, nel momento sbagliato recano un danno doppio facendo perdere forza al concetto che si vuole esprimere. \u201cChi vuol esser pi\u00f9 lieto lo sia\u201d, nel finale, ripropone una nuova linea temporale con il concetto di Lorenzo De&#8217; Medici. Ci piace ragionare anche in questi termini con dei concetti che se ne fottono di secoli che passano.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>7) &#8220;<strong>Povero Re&#8221; \u00e8 una stupenda denuncia alle difficolt\u00e0 dettate dal Sistema Capitalistico. Eppure sogniamo un mondo dove la scelta di realizzazione dovrebbe essere libera, non obbligatoria per sopravvivere all&#8217;interno del proprio contesto, cos\u00ec difficile, pieno di contraddizioni, milioni di problemi di natura politica ed una mentalit\u00e0 arretrata. Ci possono essere davvero vie d&#8217;uscita? Come, chi potrebbe risolvere questa questione che si protrae senza via d&#8217;uscita da decenni?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><em>Gi\u00e0 dall&#8217;intro del brano si sentono forti scontri, sirene della polizia e sorde esplosioni. \u201cNon \u00e8 mai bello restare, non \u00e8 mai bello anche andarsene\u201d, ancora una volta \u00e8 un modo per raccontare la precariet\u00e0 del contesto, i dubbi costanti del farne parte, del prendere parte. Ma in questo caso la spinta emotiva sta nel passaggio \u201cSe lo puoi desiderare devi saper cosa fartene\u201d. Troppe volte ci si prende questioni tanto per prendersele, senza nemmeno essere troppo certi di cosa fare anche nel caso in cui il risultato dovesse essere ottenuto. Se mi chiedi chi potrebbe risolvere questa situazione io punto ancora forte sulle persone e ti rispondo che siamo noi gli artefici del nostro destino e che se siamo socialmente in questa situazione complicata \u00e8 solo merito nostro. Dunque, senza retorica, la via di uscita siamo noi, se solo evitassimo di delegare da scansafatiche il nostro destino a gente alla quale di noi non gliene frega niente.\u00a0\u00a0 <\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>8) <strong>&#8220;Per la Gloria&#8221; invece sembra una denuncia alla povert\u00e0 culturale odierna, mancanza di cultura che porta all&#8217;esaltazione egoistica dell&#8217;Io a discapito del bene comune, dell&#8217;altruismo, dell&#8217;attivismo politico unitario, che poi porta alla violenza, alla mancanza di appartenenza nel ruolo di cittadino, alla prevaricazione sull&#8217;altro, alla violazione delle regole anche del buon senso pur di ottenere quel che si vuole a tutti i costi. Il semplificare questioni complesse per ignoranza, il semplicismo che porta al giudizio, tutti fattori ed elementi che poi si tramutano nella politica attuale: quella populista, razzista, fascista, al servizio della Finanza, Capitale, razzismo, discriminazione ed emarginazione delle minoranze. Sono tempi peggiori del passato, nonostante i passi avanti in cultura, progresso scientifico, tecnologico, nei diritti sociali&#8230;?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><em>Sono tempi terribili, questo \u00e8 certo. Non mi va di fare paragoni con il passato perch\u00e9 ogni epoca ed ogni suo protagonista si \u00e8 trovato a lottare con le contraddizioni del mondo a lui contemporaneo. Preferisco pensare alla \u201cmisura specifica di quella sedia elettrica che il mio culo glorifica\u201d, come rivendicazione del valore che ognuno di noi ha e che \u00e8 giusto ricordarsi sempre di avere.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>9) &#8220;<strong>La Ballata delle Contraddizioni&#8221;, ultimo brano del disco, sembra una denuncia del protagonista a certe costrizioni delle dinamiche della vita comune, fatta anche di superficialit\u00e0 e compromessi al ribasso all&#8217;interno di un contesto sociale superficiale, ipocrita ed approfittatore, che non ha tempo, o non si vuole dar il tempo, di approfondire il valore umano, personale e realizzativo.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><em>\u201cL&#8217;alto dei ieri?\u201d di cui al ritornello del pezzo \u00e8 un modo per tagliare corto su tutta una serie di ipocrisie e presunte promesse. Come una presa di coscienza \u201crimessa alla merc\u00e9 dei menzogneri\u201d che a volte siamo noi stessi nelle nostre stesse personali valutazioni. Essere uomini di mezz&#8217;et\u00e0 ci ha dato modo di approfondire alcuni aspetti dell&#8217;essere umani all&#8217;interno di un contesto quotidiano con il quale non possiamo non avere a che fare. \u00c8 proprio per questo che conta molto lavorare su noi stessi per provare a stabilire noi cosa possa farci bene, cosa possa farci stare bene, cosa merita il tempo a disposizione che abbiamo in questa nostra vita (che se anche durasse 200 anni, sarebbero sempre e comunque pochi). Il titolo del brano \u00e8 preso da un testo del Francois Villon, poeta, chierico, vagabondo e malavitoso francese che, attorno alla met\u00e0 del 1400, ha speso con un certo criterio i 32 anni che ha avuto a disposizione. Mi colp\u00ec la coerenza della sua vita con il titolo di questa ballata, mi \u00e8 sembrato che all&#8217;improvviso quadrasse tutto.<\/em><\/p>\n<p><em>\u00a0 <\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>10) <strong>Da quel che ho capito l&#8217;album parla di sentimenti, vita vissuta e questioni esistenziali, ma le canzoni hanno una correlazione, un filo logico tra loro o sono a compartimenti stagni l&#8217;una dall&#8217;altra? Ce n&#8217;\u00e8 una a cui siete pi\u00f9 affezionati? E in assoluto tra tutte quelle scritte?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><em>Come nella vita reale ci sono momenti e momenti, e ci sono momenti dentro i momenti che creano quella correlazione di cui parli, quella sorta di logica che per forza di cose lega la vita vissuta tanto alle questioni esistenziali quanto a una sana sbronza. Quando abbiamo deciso di raccontare storie, di raccontarci non potevamo non tenerne conto. Quindi quello che facciamo non potrebbe essere diverso da come si pu\u00f2 ascoltare sul disco.<\/em><\/p>\n<p><em>Non abbiamo una canzone preferita ma se proprio dovessi rispondere a questa domanda, ti direi che la nostra canzone preferita \u00e8 la prossima.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>11)<strong> L&#8217;album sta riscuotendo il successo sperato? Avete gi\u00e0 ottenuto contratti? Avete fatto altri album precedenti a questo e pensate gi\u00e0 ad un prossimo album?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><em>\u201cL&#8217;oro del Precipizio\u201d \u00e8 il nostro primo album. Lo abbiamo registrato al <strong>Desert Door Studio<\/strong> di Catania ed \u00e8 uscito per <strong>Overdrive Records<\/strong>, che ci sta affiancando con la promozione. Siamo consapevoli di come stanno le cose e di quante cose possa significare la parola \u201csuccesso\u201d. Nel nostro caso siamo certi di aver registrato il disco che volevamo, lo abbiamo fatto uscire e lo stiamo portando in giro perch\u00e9 il bello, la parte carnale, sta proprio nei live ai quali lavoriamo costantemente. Abbiamo un po&#8217; di concerti in programma e le date sono in aggiornamento. E, ovviamente, stiamo anche lavorando a nuove idee per i brani che saranno il corpo del prossimo album.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>12)<strong> I componenti di Plastic Farm Animals si conoscevano da prima o sono diventati band per l&#8217;occasione? Chi sono quando non suonano, amici, padri di famiglia, attivisti o altro? Quali sono le loro pi\u00f9 grandi passioni, sogni ed hanno aspirazioni future?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><em>Ci conosciamo da una vita e abbiamo condiviso i nostri percorsi musicali sin da quando eravamo poco pi\u00f9 che ragazzini. Nei Plastic Farm Animals confluiscono le persone che siamo oggi: uomini, amici, padri di famiglia, lavoratori, attivisti, liberi pensatori sicuramente appassionati di quella passione che brucia dentro e che ha ancora necessit\u00e0 di essere espressa, come accade per i vulcani attivi. Necessit\u00e0, voglia, urgenza espressiva sono concetti con i quali siamo cresciuti e che gli anni non hanno scalfito. Ci piace ancora molto che sia cos\u00ec. In merito al futuro posso dirti che ricordo di una cara considerazione secondo la quale \u201cu futuru s&#8217;u futt\u00ecru\u201d, ecco l&#8217;idea del futuro e ricostruirne quotidianamente uno nuovo, cercando sempre di riconoscere tra la le persone che ci circondano le facce di quei maledetti sciacalli e ladri.\u00a0\u00a0\u00a0\u00a0 <\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>13) <strong>Ho letto su Rockit.it che &#8220;l&#8217;idea di partenza non verr\u00e0 mai svelata&#8221;, ma \u00e8 proprio cos\u00ec o farete l&#8217;eccezione per qualcuno, regalandogli una memorabile esclusiva, tipo me?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><em>Capirai bene che purtroppo non possiamo. Quello che invece possiamo fare \u00e8 ringraziarti per la tua attenzione e per l&#8217;analisi che hai fatto di ogni pezzo contenuto nel disco, per la passione, per la curiosit\u00e0 e per la tua voglia di approfondire. A ben pensarci questa intervista \u00e8 gi\u00e0 memorabile cos\u00ec. No?<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>1) Siete la mia prima intervista di musica, mi auguro di essere all&#8217;altezza, non siete di certo la band pi\u00f9 facile da intervistare alla prima esperienza. Come prima cosa vi&hellip;<\/p>\n","protected":false},"author":12,"featured_media":20945,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[921,146,196,140],"tags":[11539,11538,603,11540,11537],"class_list":["post-20941","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-musica","category-news","category-reggio-calabria","tag-album-loro-del-precipizio","tag-band-musicale-reggina","tag-intervista","tag-intervista-su-album-loro-del-precipizio-e-curiosita-su-gruppo","tag-plastic-farm-animals"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;Oro del Precipizio, i Plastic Farm Animal a cuore aperto sull&#039;album<\/title>\n<meta name=\"description\" content=\"I Plastic Farm Animals, band di capaci artisti reggini, si raccontano in una gentile intervista, illustrandoci dettagliatamente il loro album\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2023\/03\/15\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Oro del Precipizio, i Plastic Farm Animal a cuore aperto sull&#039;album\" \/>\n<meta property=\"og:description\" content=\"I Plastic Farm Animals, band di capaci artisti reggini, si raccontano in una gentile intervista, illustrandoci dettagliatamente il loro album\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2023\/03\/15\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-15T11:56:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1193\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sebastiano Plutino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastiano Plutino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/03\\\/15\\\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/03\\\/15\\\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\\\/\"},\"author\":{\"name\":\"Sebastiano Plutino\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\"},\"headline\":\"L&#8217;Oro del Precipizio, i Plastic Farm Animals raccontano album e s\u00e8 stessi\",\"datePublished\":\"2023-03-15T11:56:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/03\\\/15\\\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\\\/\"},\"wordCount\":1898,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/03\\\/15\\\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/03\\\/WhatsApp-Image-2023-03-15-at-11.27.47-1.jpeg\",\"keywords\":[\"album \\\"L'oro del Precipizio\\\"\",\"band musicale reggina\",\"intervista\",\"Intervista su album \\\"L'oro del precipizio e curiosit\u00e0 su gruppo\\\"\",\"Plastic Farm Animals\"],\"articleSection\":[\"Home\",\"Musica\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/03\\\/15\\\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/03\\\/15\\\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\\\/\",\"name\":\"L'Oro del Precipizio, i Plastic Farm Animal a cuore aperto sull'album\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/03\\\/15\\\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/03\\\/15\\\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/03\\\/WhatsApp-Image-2023-03-15-at-11.27.47-1.jpeg\",\"datePublished\":\"2023-03-15T11:56:49+00:00\",\"description\":\"I Plastic Farm Animals, band di capaci artisti reggini, si raccontano in una gentile intervista, illustrandoci dettagliatamente il loro album\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/03\\\/15\\\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/03\\\/15\\\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/03\\\/15\\\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/03\\\/WhatsApp-Image-2023-03-15-at-11.27.47-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/03\\\/WhatsApp-Image-2023-03-15-at-11.27.47-1.jpeg\",\"width\":1600,\"height\":1193},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/03\\\/15\\\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;Oro del Precipizio, i Plastic Farm Animals raccontano album e s\u00e8 stessi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\",\"name\":\"Sebastiano Plutino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"caption\":\"Sebastiano Plutino\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/sebastiano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'Oro del Precipizio, i Plastic Farm Animal a cuore aperto sull'album","description":"I Plastic Farm Animals, band di capaci artisti reggini, si raccontano in una gentile intervista, illustrandoci dettagliatamente il loro album","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2023\/03\/15\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\/","og_locale":"it_IT","og_type":"article","og_title":"L'Oro del Precipizio, i Plastic Farm Animal a cuore aperto sull'album","og_description":"I Plastic Farm Animals, band di capaci artisti reggini, si raccontano in una gentile intervista, illustrandoci dettagliatamente il loro album","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2023\/03\/15\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\/","og_site_name":"Radio Touring 104","article_published_time":"2023-03-15T11:56:49+00:00","og_image":[{"width":1600,"height":1193,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-1.jpeg","type":"image\/jpeg"}],"author":"Sebastiano Plutino","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Sebastiano Plutino","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/03\/15\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/03\/15\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\/"},"author":{"name":"Sebastiano Plutino","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e"},"headline":"L&#8217;Oro del Precipizio, i Plastic Farm Animals raccontano album e s\u00e8 stessi","datePublished":"2023-03-15T11:56:49+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/03\/15\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\/"},"wordCount":1898,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/03\/15\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-1.jpeg","keywords":["album \"L'oro del Precipizio\"","band musicale reggina","intervista","Intervista su album \"L'oro del precipizio e curiosit\u00e0 su gruppo\"","Plastic Farm Animals"],"articleSection":["Home","Musica","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/03\/15\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2023\/03\/15\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\/","name":"L'Oro del Precipizio, i Plastic Farm Animal a cuore aperto sull'album","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/03\/15\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/03\/15\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-1.jpeg","datePublished":"2023-03-15T11:56:49+00:00","description":"I Plastic Farm Animals, band di capaci artisti reggini, si raccontano in una gentile intervista, illustrandoci dettagliatamente il loro album","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/03\/15\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2023\/03\/15\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/03\/15\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-1.jpeg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-1.jpeg","width":1600,"height":1193},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/03\/15\/loro-del-precipizio-i-plastic-farm-animals-raccontano-album-e-se-stessi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"L&#8217;Oro del Precipizio, i Plastic Farm Animals raccontano album e s\u00e8 stessi"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e","name":"Sebastiano Plutino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","caption":"Sebastiano Plutino"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/sebastiano\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/WhatsApp-Image-2023-03-15-at-11.27.47-1.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/20941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=20941"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/20941\/revisions"}],"predecessor-version":[{"id":20947,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/20941\/revisions\/20947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/20945"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=20941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=20941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=20941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}