{"id":24805,"date":"2023-05-04T11:01:21","date_gmt":"2023-05-04T09:01:21","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=24805"},"modified":"2023-05-04T12:24:23","modified_gmt":"2023-05-04T10:24:23","slug":"festival-della-democrazia-a-polistena-incontro-uno-vale-uno","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\/","title":{"rendered":"Festival della Democrazia a Polistena: incontro &#8220;uno vale uno&#8221;"},"content":{"rendered":"<p style=\"text-align: justify\">Con il<strong> Festival della Letteratura e del Diritto di Palmi<\/strong> si \u00e8 elaborata una formula originale per <strong>parlare di Leggi, anche fuori<\/strong> dalle aule universitarie e di Tribunale.<\/p>\n<p style=\"text-align: justify\"><strong>L\u2019incontro tra la letteratura e il diritto<\/strong> in generale, certamente, risale a tempi molto meno vicini, poich\u00e9\u0301 e\u0300 sempre stata presente la considerazione della letteratura antica come materiale prezioso capace di spiegare le origini e le evoluzioni dei vari istituti legislativi.<\/p>\n<p style=\"text-align: justify\">Le classi quinte del <strong>liceo Rechichi<\/strong> hanno partecipato a una due giorni di incontri importanti.<\/p>\n<p style=\"text-align: justify\">Si sono confrontati in primis con il<strong> concetto di \u201cUno vale uno\u201d<\/strong> e grazie ai relatori, gli avvocati <strong>Antonino Napoli<\/strong> e <strong>il sindaco di Polistena Michele Tripodi,<\/strong> hanno aperto un dibattito interessanti sui temi di democrazia e libert\u00e0.<\/p>\n<p style=\"text-align: justify\">Un appuntamento fortemente voluto e sostenuto dalla dirigente scolastica <strong>Francesca Morabito<\/strong> che ha invitato i suoi studenti ad essere sempre parte attiva nella societ\u00e0 con la consapevolezza e la dignit\u00e0 che solo la conoscenza pu\u00f2 dare.<\/p>\n<p style=\"text-align: justify\">Lo stesso Tripodi ha condotto i ragazzi a una riflessione che li ha portati a scoprire come \u00ab<em>I diritti sono tanti ma abbiamo consapevolezza di quanti siano<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify\">L<strong>&#8216;avvocato Maria Teresa Santoro<\/strong> ha relazionato sul tema \u201c<em>La giustizia in nome del popolo<\/em> &#8211; <em>note a margine de &#8216;La parola ai giurati &#8216;di Sydney Lumet<\/em>\u201d.<\/p>\n<p style=\"text-align: justify\">Con uno sguardo alla Costituzione e al cinema, richiamando anche l&#8217;iconico &#8216;Rashomon &#8216; di Akira Kurosawa, oltre che il film &#8216; Condannato a morte in mancanza di indizi&#8217;, sono stati presi in esame il sistema processuale delle giurie popolari statunitensi e italiane .<\/p>\n<p style=\"text-align: justify\">La complessit\u00e0 della formazione della prova nel giudizio, la regola della condanna &#8220;<strong>al di l\u00e0 di ogni ragionevole dubbio<\/strong>\u201d, i principi costituzionali del giusto processo e dell&#8217;autonomia e indipendenza della magistratura, hanno costituito il banco di confronto con gli studenti, sollecitati ad una necessaria presa di coscienza dei propri diritti per una effettiva partecipazione democratica.<\/p>\n<p style=\"text-align: justify\">Per <strong>l\u2019avvocato Napoli<\/strong> \u00e8 stato importante portare i ragazzi a una riflessione: \u00ab<em>Uno Vale Uno? E\u2019 la domanda che oggi ci poniamo, che vi poniamo e con voi vogliamo riflettere. La democrazia come modello politico, infatti, non viene mai messa in discussione; \u00e8 semmai il suo funzionamento che suscita sempre pi\u00f9 perplessit\u00e0<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify\">Diversi richiami storici sono stati forniti per arrivare ad oggi. \u00abI social oggi rappresentano un forte elemento di novit\u00e0 che ha contribuito alla creazione di una nuova forma di <strong>\u201cdemocrazia diretta\u201d<\/strong> a cui tutti possono partecipare e nella quale \u201cuno vale uno\u201d.<\/p>\n<p style=\"text-align: justify\">Il concetto di <strong>\u201cuno vale uno\u201d,<\/strong> pi\u00f9 che rimandare alla democrazia diretta di Atene, sembra un rifiuto della diversit\u00e0 e del pluralismo che sono un dato imprescindibile dell\u2019umanit\u00e0 e il vero fondamento delle civilt\u00e0 occidentali. L\u2019idea omologatrice e riduzionistica dell\u2019\u201cuno vale uno\u201d soffoca tutto questo e ci porta ad un egualitarismo di facciata, demagogico e irrealistico. Non \u00e8 pensabile che, in nome dell\u2019antipolitica, si immagini una politica dell\u2019uno vale uno, annullando il peso della cultura, il valore della competenza, la virt\u00f9 del sapere e la forza dell\u2019esperienza.<\/p>\n<p style=\"text-align: justify\">Il processo democratico avrebbe tanto da guadagnare da un maggior coinvolgimento diretto dei cittadini? Ne dubitiamo. Pensate, ad esempio, a cosa sarebbe accaduto se nel pieno dell\u2019emergenza pandemica, invece che affidarci al parere competente, meditato dei medici e degli scienziati, ci fossimo affidati al buon senso dell\u2019uomo della strada? Quanti danni in pi\u00f9 avremmo dovuto contare?<\/p>\n<p style=\"text-align: justify\">\u2018Uno vale uno\u2019 \u00e8 un concetto meraviglioso. Ma senza competenze e merito crolla tutto qui bisogna accompagnarlo da: il socratico<strong> \u201cso di non sapere\u201d<\/strong> e il latino cursus honorum.<\/p>\n<p style=\"text-align: justify\">Contengono entrambi un principio di crescita, di maturazione, da applicare all\u2019individuo e alla societ\u00e0: il primo custodisce in quattro parole la continua necessit\u00e0 di imparare, l\u2019umilt\u00e0 di chi vuole capire. L\u2019altro istituisce un preciso ordine meritocratico per passare da un incarico pubblico a un altro premiando, si presuppone, chi vale. Fermiamoci un attimo a riflettere sulla forza che questi due pilastri della societ\u00e0 antica possiedono\u00bb.<\/p>\n<p style=\"text-align: justify\">\n","protected":false},"excerpt":{"rendered":"<p>Con il Festival della Letteratura e del Diritto di Palmi si \u00e8 elaborata una formula originale per parlare di Leggi, anche fuori dalle aule universitarie e di Tribunale. L\u2019incontro tra&hellip;<\/p>\n","protected":false},"author":12,"featured_media":24821,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[921,196,140],"tags":[14328,14325,14327,14330,14326,14329,14324],"class_list":["post-24805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-news","category-reggio-calabria","tag-avvocati-antonino-napoli","tag-avvocato-maria-teresa-santoro","tag-concetto-di-uno-vale-uno","tag-dirigente-scolastica-francesca-morabito","tag-festival-della-letteratura-e-del-diritto-di-palmi","tag-il-sindaco-di-polistena-michele-tripodi","tag-liceo-rechichi-palmi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Festival della Democrazia a Palmi: incontro &quot;uno vale uno&quot;<\/title>\n<meta name=\"description\" content=\"Gli studenti del liceo Rechichi hanno partecipato ad incontri sul concetto di \u201cUno vale uno\u201d sui temi di democrazia e libert\u00e0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Festival della Democrazia a Palmi: incontro &quot;uno vale uno&quot;\" \/>\n<meta property=\"og:description\" content=\"Gli studenti del liceo Rechichi hanno partecipato ad incontri sul concetto di \u201cUno vale uno\u201d sui temi di democrazia e libert\u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-04T09:01:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-04T10:24:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/05\/Palmi-incontro-Festival-Democrazia-uno-vale-uno.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sebastiano Plutino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastiano Plutino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/05\\\/04\\\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/05\\\/04\\\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\\\/\"},\"author\":{\"name\":\"Sebastiano Plutino\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\"},\"headline\":\"Festival della Democrazia a Polistena: incontro &#8220;uno vale uno&#8221;\",\"datePublished\":\"2023-05-04T09:01:21+00:00\",\"dateModified\":\"2023-05-04T10:24:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/05\\\/04\\\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\\\/\"},\"wordCount\":656,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/05\\\/04\\\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/05\\\/Palmi-incontro-Festival-Democrazia-uno-vale-uno.jpeg\",\"keywords\":[\"avvocati Antonino Napoli\",\"avvocato Maria Teresa Santoro\",\"concetto di \u201cUno vale uno\u201d\",\"dirigente scolastica Francesca Morabito\",\"Festival della Letteratura e del Diritto di Palmi\",\"il sindaco di Polistena Michele Tripodi\",\"liceo Rechichi Palmi\"],\"articleSection\":[\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/05\\\/04\\\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/05\\\/04\\\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\\\/\",\"name\":\"Festival della Democrazia a Palmi: incontro \\\"uno vale uno\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/05\\\/04\\\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/05\\\/04\\\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/05\\\/Palmi-incontro-Festival-Democrazia-uno-vale-uno.jpeg\",\"datePublished\":\"2023-05-04T09:01:21+00:00\",\"dateModified\":\"2023-05-04T10:24:23+00:00\",\"description\":\"Gli studenti del liceo Rechichi hanno partecipato ad incontri sul concetto di \u201cUno vale uno\u201d sui temi di democrazia e libert\u00e0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/05\\\/04\\\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/05\\\/04\\\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/05\\\/04\\\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/05\\\/Palmi-incontro-Festival-Democrazia-uno-vale-uno.jpeg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/05\\\/Palmi-incontro-Festival-Democrazia-uno-vale-uno.jpeg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/05\\\/04\\\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festival della Democrazia a Polistena: incontro &#8220;uno vale uno&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\",\"name\":\"Sebastiano Plutino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"caption\":\"Sebastiano Plutino\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/sebastiano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Festival della Democrazia a Palmi: incontro \"uno vale uno\"","description":"Gli studenti del liceo Rechichi hanno partecipato ad incontri sul concetto di \u201cUno vale uno\u201d sui temi di democrazia e libert\u00e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\/","og_locale":"it_IT","og_type":"article","og_title":"Festival della Democrazia a Palmi: incontro \"uno vale uno\"","og_description":"Gli studenti del liceo Rechichi hanno partecipato ad incontri sul concetto di \u201cUno vale uno\u201d sui temi di democrazia e libert\u00e0","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\/","og_site_name":"Radio Touring 104","article_published_time":"2023-05-04T09:01:21+00:00","article_modified_time":"2023-05-04T10:24:23+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/05\/Palmi-incontro-Festival-Democrazia-uno-vale-uno.jpeg","type":"image\/jpeg"}],"author":"Sebastiano Plutino","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Sebastiano Plutino","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\/"},"author":{"name":"Sebastiano Plutino","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e"},"headline":"Festival della Democrazia a Polistena: incontro &#8220;uno vale uno&#8221;","datePublished":"2023-05-04T09:01:21+00:00","dateModified":"2023-05-04T10:24:23+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\/"},"wordCount":656,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/05\/Palmi-incontro-Festival-Democrazia-uno-vale-uno.jpeg","keywords":["avvocati Antonino Napoli","avvocato Maria Teresa Santoro","concetto di \u201cUno vale uno\u201d","dirigente scolastica Francesca Morabito","Festival della Letteratura e del Diritto di Palmi","il sindaco di Polistena Michele Tripodi","liceo Rechichi Palmi"],"articleSection":["Home","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\/","name":"Festival della Democrazia a Palmi: incontro \"uno vale uno\"","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/05\/Palmi-incontro-Festival-Democrazia-uno-vale-uno.jpeg","datePublished":"2023-05-04T09:01:21+00:00","dateModified":"2023-05-04T10:24:23+00:00","description":"Gli studenti del liceo Rechichi hanno partecipato ad incontri sul concetto di \u201cUno vale uno\u201d sui temi di democrazia e libert\u00e0","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/05\/Palmi-incontro-Festival-Democrazia-uno-vale-uno.jpeg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/05\/Palmi-incontro-Festival-Democrazia-uno-vale-uno.jpeg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/festival-della-democrazia-a-polistena-incontro-uno-vale-uno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Festival della Democrazia a Polistena: incontro &#8220;uno vale uno&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e","name":"Sebastiano Plutino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","caption":"Sebastiano Plutino"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/sebastiano\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/05\/Palmi-incontro-Festival-Democrazia-uno-vale-uno.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/24805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=24805"}],"version-history":[{"count":2,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/24805\/revisions"}],"predecessor-version":[{"id":24825,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/24805\/revisions\/24825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/24821"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=24805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=24805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=24805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}