{"id":24829,"date":"2023-05-04T12:48:49","date_gmt":"2023-05-04T10:48:49","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=24829"},"modified":"2023-05-04T12:48:49","modified_gmt":"2023-05-04T10:48:49","slug":"lega-calabria-sulloperazione-contro-la-ndrangheta","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/lega-calabria-sulloperazione-contro-la-ndrangheta\/","title":{"rendered":"Lega Calabria sull&#8217;operazione contro la &#8216;ndrangheta"},"content":{"rendered":"<p class=\"xmprfx_s8\"><span class=\"xmprfx_s7\">\u201c<\/span><span class=\"xmprfx_s7\">Una \u2018ndrangheta sempre pi\u00f9 ramificata, una \u2018ndrangheta sempre pi\u00f9 ricca, ma una \u2018ndrangheta che non ha fatto i conti con l\u2019intelligence investigative e con la preparazione di tanti magistrati che lavorano in modo brillante presso le varie Procure italiane<\/span><span class=\"xmprfx_s7\">\u00a0ed estere<\/span><span class=\"xmprfx_s7\">.<\/span><span class=\"xmprfx_s7\"> Un&#8217;operazione di largo respiro che ha messo in luce la presenza nel mondo della \u2018ndrangheta e del suo sistema di correlazioni con i vari territori<\/span><span class=\"xmprfx_s7\">,<\/span><span class=\"xmprfx_s7\"> che tendono a creare punti di riferimento ed espansione mafiosa e economica. Scenari molto gravi che, per\u00f2, grazie alle<strong> Procure <\/strong><\/span><strong><span class=\"xmprfx_s7\">antimafia\u00a0<\/span><span class=\"xmprfx_s7\">di Reggio Calabria<\/span><\/strong><span class=\"xmprfx_s7\">\u00a0(<strong>Giovanni Bombardieri<\/strong>)<\/span><span class=\"xmprfx_s7\">, di <strong>Milano<\/strong><\/span><span class=\"xmprfx_s7\">\u00a0(<strong>Marcello Viola<\/strong>)<\/span><span class=\"xmprfx_s7\">, <strong>Genova<\/strong><\/span><span class=\"xmprfx_s7\">\u00a0(<strong>Nicola Piacente<\/strong>)<\/span><span class=\"xmprfx_s7\">\u00a0e di quella nazionale<\/span><span class=\"xmprfx_s7\">\u00a0(<strong>Giovanni Melillo<\/strong>)<\/span><span class=\"xmprfx_s7\">,<\/span><span class=\"xmprfx_s7\">\u00a0in collaborazione con gli analoghi degli Stati interessati,<\/span><span class=\"xmprfx_s7\">\u00a0sono stati scoperti, con l\u2019assunzione di provvedimenti di rilevante importanza.<\/span><span class=\"xmprfx_s7\">\u00a0Mezza Europa e diverse nazioni del Sudamerica interessate all\u2019operazione con centinaia di arresti, fiumi di cocaina sequestrati e con la distruzione di una ramificazione che ha gestito un traffico di droga imponente. Il tutto con la collaborazione e l\u2019assistenza anche dei vertici delle <strong>Procure de<\/strong><\/span><strong><span class=\"xmprfx_s7\">gli<\/span><span class=\"xmprfx_s7\">\u00a0Sta<\/span><span class=\"xmprfx_s7\">t<\/span><\/strong><span class=\"xmprfx_s7\"><strong>i interessati (Germania, Belgio, Francia, Portogallo<\/strong>, ecc.).<\/span><span class=\"xmprfx_s7\">\u00a0<\/span><span class=\"xmprfx_s7\">La prova pi\u00f9 che evidente che oramai la \u2018ndrangheta veleggia in tutto il mondo ed \u00e8 diventato il gruppo criminale pi\u00f9 radicato e pericoloso, anche per la sua struttura quasi militare. E attorno all\u2019ingente traffico di droga, gli investimenti imprenditoriali che consentivano sia la presenza ne<\/span><span class=\"xmprfx_s7\">lle<\/span><span class=\"xmprfx_s7\">\u00a0vari<\/span><span class=\"xmprfx_s7\">e Nazioni<\/span><span class=\"xmprfx_s7\"> sia i punti di riferimento per la consorteria. In tale contesto, le interlocuzioni con la politica che, da una parte, rafforzavano i rapporti e le prospettive, e dall\u2019altra, il <\/span><span class=\"xmprfx_s7\">certo\u00a0<\/span><span class=\"xmprfx_s7\">condizionamento del consenso, specialmente in Calabria.\u00a0<\/span><span class=\"xmprfx_s7\">Questa, in sintesi,<\/span><span class=\"xmprfx_s7\"> il cuore dell\u2019inchiesta che, per\u00f2, non deve fermarsi e deve andare avanti per verificare se vi siano altri collegamenti con pezzi delle Istituzioni che hanno<\/span><span class=\"xmprfx_s7\">, in qualche modo, favorito questa imponente ascesa. Non si tratta pi\u00f9 di un problema calabrese e italiano, ma di un sistema, a volte sommerso, che interessa, appunto, il mondo e che solo da qualche tempo \u00e8 considerato per la pericolosit\u00e0 che effettivamente nasconde e che prima non veniva percepita. Le indagini, quindi, non possono fermarsi e devono ricostruire, anche, gli altri rapporti che sono stati solo ventilati, ma che meritano un serio e costante approfondimento. Intanto, un plauso alle Forze dell\u2019Ordine e ai Ros in particolare, alle Procure interessate, alla Dda nazionale e a tutti coloro che hanno consentito e partecipato alla<\/span><span class=\"xmprfx_s7\">\u00a0imponente<\/span><span class=\"xmprfx_s7\">\u00a0operazione<\/span><span class=\"xmprfx_s7\">\u201d.\u00a0<\/span><\/p>\n<p class=\"xmprfx_s9\"><span class=\"xmprfx_s7\">Lo dichiara <strong>Giacomo Francesco Sacc<\/strong><\/span><span class=\"xmprfx_s7\"><strong>omanno<\/strong>, <strong>Commissario R<\/strong><\/span><span class=\"xmprfx_s7\"><strong>egionale<\/strong> della <strong>Lega<\/strong><\/span><strong><span class=\"xmprfx_s7\">\u00a0Calabria<\/span><\/strong><span class=\"xmprfx_s7\">.<\/span><span class=\"xmprfx_s7\">\u00a0\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cUna \u2018ndrangheta sempre pi\u00f9 ramificata, una \u2018ndrangheta sempre pi\u00f9 ricca, ma una \u2018ndrangheta che non ha fatto i conti con l\u2019intelligence investigative e con la preparazione di tanti magistrati che&hellip;<\/p>\n","protected":false},"author":13,"featured_media":24140,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[142,921,196],"tags":[14355,11021,452,3421,8762,6308,14356,6973,14354,14353,6842],"class_list":["post-24829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-home","category-news","tag-direzione-distrettuale-antimafia-nazionale","tag-giacomo-francesco-saccomanno","tag-giovanni-bombardieri","tag-giovanni-melillo","tag-lega-calabria","tag-marcello-viola","tag-nicola-piacente","tag-operazione-antindrangheta","tag-procura-di-genova","tag-procura-di-milano","tag-procura-di-reggio-calabria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lega Calabria sull&#039;operazione contro la &#039;ndrangheta<\/title>\n<meta name=\"description\" content=\"Procure italiane e Direzioni distrettuali antimafia stanno scardinandol&#039;organizzazione criminale calabrese, ricevendo il plauso di Saccomanno\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/lega-calabria-sulloperazione-contro-la-ndrangheta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lega Calabria sull&#039;operazione contro la &#039;ndrangheta\" \/>\n<meta property=\"og:description\" content=\"Procure italiane e Direzioni distrettuali antimafia stanno scardinandol&#039;organizzazione criminale calabrese, ricevendo il plauso di Saccomanno\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/lega-calabria-sulloperazione-contro-la-ndrangheta\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-04T10:48:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/04\/Saccomanno.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"344\" \/>\n\t<meta property=\"og:image:height\" content=\"324\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Helena Pedone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Helena Pedone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/05\\\/04\\\/lega-calabria-sulloperazione-contro-la-ndrangheta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/05\\\/04\\\/lega-calabria-sulloperazione-contro-la-ndrangheta\\\/\"},\"author\":{\"name\":\"Helena Pedone\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/8458ed437f4094f881aab8e4cc572684\"},\"headline\":\"Lega Calabria sull&#8217;operazione contro la &#8216;ndrangheta\",\"datePublished\":\"2023-05-04T10:48:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/05\\\/04\\\/lega-calabria-sulloperazione-contro-la-ndrangheta\\\/\"},\"wordCount\":420,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/05\\\/04\\\/lega-calabria-sulloperazione-contro-la-ndrangheta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/04\\\/Saccomanno.jpg\",\"keywords\":[\"Direzione distrettuale antimafia nazionale\",\"Giacomo Francesco Saccomanno\",\"Giovanni Bombardieri\",\"giovanni melillo\",\"lega calabria\",\"Marcello Viola\",\"Nicola Piacente\",\"Operazione Antindrangheta\",\"Procura di Genova\",\"Procura di Milano\",\"Procura di Reggio Calabria\"],\"articleSection\":[\"Calabria\",\"Home\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/05\\\/04\\\/lega-calabria-sulloperazione-contro-la-ndrangheta\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/05\\\/04\\\/lega-calabria-sulloperazione-contro-la-ndrangheta\\\/\",\"name\":\"Lega Calabria sull'operazione contro la 'ndrangheta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/05\\\/04\\\/lega-calabria-sulloperazione-contro-la-ndrangheta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/05\\\/04\\\/lega-calabria-sulloperazione-contro-la-ndrangheta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/04\\\/Saccomanno.jpg\",\"datePublished\":\"2023-05-04T10:48:49+00:00\",\"description\":\"Procure italiane e Direzioni distrettuali antimafia stanno scardinandol'organizzazione criminale calabrese, ricevendo il plauso di Saccomanno\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/05\\\/04\\\/lega-calabria-sulloperazione-contro-la-ndrangheta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/05\\\/04\\\/lega-calabria-sulloperazione-contro-la-ndrangheta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/05\\\/04\\\/lega-calabria-sulloperazione-contro-la-ndrangheta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/04\\\/Saccomanno.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/04\\\/Saccomanno.jpg\",\"width\":344,\"height\":324},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/05\\\/04\\\/lega-calabria-sulloperazione-contro-la-ndrangheta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lega Calabria sull&#8217;operazione contro la &#8216;ndrangheta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/8458ed437f4094f881aab8e4cc572684\",\"name\":\"Helena Pedone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/95a63adf316f90175b68113b4b895a96641be06395ffeef88fea6178b30027d9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/95a63adf316f90175b68113b4b895a96641be06395ffeef88fea6178b30027d9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/95a63adf316f90175b68113b4b895a96641be06395ffeef88fea6178b30027d9?s=96&d=mm&r=g\",\"caption\":\"Helena Pedone\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/helena\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lega Calabria sull'operazione contro la 'ndrangheta","description":"Procure italiane e Direzioni distrettuali antimafia stanno scardinandol'organizzazione criminale calabrese, ricevendo il plauso di Saccomanno","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/lega-calabria-sulloperazione-contro-la-ndrangheta\/","og_locale":"it_IT","og_type":"article","og_title":"Lega Calabria sull'operazione contro la 'ndrangheta","og_description":"Procure italiane e Direzioni distrettuali antimafia stanno scardinandol'organizzazione criminale calabrese, ricevendo il plauso di Saccomanno","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/lega-calabria-sulloperazione-contro-la-ndrangheta\/","og_site_name":"Radio Touring 104","article_published_time":"2023-05-04T10:48:49+00:00","og_image":[{"width":344,"height":324,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/04\/Saccomanno.jpg","type":"image\/jpeg"}],"author":"Helena Pedone","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Helena Pedone","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/lega-calabria-sulloperazione-contro-la-ndrangheta\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/lega-calabria-sulloperazione-contro-la-ndrangheta\/"},"author":{"name":"Helena Pedone","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/8458ed437f4094f881aab8e4cc572684"},"headline":"Lega Calabria sull&#8217;operazione contro la &#8216;ndrangheta","datePublished":"2023-05-04T10:48:49+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/lega-calabria-sulloperazione-contro-la-ndrangheta\/"},"wordCount":420,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/lega-calabria-sulloperazione-contro-la-ndrangheta\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/04\/Saccomanno.jpg","keywords":["Direzione distrettuale antimafia nazionale","Giacomo Francesco Saccomanno","Giovanni Bombardieri","giovanni melillo","lega calabria","Marcello Viola","Nicola Piacente","Operazione Antindrangheta","Procura di Genova","Procura di Milano","Procura di Reggio Calabria"],"articleSection":["Calabria","Home","News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/lega-calabria-sulloperazione-contro-la-ndrangheta\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/lega-calabria-sulloperazione-contro-la-ndrangheta\/","name":"Lega Calabria sull'operazione contro la 'ndrangheta","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/lega-calabria-sulloperazione-contro-la-ndrangheta\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/lega-calabria-sulloperazione-contro-la-ndrangheta\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/04\/Saccomanno.jpg","datePublished":"2023-05-04T10:48:49+00:00","description":"Procure italiane e Direzioni distrettuali antimafia stanno scardinandol'organizzazione criminale calabrese, ricevendo il plauso di Saccomanno","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/lega-calabria-sulloperazione-contro-la-ndrangheta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/lega-calabria-sulloperazione-contro-la-ndrangheta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/lega-calabria-sulloperazione-contro-la-ndrangheta\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/04\/Saccomanno.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/04\/Saccomanno.jpg","width":344,"height":324},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/05\/04\/lega-calabria-sulloperazione-contro-la-ndrangheta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Lega Calabria sull&#8217;operazione contro la &#8216;ndrangheta"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/8458ed437f4094f881aab8e4cc572684","name":"Helena Pedone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/95a63adf316f90175b68113b4b895a96641be06395ffeef88fea6178b30027d9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/95a63adf316f90175b68113b4b895a96641be06395ffeef88fea6178b30027d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/95a63adf316f90175b68113b4b895a96641be06395ffeef88fea6178b30027d9?s=96&d=mm&r=g","caption":"Helena Pedone"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/helena\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/04\/Saccomanno.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/24829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=24829"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/24829\/revisions"}],"predecessor-version":[{"id":24836,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/24829\/revisions\/24836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/24140"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=24829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=24829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=24829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}