{"id":32564,"date":"2023-08-15T11:25:27","date_gmt":"2023-08-15T09:25:27","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=32564"},"modified":"2023-08-15T12:28:13","modified_gmt":"2023-08-15T10:28:13","slug":"san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2023\/08\/15\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\/","title":{"rendered":"San Roberto: conclusi i festeggiamenti alla Madonna del Rosario di Pompei"},"content":{"rendered":"<p style=\"text-align: justify\">Si sono conclusi con grande gioia e partecipazione i festeggiamenti in onore della <strong>Madonna del Rosario di Pompei a Colelli di San Roberto<\/strong>. La comunit\u00e0 si \u00e8 unita in un connubio di festeggiamenti civili e religiosi, trasmettendo un forte senso di tradizione e devozione.<\/p>\n<p style=\"text-align: justify\">L&#8217;atmosfera festosa ha avuto inizio Gioved\u00ec 10 Agosto con la gara di tiro a segno, un evento che ha reso omaggio alla memoria di Franco Barill\u00e0. Un momento di competizione e convivialit\u00e0 che ha coinvolto i cittadini di tutte le et\u00e0, dimostrando ancora una volta la vitalit\u00e0 e lo spirito di comunit\u00e0 che anima Colelli. Venerd\u00ec 11 Agosto \u00e8 stata svolta l\u2019iniziativa: <em>\u201cNonostante tutto ho ancora voglia di giocare\u201d,<\/em> in memoria di Vittorio Vizzari, un giovane membro attivo del comitato festa e dell\u2019associazione del territorio Colellese che prematuramente \u00e8 venuto a mancare all\u2019affetto della comunit\u00e0. Una giornata, dedicata interamente ai bambini, ricca di giochi, attivit\u00e0 e divertimento, testimoniando anche l&#8217;attenzione che l\u2019associazione e il comitato dedicano alle future generazioni.<\/p>\n<p style=\"text-align: justify\">Il culmine dei festeggiamenti \u00e8 giunto Sabato 12 Agosto con un concerto che ha visto esibirsi i VERSUD, offrendo spettacolo e intrattenimento a tutti i presenti. La serata \u00e8 stata poi incorniciata da uno spettacolo pirotecnico musicale, curato dalla ditta FirePlay Santangelo, che ha illuminato il cielo di Colelli di San Roberto con scintillanti colori e esplosioni artistiche. La componente religiosa della festa \u00e8 stata altrettanto significativa, con la processione della Madonna del Rosario di Pompei che ha attraversato le vie del paese sotto la guida spirituale di Don Oliver.<\/p>\n<p style=\"text-align: justify\">Il comitato e l\u2019associazione hanno voluto ringraziare anche tutti coloro che hanno preso parte alla processione, la comunit\u00e0 e le forze militari del paese, i Carabinieri della stazione di San Roberto e il corpo di polizia municipale che hanno garantito una perfetta organizzazione. La partecipazione e la devozione dei fedeli hanno reso l&#8217;atmosfera ancora pi\u00f9 intensa, culminando nel ritrovo nella piazza centrale del piccolo borgo, dove un commosso ricordo \u00e8 stato dedicato a <strong>Padre Benoit<\/strong>, parroco della parrocchia scomparso lo scorso anno, sotto le note della canzone intonata da Turi Rugolo, il ricordo \u00e8 stato condiviso e partecipato da tutta la platea. A seguire la tradizionale canzone dedicata alla Madonna che \u00e8 stata intonata da tutti i portatori della vara.<\/p>\n<p style=\"text-align: justify\">L&#8217;intero evento \u00e8 stato organizzato dal Comitato Festa in collaborazione con l&#8217;associazione <strong>Colelli in Progress<\/strong>, dimostrando ancora una volta come la collaborazione e l&#8217;impegno collettivo possano creare momenti di condivisione e appartenenza. L&#8217;evento ha attirato non solo i residenti di Colelli, ma anche persone provenienti da tutta la vallata del Catona, confermando l&#8217;evento come uno degli appuntamenti pi\u00f9 attesi dell&#8217;anno, consolidando il borgo come punto di riferimento nell&#8217;agenda degli eventi annuali nell&#8217;area dello stretto. La Madonna del Rosario di Pompei ha sicuramente guidato i cuori e le menti dei presenti, creando un legame che va oltre le semplici celebrazioni e che lascia una profonda impronta nella storia e nell&#8217;anima della comunit\u00e0.<\/p>\n<p style=\"text-align: justify\">L\u2019associazione Colelli in progress, in collaborazione con il Pastificio Francesco Pio d\u00e0 appuntamento alla Prima Sagra della Pasta che si svolger\u00e0 nella piazza centrale del piccolo borgo giorno 19 Agosto, una nuova iniziativa che tende a rafforzare il legame della comunit\u00e0 con tutto il territorio circostante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si sono conclusi con grande gioia e partecipazione i festeggiamenti in onore della Madonna del Rosario di Pompei a Colelli di San Roberto. La comunit\u00e0 si \u00e8 unita in un&hellip;<\/p>\n","protected":false},"author":8,"featured_media":32565,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[921,196,140],"tags":[20314,2915],"class_list":["post-32564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-news","category-reggio-calabria","tag-madonna-del-rosario-di-pompei","tag-san-roberto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>San Roberto: conclusi i festeggiamenti alla Madonna del Rosario di Pompei - Radio Touring 104<\/title>\n<meta name=\"description\" content=\"Conclusi i Festeggiamenti in Onore alla Madonna del Rosario di Pompei a Colelli di San Roberto: Unione tra Comunit\u00e0 e Devozione\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2023\/08\/15\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"San Roberto: conclusi i festeggiamenti alla Madonna del Rosario di Pompei - Radio Touring 104\" \/>\n<meta property=\"og:description\" content=\"Conclusi i Festeggiamenti in Onore alla Madonna del Rosario di Pompei a Colelli di San Roberto: Unione tra Comunit\u00e0 e Devozione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2023\/08\/15\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-15T09:25:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-15T10:28:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/08\/Madonna-del-Rosario-di-Pompei.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1331\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Filippo Francesco Idone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Filippo Francesco Idone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/08\\\/15\\\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/08\\\/15\\\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\\\/\"},\"author\":{\"name\":\"Filippo Francesco Idone\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\"},\"headline\":\"San Roberto: conclusi i festeggiamenti alla Madonna del Rosario di Pompei\",\"datePublished\":\"2023-08-15T09:25:27+00:00\",\"dateModified\":\"2023-08-15T10:28:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/08\\\/15\\\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\\\/\"},\"wordCount\":533,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/08\\\/15\\\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/08\\\/Madonna-del-Rosario-di-Pompei.jpeg\",\"keywords\":[\"Madonna del Rosario di Pompei\",\"san roberto\"],\"articleSection\":[\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/08\\\/15\\\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/08\\\/15\\\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\\\/\",\"name\":\"San Roberto: conclusi i festeggiamenti alla Madonna del Rosario di Pompei - Radio Touring 104\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/08\\\/15\\\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/08\\\/15\\\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/08\\\/Madonna-del-Rosario-di-Pompei.jpeg\",\"datePublished\":\"2023-08-15T09:25:27+00:00\",\"dateModified\":\"2023-08-15T10:28:13+00:00\",\"description\":\"Conclusi i Festeggiamenti in Onore alla Madonna del Rosario di Pompei a Colelli di San Roberto: Unione tra Comunit\u00e0 e Devozione\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/08\\\/15\\\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/08\\\/15\\\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/08\\\/15\\\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/08\\\/Madonna-del-Rosario-di-Pompei.jpeg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/08\\\/Madonna-del-Rosario-di-Pompei.jpeg\",\"width\":1080,\"height\":1331},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/08\\\/15\\\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"San Roberto: conclusi i festeggiamenti alla Madonna del Rosario di Pompei\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\",\"name\":\"Filippo Francesco Idone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"caption\":\"Filippo Francesco Idone\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/filippoidone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"San Roberto: conclusi i festeggiamenti alla Madonna del Rosario di Pompei - Radio Touring 104","description":"Conclusi i Festeggiamenti in Onore alla Madonna del Rosario di Pompei a Colelli di San Roberto: Unione tra Comunit\u00e0 e Devozione","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2023\/08\/15\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\/","og_locale":"it_IT","og_type":"article","og_title":"San Roberto: conclusi i festeggiamenti alla Madonna del Rosario di Pompei - Radio Touring 104","og_description":"Conclusi i Festeggiamenti in Onore alla Madonna del Rosario di Pompei a Colelli di San Roberto: Unione tra Comunit\u00e0 e Devozione","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2023\/08\/15\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\/","og_site_name":"Radio Touring 104","article_published_time":"2023-08-15T09:25:27+00:00","article_modified_time":"2023-08-15T10:28:13+00:00","og_image":[{"width":1080,"height":1331,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/08\/Madonna-del-Rosario-di-Pompei.jpeg","type":"image\/jpeg"}],"author":"Filippo Francesco Idone","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Filippo Francesco Idone","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/08\/15\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/08\/15\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\/"},"author":{"name":"Filippo Francesco Idone","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b"},"headline":"San Roberto: conclusi i festeggiamenti alla Madonna del Rosario di Pompei","datePublished":"2023-08-15T09:25:27+00:00","dateModified":"2023-08-15T10:28:13+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/08\/15\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\/"},"wordCount":533,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/08\/15\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/08\/Madonna-del-Rosario-di-Pompei.jpeg","keywords":["Madonna del Rosario di Pompei","san roberto"],"articleSection":["Home","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/08\/15\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2023\/08\/15\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\/","name":"San Roberto: conclusi i festeggiamenti alla Madonna del Rosario di Pompei - Radio Touring 104","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/08\/15\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/08\/15\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/08\/Madonna-del-Rosario-di-Pompei.jpeg","datePublished":"2023-08-15T09:25:27+00:00","dateModified":"2023-08-15T10:28:13+00:00","description":"Conclusi i Festeggiamenti in Onore alla Madonna del Rosario di Pompei a Colelli di San Roberto: Unione tra Comunit\u00e0 e Devozione","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/08\/15\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2023\/08\/15\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/08\/15\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/08\/Madonna-del-Rosario-di-Pompei.jpeg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/08\/Madonna-del-Rosario-di-Pompei.jpeg","width":1080,"height":1331},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/08\/15\/san-roberto-conclusi-i-festeggiamenti-alla-madonna-del-rosario-di-pompei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"San Roberto: conclusi i festeggiamenti alla Madonna del Rosario di Pompei"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b","name":"Filippo Francesco Idone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","caption":"Filippo Francesco Idone"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/filippoidone\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/08\/Madonna-del-Rosario-di-Pompei.jpeg","_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/32564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=32564"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/32564\/revisions"}],"predecessor-version":[{"id":32566,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/32564\/revisions\/32566"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/32565"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=32564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=32564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=32564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}