{"id":37658,"date":"2023-10-26T09:19:34","date_gmt":"2023-10-26T07:19:34","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=37658"},"modified":"2023-10-26T09:44:59","modified_gmt":"2023-10-26T07:44:59","slug":"processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2023\/10\/26\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\/","title":{"rendered":"Processo Miramare: Cassazione annulla senza rinvio condanna a Falcomat\u00e0. Sindaco sospeso pu\u00f2 tornare a Palazzo"},"content":{"rendered":"<p style=\"text-align: justify\">La Suprema Corte di <strong>Cassazione ha annullato senza rinvio la condanna al Sindaco sospeso Giuseppe Falcomat\u00e0 che adesso pu\u00f2 tornare ad esercitare le sue funzioni <\/strong>di primo cittadino del Comune e della citt\u00e0 metropolitana di Reggio Calabria<\/p>\n<p style=\"text-align: justify\">La sentenza del <strong>processo &#8220;Miramare&#8221;<\/strong>, arrivata ieri pomeiggio, a Roma dove si \u00e8 conclusa la camera di consiglio della Suprema Corte che ha accolto la richiesta degli avvocati <strong>Marco Panella<\/strong> e <strong>Giandomenico Caiazza<\/strong> i quali stamattina avevano chiesto l<strong>&#8216;annullamento della<\/strong> <strong>sentenza emessa nel novembre 2022 dalla Corte d&#8217;Appello di Reggio<\/strong> Calabria <strong>che aveva condannato a un anno di carcere, con pena sospesa, per abuso d&#8217;ufficio Giuseppe Falcomat\u00e0 e a 6 mesi<\/strong> gli altri imputati del processo.<\/p>\n<p style=\"text-align: justify\"><strong>Processo scaturito<\/strong> da un&#8217;inchiesta su irregolarit\u00e0 nelle procedure di affidamento ad un&#8217;associazione del Grand Hotel Miramare. Nel 2015, l&#8217;immobile era stato concesso senza alcun bando pubblico all&#8217;associazione<em> &#8220;Il sottoscala&#8221;,<\/em> riconducibile all&#8217;imprenditore <strong>Paolo Zagarella.<\/strong> <strong>Al centro delle indagini, infatti c&#8217;erano i presunti rapporti <\/strong>tra Falcomat\u00e0 e Zagarella che, in occasione delle elezioni comunali del 2014, aveva concesso gratuitamente al sindaco di Reggio Calabria alcuni locali di sua propriet\u00e0 per ospitare la segreteria politica. Stando a quanto trapela<strong>, la Cassazione avrebbe valutato la desistenza volontaria degli imputati<\/strong> che, dopo aver affidato il Miramare all&#8217;associazione di Zagarella, avevano revocato l&#8217;affidamento.<\/p>\n<p style=\"text-align: justify\">Stamattina, il sostituto procuratore generale presso la Corte di Cassazione <strong>Roberto Aniello aveva chiesto l&#8217;annullamento della sentenza per prescrizione spiegando che il fatto forse andava qualificato in maniera diversa e ci potrebbero essere dubbi sulla ricostruzione della vicenda.<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>Dubbi che<\/strong>, comunque,<strong> non potrebbero essere risolti, <\/strong>in quanto il<strong> reato <\/strong>in ogni caso<strong> sarebbe prescritto.<\/strong> <strong>Da qui l&#8217;annullamento che riapre le porte di Palazzo San Giorgio a Falcomat\u00e0. <\/strong><\/p>\n<p style=\"text-align: justify\"><strong>La Cassazione ha annullato la sentenza d&#8217;appello pure per gli altri dieci imputati.<\/strong> Tra questi, oltre al segretario comunale in carica all&#8217;epoca, <strong>Giovanna Antonia Acquaviva<\/strong>, all&#8217;ex dirigente del settore &#8220;Servizi alle imprese e sviluppo economico&#8221; del Comune,<strong> Maria Luisa Span\u00f2,<\/strong> e all&#8217;imprenditore <strong>Paolo Zagarella,<\/strong> ci sono i sette ex assessori coinvolti nel processo &#8220;Miramare&#8221;:<strong> Saverio Anghelone, Armando Neri, Rosanna Maria Nardi, Giuseppe Marino, Giovanni Muraca, Agata Quattrone e Antonino Zimbalatti.<\/strong> Anche per loro si interrompe la sospensione imposta dalla legge Severino. Se Falcomat\u00e0 torna sindaco, l&#8217;ex assessore Giovanni Muraca, difeso dall&#8217;avv. Sergio Lagan\u00e0 entra al Consiglio regionale da dove era sospeso dopo la condanna d&#8217;appello.<\/p>\n<p style=\"text-align: justify\"><em>&#8220;Faccio i complimenti al sindaco Falcomat\u00e0 per l&#8217;assoluzione: FdI non fa politica con la giustizia e siamo contenti sul piano umano. Falcomat\u00e0 \u00e8 colpevole politicamente di avere ridotto Reggio Calabria, la nostra grande citt\u00e0 metropolitana, in ginocchio&#8221;<\/em>. Lo afferma il vicecapogruppo di Fratelli d&#8217;Italia alla Camera,Assolto Falcomat\u00e0, &#8216;anni duri ma adesso un nuovo inizio&#8217; <strong>i<\/strong> &#8220;Sul piano politico lo batteremo &#8211; <strong>aggiunge Antoniozzi &#8211;<\/strong><em> anche se non potr\u00e0 essere ricandidato, e batteremo la sinistra che sta governando la nostra Reggio da ormai dieci anni. Fratelli d&#8217;Italia ha donne e uomini in grado di condurre, insieme al centrodestra, una battaglia di rinnovamento per la citt\u00e0 e di separare i giudizi personali da quelli politici. Sul piano politico Falcomata e la sinistra sono senza possibilit\u00e0 di appello&#8221;<\/em><\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: justify\">Assoluzione Falcomat\u00e0, Sindaco torna in carica: , &#8220;Anni duri ma adesso un nuovo inizio&#8221;<\/h3>\n<p style=\"text-align: justify\"><em> &#8220;Assolto. Sono stati due anni duri. Due anni in cui ho sofferto, ha sofferto la mia famiglia, ha sofferto la citt\u00e0. Questa assoluzione restituisce, in parte, le amarezze di questo periodo. Un periodo in cui non mi \u00e8 mai, mai, mancato il vostro sostegno, il sostegno dei reggini. Adesso per la citt\u00e0 ci dovr\u00e0 essere un nuovo inizio. Insieme. Vi voglio bene, ci vediamo tra poco&#8221;. Cos\u00ec il sindaco di Reggio Calabria Giuseppe Falcomat\u00e0 sulla sua pagina facebook all&#8217;indomani della sentenza della Corte di Cassazione che ha annullato la condanna in secondo grado nel processo &#8220;Miramare&#8221;. Una condanna che, a causa della legge Severino, gli \u00e8 costata due anni di sospensione durante i quali il Comune e la citt\u00e0 metropolitana sono stati guidati dai due sindaci facenti funzioni, Paolo Brunetti e Carmelo Versace. L&#8217;annullamento senza rinvio deciso dalla Suprema Corte ha rimesso al suo posto Falcomat\u00e0 che, adesso, ritorna in carica fino al 2025 quando dovrebbe concludersi il suo secondo mandato.&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Suprema Corte di Cassazione ha annullato senza rinvio la condanna al Sindaco sospeso Giuseppe Falcomat\u00e0 che adesso pu\u00f2 tornare ad esercitare le sue funzioni di primo cittadino del Comune&hellip;<\/p>\n","protected":false},"author":12,"featured_media":11878,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[921,150,196,140],"tags":[4603,23307,23312,342,11582,23310,812,23309,5497,6913,23308,23311,16789],"class_list":["post-37658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-in-primo-piano","category-news","category-reggio-calabria","tag-alfredo-antoniozzi","tag-annullamento-senza-rinvio-condanna","tag-annullata-sentenza-dappello-pure-per-gli-altri-dieci-imputati","tag-comune-di-reggio-calabria","tag-corte-dappello-di-reggio","tag-giandomenico-caiazza","tag-giuseppe-falcomata","tag-marco-panella","tag-paolo-zagarella","tag-processo-miramare","tag-ritorno-esercizio-funzioni-sindaco-rc","tag-roberto-aniello","tag-suprema-corte-di-cassazione"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Processo Miramare: Cassazione annulla condanna a Falcomat\u00e0<\/title>\n<meta name=\"description\" content=\"La Cassazione ha annullato la condanna a Falcomat\u00e0 che pu\u00f2 tornare ad esercitare le sue funzioni di primo cittadino del Comune e Metrocity\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2023\/10\/26\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Processo Miramare: Cassazione annulla condanna a Falcomat\u00e0\" \/>\n<meta property=\"og:description\" content=\"La Cassazione ha annullato la condanna a Falcomat\u00e0 che pu\u00f2 tornare ad esercitare le sue funzioni di primo cittadino del Comune e Metrocity\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2023\/10\/26\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-26T07:19:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-26T07:44:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/11\/giuseppe-falcomata.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1068\" \/>\n\t<meta property=\"og:image:height\" content=\"1075\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sebastiano Plutino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastiano Plutino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/10\\\/26\\\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/10\\\/26\\\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\\\/\"},\"author\":{\"name\":\"Sebastiano Plutino\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\"},\"headline\":\"Processo Miramare: Cassazione annulla senza rinvio condanna a Falcomat\u00e0. Sindaco sospeso pu\u00f2 tornare a Palazzo\",\"datePublished\":\"2023-10-26T07:19:34+00:00\",\"dateModified\":\"2023-10-26T07:44:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/10\\\/26\\\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\\\/\"},\"wordCount\":689,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/10\\\/26\\\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/11\\\/giuseppe-falcomata.jpg\",\"keywords\":[\"Alfredo Antoniozzi\",\"annullamento senza rinvio condanna\",\"annullata sentenza d'appello pure per gli altri dieci imputati.\",\"Comune di Reggio Calabria\",\"Corte d'Appello di Reggio\",\"Giandomenico Caiazza\",\"Giuseppe Falcomat\u00e0\",\"Marco Panella\",\"Paolo Zagarella\",\"Processo Miramare\",\"ritorno esercizio funzioni sindaco RC\",\"Roberto Aniello\",\"Suprema Corte di Cassazione\"],\"articleSection\":[\"Home\",\"In primo piano\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/10\\\/26\\\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/10\\\/26\\\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\\\/\",\"name\":\"Processo Miramare: Cassazione annulla condanna a Falcomat\u00e0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/10\\\/26\\\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/10\\\/26\\\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/11\\\/giuseppe-falcomata.jpg\",\"datePublished\":\"2023-10-26T07:19:34+00:00\",\"dateModified\":\"2023-10-26T07:44:59+00:00\",\"description\":\"La Cassazione ha annullato la condanna a Falcomat\u00e0 che pu\u00f2 tornare ad esercitare le sue funzioni di primo cittadino del Comune e Metrocity\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/10\\\/26\\\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/10\\\/26\\\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/10\\\/26\\\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/11\\\/giuseppe-falcomata.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/11\\\/giuseppe-falcomata.jpg\",\"width\":1068,\"height\":1075},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2023\\\/10\\\/26\\\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Processo Miramare: Cassazione annulla senza rinvio condanna a Falcomat\u00e0. Sindaco sospeso pu\u00f2 tornare a Palazzo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\",\"name\":\"Sebastiano Plutino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"caption\":\"Sebastiano Plutino\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/sebastiano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Processo Miramare: Cassazione annulla condanna a Falcomat\u00e0","description":"La Cassazione ha annullato la condanna a Falcomat\u00e0 che pu\u00f2 tornare ad esercitare le sue funzioni di primo cittadino del Comune e Metrocity","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2023\/10\/26\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\/","og_locale":"it_IT","og_type":"article","og_title":"Processo Miramare: Cassazione annulla condanna a Falcomat\u00e0","og_description":"La Cassazione ha annullato la condanna a Falcomat\u00e0 che pu\u00f2 tornare ad esercitare le sue funzioni di primo cittadino del Comune e Metrocity","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2023\/10\/26\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\/","og_site_name":"Radio Touring 104","article_published_time":"2023-10-26T07:19:34+00:00","article_modified_time":"2023-10-26T07:44:59+00:00","og_image":[{"width":1068,"height":1075,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/11\/giuseppe-falcomata.jpg","type":"image\/jpeg"}],"author":"Sebastiano Plutino","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Sebastiano Plutino","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/10\/26\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/10\/26\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\/"},"author":{"name":"Sebastiano Plutino","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e"},"headline":"Processo Miramare: Cassazione annulla senza rinvio condanna a Falcomat\u00e0. Sindaco sospeso pu\u00f2 tornare a Palazzo","datePublished":"2023-10-26T07:19:34+00:00","dateModified":"2023-10-26T07:44:59+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/10\/26\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\/"},"wordCount":689,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/10\/26\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/11\/giuseppe-falcomata.jpg","keywords":["Alfredo Antoniozzi","annullamento senza rinvio condanna","annullata sentenza d'appello pure per gli altri dieci imputati.","Comune di Reggio Calabria","Corte d'Appello di Reggio","Giandomenico Caiazza","Giuseppe Falcomat\u00e0","Marco Panella","Paolo Zagarella","Processo Miramare","ritorno esercizio funzioni sindaco RC","Roberto Aniello","Suprema Corte di Cassazione"],"articleSection":["Home","In primo piano","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/10\/26\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2023\/10\/26\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\/","name":"Processo Miramare: Cassazione annulla condanna a Falcomat\u00e0","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/10\/26\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/10\/26\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/11\/giuseppe-falcomata.jpg","datePublished":"2023-10-26T07:19:34+00:00","dateModified":"2023-10-26T07:44:59+00:00","description":"La Cassazione ha annullato la condanna a Falcomat\u00e0 che pu\u00f2 tornare ad esercitare le sue funzioni di primo cittadino del Comune e Metrocity","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/10\/26\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2023\/10\/26\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/10\/26\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/11\/giuseppe-falcomata.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/11\/giuseppe-falcomata.jpg","width":1068,"height":1075},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2023\/10\/26\/processo-miramare-cassazione-annulla-senza-rinvio-condanna-a-falcomata-sindaco-sospeso-puo-tornare-a-palazzo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Processo Miramare: Cassazione annulla senza rinvio condanna a Falcomat\u00e0. Sindaco sospeso pu\u00f2 tornare a Palazzo"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e","name":"Sebastiano Plutino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","caption":"Sebastiano Plutino"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/sebastiano\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/11\/giuseppe-falcomata.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/37658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=37658"}],"version-history":[{"count":3,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/37658\/revisions"}],"predecessor-version":[{"id":37674,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/37658\/revisions\/37674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/11878"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=37658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=37658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=37658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}