{"id":47162,"date":"2024-03-15T19:45:21","date_gmt":"2024-03-15T18:45:21","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=47162"},"modified":"2024-03-15T19:45:35","modified_gmt":"2024-03-15T18:45:35","slug":"reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2024\/03\/15\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\/","title":{"rendered":"Reggio Calabria: grande evento all&#8217;Aula Magna dell\u2019Accademia di Belle Arti"},"content":{"rendered":"<p style=\"text-align: justify\">Si terr\u00e0 il prossimo venerd\u00ec 22 marzo alle ore 16:00 nell\u2019A<strong>ula Magna dell\u2019Accademia<\/strong> di Belle Arti a<strong> Reggio Calabria,<\/strong> il primo seminario di divulgazione scientifica dal titolo \u201cMusei, ponti e colori: un approccio informale alla Geometria Computazionale\u201d, il primo incontro del ciclo di seminari gratuiti dedicati a temi di ricerca della Matematica moderna rivolti a tutti ed illustrati utilizzando un linguaggio semplice e comprensibile. Questa iniziativa \u00e8 inquadrata all\u2019interno della cosiddetta Terza Missione del Dipartimento di Matematica, Informatica, Fisica e scienze della Terra (MIFT) dell\u2019Universit\u00e0 di Messina (mift.unime.it) ossia di quelle attivit\u00e0 che, aggiungendosi alle due tradizionali di Didattica e Ricerca, mirano a valorizzare la formazione al fine di valicare i confini dell\u2019aule universitarie e contribuire alla diffusione della conoscenza, la mission dell\u2019associazione<strong> Calabria Formazione<\/strong> (www.calabriaformazione.it) che, non a caso, co-organizza l\u2019evento.<br \/>\nIl Comitato Scientifico \u00e8 composto da Matteo Gorgone, Giorgio Nordo, Francesco Oliveri e Patrizia Rogolino del Dipartimento MIFT dell&#8217;Universit\u00e0 di Messina, Angela Misiano Martino del Planetario Pythagoras di Reggio Calabria, Romano Britti, Antonio Galletta e Carmelo Nucera di Calabria Formazione.<\/p>\n<p style=\"text-align: justify\">In particolare, in questo primo incontro, il relatore, <strong>Giorgio Nordo<\/strong> dell\u2019Universit\u00e0 di Messina, illustrer\u00e0 con uno stile semplice e colloquiale, la storia, i fondamenti teorici e le applicazioni della Geometria Computazionale, una branca dell\u2019Informatica che, anche se non lo notiamo, ci aiuta quotidianamente persino quando usiamo il nostro smartphone o utilizziamo Office. L\u2019incontro, dal tono informale e \u2013 ci si augura \u2013 anche divertente, si terr\u00e0 a partire dalle ore 16:00 del prossimo venerd\u00ec 22 marzo presso l&#8217;Aula Magna dell&#8217;Accademia di <strong>Belle Arti sita in via XXV Luglio, 10 a Reggio Calabria<\/strong>. Alla conclusione del ciclo di seminari, ai partecipanti verr\u00e0 rilasciato un attestato di partecipazione e, per questo motivo, nonostante l&#8217;evento sia assolutamente gratuito e l\u2019accesso sia aperto a tutti, \u00e8 obbligatorio registrarsi e prenotare i posti mediante il modulo online disponibile all\u2019indirizzo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si terr\u00e0 il prossimo venerd\u00ec 22 marzo alle ore 16:00 nell\u2019Aula Magna dell\u2019Accademia di Belle Arti a Reggio Calabria, il primo seminario di divulgazione scientifica dal titolo \u201cMusei, ponti e&hellip;<\/p>\n","protected":false},"author":8,"featured_media":47163,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[921,196,140],"tags":[29023,29024,236],"class_list":["post-47162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-news","category-reggio-calabria","tag-aula-magna-dellaccademia","tag-giorgio-nordo","tag-reggio-calabria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reggio Calabria: grande evento all&#039;Aula Magna dell\u2019Accademia di Belle Arti - Radio Touring 104<\/title>\n<meta name=\"description\" content=\"All\u2019Aula Magna dell\u2019Accademia di Belle Arti si svolger\u00e0 \u201cMusei, ponti e colori: un approccio informale alla Geometria Computazionale\u201d\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/03\/15\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reggio Calabria: grande evento all&#039;Aula Magna dell\u2019Accademia di Belle Arti - Radio Touring 104\" \/>\n<meta property=\"og:description\" content=\"All\u2019Aula Magna dell\u2019Accademia di Belle Arti si svolger\u00e0 \u201cMusei, ponti e colori: un approccio informale alla Geometria Computazionale\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/03\/15\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-15T18:45:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-15T18:45:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/03\/locandina_math-in-action_seminario_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"820\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Filippo Francesco Idone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Filippo Francesco Idone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/03\\\/15\\\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/03\\\/15\\\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\\\/\"},\"author\":{\"name\":\"Filippo Francesco Idone\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\"},\"headline\":\"Reggio Calabria: grande evento all&#8217;Aula Magna dell\u2019Accademia di Belle Arti\",\"datePublished\":\"2024-03-15T18:45:21+00:00\",\"dateModified\":\"2024-03-15T18:45:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/03\\\/15\\\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\\\/\"},\"wordCount\":323,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/03\\\/15\\\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/03\\\/locandina_math-in-action_seminario_1.jpg\",\"keywords\":[\"Aula Magna dell\u2019Accademia\",\"Giorgio Nordo\",\"reggio calabria\"],\"articleSection\":[\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/03\\\/15\\\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/03\\\/15\\\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\\\/\",\"name\":\"Reggio Calabria: grande evento all'Aula Magna dell\u2019Accademia di Belle Arti - Radio Touring 104\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/03\\\/15\\\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/03\\\/15\\\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/03\\\/locandina_math-in-action_seminario_1.jpg\",\"datePublished\":\"2024-03-15T18:45:21+00:00\",\"dateModified\":\"2024-03-15T18:45:35+00:00\",\"description\":\"All\u2019Aula Magna dell\u2019Accademia di Belle Arti si svolger\u00e0 \u201cMusei, ponti e colori: un approccio informale alla Geometria Computazionale\u201d\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/03\\\/15\\\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/03\\\/15\\\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/03\\\/15\\\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/03\\\/locandina_math-in-action_seminario_1.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/03\\\/locandina_math-in-action_seminario_1.jpg\",\"width\":1400,\"height\":820},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/03\\\/15\\\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reggio Calabria: grande evento all&#8217;Aula Magna dell\u2019Accademia di Belle Arti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\",\"name\":\"Filippo Francesco Idone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"caption\":\"Filippo Francesco Idone\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/filippoidone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reggio Calabria: grande evento all'Aula Magna dell\u2019Accademia di Belle Arti - Radio Touring 104","description":"All\u2019Aula Magna dell\u2019Accademia di Belle Arti si svolger\u00e0 \u201cMusei, ponti e colori: un approccio informale alla Geometria Computazionale\u201d","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2024\/03\/15\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\/","og_locale":"it_IT","og_type":"article","og_title":"Reggio Calabria: grande evento all'Aula Magna dell\u2019Accademia di Belle Arti - Radio Touring 104","og_description":"All\u2019Aula Magna dell\u2019Accademia di Belle Arti si svolger\u00e0 \u201cMusei, ponti e colori: un approccio informale alla Geometria Computazionale\u201d","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/03\/15\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\/","og_site_name":"Radio Touring 104","article_published_time":"2024-03-15T18:45:21+00:00","article_modified_time":"2024-03-15T18:45:35+00:00","og_image":[{"width":1400,"height":820,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/03\/locandina_math-in-action_seminario_1.jpg","type":"image\/jpeg"}],"author":"Filippo Francesco Idone","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Filippo Francesco Idone","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/03\/15\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/03\/15\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\/"},"author":{"name":"Filippo Francesco Idone","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b"},"headline":"Reggio Calabria: grande evento all&#8217;Aula Magna dell\u2019Accademia di Belle Arti","datePublished":"2024-03-15T18:45:21+00:00","dateModified":"2024-03-15T18:45:35+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/03\/15\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\/"},"wordCount":323,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/03\/15\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/03\/locandina_math-in-action_seminario_1.jpg","keywords":["Aula Magna dell\u2019Accademia","Giorgio Nordo","reggio calabria"],"articleSection":["Home","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/03\/15\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/03\/15\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\/","name":"Reggio Calabria: grande evento all'Aula Magna dell\u2019Accademia di Belle Arti - Radio Touring 104","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/03\/15\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/03\/15\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/03\/locandina_math-in-action_seminario_1.jpg","datePublished":"2024-03-15T18:45:21+00:00","dateModified":"2024-03-15T18:45:35+00:00","description":"All\u2019Aula Magna dell\u2019Accademia di Belle Arti si svolger\u00e0 \u201cMusei, ponti e colori: un approccio informale alla Geometria Computazionale\u201d","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/03\/15\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2024\/03\/15\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/03\/15\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/03\/locandina_math-in-action_seminario_1.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/03\/locandina_math-in-action_seminario_1.jpg","width":1400,"height":820},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/03\/15\/reggio-calabria-grande-evento-allaula-magna-dellaccademia-di-belle-arti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Reggio Calabria: grande evento all&#8217;Aula Magna dell\u2019Accademia di Belle Arti"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b","name":"Filippo Francesco Idone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","caption":"Filippo Francesco Idone"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/filippoidone\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/03\/locandina_math-in-action_seminario_1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/47162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=47162"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/47162\/revisions"}],"predecessor-version":[{"id":47164,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/47162\/revisions\/47164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/47163"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=47162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=47162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=47162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}