{"id":49188,"date":"2024-04-13T13:05:35","date_gmt":"2024-04-13T11:05:35","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=49188"},"modified":"2024-04-13T15:14:07","modified_gmt":"2024-04-13T13:14:07","slug":"reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/13\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\/","title":{"rendered":"Reggio Calabria: presentato il programma delle fasi finali dei Campionati Italiani di Astronomia"},"content":{"rendered":"<p style=\"text-align: justify\">E&#8217; stato presentato <strong>a Palazzo Alvaro,<\/strong> sede della Citt\u00e0 Metropolitana di Reggio Calabria, il programma della finale nazionale dei <strong>Campionati italiani di Astronomia<\/strong>, giunti alla loro XXII edizione, che, dal 16 al 18 aprile, si terranno appunto nella citt\u00e0 dello Stretto. L\u2019iniziativa, promossa dal Ministero dell\u2019Istruzione alla Societ\u00e0 astronomica italiana ed all\u2019Istituto nazionale di astrofisica, in collaborazione appunto con la Citt\u00e0 Metropolitana di <strong>Reggio<\/strong> <strong>Calabria<\/strong>, coinvolger\u00e0 circa un centinaio di studenti ed altrettanti docenti dell\u2019intero Paese.<\/p>\n<p style=\"text-align: justify\">I dettagli dell&#8217;evento sono stati illustrati dal sindaco della <strong>Citt\u00e0 Metropolitana Giuseppe Falcomat\u00e0<\/strong> nel corso di una conferenza stampa che, nella sala \u201c<strong>Trisolini<\/strong>\u201d di Palazzo Alvaro, ha riunito il consigliere delegato alla Cultura, Filippo Quartuccio, la dirigente del settore metropolitano, Giuseppina Attanasio, la responsabile del Planetario \u201cPythagoras\u201d della Citt\u00e0 Metropolitana, Angela Misiano, il Professor Giuseppe Cutispoto della Societ\u00e0 astronomica italiana e la Professoressa Anna Brancaccio per il Ministero dell\u2019Istruzione e del Merito. Presenti in sala anche il vicesindaco metropolitano Carmelo Versace, l&#8217;Assessore comunale Carmelo Romeo ed il Consigliere Filippo Burrone, il Professor Francesco Carlo Morabito dell\u2019Universit\u00e0 \u201cMediterranea\u201d, il Professor Riccardo Barbieri dell\u2019Unical, la Professoressa Miriam Calipari del Liceo scientifico \u201cLeonardo da Vinci\u201d, tutti partner dell&#8217;evento, ed infine, in qualit\u00e0 di sponsor, la societ\u00e0 titolare del servizio di trasporto Atam e l&#8217;Hotel Altafiumara, rappresentati dall\u2019amministratore Giuseppe Basile e dal responsabile marketing e comunicazione, Christian Zuin.<\/p>\n<p style=\"text-align: justify\">Per il sindaco <strong>Falcomat\u00e0<\/strong>, si tratta di un &#8220;<em>evento che d\u00e0 lustro alla nostra citt\u00e0 che ci permette di conoscere meglio e approfondire una materia come <strong>l&#8217;astronomia<\/strong> che ha due meriti su tutti&#8221;. &#8220;Il primo &#8211;<\/em> ha spiegato &#8211;<em> \u00e8 quello di farci stare a testa in su per guardare il cielo e l\u2019universo, che \u00e8 sempre fonte di ispirazione e speranza. Quindi, lo studio delle stelle, consente ai ragazzi di sviluppare una consapevolezza diversa. Anche se non tutti diventeranno scienziati, potranno per\u00f2 entrare in contatto col cosmo e capire che siamo soltanto un granello di sabbia in mezzo all&#8217;universo. L&#8217;universo, dunque, ci insegna ad essere umili&#8221;. &#8220;Un errore che si commette spesso<\/em> &#8211; ha proseguito il sindaco &#8211; <em>\u00e8 quello di credere che tutto ruoti intorno a noi e alle nostre scelte. Cos\u00ec, quando i nostri bisogni non si realizzano, invochiamo la malasorte, la presenza di una sorta di congiura nei nostri confronti che siamo sfortunati e perseguitati dalla iattura. <strong>L&#8217;astronomia<\/strong>, invece, ci permette di provare a comprendere la vastit\u00e0 dell\u2019universo e, quindi, il nostro essere semplicemente un granello di sabbia al cospetto di tutto il resto&#8221;.<\/em><\/p>\n<p style=\"text-align: justify\">Nel ringraziare l&#8217;impegno del consigliere Quartuccio, della dirigente Attanasio e di tutto il Settore, della professoressa Misiano, del Ministero e di tutti gli attori coinvolti nel grande progetto scientifico che ha anche ricevuto il patrocinio morale della <strong>Regione Calabria<\/strong>, il sindaco <strong>Falcomat\u00e0<\/strong> ha poi sottolineato &#8220;<em>la bont\u00e0 di simili iniziative che generano diversi risvolti molto positivi anche in chiave turistica, comprendendo la partecipazione e la presenza, nella nostra citt\u00e0, di numerose famiglie che, per tutta la durata dei campionati, potranno conoscere meglio ed apprezzare i nostri luoghi, le bellezze del territorio, e che avranno l&#8217;opportunit\u00e0 di vedere <strong>Reggio<\/strong> <strong>Calabria<\/strong> sotto una luce diversa da quella che, spesso, passa dalle cronache giornalistiche\u00bb. \u00abLa finale nazionale dei <strong>Campionati<\/strong> <strong>di<\/strong> <strong>astronomia<\/strong> &#8211; ha continuato Falcomat\u00e0 &#8211; \u00e8 importante anche per il brand Reggio, per un&#8217;idea di citt\u00e0 che sia anche destinazione turistica per eventi culturali&#8221;.<\/em><\/p>\n<p style=\"text-align: justify\">Secondo il consigliere Quartuccio, poi, <em>&#8220;\u00e8 un orgoglio poter ospitare questa manifestazione meravigliosa che proietta il territorio metropolitano su livelli culturali e scientifici molto alti&#8221;. &#8220;Il prezioso contributo degli sponsor e dei partner istituzionali <\/em>&#8211; ha proseguito &#8211; <em>fa capire quanto sia importante la sinergia per allestire iniziative di rilievo e di spessore accademico e culturale mastodontici. Arriveranno nella nostra citt\u00e0 circa duecento persone tra studenti, docenti e giurati, ai quali si aggiungeranno le famiglie al seguito, e siamo certi che Reggio ed i reggini sapranno accogliere al meglio questo grandissimo evento&#8221;.<\/em><\/p>\n<p style=\"text-align: justify\">E se Giuseppe Cutispoto, del Sait, ha ricordato come proprio Reggio sia &#8220;<strong><em>la citt\u00e0 con il record di partecipazioni&#8221;<\/em><\/strong>, sottolineando &#8220;<em>l&#8217;impegno eccezionale della <strong>Citt\u00e0<\/strong> <strong>Metropolitana<\/strong> che ha consentito di poter svolgere una finale che selezioner\u00e0 la squadra italiana per prossime olimpiadi internazionali&#8221;<\/em>, la professoressa <strong>Brancaccio<\/strong> ha apprezzato molto il lavoro di Palazzo Alvaro quale \u00ab<em>esempio di eccellenza di politica che sposa la cultura e la formazione dei nostri studenti per la crescita del nostro Paese&#8221;. La rappresentante del Ministero ha, cos\u00ec, ringraziato il sindaco Falcomat\u00e0 ed il settore diretto da Giuseppina Attanasio perch\u00e9 &#8220;\u00e8 con il sapere che investono nelle nuove generazioni&#8221;<\/em>.<\/p>\n<p style=\"text-align: justify\">Proprio la dirigente Attanasio ha evidenziato la bont\u00e0 della programmazione dell&#8217;amministrazione che &#8220;<em>ci da la possibilit\u00e0 di organizzare eventi come questo o come il Festival Cosmos che ci rendono orgogliosi e offrono una narrazione positiva del territorio e delle sue eccellenze, anche attraverso il fattivo coinvolgimento del partner istituzionali che ci accompagno in questa bellissima esperienza&#8221;. <\/em>Infine, Angela Misiano ha tessuto &#8220;<em>le lodi delle attivit\u00e0 promosse dalla <strong>Citt\u00e0<\/strong><strong>Metropolitana<\/strong> intorno all&#8217;oratorio laico rappresentato dal <strong>Planetario Pythagoras<\/strong>, un luogo dove i ragazzi possono incontrarsi e parlare di scienza&#8221;.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; stato presentato a Palazzo Alvaro, sede della Citt\u00e0 Metropolitana di Reggio Calabria, il programma della finale nazionale dei Campionati italiani di Astronomia, giunti alla loro XXII edizione, che, dal&hellip;<\/p>\n","protected":false},"author":8,"featured_media":49198,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[921,196,140],"tags":[747,30212,743,468,812,480,236],"class_list":["post-49188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-news","category-reggio-calabria","tag-angela-misiano","tag-campionati-italiani-di-astronomia","tag-citta-metropolitana","tag-filippo-quartuccio","tag-giuseppe-falcomata","tag-planetario-pythagoras","tag-reggio-calabria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reggio Calabria: presentato il programma delle fasi finali dei Campionati Italiani di Astronomia - Radio Touring 104<\/title>\n<meta name=\"description\" content=\"A Palazzo Corrado Alvaro presentato il programma della Finale Nazionale della XXII edizione dei Campionati Italiani di Astronomia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/13\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reggio Calabria: presentato il programma delle fasi finali dei Campionati Italiani di Astronomia - Radio Touring 104\" \/>\n<meta property=\"og:description\" content=\"A Palazzo Corrado Alvaro presentato il programma della Finale Nazionale della XXII edizione dei Campionati Italiani di Astronomia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/13\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-13T11:05:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-13T13:14:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/04\/finale-campionati-astronomia-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Filippo Francesco Idone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Filippo Francesco Idone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/13\\\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/13\\\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\\\/\"},\"author\":{\"name\":\"Filippo Francesco Idone\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\"},\"headline\":\"Reggio Calabria: presentato il programma delle fasi finali dei Campionati Italiani di Astronomia\",\"datePublished\":\"2024-04-13T11:05:35+00:00\",\"dateModified\":\"2024-04-13T13:14:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/13\\\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\\\/\"},\"wordCount\":846,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/13\\\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/04\\\/finale-campionati-astronomia-1.jpeg\",\"keywords\":[\"Angela Misiano\",\"Campionati Italiani di Astronomia\",\"Citt\u00e0 metropolitana\",\"filippo quartuccio\",\"Giuseppe Falcomat\u00e0\",\"Planetario Pythagoras\",\"reggio calabria\"],\"articleSection\":[\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/13\\\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/13\\\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\\\/\",\"name\":\"Reggio Calabria: presentato il programma delle fasi finali dei Campionati Italiani di Astronomia - Radio Touring 104\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/13\\\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/13\\\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/04\\\/finale-campionati-astronomia-1.jpeg\",\"datePublished\":\"2024-04-13T11:05:35+00:00\",\"dateModified\":\"2024-04-13T13:14:07+00:00\",\"description\":\"A Palazzo Corrado Alvaro presentato il programma della Finale Nazionale della XXII edizione dei Campionati Italiani di Astronomia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/13\\\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/13\\\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/13\\\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/04\\\/finale-campionati-astronomia-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/04\\\/finale-campionati-astronomia-1.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/13\\\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reggio Calabria: presentato il programma delle fasi finali dei Campionati Italiani di Astronomia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\",\"name\":\"Filippo Francesco Idone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"caption\":\"Filippo Francesco Idone\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/filippoidone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reggio Calabria: presentato il programma delle fasi finali dei Campionati Italiani di Astronomia - Radio Touring 104","description":"A Palazzo Corrado Alvaro presentato il programma della Finale Nazionale della XXII edizione dei Campionati Italiani di Astronomia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/13\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\/","og_locale":"it_IT","og_type":"article","og_title":"Reggio Calabria: presentato il programma delle fasi finali dei Campionati Italiani di Astronomia - Radio Touring 104","og_description":"A Palazzo Corrado Alvaro presentato il programma della Finale Nazionale della XXII edizione dei Campionati Italiani di Astronomia","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/13\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\/","og_site_name":"Radio Touring 104","article_published_time":"2024-04-13T11:05:35+00:00","article_modified_time":"2024-04-13T13:14:07+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/04\/finale-campionati-astronomia-1.jpeg","type":"image\/jpeg"}],"author":"Filippo Francesco Idone","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Filippo Francesco Idone","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/13\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/13\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\/"},"author":{"name":"Filippo Francesco Idone","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b"},"headline":"Reggio Calabria: presentato il programma delle fasi finali dei Campionati Italiani di Astronomia","datePublished":"2024-04-13T11:05:35+00:00","dateModified":"2024-04-13T13:14:07+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/13\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\/"},"wordCount":846,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/13\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/04\/finale-campionati-astronomia-1.jpeg","keywords":["Angela Misiano","Campionati Italiani di Astronomia","Citt\u00e0 metropolitana","filippo quartuccio","Giuseppe Falcomat\u00e0","Planetario Pythagoras","reggio calabria"],"articleSection":["Home","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/13\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/13\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\/","name":"Reggio Calabria: presentato il programma delle fasi finali dei Campionati Italiani di Astronomia - Radio Touring 104","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/13\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/13\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/04\/finale-campionati-astronomia-1.jpeg","datePublished":"2024-04-13T11:05:35+00:00","dateModified":"2024-04-13T13:14:07+00:00","description":"A Palazzo Corrado Alvaro presentato il programma della Finale Nazionale della XXII edizione dei Campionati Italiani di Astronomia","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/13\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/13\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/13\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/04\/finale-campionati-astronomia-1.jpeg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/04\/finale-campionati-astronomia-1.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/13\/reggio-calabria-presentato-programma-delle-fasi-finali-dei-campionati-italiani-di-astronomia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Reggio Calabria: presentato il programma delle fasi finali dei Campionati Italiani di Astronomia"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b","name":"Filippo Francesco Idone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","caption":"Filippo Francesco Idone"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/filippoidone\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/04\/finale-campionati-astronomia-1.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/49188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=49188"}],"version-history":[{"count":3,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/49188\/revisions"}],"predecessor-version":[{"id":49199,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/49188\/revisions\/49199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/49198"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=49188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=49188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=49188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}