{"id":49515,"date":"2024-04-18T09:38:58","date_gmt":"2024-04-18T07:38:58","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=49515"},"modified":"2024-04-18T10:18:54","modified_gmt":"2024-04-18T08:18:54","slug":"ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/18\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\/","title":{"rendered":"Ponte sullo Stretto, Ministro Salvini: &#8220;Avanti dritto, al via lavori entro l&#8217;estate&#8221;. Morabito (Pd): &#8220;Opera \u00e8 spreco di denaro pubblico&#8221;"},"content":{"rendered":"<p style=\"text-align: justify\"><em>&#8220;Vado avanti dritto e conto che entro i 30 giorni la societ\u00e0 Stretto di Messina dia le risposte a tutte le osservazioni fatte dagli altri ministeri: l&#8217;obiettivo, lo ribadisco, \u00e8 arrivare all&#8217;avvio dei lavori entro l&#8217;estate 2024. Conto che l&#8217;Italia possa essere un modello di sviluppo e crescita e di ingegneria&#8221;.<\/em><\/p>\n<p id=\"ob\" style=\"text-align: justify\"><strong>Cos\u00ec il vicepremier<\/strong> e ministro delle Infrastrutture e dei trasporti, <strong>Matteo Salvini, intervenendo all&#8217;iniziativa sui contratti pubblici,<\/strong> organizzata da Confcooperative Lavoro e servizi,<strong> parlando del Ponte sullo Stretto.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: justify\">Ponte Stretto, Morabito (Pd): &#8220;La grande opera \u00e8 spreco di denaro pubblico&#8221;<\/h3>\n<p style=\"text-align: justify\">Ora che, anche dal Ministero dell\u2019Ambiente, per il<strong> tramite della commissione di Valutazione impatto ambientale, si chiedono 237 chiarimenti su progetto<\/strong> definitivo della societ\u00e0 Stretto di Messina, dobbiamo aspettare ancora oltre e subire la protervia salviniana che magari <strong>non si risparmier\u00e0 per sperperare altri soldi dei cittadini?<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>Ma qualsiasi cosa Salvini &amp;C pensino<\/strong>, sappiano che il PD ad ogni livello contraster\u00e0 ogni ipotesi di avvio dei lavori per una opera pubblica che ad oggi si \u00e8<strong> dimostrata solo ed esclusivamente uno spreco di denaro pubblico, senza alcuna ricaduta positiva sul territorio.<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>Adesso \u00e8 solo giunto il momento di fermare gli espropri<\/strong> e dare tranquillit\u00e0 a tutti i cittadini che hanno vissuto e vivono nell\u2019inquietudine di dovere lasciare le proprie abitazioni.<\/p>\n<p style=\"text-align: justify\">Abbiamo fatto bene ad essere a fianco dei cittadini e delle<strong> comunit\u00e0 interessate a contrastare il tentativo di scempio<\/strong> di un territorio,<strong> la Costa Viola<\/strong>, la cui bellezza non ha uguali al mondo.<\/p>\n<p style=\"text-align: justify\">Infatti, l\u2019area marina sulla quale dovrebbe sorgere il Ponte \u00e8 zona di protezione speciale caratterizzata da emergenze naturalistiche rilevanti ancora ben conservate, che conferiscono ai fondali caratteristiche di unicit\u00e0.<\/p>\n<p style=\"text-align: justify\">Si tratta di aree protette ed in quanto tali chiamate a svolgere un ruolo strategico nella conservazione della biodiversit\u00e0 di specie, della biodiversit\u00e0 degli ecosistemi, nonch\u00e9 nella tutela e conservazione del territorio e del paesaggio.<\/p>\n<p style=\"text-align: justify\"><strong>Ma dobbiamo essere consapevoli che ora viene la parte pi\u00f9 importante<\/strong> e delicata, quella di proporre ed<strong> utilizzare i fondi destinati per il ponte sullo stretto, come volano per lo sviluppo del territorio.<\/strong><\/p>\n<p style=\"text-align: justify\">Dobbiamo pensare a rendere ancora pi\u00f9 belli i nostri luoghi per attrarre maggiori flussi turistici. Rigenerare la nostra Costa Viola avendo cura di farne un luogo in cui lo sviluppo turistico sia un tutt\u2019uno con il rispetto dell\u2019ambiente, senza disperdere i profumi, le culture, le storie di un tempo.<\/p>\n<p style=\"text-align: justify\"><strong>In questo scenario, non vi \u00e8 dubbio alcuno che la citt\u00e0 di Reggio Calabria dovr\u00e0 assumere un ruolo di traino<\/strong>: l\u2019aeroporto che va rapidamente ammodernato, il Museo che celebra nei Bronzi di Riace la sua magnificenza, i lavori di riqualificazione di alcuni territori periferici vanno nella giusta direzione, quella di ridare bellezza e vita ad un territorio che presenta ancora molti elementi di criticit\u00e0 e complessit\u00e0.<\/p>\n<p style=\"text-align: justify\"><strong>Ma crediamo che la direzione imboccata sia quella giusta<\/strong>, andiamo avanti monitorando ascoltando i territori che devono rappresentare un vero punto di riferimento per un buon governo della pubblica amministrazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Vado avanti dritto e conto che entro i 30 giorni la societ\u00e0 Stretto di Messina dia le risposte a tutte le osservazioni fatte dagli altri ministeri: l&#8217;obiettivo, lo ribadisco, \u00e8&hellip;<\/p>\n","protected":false},"author":12,"featured_media":14138,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[921,196,140],"tags":[30424,30417,30416,30418,25057,5253,30425],"class_list":["post-49515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-news","category-reggio-calabria","tag-antonio-morabito-pd","tag-avanti-dritto","tag-avvio-cantieri-ponte-stretto-entro-estate","tag-confcooperative-lavoro-e-servizi","tag-ponte-stretto-messina","tag-salvini","tag-spreco-denaro-pubblico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ponte Stretto, Salvini: &quot;Avanti dritto, al via lavori entro l&#039;estate&quot;<\/title>\n<meta name=\"description\" content=\"Intervento del Ministro delle Infrastrutture conferma la volont\u00e0 dell&#039;inizio della cantierizzazione dell&#039;opera entro l&#039;estate.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/18\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ponte Stretto, Salvini: &quot;Avanti dritto, al via lavori entro l&#039;estate&quot;\" \/>\n<meta property=\"og:description\" content=\"Intervento del Ministro delle Infrastrutture conferma la volont\u00e0 dell&#039;inizio della cantierizzazione dell&#039;opera entro l&#039;estate.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/18\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-18T07:38:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T08:18:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/12\/ponte-salvini.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"374\" \/>\n\t<meta property=\"og:image:height\" content=\"230\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sebastiano Plutino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastiano Plutino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/18\\\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/18\\\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\\\/\"},\"author\":{\"name\":\"Sebastiano Plutino\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\"},\"headline\":\"Ponte sullo Stretto, Ministro Salvini: &#8220;Avanti dritto, al via lavori entro l&#8217;estate&#8221;. Morabito (Pd): &#8220;Opera \u00e8 spreco di denaro pubblico&#8221;\",\"datePublished\":\"2024-04-18T07:38:58+00:00\",\"dateModified\":\"2024-04-18T08:18:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/18\\\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\\\/\"},\"wordCount\":504,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/18\\\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/12\\\/ponte-salvini.jpg\",\"keywords\":[\"Antonio Morabito PD\",\"avanti dritto\",\"avvio cantieri Ponte stretto entro estate\",\"Confcooperative Lavoro e servizi\",\"ponte stretto messina\",\"salvini\",\"spreco denaro pubblico\"],\"articleSection\":[\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/18\\\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/18\\\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\\\/\",\"name\":\"Ponte Stretto, Salvini: \\\"Avanti dritto, al via lavori entro l'estate\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/18\\\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/18\\\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/12\\\/ponte-salvini.jpg\",\"datePublished\":\"2024-04-18T07:38:58+00:00\",\"dateModified\":\"2024-04-18T08:18:54+00:00\",\"description\":\"Intervento del Ministro delle Infrastrutture conferma la volont\u00e0 dell'inizio della cantierizzazione dell'opera entro l'estate.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/18\\\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/18\\\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/18\\\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/12\\\/ponte-salvini.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/12\\\/ponte-salvini.jpg\",\"width\":374,\"height\":230},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/18\\\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ponte sullo Stretto, Ministro Salvini: &#8220;Avanti dritto, al via lavori entro l&#8217;estate&#8221;. Morabito (Pd): &#8220;Opera \u00e8 spreco di denaro pubblico&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\",\"name\":\"Sebastiano Plutino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"caption\":\"Sebastiano Plutino\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/sebastiano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ponte Stretto, Salvini: \"Avanti dritto, al via lavori entro l'estate\"","description":"Intervento del Ministro delle Infrastrutture conferma la volont\u00e0 dell'inizio della cantierizzazione dell'opera entro l'estate.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/18\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\/","og_locale":"it_IT","og_type":"article","og_title":"Ponte Stretto, Salvini: \"Avanti dritto, al via lavori entro l'estate\"","og_description":"Intervento del Ministro delle Infrastrutture conferma la volont\u00e0 dell'inizio della cantierizzazione dell'opera entro l'estate.","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/18\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\/","og_site_name":"Radio Touring 104","article_published_time":"2024-04-18T07:38:58+00:00","article_modified_time":"2024-04-18T08:18:54+00:00","og_image":[{"width":374,"height":230,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/12\/ponte-salvini.jpg","type":"image\/jpeg"}],"author":"Sebastiano Plutino","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Sebastiano Plutino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/18\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/18\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\/"},"author":{"name":"Sebastiano Plutino","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e"},"headline":"Ponte sullo Stretto, Ministro Salvini: &#8220;Avanti dritto, al via lavori entro l&#8217;estate&#8221;. Morabito (Pd): &#8220;Opera \u00e8 spreco di denaro pubblico&#8221;","datePublished":"2024-04-18T07:38:58+00:00","dateModified":"2024-04-18T08:18:54+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/18\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\/"},"wordCount":504,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/18\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/12\/ponte-salvini.jpg","keywords":["Antonio Morabito PD","avanti dritto","avvio cantieri Ponte stretto entro estate","Confcooperative Lavoro e servizi","ponte stretto messina","salvini","spreco denaro pubblico"],"articleSection":["Home","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/18\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/18\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\/","name":"Ponte Stretto, Salvini: \"Avanti dritto, al via lavori entro l'estate\"","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/18\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/18\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/12\/ponte-salvini.jpg","datePublished":"2024-04-18T07:38:58+00:00","dateModified":"2024-04-18T08:18:54+00:00","description":"Intervento del Ministro delle Infrastrutture conferma la volont\u00e0 dell'inizio della cantierizzazione dell'opera entro l'estate.","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/18\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/18\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/18\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/12\/ponte-salvini.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/12\/ponte-salvini.jpg","width":374,"height":230},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/18\/ponte-sullo-stretto-ministro-salvini-vanti-dritto-al-via-lavori-entro-lestate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Ponte sullo Stretto, Ministro Salvini: &#8220;Avanti dritto, al via lavori entro l&#8217;estate&#8221;. Morabito (Pd): &#8220;Opera \u00e8 spreco di denaro pubblico&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e","name":"Sebastiano Plutino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","caption":"Sebastiano Plutino"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/sebastiano\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/12\/ponte-salvini.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/49515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=49515"}],"version-history":[{"count":5,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/49515\/revisions"}],"predecessor-version":[{"id":49527,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/49515\/revisions\/49527"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/14138"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=49515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=49515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=49515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}