{"id":50240,"date":"2024-04-26T15:33:06","date_gmt":"2024-04-26T13:33:06","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=50240"},"modified":"2024-04-26T15:33:06","modified_gmt":"2024-04-26T13:33:06","slug":"calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/26\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\/","title":{"rendered":"Calabria: Ernesto Rapani affronta il tema dello spopolamento"},"content":{"rendered":"<p style=\"text-align: justify\">Durante un incontro a <strong>Mormanno<\/strong> sul futuro dei borghi piccoli e sull&#8217;importanza di preservarne l&#8217;identit\u00e0, il senatore <strong>Ernesto Rapani<\/strong> ha affrontato il tema dello spopolamento dei centri storici e dei piccoli borghi, sottolineando che non \u00e8 un problema esclusivo di Mormanno, ma riguarda molte altre comunit\u00e0 italiane. Ha evidenziato che su 7.896 comuni italiani, ben 5.520 hanno meno di 5.000 abitanti, e molti di questi presentano il centro storico situato in zone collinari. A <strong>Mormanno<\/strong> l&#8217;intero centro \u00e8 concentrato in un&#8217;unica area, gode di un clima favorevole e di una posizione planoaltimetrica che rendono la comunit\u00e0 unica e irripetibile.<\/p>\n<p style=\"text-align: justify\">Tuttavia, <strong>Rapani<\/strong> ha ammesso che la politica ha spesso sottovalutato o trascurato il problema dello spopolamento, mancando di prendere decisioni mirate per la valorizzazione dei borghi. Ha citato l&#8217;importanza dell&#8217;agricoltura e del turismo come possibili fonti di sostentamento economico per i borghi, ma ha sottolineato che il turismo non pu\u00f2 essere limitato a pochi mesi all&#8217;anno. Deve essere reso possibile tutto l&#8217;anno, valorizzando settori come l&#8217;artigianato locale. Il senatore ha parlato dell&#8217;importanza di incentivare l&#8217;apertura di attivit\u00e0 nei centri storici, proponendo deroghe ai regolamenti urbanistici e l&#8217;azzeramento dei tributi comunali per chi decide di insediarsi in queste zone. Ha condiviso la sua esperienza personale riguardante incentivi economici per il recupero dei centri storici e ha espresso il suo sostegno a un disegno di legge per la valorizzazione dei borghi e dei centri storici, che include misure come la semplificazione delle procedure burocratiche e il finanziamento per chi vuole investire in queste aree.<\/p>\n<p style=\"text-align: justify\">Infine, ha parlato dell&#8217;importanza dei cammini e dei sentieri, proponendo investimenti per il ripristino e la valorizzazione di tali percorsi, che potrebbero attirare turisti interessati alla natura e all&#8217;enogastronomia locale, contribuendo cos\u00ec a dinamizzare l&#8217;economia dei borghi. Il senatore ha ribadito che credere nel potenziale dei territori e lavorare insieme possono contribuire a risolvere il problema dello spopolamento dei borghi e dei centri storici, offrendo opportunit\u00e0 di crescita e sviluppo per le comunit\u00e0 locali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante un incontro a Mormanno sul futuro dei borghi piccoli e sull&#8217;importanza di preservarne l&#8217;identit\u00e0, il senatore Ernesto Rapani ha affrontato il tema dello spopolamento dei centri storici e dei&hellip;<\/p>\n","protected":false},"author":8,"featured_media":46446,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[142,921,196,195],"tags":[4591,24709],"class_list":["post-50240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-home","category-news","category-politica","tag-ernesto-rapani","tag-mormanno"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Calabria: Ernesto Rapani affronta il tema dello spopolamento - Radio Touring 104<\/title>\n<meta name=\"description\" content=\"Il senatore Ernesto Rapani ha affrontato il tema dello spopolamento dei centri storici e dei piccoli borghi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/26\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Calabria: Ernesto Rapani affronta il tema dello spopolamento - Radio Touring 104\" \/>\n<meta property=\"og:description\" content=\"Il senatore Ernesto Rapani ha affrontato il tema dello spopolamento dei centri storici e dei piccoli borghi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/26\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-26T13:33:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/03\/RAPANI-ERNESTO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Filippo Francesco Idone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Filippo Francesco Idone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/26\\\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/26\\\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\\\/\"},\"author\":{\"name\":\"Filippo Francesco Idone\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\"},\"headline\":\"Calabria: Ernesto Rapani affronta il tema dello spopolamento\",\"datePublished\":\"2024-04-26T13:33:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/26\\\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\\\/\"},\"wordCount\":328,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/26\\\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/03\\\/RAPANI-ERNESTO.jpg\",\"keywords\":[\"Ernesto Rapani\",\"Mormanno\"],\"articleSection\":[\"Calabria\",\"Home\",\"News\",\"Politica\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/26\\\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/26\\\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\\\/\",\"name\":\"Calabria: Ernesto Rapani affronta il tema dello spopolamento - Radio Touring 104\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/26\\\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/26\\\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/03\\\/RAPANI-ERNESTO.jpg\",\"datePublished\":\"2024-04-26T13:33:06+00:00\",\"description\":\"Il senatore Ernesto Rapani ha affrontato il tema dello spopolamento dei centri storici e dei piccoli borghi\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/26\\\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/26\\\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/26\\\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/03\\\/RAPANI-ERNESTO.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/03\\\/RAPANI-ERNESTO.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/26\\\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calabria: Ernesto Rapani affronta il tema dello spopolamento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\",\"name\":\"Filippo Francesco Idone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"caption\":\"Filippo Francesco Idone\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/filippoidone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Calabria: Ernesto Rapani affronta il tema dello spopolamento - Radio Touring 104","description":"Il senatore Ernesto Rapani ha affrontato il tema dello spopolamento dei centri storici e dei piccoli borghi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/26\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\/","og_locale":"it_IT","og_type":"article","og_title":"Calabria: Ernesto Rapani affronta il tema dello spopolamento - Radio Touring 104","og_description":"Il senatore Ernesto Rapani ha affrontato il tema dello spopolamento dei centri storici e dei piccoli borghi","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/26\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\/","og_site_name":"Radio Touring 104","article_published_time":"2024-04-26T13:33:06+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/03\/RAPANI-ERNESTO.jpg","type":"image\/jpeg"}],"author":"Filippo Francesco Idone","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Filippo Francesco Idone","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/26\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/26\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\/"},"author":{"name":"Filippo Francesco Idone","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b"},"headline":"Calabria: Ernesto Rapani affronta il tema dello spopolamento","datePublished":"2024-04-26T13:33:06+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/26\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\/"},"wordCount":328,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/26\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/03\/RAPANI-ERNESTO.jpg","keywords":["Ernesto Rapani","Mormanno"],"articleSection":["Calabria","Home","News","Politica"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/26\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/26\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\/","name":"Calabria: Ernesto Rapani affronta il tema dello spopolamento - Radio Touring 104","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/26\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/26\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/03\/RAPANI-ERNESTO.jpg","datePublished":"2024-04-26T13:33:06+00:00","description":"Il senatore Ernesto Rapani ha affrontato il tema dello spopolamento dei centri storici e dei piccoli borghi","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/26\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/26\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/26\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/03\/RAPANI-ERNESTO.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/03\/RAPANI-ERNESTO.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/26\/calabria-ernesto-rapani-affronta-il-tema-dello-spopolamento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Calabria: Ernesto Rapani affronta il tema dello spopolamento"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b","name":"Filippo Francesco Idone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","caption":"Filippo Francesco Idone"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/filippoidone\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/03\/RAPANI-ERNESTO.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/50240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=50240"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/50240\/revisions"}],"predecessor-version":[{"id":50241,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/50240\/revisions\/50241"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/46446"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=50240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=50240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=50240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}