{"id":50292,"date":"2024-04-27T17:30:43","date_gmt":"2024-04-27T15:30:43","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=50292"},"modified":"2024-04-27T17:30:43","modified_gmt":"2024-04-27T15:30:43","slug":"calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/27\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\/","title":{"rendered":"Calabria presente alla XXXVI edizione del Salone internazionale del Libro"},"content":{"rendered":"<p style=\"text-align: justify\">Partecipazione da record quest\u2019anno per la <strong>Regione Calabria alla XXXVI edizione del Salone internazionale del Libro<\/strong>, in programma a Torino dal 9 al 13 Maggio prossimi. La presenza della Calabria nell\u2019edizione 2024 \u00e8 destinata a superare i numeri gi\u00e0 lusinghieri delle scorse edizioni: saranno presenti, infatti, 41 case editrici calabresi (lo scorso anno erano state 32); troveranno spazio anche 20 autori calabresi che hanno fatto richiesta di partecipazione come singoli e non come case editrici. Un fittissimo calendario di incontri che vedr\u00e0 susseguirsi, nelle cinque giornate della kermesse, 85 incontri con la presenza di oltre 220 autori, editori, giornalisti, rappresentanti istituzionali, nell\u2019area espositiva della Regione Calabria, U138 &#8211; V137 <strong>Padiglione Oval, del Lingotto Fiere.<\/strong><\/p>\n<p style=\"text-align: justify\"><em>\u201cViaggio nel cuore della Calabria: una emozionante sinfonia di poesia, storia e arte. Vi aspettiamo numerosi in uno stand moderno ed accogliente, per diffondere nel mondo la vitalit\u00e0, le luci e i colori della nostra Calabria\u201d. <\/em>Cos\u00ec il presidente <strong>Roberto Occhiuto<\/strong> e la vice presidente<strong> Giusi Princi<\/strong> invitano ad esplorare<em> \u201cl&#8217;incanto della Calabria\u201d perch\u00e9, per dirla con le parole di Saverio Strati: \u201c\u2026Si potrebbe fare di questa terra il paradiso\u201d. \u201cLo slogan<\/em> &#8211; dichiara la vicepresidente con delega alla cultura &#8211; <em>riprende una suggestione e una speranza di Saverio Strati nel centenario della sua nascita; il grande scrittore calabrese sar\u00e0 ricordato al Salone con una serie di incontri e di approfondimenti tematici con il contributo di autorit\u00e0 e di studiosi e letterati come Goffredo Fofi, Gioacchino Criaco, Giancarlo Cauteruccio, Giuseppe Polimeni, Luigi Franco, Benedetta Borrata, Mario Musolino, Elisa Chiriano, Luigi Tassoni\u201d.<\/em><\/p>\n<p style=\"text-align: justify\">Nell\u2019ambito delle giornate sar\u00e0 anche ricordato il poeta lametino Franco Costabile, nel centenario della nascita. Agli incontri parteciperanno i sindaci di Acri, Gioiosa Jonica, Lamezia Terme, Melicucc\u00e0, Paola, Rovito, Sant\u2019Agata del Bianco, Taurianova e Vibo Valentia. Numerosi anche gli Istituti Culturali e le Fondazioni calabresi: la Fondazione universitaria &#8220;F. Solano&#8221; dell\u2019Unical, la Fondazione Trame, la Fondazione Padula, l\u2019Accademia dei Caccuriani, il Gal Terre Locridee, la Cineteca della Calabria, i Sistemi Bibliotecari Territoriali di Bovalino, Lamezia Terme, San Giovanni in Fiore e Vibo Valentia, la Fita (Federazione Italiana Teatro Amatori) e l\u2019Associazione Maschera e Volto. Come gi\u00e0 lo scorso anno l\u2019Associazione Via Verdi 11 \u2013 Educational Web Tv &#8211; di Locri curer\u00e0 la partecipazione di gruppi di studenti calabresi e piemontesi che sperimenteranno le tecniche di ripresa e trasmissione Tv degli incontri in programma, guidati da professionisti del settore e insegnanti.<\/p>\n<p style=\"text-align: justify\"><strong>Numerosi gli autori ospiti:<\/strong> il professor Piergiorgio Odifreddi, gli scrittori Carmine Abate, Angela Bubba, Mario Caligiuri, Gioacchino Criaco, Domenico Dara, Mario Fortunato, Mimmo Gangemi, Raffaele Gaetano, Mauro Francesco Minervino, Tonino Perna, Vito Teti, Giordano Bruno Guerri e Olimpio Talarico.<\/p>\n<p style=\"text-align: justify\"><strong>Diverse scuole calabresi saranno presenti al Salone:<\/strong> l\u2019I.C. Ardito di Lamezia Terme, il Liceo Mazzini di Locri, il Liceo Galilei di Paola, il Liceo Morelli di Vibo Valentia. Molte altre seguiranno gli incontri on line attraverso la piattaforma che sar\u00e0 messa a disposizione dalla Regione, in collaborazione con l\u2019Ufficio scolastico della <strong>Calabria<\/strong>. Nella mattinata di sabato 11 maggio si dar\u00e0 spazio a \u201c<strong>Taurianova Capitale del Libro 2024\u201d<\/strong>, saranno presentate le attivit\u00e0 previste durante l\u2019anno in citt\u00e0 e nella regione. A seguire il giovane calabrese Gabriele Vagnato, da Viva Rai 2 con Fiorello, al Salone del Libro nello stand della sua Calabria, si confronter\u00e0 con gli studenti calabresi presenti.<\/p>\n<p style=\"text-align: justify\">Il ricco programma, su indirizzo della vice presidente Princi, \u00e8 stato curato dal Dipartimento istruzione, formazione e pari opportunit\u00e0, dirigente generale Maria Francesca Gatto; settore cultura, attivit\u00e0 culturali, biblioteche, musei, teatri, alta formazione artistica musicale, dirigente Ersilia Amatruda. <strong>Bookshop libreria Calabria<\/strong> a cura del <strong>Sistema Bibliotecario Lametino<\/strong>. <em>\u201cAnche in questa edizione <\/em>\u2013 evidenzia infine la vicepresidente Princi-,<em> il ricco e partecipato programma, ci dar\u00e0 l\u2019occasione di narrare al Paese una Calabria diversa che da valore al suo patrimonio artistico, culturale e storico che deve essere sempre pi\u00f9 esportato e valorizzato. Al Salone di Torino vogliamo fare vedere al mondo una Calabria che crede nella cultura come volano di sviluppo e come presupposto per la formazione della nuove generazioni\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Partecipazione da record quest\u2019anno per la Regione Calabria alla XXXVI edizione del Salone internazionale del Libro, in programma a Torino dal 9 al 13 Maggio prossimi. La presenza della Calabria&hellip;<\/p>\n","protected":false},"author":8,"featured_media":50293,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[921,196,140],"tags":[219,30829],"class_list":["post-50292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-news","category-reggio-calabria","tag-regione-calabria","tag-salone-internazionale-del-libro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Calabria presente alla XXXVI edizione del Salone internazionale del Libro - Radio Touring 104<\/title>\n<meta name=\"description\" content=\"La Regione Calabria sar\u00e0 presente alla XXXVI edizione del Salone internazionale del Libro, in programma a Torino dal 9 al 13 Maggio prossimi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/27\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Calabria presente alla XXXVI edizione del Salone internazionale del Libro - Radio Touring 104\" \/>\n<meta property=\"og:description\" content=\"La Regione Calabria sar\u00e0 presente alla XXXVI edizione del Salone internazionale del Libro, in programma a Torino dal 9 al 13 Maggio prossimi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/27\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-27T15:30:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/04\/Salone-internazionale-del-Libro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"224\" \/>\n\t<meta property=\"og:image:height\" content=\"224\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Filippo Francesco Idone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Filippo Francesco Idone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/27\\\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/27\\\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\\\/\"},\"author\":{\"name\":\"Filippo Francesco Idone\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\"},\"headline\":\"Calabria presente alla XXXVI edizione del Salone internazionale del Libro\",\"datePublished\":\"2024-04-27T15:30:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/27\\\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\\\/\"},\"wordCount\":669,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/27\\\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/04\\\/Salone-internazionale-del-Libro.jpg\",\"keywords\":[\"regione calabria\",\"Salone internazionale del Libro\"],\"articleSection\":[\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/27\\\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/27\\\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\\\/\",\"name\":\"Calabria presente alla XXXVI edizione del Salone internazionale del Libro - Radio Touring 104\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/27\\\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/27\\\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/04\\\/Salone-internazionale-del-Libro.jpg\",\"datePublished\":\"2024-04-27T15:30:43+00:00\",\"description\":\"La Regione Calabria sar\u00e0 presente alla XXXVI edizione del Salone internazionale del Libro, in programma a Torino dal 9 al 13 Maggio prossimi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/27\\\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/27\\\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/27\\\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/04\\\/Salone-internazionale-del-Libro.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/04\\\/Salone-internazionale-del-Libro.jpg\",\"width\":224,\"height\":224},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/04\\\/27\\\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calabria presente alla XXXVI edizione del Salone internazionale del Libro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\",\"name\":\"Filippo Francesco Idone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"caption\":\"Filippo Francesco Idone\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/filippoidone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Calabria presente alla XXXVI edizione del Salone internazionale del Libro - Radio Touring 104","description":"La Regione Calabria sar\u00e0 presente alla XXXVI edizione del Salone internazionale del Libro, in programma a Torino dal 9 al 13 Maggio prossimi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/27\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\/","og_locale":"it_IT","og_type":"article","og_title":"Calabria presente alla XXXVI edizione del Salone internazionale del Libro - Radio Touring 104","og_description":"La Regione Calabria sar\u00e0 presente alla XXXVI edizione del Salone internazionale del Libro, in programma a Torino dal 9 al 13 Maggio prossimi.","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/27\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\/","og_site_name":"Radio Touring 104","article_published_time":"2024-04-27T15:30:43+00:00","og_image":[{"width":224,"height":224,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/04\/Salone-internazionale-del-Libro.jpg","type":"image\/jpeg"}],"author":"Filippo Francesco Idone","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Filippo Francesco Idone","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/27\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/27\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\/"},"author":{"name":"Filippo Francesco Idone","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b"},"headline":"Calabria presente alla XXXVI edizione del Salone internazionale del Libro","datePublished":"2024-04-27T15:30:43+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/27\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\/"},"wordCount":669,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/27\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/04\/Salone-internazionale-del-Libro.jpg","keywords":["regione calabria","Salone internazionale del Libro"],"articleSection":["Home","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/27\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/27\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\/","name":"Calabria presente alla XXXVI edizione del Salone internazionale del Libro - Radio Touring 104","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/27\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/27\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/04\/Salone-internazionale-del-Libro.jpg","datePublished":"2024-04-27T15:30:43+00:00","description":"La Regione Calabria sar\u00e0 presente alla XXXVI edizione del Salone internazionale del Libro, in programma a Torino dal 9 al 13 Maggio prossimi.","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/27\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/27\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/27\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/04\/Salone-internazionale-del-Libro.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/04\/Salone-internazionale-del-Libro.jpg","width":224,"height":224},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/04\/27\/calabria-presente-alla-xxxvi-edizione-del-salone-internazionale-del-libro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Calabria presente alla XXXVI edizione del Salone internazionale del Libro"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b","name":"Filippo Francesco Idone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","caption":"Filippo Francesco Idone"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/filippoidone\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/04\/Salone-internazionale-del-Libro.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/50292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=50292"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/50292\/revisions"}],"predecessor-version":[{"id":50294,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/50292\/revisions\/50294"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/50293"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=50292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=50292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=50292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}