{"id":50836,"date":"2024-05-05T09:55:47","date_gmt":"2024-05-05T07:55:47","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=50836"},"modified":"2024-05-05T09:55:47","modified_gmt":"2024-05-05T07:55:47","slug":"effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/05\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\/","title":{"rendered":"Effetto Volta: la comunicazione della scienza all\u2019auditorium Santa Caterina"},"content":{"rendered":"<p style=\"text-align: justify\">Gli studenti salgono sul palco ed espongono oralmente alla platea un tema scientifico frutto di un\u2019elaborazione personale. Brevi talks, di una decina di minuti ciascuno, che saranno la struttura portante dell\u2019evento conclusivo del progetto <strong>\u201cEffetto Volta \u2013 comunicare la scienza\u201d<\/strong> che si terr\u00e0 marted\u00ec 7 maggio alle ore 18.00 all\u2019auditorium Santa Caterina (ex Cinema Aurora). Dopo il successo della prima edizione torna l\u2019appuntamento con l\u2019innovativo format didattico-divulgativo proposto dal Liceo Scientifico \u201c<strong>Alessandro Volta\u201d di Reggio Calabria,<\/strong> fortemente caldeggiato dalla dirigente scolastica Maria Rosa Monterosso, ideato e coordinato dalla professoressa <strong>Simona<\/strong> <strong>Ambusto<\/strong>, docente di matematica e fisica e divulgatrice scientifica. Gli studenti partecipanti al progetto hanno preso parte, nel corso di questi mesi, ad incontri di studio e approfondimento, attivandosi in laboratori di public speaking, un lavoro attraverso il quale sono stati coinvolti in prima persona nella preparazione di un proprio \u201cdiscorso scientifico\u201d. La preparazione, la scelta dei temi, l&#8217;approfondimento hanno comportato una concreta sperimentazione sul campo concorrendo ad un\u2019opera di documentazione, ricerca, riconoscimento delle fonti, scrittura, elaborazione del testo ed esposizione orale in pubblico che li ha resi parte attiva nel processo di apprendimento. Adesso \u00e8 giunto il momento della condivisione del lavoro svolto, attraverso l\u2019evento conclusivo finale, che mira alla contaminazione di quelle idee che hanno il potere di cambiare gli atteggiamenti, la vita, e in ultima analisi, il mondo: \u201cIdee che meritano di essere diffuse\u201d (\u201cideas worth spreading\u201d), in linea con la stessa visione dell&#8217;organizzazione che ha fatto dei Ted (\u201cTechnology Entertainment Design\u201d) veicolo di diffusione di idee ispiratrici e alla quale il progetto stesso si ispira.<\/p>\n<p style=\"text-align: justify\"><strong>Programma<\/strong><\/p>\n<p style=\"text-align: justify\">Introduce la manifestazione la dirigente Monterosso, presenta il progetto la referente professoressa Ambusto, seguono gli speech degli studenti, tutti di V C nuovo ordinamento: Chiara Martino (\u201cNeuroni specchio, dall\u2019io al noi\u201d), Federica Rosaci (\u201cShinrin-yoku\u2026 Pi\u00f9 verde \u00e8 pi\u00f9 bello\u201d), Gabriele Pellican\u00f2 (\u201cEffetto Matilda, il contributo delle donne nella scienza\u201d), Salvatore Burrone (\u201cUna paura per amica\u201d), Fortunata Chil\u00e0 (\u201cGenitori &#8211; figli, imperfetti ma felici\u201d), Giovanni Pavone (\u201cIl destino come scelta\u201d), Letizia Quattrone (\u201cGiusto o sbagliato? Questo \u00e8 il dilemma\u201d), Maira Bellorio (\u201cBilinguismo?\u2026parliamone!\u201d). Presenta Demetrio Cutrupi (IV D Scienze applicate). Ingresso libero e gratuito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gli studenti salgono sul palco ed espongono oralmente alla platea un tema scientifico frutto di un\u2019elaborazione personale. Brevi talks, di una decina di minuti ciascuno, che saranno la struttura portante&hellip;<\/p>\n","protected":false},"author":8,"featured_media":50837,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[921,196,140],"tags":[31126,236,4232,1786],"class_list":["post-50836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-news","category-reggio-calabria","tag-alessandro-volta","tag-reggio-calabria","tag-santa-caterina","tag-simona-ambusto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Effetto Volta: la comunicazione della scienza all\u2019auditorium Santa Caterina - Radio Touring 104<\/title>\n<meta name=\"description\" content=\"L&#039;evento di comunicazione della scienza andr\u00e0 in scena il 7 maggio alle 18.00 all\u2019auditorium Santa Caterina (ex Cinema Aurora)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/05\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Effetto Volta: la comunicazione della scienza all\u2019auditorium Santa Caterina - Radio Touring 104\" \/>\n<meta property=\"og:description\" content=\"L&#039;evento di comunicazione della scienza andr\u00e0 in scena il 7 maggio alle 18.00 all\u2019auditorium Santa Caterina (ex Cinema Aurora)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/05\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-05T07:55:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/EventoFinaleEffettoVolta2023.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1944\" \/>\n\t<meta property=\"og:image:height\" content=\"1458\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Filippo Francesco Idone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Filippo Francesco Idone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/05\\\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/05\\\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\\\/\"},\"author\":{\"name\":\"Filippo Francesco Idone\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\"},\"headline\":\"Effetto Volta: la comunicazione della scienza all\u2019auditorium Santa Caterina\",\"datePublished\":\"2024-05-05T07:55:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/05\\\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\\\/\"},\"wordCount\":365,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/05\\\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/05\\\/EventoFinaleEffettoVolta2023.jpg\",\"keywords\":[\"Alessandro Volta\",\"reggio calabria\",\"Santa Caterina\",\"simona ambusto\"],\"articleSection\":[\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/05\\\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/05\\\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\\\/\",\"name\":\"Effetto Volta: la comunicazione della scienza all\u2019auditorium Santa Caterina - Radio Touring 104\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/05\\\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/05\\\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/05\\\/EventoFinaleEffettoVolta2023.jpg\",\"datePublished\":\"2024-05-05T07:55:47+00:00\",\"description\":\"L'evento di comunicazione della scienza andr\u00e0 in scena il 7 maggio alle 18.00 all\u2019auditorium Santa Caterina (ex Cinema Aurora)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/05\\\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/05\\\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/05\\\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/05\\\/EventoFinaleEffettoVolta2023.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/05\\\/EventoFinaleEffettoVolta2023.jpg\",\"width\":1944,\"height\":1458},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/05\\\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Effetto Volta: la comunicazione della scienza all\u2019auditorium Santa Caterina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\",\"name\":\"Filippo Francesco Idone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"caption\":\"Filippo Francesco Idone\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/filippoidone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Effetto Volta: la comunicazione della scienza all\u2019auditorium Santa Caterina - Radio Touring 104","description":"L'evento di comunicazione della scienza andr\u00e0 in scena il 7 maggio alle 18.00 all\u2019auditorium Santa Caterina (ex Cinema Aurora)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/05\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\/","og_locale":"it_IT","og_type":"article","og_title":"Effetto Volta: la comunicazione della scienza all\u2019auditorium Santa Caterina - Radio Touring 104","og_description":"L'evento di comunicazione della scienza andr\u00e0 in scena il 7 maggio alle 18.00 all\u2019auditorium Santa Caterina (ex Cinema Aurora)","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/05\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\/","og_site_name":"Radio Touring 104","article_published_time":"2024-05-05T07:55:47+00:00","og_image":[{"width":1944,"height":1458,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/EventoFinaleEffettoVolta2023.jpg","type":"image\/jpeg"}],"author":"Filippo Francesco Idone","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Filippo Francesco Idone","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/05\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/05\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\/"},"author":{"name":"Filippo Francesco Idone","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b"},"headline":"Effetto Volta: la comunicazione della scienza all\u2019auditorium Santa Caterina","datePublished":"2024-05-05T07:55:47+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/05\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\/"},"wordCount":365,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/05\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/EventoFinaleEffettoVolta2023.jpg","keywords":["Alessandro Volta","reggio calabria","Santa Caterina","simona ambusto"],"articleSection":["Home","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/05\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/05\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\/","name":"Effetto Volta: la comunicazione della scienza all\u2019auditorium Santa Caterina - Radio Touring 104","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/05\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/05\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/EventoFinaleEffettoVolta2023.jpg","datePublished":"2024-05-05T07:55:47+00:00","description":"L'evento di comunicazione della scienza andr\u00e0 in scena il 7 maggio alle 18.00 all\u2019auditorium Santa Caterina (ex Cinema Aurora)","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/05\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/05\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/05\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/EventoFinaleEffettoVolta2023.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/EventoFinaleEffettoVolta2023.jpg","width":1944,"height":1458},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/05\/effetto-volta-la-comunicazione-della-scienza-allauditorium-santa-caterina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Effetto Volta: la comunicazione della scienza all\u2019auditorium Santa Caterina"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b","name":"Filippo Francesco Idone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","caption":"Filippo Francesco Idone"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/filippoidone\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/EventoFinaleEffettoVolta2023.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/50836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=50836"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/50836\/revisions"}],"predecessor-version":[{"id":50838,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/50836\/revisions\/50838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/50837"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=50836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=50836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=50836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}