{"id":51574,"date":"2024-05-17T12:43:52","date_gmt":"2024-05-17T10:43:52","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=51574"},"modified":"2024-05-17T12:43:52","modified_gmt":"2024-05-17T10:43:52","slug":"taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/17\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\/","title":{"rendered":"Taurianova Capitale del Libro 2024: aperta la biblioteca comunale &#8220;Renda&#8221;"},"content":{"rendered":"<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span style=\"color: #000000\"><span lang=\"it\">Riscatto del territorio, contrasto alla povert\u00e0 educativa e promozione della cultura come strumenti di inclusione e trasformazione sociale. Questi i temi dell\u2019evento inaugurale di\u00a0<b>Taurianova Capitale Italiana del Libro 2024<\/b>\u00a0che ha messo al centro della giornata l\u2019attesissima riapertura della biblioteca comunale \u201c<b>Antonio Renda\u201d.<\/b><\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span lang=\"it\"><span style=\"color: #000000\">\u00a0<\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span lang=\"it\"><span style=\"color: #000000\">Dopo sette anni di chiusura, Taurianova avr\u00e0 di nuovo attiva la propria biblioteca comunale nella nuova sede, l\u2019edificio storico nel centro del borgo, sede dell\u2019ex municipio di Radicena di via XX settembre. Oltre<b><i>\u00a020mila i libri custoditi<\/i><\/b>, tra i quali il prezioso archivio del filosofo Antonio Renda, a cui \u00e8 intitolata, il quale,\u00a0 nel 1959 don\u00f2 alla Citt\u00e0 ben 5.500 volumi, tra cui spiccano testi giuridici e di medicina risalenti al \u2018500.<\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span lang=\"it\"><span style=\"color: #000000\">\u00a0<\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span lang=\"it\"><span style=\"color: #000000\">\u00ab<i>La riapertura della biblioteca \u00e8 un progetto coltivato con determinazione in questi ultimi due anni\u00a0<\/i>&#8211; ha dichiarato il sindaco di Taurianova Rocco Biasi -.\u00a0<i>Grazie al riconoscimento ottenuto, oggi la Biblioteca \u201cAntonio Renda\u201d\u00a0 esiste e appartiene alla comunit\u00e0, non solo di Taurianova, ma dell\u2019intera Piana. La biblioteca \u00e8 un luogo speciale:\u00a0 \u00e8 tra le pagine dei libri che si trovano i veri strumenti per la trasformazione, il riscatto di cui oggi parliamo. Ci siamo impegnati affinch\u00e9 questo spazio potesse essere dotato di infrastrutture moderne e accessibili, e vogliamo che diventi un luogo vivo e ricco di iniziative<\/i>\u00bb.<b><\/b><\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><b><span lang=\"it\"><span style=\"color: #000000\">\u00a0<\/span><\/span><\/b><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span lang=\"it\"><span style=\"color: #000000\">Oltre agli importanti lavori di riqualificazione realizzati, la struttura della biblioteca \u00e8 stata infatti potenziata con strumentazioni tecnologiche volte a garantire l\u2019accessibilit\u00e0 per i soggetti fragili, inclusa una postazione per disabili non vedenti, ed \u00e8 stata sviluppata l\u2019app \u201cBibliotaurus\u201d \u2013 che si interfaccia direttamente con il portale web comunale \u2013 per favorire la fruizione dei servizi bibliotecari.<\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span lang=\"it\"><span style=\"color: #000000\">\u00a0<\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span style=\"color: #000000\"><i><span lang=\"it\">\u00abUn primo importante traguardo che inaugura oggi l\u2019anno di Taurianova Capitale Italiana del libro 2024<\/span><\/i><span lang=\"it\">\u00a0\u2013 l\u2019assessore alla Cultura e direttore artistico di Taurianova Capitale Italiana del Libro\u00a0<b>Maria Fedele<\/b>\u00a0\u2013.\u00a0<i>Puntiamo sul coinvolgimento del territorio, ma soprattutto su quello dei pi\u00f9 giovani. In questo 2024 approderemo alla lettura in tanti modi, i libri saranno protagonisti di giochi, serate speciali e innesti tra arti, archeologia e storia. Partire dalla riapertura della biblioteca significa iniziare il nostro percorso come comunit\u00e0 per colmare le disuguaglianze educative, una tematica chiave per noi. Cos\u00ec iniziamo a scrivere una nuova storia\u00bb.<\/i><\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span lang=\"it\"><span style=\"color: #000000\">\u00a0<\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span style=\"color: #000000\"><b><span lang=\"it\">Pierfranco Bruni<\/span><\/b><span lang=\"it\">, Presidente di Commissione della Capitale Italiana del Libro 2024 del Ministero della Cultura:\u00a0\u00a0<i>\u00abCome Commissione della Capitale Italiana del Libro del Ministero della Cultura abbiamo ritenuto opportuno e necessario conferire il riconoscimento a Taurianova, non soltanto come riscatto di un&#8217;intera area territoriale &#8211; partendo dalla cultura e dall&#8217;educazione alla lettura &#8211; ma anche per creare un volano di sviluppo che attivi processi culturali utili al nostro Sud per divenire un vero e proprio tramite con le grandi capitali e culture europee. Taurianova ha tutte le potenzialit\u00e0 per farlo. Ci attendiamo sinergia e compartecipazione con le realt\u00e0 editoriali del territorio e non solo: Taurianova pu\u00f2 essere un riferimento concreto per l\u2019intera cultura Italiana. Noi , come Ministero della Cultura, ne siamo certi\u00bb.<\/i><\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span lang=\"it\"><span style=\"color: #000000\">Dai libri come luoghi di approdo in cui poter iniziare a dar forma ai sogni, in una visione identitaria individuale quanto collettiva &#8211; come la biblioteca \u201cAntonio Renda\u201d &#8211; alla promozione della lettura come strumento fondamentale per garantire l\u2019inclusione sociale e contrastare la dispersione scolastica.<\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span lang=\"it\"><span style=\"color: #000000\">\u00a0<\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span lang=\"it\"><span style=\"color: #000000\">Dopo il consueto taglio del nastro \u00e8 stato infatti il convegno sul contrasto alla povert\u00e0 educativa a segnare il via di \u201c<b>Taurianova Legge<\/b>\u201d, la rassegna letteraria principale della programmazione di Taurianova Capitale del Libro. Nei mesi di maggio e giugno, in\u00a0 cartellone oltre 40 eventi tra presentazioni di libri, mostre, convegni e dibattiti, che vedranno protagonisti scrittori, studiosi e artisti del panorama culturale italiano, con uno sguardo particolare rivolto agli autori calabresi contemporanei, agli emergenti e ai piccoli editori, per poi proseguire anche nei mesi successivi con programmazioni speciali come \u201c<b>Taurianova Legge &#8211; La fiera<\/b>\u201d.<\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span lang=\"it\"><span style=\"color: #000000\">\u00a0<\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span style=\"color: #000000\"><i><span lang=\"it\">\u00abPer me oggi \u00e8 una giornata emotivamente importante<\/span><\/i><span lang=\"it\">\u00a0&#8211; ha dichiarato\u00a0<b>Antonio Marziale<\/b>, Autorit\u00e0 Garante per l&#8217;Infanzia e l&#8217;Adolescenza della Regione Calabria, tra i relatori del panel -.\u00a0<i>Ero tra i bambini che frequentavano la biblioteca comunale di Taurianova, allora chiamata Centro Servizi Culturali, per fare le ricerche. Perch\u00e9 tutti noi bambini andavamo l\u00ec a fare le ricerche, magari altri avevano famiglie pi\u00f9 abbienti, avevano l&#8217;enciclopedia a casa, e noi che non ce l&#8217;avevamo ci recavamo l\u00ec. Quindi oggi essere tra coloro i quali danno l&#8217;avvio con manifestazioni a questa giornata mi lusinga, mi onora, anche come ex amministratore del paese di Taurianova che mi ha dato i natali. Sono molto grato all&#8217;Amministrazione Comunale per questo risultato, con l\u2019augurio e la speranza che sia veramente il riscatto che Taurianova merita\u00bb.<\/i><\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span lang=\"it\"><span style=\"color: #000000\">\u00a0<\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span lang=\"it\"><span style=\"color: #000000\">Secondo il rapporto Save the Children del 2022 sulla povert\u00e0 educativa in Italia, il 67,6% dei minori di 17 anni non \u00e8 mai andato a teatro, il 62,8% non ha mai visitato un sito archeologico, e il 48,8% non ha mai letto un libro non scolastico. Dati allarmanti, che registrano un incremento nelle regioni del Meridione: se la media nazionale di giovani maggiorenni che lasciano gli studi prematuramente gli studi si attesta al 13%, nel meridione aumenta al 15%, con il 16,6% registrato in Calabria.<\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span lang=\"it\"><span style=\"color: #000000\">\u00a0<\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span lang=\"it\"><span style=\"color: #000000\">Un tema importante per Taurianova Capitale del Libro, che il riconoscimento del MiC l\u2019ha ottenuto proprio per l\u2019impatto sociale del progetto sul territorio. Avviata i primi di maggio l\u2019iniziativa \u201cNati per la Cultura\u201d, dedicata ai bambini tra 0 e 6 anni, all\u2019interno della quale confluiscono i progetti nazionali \u201cNati per Leggere\u201d e \u201cNati per la Musica\u201d, che prevedono l\u2019educazione all\u2019ascolto di libri e musica fin da neonati per incentivare lo sviluppo psico cognitivo e facilitare l\u2019inserimento paritario dei bambini nelle scuole primarie.<\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span lang=\"it\"><span style=\"color: #000000\">\u00a0<\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span lang=\"it\"><span style=\"color: #000000\">Il progetto ha preso il via lo scorso 5 maggio con la consegna del kit \u201dNati per la Cultura\u201d a tutti i nuovi nati in citt\u00e0 nel 2023. All\u2019interno del kit \u00e8 stato inserito un libro tra quelli presenti nell\u2019elenco dei libri irrinunciabili di Nati per Leggere, con una dedica speciale e una lettera di benvenuto al mondo firmate dal sindaco e dell\u2019assessore alla Cultura.<\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span lang=\"it\"><span style=\"color: #000000\">\u00a0<\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span lang=\"it\"><span style=\"color: #000000\">Tra le iniziative che rientrano in questa linea di indirizzo, anche la partecipazione, il prossimo 18 maggio, all\u2019incontro promosso dall\u2019associazione Calabria Condivisa, in collaborazione con altre realt\u00e0 associative, che si svolger\u00e0 nella Comunit\u00e0 Ministeriale Minorile di Catanzaro. Taurianova Capitale Italiana del Libro sar\u00e0 infatti tra i partner che doneranno alla comunit\u00e0 un cospicuo patrimonio librario, per promuovere l&#8217;importanza della lettura e della scrittura, non solo come elementi utili ad ampliare il proprio bagaglio culturale, ma come strumenti concreti di reinserimento sociale in grado facilitare l\u2019accesso al mondo del lavoro.<\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span lang=\"it\"><span style=\"color: #000000\">\u00a0<\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span lang=\"it\"><span style=\"color: #000000\">All\u2019evento di inaugurazione hanno preso parte:\u00a0<b>Roberto Marti<\/b>, Presidente Commissione Cultura Senato della Repubblica;\u00a0<b>Pierfranco Bruni<\/b>, Presidente di Commissione della Capitale Italiana del Libro 2024 del Ministero della Cultura;\u00a0<b>Clara Vaccaro<\/b>, Prefetto di Reggio Calabria;\u00a0<b>Emma Staine<\/b>, Assessore Regionale alle Politiche Sociali e Trasporti;\u00a0<b>Filippo Quartuccio<\/b>, Consigliere Metropolitano con delega alla Cultura;\u00a0<b>Rocco Biasi<\/b>, Sindaco di Taurianova;\u00a0<b>Antonio Marziale<\/b>, Autorit\u00e0 Garante per l\u2019Infanzia e l\u2019Adolescenza della Regione Calabria;\u00a0<b>Maria Fedele<\/b>, Assessore alla Cultura Comune di Taurianova e direttore artistico di Taurianova Capitale Italiana del Libro;\u00a0<b>Raffaele Tarantino<\/b>, Presidente AIB Calabria;\u00a0<b>Maria Pia Cacace<\/b>, componente Comitato Esecutivo Nazionale AIB con delega alla Formazione, Rapporto con i territori, Politica della lettura e Welfare Culturale. L\u2019evento \u00e8 stato moderato dal giornalista e condirettore artistico di Taurianova Capitale Italiana del Libro\u00a0<b>Piero Muscari<\/b>.<\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span lang=\"it\"><span style=\"color: #000000\">\u00a0<\/span><\/span><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><span lang=\"it\"><span style=\"color: #000000\">Chiusura all\u2019insegna della contaminazione tra letteratura, arte e musica, con il concerto della\u00a0<b>Saverio Arlia Wind Orchestra\u00a0<\/b>del Conservatorio P.I. Tchaikovsky, diretta dal Maestro Cettina Nicolosi e l\u2019apertura della mostra artistica di\u00a0<b>Maria Morgante<\/b>, artista originaria di Rosarno che, nella piegatura e nell&#8217;intaglio delle pagine dei libri, ha individuato un modo esemplare di esprimere la propria creativit\u00e0 trasformando oggetti comuni in vere e proprie opere d&#8217;arte tridimensionali.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Riscatto del territorio, contrasto alla povert\u00e0 educativa e promozione della cultura come strumenti di inclusione e trasformazione sociale. Questi i temi dell\u2019evento inaugurale di\u00a0Taurianova Capitale Italiana del Libro 2024\u00a0che ha&hellip;<\/p>\n","protected":false},"author":12,"featured_media":51575,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[921,196,140],"tags":[31676,24769,24043,31675],"class_list":["post-51574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-news","category-reggio-calabria","tag-aperta-la-biblioteca-comunale-renda","tag-maria-fedele","tag-roy-biasi","tag-taurianova-capitale-del-libro-2024"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Taurianova Capitale Libro: aperta la biblioteca comunale &quot;Renda&quot;<\/title>\n<meta name=\"description\" content=\"Riapre la biblioteca Comunale. L\u2019assessore e direttore artistico Maria Fedele: \u00abIniziamo a scrivere una nuova storia\u00bb\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/17\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Taurianova Capitale Libro: aperta la biblioteca comunale &quot;Renda&quot;\" \/>\n<meta property=\"og:description\" content=\"Riapre la biblioteca Comunale. L\u2019assessore e direttore artistico Maria Fedele: \u00abIniziamo a scrivere una nuova storia\u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/17\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-17T10:43:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/Biblioteca-Comunale-Taurianova-Renda.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1252\" \/>\n\t<meta property=\"og:image:height\" content=\"812\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sebastiano Plutino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastiano Plutino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/17\\\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/17\\\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\\\/\"},\"author\":{\"name\":\"Sebastiano Plutino\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\"},\"headline\":\"Taurianova Capitale del Libro 2024: aperta la biblioteca comunale &#8220;Renda&#8221;\",\"datePublished\":\"2024-05-17T10:43:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/17\\\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\\\/\"},\"wordCount\":1280,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/17\\\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/05\\\/Biblioteca-Comunale-Taurianova-Renda.jpeg\",\"keywords\":[\"aperta la biblioteca comunale \\\"Renda\\\"\",\"Maria Fedele\",\"Roy Biasi\",\"Taurianova Capitale del Libro 2024\"],\"articleSection\":[\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/17\\\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/17\\\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\\\/\",\"name\":\"Taurianova Capitale Libro: aperta la biblioteca comunale \\\"Renda\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/17\\\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/17\\\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/05\\\/Biblioteca-Comunale-Taurianova-Renda.jpeg\",\"datePublished\":\"2024-05-17T10:43:52+00:00\",\"description\":\"Riapre la biblioteca Comunale. L\u2019assessore e direttore artistico Maria Fedele: \u00abIniziamo a scrivere una nuova storia\u00bb\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/17\\\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/17\\\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/17\\\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/05\\\/Biblioteca-Comunale-Taurianova-Renda.jpeg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/05\\\/Biblioteca-Comunale-Taurianova-Renda.jpeg\",\"width\":1252,\"height\":812},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/17\\\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Taurianova Capitale del Libro 2024: aperta la biblioteca comunale &#8220;Renda&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\",\"name\":\"Sebastiano Plutino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"caption\":\"Sebastiano Plutino\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/sebastiano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Taurianova Capitale Libro: aperta la biblioteca comunale \"Renda\"","description":"Riapre la biblioteca Comunale. L\u2019assessore e direttore artistico Maria Fedele: \u00abIniziamo a scrivere una nuova storia\u00bb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/17\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\/","og_locale":"it_IT","og_type":"article","og_title":"Taurianova Capitale Libro: aperta la biblioteca comunale \"Renda\"","og_description":"Riapre la biblioteca Comunale. L\u2019assessore e direttore artistico Maria Fedele: \u00abIniziamo a scrivere una nuova storia\u00bb","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/17\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\/","og_site_name":"Radio Touring 104","article_published_time":"2024-05-17T10:43:52+00:00","og_image":[{"width":1252,"height":812,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/Biblioteca-Comunale-Taurianova-Renda.jpeg","type":"image\/jpeg"}],"author":"Sebastiano Plutino","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Sebastiano Plutino","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/17\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/17\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\/"},"author":{"name":"Sebastiano Plutino","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e"},"headline":"Taurianova Capitale del Libro 2024: aperta la biblioteca comunale &#8220;Renda&#8221;","datePublished":"2024-05-17T10:43:52+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/17\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\/"},"wordCount":1280,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/17\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/Biblioteca-Comunale-Taurianova-Renda.jpeg","keywords":["aperta la biblioteca comunale \"Renda\"","Maria Fedele","Roy Biasi","Taurianova Capitale del Libro 2024"],"articleSection":["Home","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/17\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/17\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\/","name":"Taurianova Capitale Libro: aperta la biblioteca comunale \"Renda\"","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/17\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/17\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/Biblioteca-Comunale-Taurianova-Renda.jpeg","datePublished":"2024-05-17T10:43:52+00:00","description":"Riapre la biblioteca Comunale. L\u2019assessore e direttore artistico Maria Fedele: \u00abIniziamo a scrivere una nuova storia\u00bb","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/17\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/17\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/17\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/Biblioteca-Comunale-Taurianova-Renda.jpeg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/Biblioteca-Comunale-Taurianova-Renda.jpeg","width":1252,"height":812},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/17\/taurianova-capitale-del-libro-2024-aperta-la-biblioteca-comunale-renda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Taurianova Capitale del Libro 2024: aperta la biblioteca comunale &#8220;Renda&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e","name":"Sebastiano Plutino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","caption":"Sebastiano Plutino"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/sebastiano\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/Biblioteca-Comunale-Taurianova-Renda.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/51574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=51574"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/51574\/revisions"}],"predecessor-version":[{"id":51576,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/51574\/revisions\/51576"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/51575"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=51574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=51574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=51574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}