{"id":52156,"date":"2024-05-26T10:46:04","date_gmt":"2024-05-26T08:46:04","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=52156"},"modified":"2024-05-26T10:46:04","modified_gmt":"2024-05-26T08:46:04","slug":"cgil-1500-i-calabresi-partiti-alla-volta-di-napoli","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/26\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\/","title":{"rendered":"CGIL: 1500 i calabresi partiti alla volta di Napoli"},"content":{"rendered":"<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\">Sono oltre 1500 i calabresi partiti alla volta di <strong>Napoli<\/strong> per prendere parte alla manifestazione \u201c<strong>La Via Maestra\u201d<\/strong> promossa dal coordinamento nazionale della Cgil di cui fanno parte, oltre al sindacato, 150 tra associazioni e movimenti. Una mobilitazione importante \u201cper un\u2019Italia capace di futuro, per un\u2019Europa giusta e solidale\u201d che ha portato innanzitutto in piazza la forza della nostra Costituzione, nata dalla Resistenza e fondata sul lavoro, contro ogni tentativo di sovvertirla. Difendere la Carta Costituzionale significa innanzitutto per noi osteggiare il progetto di Autonomia Differenziata che andrebbe a cancellare l\u2019unit\u00e0 del Paese e ad aggravare il gi\u00e0 pesante divario nord-sud, lasciando il Meridione con servizi sempre pi\u00f9 depauperati e, invitando, cos\u00ec alla fuga e allo spopolamento. Una manovra scellerata portata avanti da un governo che sta dimostrando costantemente la sua mancanza di attenzione verso il Sud e i pi\u00f9 fragili. Quello che si prospetta \u00e8 uno scenario devastante contro cui la <strong>Cgil<\/strong> \u00e8 impegnata da tempo e che continuer\u00e0 a contrastare. Il Sud ha bisogno di altro, di infrastrutture, di investimenti, di sviluppo e di lavoro dignitoso. C\u2019\u00e8 bisogno di un cambiamento, ce lo chiede il Paese, ce lo chiedono le lavoratrici e i lavoratori, i giovani a cui dobbiamo dare prospettive migliori di oggi e politiche fattive. Ecco perch\u00e9 in piazza abbiamo portato anche la nostra campagna referendaria per un lavoro sicuro, tutelato, dignitoso e stabile. In <strong>Calabria<\/strong> la raccolta firme procede speditamente, tredicimila ad oggi quelle raccolte, ma per invertire la rotta, dire basta al precariato, alle morti sul lavoro, allo sfruttamento delle attuali e delle nuove generazioni, abbiamo bisogno della collaborazione di tutti. Invitiamo a firmare nei banchetti, nella Camere del Lavoro oppure on line su\u00a0www.cgil.it\/referendum\u00a0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono oltre 1500 i calabresi partiti alla volta di Napoli per prendere parte alla manifestazione \u201cLa Via Maestra\u201d promossa dal coordinamento nazionale della Cgil di cui fanno parte, oltre al&hellip;<\/p>\n","protected":false},"author":8,"featured_media":52157,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[142,921,196,195],"tags":[586,28380,1305],"class_list":["post-52156","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-home","category-news","category-politica","tag-calabria","tag-la-via-maestra","tag-napoli"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CGIL: 1500 i calabresi partiti alla volta di Napoli - Radio Touring 104<\/title>\n<meta name=\"description\" content=\"1500 calabresi partiti alla volta di Napoli per prendere parte alla manifestazione \u201cLa Via Maestra&quot; promossa dalla Cgil\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/26\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CGIL: 1500 i calabresi partiti alla volta di Napoli - Radio Touring 104\" \/>\n<meta property=\"og:description\" content=\"1500 calabresi partiti alla volta di Napoli per prendere parte alla manifestazione \u201cLa Via Maestra&quot; promossa dalla Cgil\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/26\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-26T08:46:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/cgil.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Filippo Francesco Idone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Filippo Francesco Idone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/26\\\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/26\\\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\\\/\"},\"author\":{\"name\":\"Filippo Francesco Idone\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\"},\"headline\":\"CGIL: 1500 i calabresi partiti alla volta di Napoli\",\"datePublished\":\"2024-05-26T08:46:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/26\\\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\\\/\"},\"wordCount\":291,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/26\\\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/05\\\/cgil.jpeg\",\"keywords\":[\"calabria\",\"La Via Maestra\",\"Napoli\"],\"articleSection\":[\"Calabria\",\"Home\",\"News\",\"Politica\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/26\\\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/26\\\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\\\/\",\"name\":\"CGIL: 1500 i calabresi partiti alla volta di Napoli - Radio Touring 104\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/26\\\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/26\\\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/05\\\/cgil.jpeg\",\"datePublished\":\"2024-05-26T08:46:04+00:00\",\"description\":\"1500 calabresi partiti alla volta di Napoli per prendere parte alla manifestazione \u201cLa Via Maestra\\\" promossa dalla Cgil\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/26\\\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/26\\\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/26\\\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/05\\\/cgil.jpeg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/05\\\/cgil.jpeg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/26\\\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CGIL: 1500 i calabresi partiti alla volta di Napoli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\",\"name\":\"Filippo Francesco Idone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"caption\":\"Filippo Francesco Idone\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/filippoidone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CGIL: 1500 i calabresi partiti alla volta di Napoli - Radio Touring 104","description":"1500 calabresi partiti alla volta di Napoli per prendere parte alla manifestazione \u201cLa Via Maestra\" promossa dalla Cgil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/26\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\/","og_locale":"it_IT","og_type":"article","og_title":"CGIL: 1500 i calabresi partiti alla volta di Napoli - Radio Touring 104","og_description":"1500 calabresi partiti alla volta di Napoli per prendere parte alla manifestazione \u201cLa Via Maestra\" promossa dalla Cgil","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/26\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\/","og_site_name":"Radio Touring 104","article_published_time":"2024-05-26T08:46:04+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/cgil.jpeg","type":"image\/jpeg"}],"author":"Filippo Francesco Idone","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Filippo Francesco Idone","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/26\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/26\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\/"},"author":{"name":"Filippo Francesco Idone","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b"},"headline":"CGIL: 1500 i calabresi partiti alla volta di Napoli","datePublished":"2024-05-26T08:46:04+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/26\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\/"},"wordCount":291,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/26\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/cgil.jpeg","keywords":["calabria","La Via Maestra","Napoli"],"articleSection":["Calabria","Home","News","Politica"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/26\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/26\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\/","name":"CGIL: 1500 i calabresi partiti alla volta di Napoli - Radio Touring 104","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/26\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/26\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/cgil.jpeg","datePublished":"2024-05-26T08:46:04+00:00","description":"1500 calabresi partiti alla volta di Napoli per prendere parte alla manifestazione \u201cLa Via Maestra\" promossa dalla Cgil","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/26\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/26\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/26\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/cgil.jpeg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/cgil.jpeg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/26\/cgil-1500-i-calabresi-partiti-alla-volta-di-napoli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"CGIL: 1500 i calabresi partiti alla volta di Napoli"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b","name":"Filippo Francesco Idone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","caption":"Filippo Francesco Idone"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/filippoidone\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/cgil.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/52156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=52156"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/52156\/revisions"}],"predecessor-version":[{"id":52158,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/52156\/revisions\/52158"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/52157"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=52156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=52156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=52156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}