{"id":52531,"date":"2024-05-31T11:28:41","date_gmt":"2024-05-31T09:28:41","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=52531"},"modified":"2024-05-31T14:04:51","modified_gmt":"2024-05-31T12:04:51","slug":"catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\/","title":{"rendered":"Catanzaro: appuntamento con la XIV edizione del Corso di aggiornamento in odontoiatria"},"content":{"rendered":"<p style=\"text-align: justify\">Terzo e quarto appuntamento con la XIV edizione del Corso di aggiornamento in odontoiatria \u201cGli odontoiatri al servizio delle famiglie\u201d, organizzato dall\u2019Albo Odontoiatri di Catanzaro,\u00a0<b>presieduto dal dottor Salvatore De Filippo. <\/b>Nella sala \u201cC. Catuogno\u201d dell&#8217;Ordine dei Medici del capoluogo, si sono tenute le lezioni del dottor Umberto Romeo sul tema \u201cMedicina orale: dalla teoria alla pratica quotidiana\u201d e del Professor Andrea Pilloni, che ha parlato di chirurgia mucogengivale biologicamente guidata. In apertura dei lavori, il presidente De Filippo ha sottolineato ancora una volta l\u2019importanza di una formazione costante e innovativa, e libera da condizionamenti.<\/p>\n<p style=\"text-align: justify\"><em>\u201cHo accettato con entusiasmo l&#8217;invito del<strong> Presidente De Filippo e della Commissione Albo Odontoiatri<\/strong> per condividere conoscenze su tematiche meno comuni per gli odontoiatri, ma rilevanti nell&#8217;ambito della medicina<\/em> &#8211; ha affermato il\u00a0<b>Professor Umberto Romeo<\/b>\u00a0-. <em>\u00c8 importante includere l&#8217;odontoiatria nell&#8217;ambito medico, evidenziando temi come la prevenzione del carcinoma orale e la gestione dei pazienti che assumono farmaci che influenzano il metabolismo osseo\u201d.<\/em><\/p>\n<p style=\"text-align: justify\"><em>\u201cL&#8217;odontoiatra, contrariamente a quanto possa sembrare, riveste un ruolo cruciale nella gestione dei pazienti oncologici, i quali inevitabilmente generano un disagio nell&#8217;ambiente familiare<\/em> &#8211; ha detto ancora Romeo -. <em>Offrire loro un sorriso, un momento di distrazione dalle loro quotidiane sfide oncologiche, \u00e8 di grande beneficio. Tuttavia, questo non esclude l&#8217;odontoiatria dal servizio delle famiglie, anche perch\u00e9 i pazienti oncologici sono diventati cronici grazie alle terapie moderne che consentono loro di vivere con la malattia per diversi anni. Essi richiedono anche riabilitazioni protesiche odontoiatriche, evidenziando cos\u00ec la necessit\u00e0 che l&#8217;odontoiatria sia al servizio non solo dei singoli pazienti, ma anche delle loro famiglie, soprattutto quando si affrontano problemi che vanno oltre la tipica cura delle carie o dei problemi parodontali.\u201d<\/em><\/p>\n<p style=\"text-align: justify\">Secondo Romeo, il titolo dell&#8217;evento,<em> \u201cMedicina Orale: dalla teoria alla pratica quotidiana&#8221;<\/em>, riflette l&#8217;intenzione di <em>\u201caffrontare questioni mediche nell&#8217;odontoiatria, spostandosi dalla consueta focalizzazione su aspetti tecnici come la conservativa e gli impianti. Si mira a fornire formazione e aggiornamento in un contesto pi\u00f9 ampio e medico-odontoiatrico\u201d. <\/em><em>\u201cLa parodontologia,\u201d<\/em> ha spiegato invece il\u00a0<b>Professor Andrea Pilloni<\/b>\u00a0nel corso della lezione del 25 maggio, \u201c<em>\u00e8 una scienza che mira a ridurre il numero di pazienti che rischiano di perdere i denti a causa della parodontite, una malattia che ancora oggi \u00e8 tra le sei pi\u00f9 comuni nell&#8217;uomo. Troppi pazienti, anche giovani, rischiano di dover farsi estrarre i denti, con tutte le implicazioni economiche e sociali che questo comporta. La parodontite costa ancora oggi 54 miliardi di dollari all&#8217;anno a livello mondiale, rappresentando un peso non solo per le famiglie, ma anche a livello psicosociale. Chi non pu\u00f2 permettersi le cure necessarie spesso deve convivere con l&#8217;edentulismo parziale o totale.<strong> \u00c8 essenziale guardare al paziente con parodontite come a qualcuno<\/strong> che deve essere seguito da un professionista. <strong>Non pu\u00f2 essere lasciato a gestire la malattia solo con delle informazioni<\/strong>, un po&#8217; come accade con altre malattie croniche come il diabete o l&#8217;ipertensione. Questi pazienti devono rimanere sotto controllo professionale, perch\u00e9 da soli non ce la farebbero mai. Se sono seguiti da un medico specialista, in questo caso il dentista, che sa come trattare la parodontite, il rischio di perdere denti si riduce enormemente\u201d.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Terzo e quarto appuntamento con la XIV edizione del Corso di aggiornamento in odontoiatria \u201cGli odontoiatri al servizio delle famiglie\u201d, organizzato dall\u2019Albo Odontoiatri di Catanzaro,\u00a0presieduto dal dottor Salvatore De Filippo.&hellip;<\/p>\n","protected":false},"author":8,"featured_media":52532,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[142,921,196],"tags":[698,17879],"class_list":["post-52531","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-home","category-news","tag-catanzaro","tag-corso-di-aggiornamento-in-odontoiatria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Catanzaro: appuntamento con la XIV edizione del Corso di aggiornamento in odontoiatria - Radio Touring 104<\/title>\n<meta name=\"description\" content=\"Terzo e Quarto appuntamento con la XIV edizione del Corso di aggiornamento in odontoiatria \u201cGli odontoiatri al servizio delle famiglie\u201d\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Catanzaro: appuntamento con la XIV edizione del Corso di aggiornamento in odontoiatria - Radio Touring 104\" \/>\n<meta property=\"og:description\" content=\"Terzo e Quarto appuntamento con la XIV edizione del Corso di aggiornamento in odontoiatria \u201cGli odontoiatri al servizio delle famiglie\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-31T09:28:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-31T12:04:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/Romeo-Truglia-Pilloni-De-Filippo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1333\" \/>\n\t<meta property=\"og:image:height\" content=\"982\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Filippo Francesco Idone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Filippo Francesco Idone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/31\\\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/31\\\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\\\/\"},\"author\":{\"name\":\"Filippo Francesco Idone\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\"},\"headline\":\"Catanzaro: appuntamento con la XIV edizione del Corso di aggiornamento in odontoiatria\",\"datePublished\":\"2024-05-31T09:28:41+00:00\",\"dateModified\":\"2024-05-31T12:04:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/31\\\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\\\/\"},\"wordCount\":526,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/31\\\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/05\\\/Romeo-Truglia-Pilloni-De-Filippo.png\",\"keywords\":[\"catanzaro\",\"Corso di aggiornamento in odontoiatria\"],\"articleSection\":[\"Calabria\",\"Home\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/31\\\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/31\\\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\\\/\",\"name\":\"Catanzaro: appuntamento con la XIV edizione del Corso di aggiornamento in odontoiatria - Radio Touring 104\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/31\\\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/31\\\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/05\\\/Romeo-Truglia-Pilloni-De-Filippo.png\",\"datePublished\":\"2024-05-31T09:28:41+00:00\",\"dateModified\":\"2024-05-31T12:04:51+00:00\",\"description\":\"Terzo e Quarto appuntamento con la XIV edizione del Corso di aggiornamento in odontoiatria \u201cGli odontoiatri al servizio delle famiglie\u201d\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/31\\\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/31\\\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/31\\\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/05\\\/Romeo-Truglia-Pilloni-De-Filippo.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/05\\\/Romeo-Truglia-Pilloni-De-Filippo.png\",\"width\":1333,\"height\":982},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/31\\\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catanzaro: appuntamento con la XIV edizione del Corso di aggiornamento in odontoiatria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\",\"name\":\"Filippo Francesco Idone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"caption\":\"Filippo Francesco Idone\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/filippoidone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Catanzaro: appuntamento con la XIV edizione del Corso di aggiornamento in odontoiatria - Radio Touring 104","description":"Terzo e Quarto appuntamento con la XIV edizione del Corso di aggiornamento in odontoiatria \u201cGli odontoiatri al servizio delle famiglie\u201d","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\/","og_locale":"it_IT","og_type":"article","og_title":"Catanzaro: appuntamento con la XIV edizione del Corso di aggiornamento in odontoiatria - Radio Touring 104","og_description":"Terzo e Quarto appuntamento con la XIV edizione del Corso di aggiornamento in odontoiatria \u201cGli odontoiatri al servizio delle famiglie\u201d","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\/","og_site_name":"Radio Touring 104","article_published_time":"2024-05-31T09:28:41+00:00","article_modified_time":"2024-05-31T12:04:51+00:00","og_image":[{"width":1333,"height":982,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/Romeo-Truglia-Pilloni-De-Filippo.png","type":"image\/png"}],"author":"Filippo Francesco Idone","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Filippo Francesco Idone","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\/"},"author":{"name":"Filippo Francesco Idone","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b"},"headline":"Catanzaro: appuntamento con la XIV edizione del Corso di aggiornamento in odontoiatria","datePublished":"2024-05-31T09:28:41+00:00","dateModified":"2024-05-31T12:04:51+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\/"},"wordCount":526,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/Romeo-Truglia-Pilloni-De-Filippo.png","keywords":["catanzaro","Corso di aggiornamento in odontoiatria"],"articleSection":["Calabria","Home","News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\/","name":"Catanzaro: appuntamento con la XIV edizione del Corso di aggiornamento in odontoiatria - Radio Touring 104","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/Romeo-Truglia-Pilloni-De-Filippo.png","datePublished":"2024-05-31T09:28:41+00:00","dateModified":"2024-05-31T12:04:51+00:00","description":"Terzo e Quarto appuntamento con la XIV edizione del Corso di aggiornamento in odontoiatria \u201cGli odontoiatri al servizio delle famiglie\u201d","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/Romeo-Truglia-Pilloni-De-Filippo.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/Romeo-Truglia-Pilloni-De-Filippo.png","width":1333,"height":982},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/catanzaro-appuntamento-con-la-xiv-edizione-del-corso-di-aggiornamento-in-odontoiatria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Catanzaro: appuntamento con la XIV edizione del Corso di aggiornamento in odontoiatria"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b","name":"Filippo Francesco Idone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","caption":"Filippo Francesco Idone"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/filippoidone\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/05\/Romeo-Truglia-Pilloni-De-Filippo.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/52531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=52531"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/52531\/revisions"}],"predecessor-version":[{"id":52533,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/52531\/revisions\/52533"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/52532"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=52531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=52531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=52531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}