{"id":52545,"date":"2024-05-31T15:29:49","date_gmt":"2024-05-31T13:29:49","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=52545"},"modified":"2024-05-31T15:35:59","modified_gmt":"2024-05-31T13:35:59","slug":"calabria-la-snap-chiede-interventi-urgenti","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/calabria-la-snap-chiede-interventi-urgenti\/","title":{"rendered":"Calabria: il Sindacato SNAP chiede interventi urgenti"},"content":{"rendered":"<p style=\"text-align: justify\">In data 26 giugno 2017 veniva stipulata la convenzione tra Polizia di Stato e Ferrovie dello Stato Italiane S.p.a. tramite cui vengono disciplinati i servizi predisposti dalla Polizia Ferroviaria nell\u2019interesse del Gruppo FS Italiane, mirati alla tutela della sicurezza ferroviaria. <strong>L\u2019art. 5 c. 1 della medesima convenzione:<\/strong> \u201cServizi di scorta treno e corresponsione delle indennit\u00e0\u201d, recita testualmente: \u201cil Gruppo FS Italiane, per i servizi di specialit\u00e0 svolti dalla Polizia Ferroviaria, si impegna nei confronti del Dipartimento a corrispondere un\u2019indennit\u00e0 di scorta agli OPF che effettuano servizio a bordo treno, con esclusione degli appartenenti ai ruoli dirigenziali e direttivi\u201d, continuando il comma 3 del medesimo articolo indica:<em> \u201cLa Polizia Ferroviaria assicura il servizio di scorta per i treni ritenuti ad alto profilo di <\/em><em>criticit\u00e0, individuati o autorizzati dal Comitato Centrale in relazione alle problematiche effettivamente riscontrate e alle tratte <\/em><em>ritenute critiche proposte dal Comitato Territoriale, sulla base di elementi oggettivi documentabili\u201d<\/em>.<\/p>\n<p style=\"text-align: justify\"><strong> Il comma 5 sempre dell\u2019art. 5 disciplina quanto di seguito:<\/strong> <em>\u201cL\u2019indennit\u00e0 di scorta treno viene riconosciuta a partire dal momento della <\/em><em>partenza del convoglio scortato previsto dall\u2019Orario Ufficiale ed include il tempo di sosta per il cambio treno nel corso del <\/em><em>servizio\u2026 i treni funzionali a quelli critici, in quanto connessi con l\u2019effettuazione delle scorte, sono remunerati al pari di quelli <\/em><em>critici\u2026a bordo del medesimo treno vengono corrisposte indennit\u00e0 per un massimo di tre OPF per singola tratta\u2026\u201d <\/em>Dopo questa necessaria premessa, questa O.S. SNAP entra nel merito della questione rappresentando che, con circolare protocollo N.300\/FER\/0000002641.U\/24, del <strong>15 febbraio 2024 avente ad oggetto<\/strong>: \u201cServizi rafforzati di controllo a bordo dei treni\u201d, il Servizio di Polizia Ferroviaria prevedeva \u201cl\u2019impiego di un\u2019adeguata aliquota di personale (8\/10 operatori) con l\u2019obiettivo di procedere ad un controllo identificativo rafforzato dei viaggiatori e, all\u2019occorrenza, dei bagagli su convogli interregionali che presentano profili di rischio legati alla tratta, agli orari e all\u2019area geografica\u201d, altres\u00ec indicava che: \u201cper quanto riguarda l\u2019indennit\u00e0 maggiorata, attualmente prevista dalla convenzione per un massimo di tre operatori, fatte salve particolari ed eccezionali situazioni di necessit\u00e0 preventivamente concordate tra le parti, e solo per i treni ritenuti ad alto profilo di criticit\u00e0, si rimette alle valutazioni di codesto Gruppo la possibilit\u00e0 di superare tali vincoli autorizzando pertanto di estenderla a tutto il personale impiegato &#8230; in attesa di determinazioni da parte del Gruppo FSI, si proceder\u00e0 a inserire la misura dell\u2019indennit\u00e0 di scorta a treno ordinario\u201d (ndr 1,22 euro l\u2019ora sia notturna che diurna).<\/p>\n<p style=\"text-align: justify\">Di seguito, in data <strong>24 maggio 2024,<\/strong> con circolare protocollo N.300\/FER\/2\/0000008858.U\/2024, avente ad oggetto: \u201cServizi rafforzati di controllo a bordo dei treni. Contabilizzazione\u201d, veniva indicato che, in riguardo alla corresponsione del pagamento delle indennit\u00e0 connesse ai citati servizi rafforzati, la Convenzione ed il sistema <strong>GASP<\/strong> non consentono la possibilit\u00e0 di corrispondere l\u2019indennit\u00e0 di vigilanza a bordo treno ad un numero superiore di tre operatori. La nota si conclude testualmente come di seguito:<em> \u201cpreso atto che al momento le indennit\u00e0 in argomento non saranno corrisposte, fino ad eventuali cambiamenti si dispone che sia i servizi gi\u00e0 espletati (quindi con valenza retroattiva) che quelli da effettuare, qualora ne ricorrano in presupposti, saranno contabilizzati ricorrendo all\u2019istituto della missione che ovviamente non \u00e8 cumulabile con l\u2019indennit\u00e0 di vigilanza scalo\u201d.<\/em><\/p>\n<p style=\"text-align: justify\"><strong>A giudizio di questa O.S. SNAP<\/strong> \u201cla toppa \u00e8 peggio del buco\u201d\u2026 invero ci pare assurdo, e privo di ogni logica sia giuridica che di buon senso, far partire su scala nazionale un imponente servizio straordinario di controllo sui mezzi ferroviari (attingendo anche alle esigue risorse umane impiegate in servizi burocratici) senza assicurarsi di una preventiva e concreta possibilit\u00e0 che, detti servizi di scorta a convogli e tratte critiche (da remunerare necessariamente con la prevista \u201cindennit\u00e0 maggiorata\u201d), abbiano l\u2019avvallo e la copertura da parte del Gruppo FSI. Continuando, evidenziamo che i servizi de qua, in un primo momento, sono stati previsti con \u201cindennit\u00e0 di scorta\u201d per poi essere mutati in servizi di \u201cmissione\u201d.<\/p>\n<p style=\"text-align: justify\">Sottolineiamo che la narrata situazione non \u00e8 stata portata a conoscenza delle sigle sindacali ed ancor peggio all\u2019attenzione del personale che \u00e8 convinto, da mesi, di effettuare regolarmente scorte per cui sia prevista un\u2019indennit\u00e0 maggiorata. Ci interroghiamo su quale sar\u00e0 il criterio con cui saranno attribuite le previste tre scorte con indennit\u00e0 maggiorata, a fronte degli <strong>8\/10 colleghi impiegati,<\/strong> e su come sia pensabile far svolgere a degli operatori un medesimo servizio con remunerazione nettamente differente, in spregio ai dettami costituzionali di cui all\u2019art. 36 che prevede: \u201cIl lavoratore ha diritto ad una retribuzione proporzionata alla quantit\u00e0 e qualit\u00e0 del suo lavoro\u2026\u201d e dell\u2019art. 97: \u201cI pubblici uffici sono organizzati secondo disposizioni di legge, in modo che siano assicurati il buon andamento e l&#8217;imparzialit\u00e0 dell&#8217;amministrazione\u201d. Si dovr\u00e0 pertanto scongiurare che, per cercare di creare una parvenza di trattamento economico omogeneo, si ricorra a remunerare tutti gli operatori col trattamento di missione anzich\u00e9 con la prevista scorta treno; significando che non \u00e8 tollerabile che ci si trovi dinanzi a tratte critiche sovrapponibili che, di volta in volta, possano essere pagate con indennit\u00e0 maggiorata o missione fuori sede solo perch\u00e9\u2019 rientrino o meno nel previsto report <strong>\u201ctreni ad alta criticit\u00e0\u201d<\/strong> individuati dal citato <strong>Comitato<\/strong>.<\/p>\n<p style=\"text-align: justify\">Allo stato attuale, con effetto retroattivo, si sta procedendo (nel riserbo pi\u00f9 assoluto) ad eliminare l\u2019attribuzione dell\u2019indennit\u00e0 prevista per scorta critica, e quindi maggiorata, per attribuire al personale impiegato in detti servizi straordinari esclusivamente l\u2019indennit\u00e0 di missione, escludendo finanche la vigilanza scalo nonostante sia prevista dalla Convenzione in favore del personale Polfer. In buona sostanza \u00e8 come se questi operatori non fossero mai saliti a bordo treno o abbiano operato in ambito ferroviario, pur avendo svolto concretamente servizi di scorta a convogli ferroviari, percependo un compenso economico inferiore alla mera vigilanza in stazione; difatti la diaria di trasferta spetta in misura intera, se la durata della missione supera le 4 ore ed \u00e8 inferiore alle 8 ore, con un compenso economico pari a euro 0,86 per ogni ora. Paradossalmente la propria retribuzione risulter\u00e0 ridotta.<\/p>\n<p style=\"text-align: justify\">Evidenziamo che, la scelta incomprensibile (alias non contemplata) di attribuire, addirittura retroattivamente, l\u2019indennit\u00e0 di missione presuppone che i colleghi debbano intraprendere il proprio servizio nella localit\u00e0 di arrivo della missione e non durante il tragitto per raggiungere la stessa; come effettivamente richiesto ed espletato con l\u2019effettuazione concreta di scorta treno, con identificazione e controllo di passeggeri e bagagli. Inoltre, la \u201cmissione\u201d presuppone formali ordini di servizio con compilazione, da parte del personale, del c.d. \u201cfoglio di viaggio\u201d e di eventuali mancati pasti; situazione di cui (in maniera scorretta) non sono stati resi edotti i colleghi interessati. Rammentiamo altres\u00ec che l\u2019indennit\u00e0 di missione compete per servizi fuori sede con durata superiore alle 4 ore, in difetto nulla sar\u00e0 percepito.<\/p>\n<p style=\"text-align: justify\">Per definizione per \u201cmissione\u201d si intende il servizio temporaneo espletato dal dipendente in una localit\u00e0 al di fuori del comune dell\u2019ordinaria sede di servizio per ottemperare a un formale provvedimento emesso dall\u2019Amministrazione; provvedimento che ad oggi, la stessa, non avrebbe provveduto ad emettere. Si sottolinea che non si potr\u00e0 procedere alla liquidazione del trattamento economico di missione, in assenza del relativo provvedimento. Questa O.S. SNAP segnala, per i relativi accertamenti di competenza dell\u2019Ufficio Centrale Ispettivo (considerato che il rispetto dei budget rientra nelle specifiche responsabilit\u00e0 gestionali dei dirigenti) quanto riportato nella circolare del 12 marzo 2024 protocollo N. 0001879, a firma del <strong>Capo della Polizia,<\/strong> relativamente al contenimento della spesa per l\u2019effettuazione delle missioni: \u201cnell\u2019ottica del raggiungimento dei limiti previsti, avranno cura di promuovere tutte le opportune iniziative finalizzate ad un\u2019accurata gestione, procedendo, in particolare:<\/p>\n<p style=\"text-align: justify\">&#8211; all\u2019oculata valutazione delle trasferte, in relazione alla loro obbligatoriet\u00e0 ed inderogabilit\u00e0;<br \/>\n&#8211; al costante monitoraggio bimestrale del consumo del budget annualmente assegnato;<br \/>\n&#8211; a garantire il rispetto dei tempi di presentazione della documentazione relativa alla missione, entro 7 giorni dalla conclusione del servizio fuori sede\u2026\u201d .<br \/>\nCi domandiamo come sia possibile inserire retroattivamente servizi fuori sede svolti dal personale mesi addietro e tra l\u2019altro trattasi di servizi svolti in favore di una Spa, qual \u00e8 il Gruppo FSI, con esborso evidente di risorse economiche dell\u2019Erario (utilizzate verosimilmente impropriamente) e per le quali solo pochi mesi addietro il Capo della Polizia ha diramato apposita nota, sopra riportata, finalizzata ad un\u2019oculata gestione delle risorse richiamando i dirigenti alle proprie specifiche responsabilit\u00e0, a tal punto da prevedere quanto di seguito: <em><strong>\u201cL\u2019Ufficio Centrale Ispettivo<\/strong> provveder\u00e0, anche attraverso la verifica dei monitoraggi compiuti dagli Uffici, ad adottare le iniziative ritenute opportune, d\u2019intesa con le Direzioni Centrali competenti, al fine di garantire l\u2019osservanza delle disposizioni emanate per la razionalizzazione delle spese\u201d.<\/em><\/p>\n<p style=\"text-align: justify\">Dinanzi a tutto ci\u00f2 rimaniamo basiti e, considerato che l\u2019Amministrazione ha generato questa imbarazzante situazione, adesso se ne faccia carico remunerando con l\u2019indennit\u00e0 maggiorata tutti gli operatori che hanno svolto il medesimo servizio, ignari di essere destinatari di indennit\u00e0 non consone e proporzionali all\u2019attivit\u00e0 specifica richiesta e svolta dalla specialit\u00e0 di <strong>Polizia<\/strong> <strong>Ferroviaria<\/strong>! Nelle more evidenziamo l\u2019inopportunit\u00e0 di continuare a richiedere agli operatori della Polfer l\u2019effettuazione di scorte mascherate da servizi fuori sede. Confidando nell\u2019attenzione, per l\u2019urgenza e l\u2019importanza delle tematiche trattate, rimaniamo in attesa di cortese sollecito riscontro, cogliendo l\u2019occasione per porgere distinti saluti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In data 26 giugno 2017 veniva stipulata la convenzione tra Polizia di Stato e Ferrovie dello Stato Italiane S.p.a. tramite cui vengono disciplinati i servizi predisposti dalla Polizia Ferroviaria nell\u2019interesse&hellip;<\/p>\n","protected":false},"author":8,"featured_media":42544,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[921,196,140],"tags":[32191,2559,2378,32190],"class_list":["post-52545","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-news","category-reggio-calabria","tag-o-s-snap","tag-polfer","tag-polizia-ferroviaria","tag-ufficio-centrale-ispettivo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Calabria: il Sindacato SNAP chiede interventi urgenti - Radio Touring 104<\/title>\n<meta name=\"description\" content=\"Mancata previsione pagamento scorte a bordo treno. La SNAP richiede un intervento urgente e messa in mora.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/calabria-la-snap-chiede-interventi-urgenti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Calabria: il Sindacato SNAP chiede interventi urgenti - Radio Touring 104\" \/>\n<meta property=\"og:description\" content=\"Mancata previsione pagamento scorte a bordo treno. La SNAP richiede un intervento urgente e messa in mora.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/calabria-la-snap-chiede-interventi-urgenti\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-31T13:29:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-31T13:35:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/01\/polfer.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"457\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Filippo Francesco Idone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Filippo Francesco Idone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/31\\\/calabria-la-snap-chiede-interventi-urgenti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/31\\\/calabria-la-snap-chiede-interventi-urgenti\\\/\"},\"author\":{\"name\":\"Filippo Francesco Idone\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\"},\"headline\":\"Calabria: il Sindacato SNAP chiede interventi urgenti\",\"datePublished\":\"2024-05-31T13:29:49+00:00\",\"dateModified\":\"2024-05-31T13:35:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/31\\\/calabria-la-snap-chiede-interventi-urgenti\\\/\"},\"wordCount\":1523,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/31\\\/calabria-la-snap-chiede-interventi-urgenti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/01\\\/polfer.jpg\",\"keywords\":[\"O.S. SNAP\",\"PolFer\",\"polizia ferroviaria\",\"Ufficio Centrale Ispettivo\"],\"articleSection\":[\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/31\\\/calabria-la-snap-chiede-interventi-urgenti\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/31\\\/calabria-la-snap-chiede-interventi-urgenti\\\/\",\"name\":\"Calabria: il Sindacato SNAP chiede interventi urgenti - Radio Touring 104\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/31\\\/calabria-la-snap-chiede-interventi-urgenti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/31\\\/calabria-la-snap-chiede-interventi-urgenti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/01\\\/polfer.jpg\",\"datePublished\":\"2024-05-31T13:29:49+00:00\",\"dateModified\":\"2024-05-31T13:35:59+00:00\",\"description\":\"Mancata previsione pagamento scorte a bordo treno. La SNAP richiede un intervento urgente e messa in mora.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/31\\\/calabria-la-snap-chiede-interventi-urgenti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/31\\\/calabria-la-snap-chiede-interventi-urgenti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/31\\\/calabria-la-snap-chiede-interventi-urgenti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/01\\\/polfer.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/01\\\/polfer.jpg\",\"width\":457,\"height\":395,\"caption\":\"Un agente di Polizia durante l'attivit\u00e0 di controllo alla stazione Termini di Roma, 23 agosto 2019. Ben 28.767 identificati, 24 arrestati e 184 indagati: \u00e8 questo il bilancio della settimana di controlli della Polizia Ferroviaria. Sono 3.397 le pattuglie impegnate in stazione e 746 a bordo treno, per un totale di 1.579 treni scortati; 221 servizi antiborseggio e 57 le sanzioni elevate in materia di sicurezza ferroviaria. ANSA \\\/ us Polizia di Stato +++ ANSA PROVIDES ACCESS TO THIS HANDOUT PHOTO TO BE USED SOLELY TO ILLUSTRATE NEWS REPORTING OR COMMENTARY ON THE FACTS OR EVENTS DEPICTED IN THIS IMAGE; NO ARCHIVING; NO LICENSING +++\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/05\\\/31\\\/calabria-la-snap-chiede-interventi-urgenti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calabria: il Sindacato SNAP chiede interventi urgenti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\",\"name\":\"Filippo Francesco Idone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"caption\":\"Filippo Francesco Idone\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/filippoidone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Calabria: il Sindacato SNAP chiede interventi urgenti - Radio Touring 104","description":"Mancata previsione pagamento scorte a bordo treno. La SNAP richiede un intervento urgente e messa in mora.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/calabria-la-snap-chiede-interventi-urgenti\/","og_locale":"it_IT","og_type":"article","og_title":"Calabria: il Sindacato SNAP chiede interventi urgenti - Radio Touring 104","og_description":"Mancata previsione pagamento scorte a bordo treno. La SNAP richiede un intervento urgente e messa in mora.","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/calabria-la-snap-chiede-interventi-urgenti\/","og_site_name":"Radio Touring 104","article_published_time":"2024-05-31T13:29:49+00:00","article_modified_time":"2024-05-31T13:35:59+00:00","og_image":[{"width":457,"height":395,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/01\/polfer.jpg","type":"image\/jpeg"}],"author":"Filippo Francesco Idone","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Filippo Francesco Idone","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/calabria-la-snap-chiede-interventi-urgenti\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/calabria-la-snap-chiede-interventi-urgenti\/"},"author":{"name":"Filippo Francesco Idone","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b"},"headline":"Calabria: il Sindacato SNAP chiede interventi urgenti","datePublished":"2024-05-31T13:29:49+00:00","dateModified":"2024-05-31T13:35:59+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/calabria-la-snap-chiede-interventi-urgenti\/"},"wordCount":1523,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/calabria-la-snap-chiede-interventi-urgenti\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/01\/polfer.jpg","keywords":["O.S. SNAP","PolFer","polizia ferroviaria","Ufficio Centrale Ispettivo"],"articleSection":["Home","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/calabria-la-snap-chiede-interventi-urgenti\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/calabria-la-snap-chiede-interventi-urgenti\/","name":"Calabria: il Sindacato SNAP chiede interventi urgenti - Radio Touring 104","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/calabria-la-snap-chiede-interventi-urgenti\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/calabria-la-snap-chiede-interventi-urgenti\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/01\/polfer.jpg","datePublished":"2024-05-31T13:29:49+00:00","dateModified":"2024-05-31T13:35:59+00:00","description":"Mancata previsione pagamento scorte a bordo treno. La SNAP richiede un intervento urgente e messa in mora.","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/calabria-la-snap-chiede-interventi-urgenti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/calabria-la-snap-chiede-interventi-urgenti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/calabria-la-snap-chiede-interventi-urgenti\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/01\/polfer.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/01\/polfer.jpg","width":457,"height":395,"caption":"Un agente di Polizia durante l'attivit\u00e0 di controllo alla stazione Termini di Roma, 23 agosto 2019. Ben 28.767 identificati, 24 arrestati e 184 indagati: \u00e8 questo il bilancio della settimana di controlli della Polizia Ferroviaria. Sono 3.397 le pattuglie impegnate in stazione e 746 a bordo treno, per un totale di 1.579 treni scortati; 221 servizi antiborseggio e 57 le sanzioni elevate in materia di sicurezza ferroviaria. ANSA \/ us Polizia di Stato +++ ANSA PROVIDES ACCESS TO THIS HANDOUT PHOTO TO BE USED SOLELY TO ILLUSTRATE NEWS REPORTING OR COMMENTARY ON THE FACTS OR EVENTS DEPICTED IN THIS IMAGE; NO ARCHIVING; NO LICENSING +++"},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/05\/31\/calabria-la-snap-chiede-interventi-urgenti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Calabria: il Sindacato SNAP chiede interventi urgenti"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b","name":"Filippo Francesco Idone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","caption":"Filippo Francesco Idone"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/filippoidone\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/01\/polfer.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/52545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=52545"}],"version-history":[{"count":2,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/52545\/revisions"}],"predecessor-version":[{"id":52547,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/52545\/revisions\/52547"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/42544"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=52545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=52545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=52545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}