{"id":53452,"date":"2024-06-15T19:03:55","date_gmt":"2024-06-15T17:03:55","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=53452"},"modified":"2024-06-16T09:20:59","modified_gmt":"2024-06-16T07:20:59","slug":"aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2024\/06\/15\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\/","title":{"rendered":"Aggressione in carcere, il SAPPE: &#8220;Valuter\u00e0 ogni forma di tutela dei colleghi aggrediti e minacciati\u201d"},"content":{"rendered":"<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\">Giornata choc, l\u2019ennesima, di sangue e violenza nel carcere di Paola, da tempo al centro delle cronache per le continue aggressioni al personale di Polizia Penitenziaria che vi presta servizio. Su quanto \u00e8 avvenuto nelle ultime ore\u00a0riferisce<span class=\"xmprfx_apple-converted-space\">\u00a0<\/span>Salvatore Panaro, vicesegretario<span class=\"xmprfx_apple-converted-space\">\u00a0<\/span>regionale<span class=\"xmprfx_apple-converted-space\">\u00a0<\/span>per la Calabria del Sindacato<span class=\"xmprfx_apple-converted-space\">\u00a0<\/span>Autonomo<span class=\"xmprfx_apple-converted-space\">\u00a0<\/span>Polizia Penitenziaria: <em>\u201cE\u2019 successo che,<strong>\u00a0all&#8217;atto dell&#8217;apertura di una cella<\/strong>, un detenuto, proditoriamente e senza alcun motivo,<strong> si \u00e8 scagliato contro l\u2019Agente di servizio<\/strong>, aggredendolo, afferrandolo per il collo e spingendolo per diversi metri. Sembrerebbe che il ristretto aggressore sia affetto da problematiche psichiatriche: per fortuna, Il collega \u00e8 riuscito a divincolarsi dall&#8217;aggressione, anche grazie all&#8217;intervento di un altro detenuto presente intervenuto in soccorso all&#8217;unit\u00e0 di polizia penitenziaria\u201d.<\/em> Ma, prosegue il sindacalista, proprio il <em>fatto che era intervenuto a difesa di un Agente, quel detenuto \u00e8 stato successivamente aggredito da altri detenuti e questo episodio riveste carattere di gravissima rilevanza\u201d.<\/em><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\">Per Panaro, \u201c<em>occorrerebbe che i detenuti violenti, che pensano il carcere come luogo di villeggiatura dove poter commettere reati, vengano trasferiti immediatamente fuori regione. Negli ultimi tempi stiamo assistendo ad un cambiamento sociale, dove il male \u00e8 visto come bene e viceversa, dove all&#8217;esterno del carcere il reato \u00e8 cattivo ed all&#8217;interno chi ha commesso reato sia buono. \u00c8 giunto il momento di dire basta al finto buonismo, <strong>I detenuti che trasgrediscono le regole<\/strong> o peggio ancora che aggrediscono la Polizia Penitenziaria devono essere perseguiti a norma di legge ma soprattutto scardinati dal contesto ove si sentono appoggiati da altri reclusi amici e quindi forti di questo, non esitano a commettere altri reati\u201d.<\/em> <em>Per questo<\/em>, conclude il sindacalista del SAPPE, I<em>l Dipartimento dell&#8217;amministrazione Penitenziaria e gli organi Statali preposti devono assumersi le responsabilit\u00e0 ed attuare, ognuno per la parte di propria competenza, azioni mirate\u00a0\u00a0\u00a0a dare garanzia di intervento al corpo di Polizia penitenziaria che opera nell&#8217;ultima trincea della giustizia. Il <strong>SAPPE<\/strong> valuter\u00e0 ogni forma di tutela anche in sede giudiziaria dei colleghi aggrediti e minacciati\u201d.<\/em><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\">Per Donato Capece, segretario generale del <strong>SAPPE<\/strong>, \u201c<i>la situazione penitenziaria regionale e nazionale fa, ogni giorno di pi\u00f9, emergere la tensione che \u00e8 non pi\u00f9 latente ma palese ed evidente.\u00a0<\/i><span class=\"xmprfx_s5\"><i>Bisogna intervenire con celerit\u00e0, a tutela dei poliziotti penitenziari, orgoglio non solo del <strong>SAPPE<\/strong> e di tutto il Corpo ma dell\u2019intera Nazione\u201d.\u00a0<\/i><\/span><span class=\"xmprfx_s5\">Ed evidenzia: \u201c<\/span><i>La denuncia del SAPPE: \u201cNel Distretto penitenziario calabrese, nel solo primo quadrimestre del 2024, una marea di eventi critici tra le sbarre delle carceri regionali:\u00a0<b>236<\/b>\u00a0resistenze ed ingiurie,\u00a0<b>un atto intimidatorio\u00a0<\/b>contro un Agente,\u00a0<b>12 proteste collettive con battitura<\/b>. Ben\u00a0<b>76 i poliziotti feriti\u00a0<\/b>con prognosi fino a 7 giorni,\u00a0<b>2<\/b>\u00a0con prognosi di oltre i 20 giorni\u201d.<\/i><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\">Torna quindi a sollecitare\u00a0<i>\u201cprovvedimenti urgenti\u201d,<\/i>\u00a0a cominciare da \u201c<b><i>un inasprimento di pena per i detenuti che aggrediscono il personale di Polizia Penitenziaria durante la permanenza e l\u2019espiazione di pena in carcere<\/i><\/b><i>\u201d. \u201cS<\/i><em>erve, forte ed evidente, la presenza dello Stato, che non pu\u00f2 tollerare questa diffusa impunit\u00e0, e servono provvedimenti urgenti ed efficaci!\u201d, conclude il leader del primo Sindacato dei Baschi Azzurri, che si appella ai vertici del DAP affinch\u00e9 creino le condizioni\u00a0<\/em><i>\u201cper ristabilire ordine e sicurezza, attuando davvero quella tolleranza zero verso quei detenuti violenti che, anche in carcere, sono convinti di poter continuare a delinquere nella impunit\u00e0 assoluta!\u201d.\u00a0<\/i><em>\u201c<\/em><i><\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Giornata choc, l\u2019ennesima, di sangue e violenza nel carcere di Paola, da tempo al centro delle cronache per le continue aggressioni al personale di Polizia Penitenziaria che vi presta servizio.&hellip;<\/p>\n","protected":false},"author":8,"featured_media":28396,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[921,196,140],"tags":[5441,8044,18191],"class_list":["post-53452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-news","category-reggio-calabria","tag-carceri","tag-paola","tag-sappe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aggressione in carcere, il SAPPE: &quot;Valuter\u00e0 ogni forma di tutela dei colleghi aggrediti e minacciati\u201d - Radio Touring 104<\/title>\n<meta name=\"description\" content=\"Il Sindacato\u00a0Autonomo\u00a0Polizia Penitenziaria dar\u00e0 il massimo sostegno agli agenti aggrediti nelle carceri di Paola\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/06\/15\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aggressione in carcere, il SAPPE: &quot;Valuter\u00e0 ogni forma di tutela dei colleghi aggrediti e minacciati\u201d - Radio Touring 104\" \/>\n<meta property=\"og:description\" content=\"Il Sindacato\u00a0Autonomo\u00a0Polizia Penitenziaria dar\u00e0 il massimo sostegno agli agenti aggrediti nelle carceri di Paola\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/06\/15\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-15T17:03:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-16T07:20:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/06\/SAPPE-Sindacato-Polizia-Penitenziaria.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Filippo Francesco Idone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Filippo Francesco Idone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/06\\\/15\\\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/06\\\/15\\\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\\\/\"},\"author\":{\"name\":\"Filippo Francesco Idone\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\"},\"headline\":\"Aggressione in carcere, il SAPPE: &#8220;Valuter\u00e0 ogni forma di tutela dei colleghi aggrediti e minacciati\u201d\",\"datePublished\":\"2024-06-15T17:03:55+00:00\",\"dateModified\":\"2024-06-16T07:20:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/06\\\/15\\\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\\\/\"},\"wordCount\":543,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/06\\\/15\\\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/06\\\/SAPPE-Sindacato-Polizia-Penitenziaria.jpg\",\"keywords\":[\"carceri\",\"Paola\",\"Sappe\"],\"articleSection\":[\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/06\\\/15\\\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/06\\\/15\\\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\\\/\",\"name\":\"Aggressione in carcere, il SAPPE: \\\"Valuter\u00e0 ogni forma di tutela dei colleghi aggrediti e minacciati\u201d - Radio Touring 104\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/06\\\/15\\\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/06\\\/15\\\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/06\\\/SAPPE-Sindacato-Polizia-Penitenziaria.jpg\",\"datePublished\":\"2024-06-15T17:03:55+00:00\",\"dateModified\":\"2024-06-16T07:20:59+00:00\",\"description\":\"Il Sindacato\u00a0Autonomo\u00a0Polizia Penitenziaria dar\u00e0 il massimo sostegno agli agenti aggrediti nelle carceri di Paola\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/06\\\/15\\\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/06\\\/15\\\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/06\\\/15\\\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/06\\\/SAPPE-Sindacato-Polizia-Penitenziaria.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/06\\\/SAPPE-Sindacato-Polizia-Penitenziaria.jpg\",\"width\":640,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/06\\\/15\\\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aggressione in carcere, il SAPPE: &#8220;Valuter\u00e0 ogni forma di tutela dei colleghi aggrediti e minacciati\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\",\"name\":\"Filippo Francesco Idone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"caption\":\"Filippo Francesco Idone\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/filippoidone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aggressione in carcere, il SAPPE: \"Valuter\u00e0 ogni forma di tutela dei colleghi aggrediti e minacciati\u201d - Radio Touring 104","description":"Il Sindacato\u00a0Autonomo\u00a0Polizia Penitenziaria dar\u00e0 il massimo sostegno agli agenti aggrediti nelle carceri di Paola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2024\/06\/15\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\/","og_locale":"it_IT","og_type":"article","og_title":"Aggressione in carcere, il SAPPE: \"Valuter\u00e0 ogni forma di tutela dei colleghi aggrediti e minacciati\u201d - Radio Touring 104","og_description":"Il Sindacato\u00a0Autonomo\u00a0Polizia Penitenziaria dar\u00e0 il massimo sostegno agli agenti aggrediti nelle carceri di Paola","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/06\/15\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\/","og_site_name":"Radio Touring 104","article_published_time":"2024-06-15T17:03:55+00:00","article_modified_time":"2024-06-16T07:20:59+00:00","og_image":[{"width":640,"height":640,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/06\/SAPPE-Sindacato-Polizia-Penitenziaria.jpg","type":"image\/jpeg"}],"author":"Filippo Francesco Idone","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Filippo Francesco Idone","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/06\/15\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/06\/15\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\/"},"author":{"name":"Filippo Francesco Idone","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b"},"headline":"Aggressione in carcere, il SAPPE: &#8220;Valuter\u00e0 ogni forma di tutela dei colleghi aggrediti e minacciati\u201d","datePublished":"2024-06-15T17:03:55+00:00","dateModified":"2024-06-16T07:20:59+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/06\/15\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\/"},"wordCount":543,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/06\/15\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/06\/SAPPE-Sindacato-Polizia-Penitenziaria.jpg","keywords":["carceri","Paola","Sappe"],"articleSection":["Home","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/06\/15\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/06\/15\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\/","name":"Aggressione in carcere, il SAPPE: \"Valuter\u00e0 ogni forma di tutela dei colleghi aggrediti e minacciati\u201d - Radio Touring 104","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/06\/15\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/06\/15\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/06\/SAPPE-Sindacato-Polizia-Penitenziaria.jpg","datePublished":"2024-06-15T17:03:55+00:00","dateModified":"2024-06-16T07:20:59+00:00","description":"Il Sindacato\u00a0Autonomo\u00a0Polizia Penitenziaria dar\u00e0 il massimo sostegno agli agenti aggrediti nelle carceri di Paola","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/06\/15\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2024\/06\/15\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/06\/15\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/06\/SAPPE-Sindacato-Polizia-Penitenziaria.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/06\/SAPPE-Sindacato-Polizia-Penitenziaria.jpg","width":640,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/06\/15\/aggressione-in-carcere-il-sappe-valutera-ogni-forma-di-tutela-dei-colleghi-aggrediti-e-minacciati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Aggressione in carcere, il SAPPE: &#8220;Valuter\u00e0 ogni forma di tutela dei colleghi aggrediti e minacciati\u201d"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b","name":"Filippo Francesco Idone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","caption":"Filippo Francesco Idone"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/filippoidone\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/06\/SAPPE-Sindacato-Polizia-Penitenziaria.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/53452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=53452"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/53452\/revisions"}],"predecessor-version":[{"id":53453,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/53452\/revisions\/53453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/28396"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=53452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=53452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=53452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}