{"id":54288,"date":"2024-07-02T09:57:05","date_gmt":"2024-07-02T07:57:05","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=54288"},"modified":"2024-07-02T09:57:50","modified_gmt":"2024-07-02T07:57:50","slug":"suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/02\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\/","title":{"rendered":"Suicidi in carcere: il Presidente Marra interviene all&#8217;iniziativa della Camera Penale di Reggio"},"content":{"rendered":"<p style=\"text-align: justify\">Quando l\u2019avvocato<strong> Pasquale Foti, Presidente della Camera Penale di Reggio<\/strong> Calabria mi ha chiesto di poter dire anch\u2019io qualcosa in merito ad un tema cos\u00ec tanto delicato come quello dei<strong> suicidi in carcere,<\/strong> per un attimo, lo ammetto, ho esitato. Non perch\u00e9 non avessi nulla da dire in proposito, anzi. Ma perch\u00e9 credo che si tratti di un <strong>argomento talmente tanto complesso<\/strong> da non poter essere condensato in poche battute. Tuttavia, mi sono domandato quale possa essere il contributo di un<strong> amministratore pubblico che prescinda dai soliti stereotipi<\/strong> e si cali, concretamente, <strong>nella realt\u00e0 carceraria per provare a fornire una chiave che non sia solo di lettura, ma anche d\u2019intervento.<\/strong><\/p>\n<p style=\"text-align: justify\">E allora non posso che partire dai <strong>dati oggettivi che mi sono stati<\/strong> \u201csbattuti\u201d<strong> in faccia nel momento in cui sono andato a studiarl<\/strong>i: solo nel 2024, al 19 giugno, si contano 44 suicidi in carcere. Uno ogni tre giorni. Una persona ogni tre giorni, che si trova in stato di detenzione, decide di togliersi la vita.<\/p>\n<p style=\"text-align: justify\">Ma se questo pu\u00f2 apparire il dato pi\u00f9 problematico, vi assicuro che ne ho trovato un<strong> altro che mi ha davvero sconvolto: nel 2023 il tasso di suicidi delle donne detenute \u00e8 sensibilmente superiore,<\/strong> in termini percentuali, a quello degli uomini.<\/p>\n<p style=\"text-align: justify\">Sono quindi andato alla ricerca delle possibili cause di un fenomeno che non accenna a placarsi. Ho letto di marginalit\u00e0, di patologie psichiatriche pregresse, tossicodipendenza, persone senza fissa dimora. E un particolare: la maggior parte dei suicidi interessa detenuti di nazionalit\u00e0 straniera.<\/p>\n<p style=\"text-align: justify\">Cos\u00ec, la mia mente \u00e8 andata subito all\u2019ipotesi secondo cui chi decide di togliersi la vita \u00e8 probabilmente stanco di una vita carceraria che, nella sua prospettazione, appare molto lunga. Infinita<strong>. Anche qui sono stato smentito dai fatti:<\/strong> <strong>molte delle persone che si sono suicidate erano in attesa di giudizio. Capite?<\/strong> Ancora in attesa di giudizio, dunque innocenti fino a prova contraria. Altri l\u2019hanno fatta finita dopo brevissimi periodi di detenzione, poche settimane o qualche mese. Altri solo una manciata di giorni.<\/p>\n<p style=\"text-align: justify\">Ma c\u2019\u00e8 un dato \u2013 e qui mi soffermo <strong>\u2013 che mi ha lasciato un senso di fallimento addosso: sono tanti, troppi i suicidi di chi il carcere \u00e8 in procinto di lasciarlo o per un residuo breve di pena o per una prevista misura alternativa.<\/strong> Si tratta di persona che dovevano rientrare nella societ\u00e0 e farlo dopo un periodo che avrebbe dovuto rappresentare per loro una opportunit\u00e0. E invece, suicidandosi a poche miglia dal traguardo ci hanno fatto comprendere come non sentissero dentro di loro nemmeno il germe della speranza.<\/p>\n<p style=\"text-align: justify\">Non mi addentro su questioni come il sovraffollamento, la costruzione di nuove strutture o il miglioramento di quelle esistenti. Lascio che siano i tecnici e i politici di rango nazionale a farlo. <strong>Mi domando, piuttosto,<\/strong> cosa la politica locale, un\u2019amministrazione comunale o regionale <strong>possano fare per mitigare<\/strong>, per quanto possibile, u<strong>n simile trend che non accenna a placarsi.<\/strong> Ritorno alla speranza: ecco, credo che noi dobbiamo essere in grado di fornire a coloro che entrano in una cella il dono della speranza. Che non pu\u00f2 e non deve declinarsi solo nell\u2019idea di una uscita quanto pi\u00f9 possibile anticipata, ma che deve concretizzarsi nel poter garantire a chi finisce in cella tutta l\u2019assistenza morale e materiale possibile.<\/p>\n<p style=\"text-align: justify\">Non dimentichiamo che gran parte di coloro che affollano le carceri sono persone in attesa di giudizio. Dunque presunti innocenti che, per gravi fatti, sono in uno stato di custodia cautelare in carcere<strong>. Qui bisogna gi\u00e0 intervenire con percorsi che possano aiutare quelle persone a sostenere il peso dell\u2019attesa del giudizio che, l<\/strong>o sappiamo, a volte pu\u00f2 essere estenuante, nonostante gli sforzi profusi dalla magistratura. Ma nel loro caso un\u2019amministrazione locale pu\u00f2, ad esempio, approntare una serie di percorsi e progetti che consentano di alleviare quel senso di disorientamento che vive colui o colei che varca per la prima volta la porta del carcere. Cos\u00ec come pu\u00f2 essere per chi ci sta finendo non per la prima volta. La carcerazione, non va dimenticato, rappresenta un fallimento in primis per chi la subisce. Nessuno sceglie di essere carcerato, ma ne accetta il rischio. A volte perch\u00e9 sente \u2013 sbagliando \u2013 di non avere altre opportunit\u00e0. Ecco cosa pu\u00f2 fare un\u2019amministrazione locale: aiutare concretamente chi lo desidera a poter avere un\u2019alternativa. Una opportunit\u00e0. Cos\u00ec come coloro che scontano pene definitive.<\/p>\n<p style=\"text-align: justify\"><strong>Non possiamo pi\u00f9 lasciare che il tema della<\/strong> \u201crieducazione\u201d<strong> del condannato possa essere delegata alla sola politica nazionale<\/strong> e agli istituti penitenziari. Io ritengo che occorra una politica diffusa di rieducazione, che coinvolga i territori e faccia sentire protagonista la cittadinanza.<\/p>\n<p style=\"text-align: justify\"><strong>Di certo si pu\u00f2 e si deve tendere al miglioramento delle condizioni carcerarie<\/strong>. Tuttavia questo richiede tempi lunghi che mal si conciliano con l\u2019esigenza di celerit\u00e0 che richiede invece un\u2019emergenza come quella dei suicidi. Allora, in attesa che le istituzioni nazionali affrontino di petto la questione, a livello locale non possiamo rimanere fermi, come gi\u00e0 stiamo facendo a Reggio Calabria. Occorre incrementare e migliorare tali percorsi. Se una politica diffusa e delocalizzata di accoglienza, di opportunit\u00e0, di alternative, inizier\u00e0 a diffondersi, migliorer\u00e0 anche la capacit\u00e0 di ascolto e assistenza dei detenuti. <strong>A volte basta poco per salvare una vita e dare una seconda opportunit\u00e0.<\/strong> Io sono a disposizione e pronto a fornire il mio contributo concreto, poich\u00e9 sono convinto che, con azioni come quelle poc\u2019anzi enunciate, il numero dei suicidi in carcere potrebbe iniziare a contrarsi gi\u00e0 nel breve periodo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando l\u2019avvocato Pasquale Foti, Presidente della Camera Penale di Reggio Calabria mi ha chiesto di poter dire anch\u2019io qualcosa in merito ad un tema cos\u00ec tanto delicato come quello dei&hellip;<\/p>\n","protected":false},"author":12,"featured_media":54289,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[921,196,140],"tags":[33353,28693,33352],"class_list":["post-54288","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-news","category-reggio-calabria","tag-camera-penale-di-reggio-calabria","tag-marra-vincenzo","tag-suicidi-in-carcere"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Suicidi in carcere: Marra interviene ad iniziativa Camera Penale Rc<\/title>\n<meta name=\"description\" content=\"Il Presidente del Consiglio Comunale \u00e8 intervenuto all&#039;iniziativa svolta a Piazza Italia sulla delicata questione dei suicidi in carcere\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/02\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Suicidi in carcere: Marra interviene ad iniziativa Camera Penale Rc\" \/>\n<meta property=\"og:description\" content=\"Il Presidente del Consiglio Comunale \u00e8 intervenuto all&#039;iniziativa svolta a Piazza Italia sulla delicata questione dei suicidi in carcere\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/02\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-02T07:57:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-02T07:57:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/07\/Maratona-Oratoria-suicidi-in-carcere-Vincenzo-Marra.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1071\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sebastiano Plutino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastiano Plutino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/02\\\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/02\\\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\\\/\"},\"author\":{\"name\":\"Sebastiano Plutino\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\"},\"headline\":\"Suicidi in carcere: il Presidente Marra interviene all&#8217;iniziativa della Camera Penale di Reggio\",\"datePublished\":\"2024-07-02T07:57:05+00:00\",\"dateModified\":\"2024-07-02T07:57:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/02\\\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\\\/\"},\"wordCount\":914,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/02\\\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/07\\\/Maratona-Oratoria-suicidi-in-carcere-Vincenzo-Marra.jpeg\",\"keywords\":[\"camera penale di Reggio Calabria\",\"Marra Vincenzo\",\"suicidi in carcere\"],\"articleSection\":[\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/02\\\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/02\\\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\\\/\",\"name\":\"Suicidi in carcere: Marra interviene ad iniziativa Camera Penale Rc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/02\\\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/02\\\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/07\\\/Maratona-Oratoria-suicidi-in-carcere-Vincenzo-Marra.jpeg\",\"datePublished\":\"2024-07-02T07:57:05+00:00\",\"dateModified\":\"2024-07-02T07:57:50+00:00\",\"description\":\"Il Presidente del Consiglio Comunale \u00e8 intervenuto all'iniziativa svolta a Piazza Italia sulla delicata questione dei suicidi in carcere\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/02\\\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/02\\\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/02\\\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/07\\\/Maratona-Oratoria-suicidi-in-carcere-Vincenzo-Marra.jpeg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/07\\\/Maratona-Oratoria-suicidi-in-carcere-Vincenzo-Marra.jpeg\",\"width\":1071,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/02\\\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Suicidi in carcere: il Presidente Marra interviene all&#8217;iniziativa della Camera Penale di Reggio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\",\"name\":\"Sebastiano Plutino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"caption\":\"Sebastiano Plutino\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/sebastiano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Suicidi in carcere: Marra interviene ad iniziativa Camera Penale Rc","description":"Il Presidente del Consiglio Comunale \u00e8 intervenuto all'iniziativa svolta a Piazza Italia sulla delicata questione dei suicidi in carcere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/02\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\/","og_locale":"it_IT","og_type":"article","og_title":"Suicidi in carcere: Marra interviene ad iniziativa Camera Penale Rc","og_description":"Il Presidente del Consiglio Comunale \u00e8 intervenuto all'iniziativa svolta a Piazza Italia sulla delicata questione dei suicidi in carcere","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/02\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\/","og_site_name":"Radio Touring 104","article_published_time":"2024-07-02T07:57:05+00:00","article_modified_time":"2024-07-02T07:57:50+00:00","og_image":[{"width":1071,"height":1600,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/07\/Maratona-Oratoria-suicidi-in-carcere-Vincenzo-Marra.jpeg","type":"image\/jpeg"}],"author":"Sebastiano Plutino","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Sebastiano Plutino","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/02\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/02\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\/"},"author":{"name":"Sebastiano Plutino","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e"},"headline":"Suicidi in carcere: il Presidente Marra interviene all&#8217;iniziativa della Camera Penale di Reggio","datePublished":"2024-07-02T07:57:05+00:00","dateModified":"2024-07-02T07:57:50+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/02\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\/"},"wordCount":914,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/02\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/07\/Maratona-Oratoria-suicidi-in-carcere-Vincenzo-Marra.jpeg","keywords":["camera penale di Reggio Calabria","Marra Vincenzo","suicidi in carcere"],"articleSection":["Home","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/02\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/02\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\/","name":"Suicidi in carcere: Marra interviene ad iniziativa Camera Penale Rc","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/02\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/02\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/07\/Maratona-Oratoria-suicidi-in-carcere-Vincenzo-Marra.jpeg","datePublished":"2024-07-02T07:57:05+00:00","dateModified":"2024-07-02T07:57:50+00:00","description":"Il Presidente del Consiglio Comunale \u00e8 intervenuto all'iniziativa svolta a Piazza Italia sulla delicata questione dei suicidi in carcere","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/02\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/02\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/02\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/07\/Maratona-Oratoria-suicidi-in-carcere-Vincenzo-Marra.jpeg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/07\/Maratona-Oratoria-suicidi-in-carcere-Vincenzo-Marra.jpeg","width":1071,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/02\/suicidi-in-carcere-il-presidente-marra-interviene-alliniziativa-della-camera-penale-di-reggio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Suicidi in carcere: il Presidente Marra interviene all&#8217;iniziativa della Camera Penale di Reggio"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e","name":"Sebastiano Plutino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","caption":"Sebastiano Plutino"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/sebastiano\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/07\/Maratona-Oratoria-suicidi-in-carcere-Vincenzo-Marra.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/54288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=54288"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/54288\/revisions"}],"predecessor-version":[{"id":54290,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/54288\/revisions\/54290"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/54289"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=54288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=54288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=54288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}