{"id":54351,"date":"2024-07-03T09:30:31","date_gmt":"2024-07-03T07:30:31","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=54351"},"modified":"2024-07-03T09:30:31","modified_gmt":"2024-07-03T07:30:31","slug":"prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/03\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\/","title":{"rendered":"Prete prescritto per pedofilia: Arcivescovo Morrone revoca nomina a don Perrello"},"content":{"rendered":"<div>ll sociologo<strong> Antonio Marziale, Garante per l\u2019infanzia<\/strong> e l\u2019adolescenza della Regione Calabria,<strong> accoglie con soddisfazione<\/strong> il passo indietro e la <strong>revoca della nomina di Don Perello, prescritto per il reato di pedofilia, da parte dell&#8217;Arcivescovo Morrone, <\/strong>su segnalazione pervenutegli e interpellato dal giornale il <i><a href=\"http:\/\/dispaccio.it\/\" target=\"_blank\" rel=\"noopener noreferrer\">Dispaccio.it<\/a><\/i>\u00a0aveva espresso il proprio disappunto, perch\u00e9 il prete in questione risulta essere prescritto per reati di abusi sui minori.<\/div>\n<div><\/div>\n<div style=\"text-align: justify\"><strong>Ringrazio sentitamente l\u2019arcivescovo<\/strong> di Reggio Calabria, <strong>Fortunato Morrone, per avere inteso revocare la nomina del sacerdote Carmelo Perrello<\/strong> ad amministratore parrocchiale di Santa Maria del Buon Consiglio di Concessa di Reggio Calabria\u201d<strong>, dichiara Marziale\u00a0<\/strong><\/div>\n<div><\/div>\n<div style=\"text-align: justify\"><em>\u201cLa pedofilia \u00e8 un terreno minato per la societ\u00e0 e soprattutto ha cagionato al Vaticano guai non di poco conto<\/em> \u2013<strong> evidenzia il Garante \u2013<\/strong><em> spingendo Papa Francesco a dichiarare che un prete che molesta i bambini non pu\u00f2 continuare a fare il prete e che il processo di tolleranza zero \u00e8 da considerarsi irreversibile. La nomina, oggi revocata, non poteva dunque passare inosservata. Non si tratta di un prete assolto, ma prescritto e lo stesso presule reggino, nel comunicato di due giorni fa, aveva rilevato come sia stato necessario farlo seguire da uno psicoterapeuta e da due confratelli\u201d.<\/em><\/div>\n<div><\/div>\n<div style=\"text-align: justify\"><em>\u201cDa Garante<\/em> \u2013 <strong>aggiunge Marziale \u2013<\/strong> <em>non potevo non ascoltare le sollecitazioni pervenutemi, perch\u00e9 la parrocchia rimane pur sempre un centro di aggregazione minorile di mia competenza territoriale in tema di sicurezza dei bambini e degli adolescenti. E, sinceramente, conoscendo molto da vicino la pedofilia anche nei suoi risvolti psichici, non avrei potuto dirmi tranquillo, al pari di quanti hanno inteso contattarmi\u201d.<\/em><\/div>\n<div style=\"text-align: justify\"><em>\u201cL\u2019odierna determinazione dell\u2019arcivescovo Morrone, riconcilia l\u2019azione della chiesa locale al pronunciamento papale e pertanto<\/em> \u2013 <strong>conclude il Garante<\/strong> \u2013<em> \u00e8 da salutarsi con la certezza che tutti insieme, istituzioni laiche e religiose, si sia impegnati sullo stesso fronte a tutela dei pi\u00f9 piccoli\u201d.<\/em><\/div>\n<div class=\"xmprfx_elementToProof\"><\/div>\n<div id=\"Signature\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>ll sociologo Antonio Marziale, Garante per l\u2019infanzia e l\u2019adolescenza della Regione Calabria, accoglie con soddisfazione il passo indietro e la revoca della nomina di Don Perello, prescritto per il reato&hellip;<\/p>\n","protected":false},"author":12,"featured_media":43695,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[921,196,140],"tags":[5345,7994,33398,33397],"class_list":["post-54351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-news","category-reggio-calabria","tag-antonio-marziale","tag-arcivescovo-morrone","tag-reato-di-pedofilia-prescritto","tag-revoca-nomina-a-don-perrello"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arcivescovo Morrone revoca nomina don Perrello. Plauso Marziale<\/title>\n<meta name=\"description\" content=\"Marziale ringrazia il presule dopo revoca del parroco prescritto per pedofilia: &quot;Tutti insieme a tutela dell&#039;infanzia&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/03\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arcivescovo Morrone revoca nomina don Perrello. Plauso Marziale\" \/>\n<meta property=\"og:description\" content=\"Marziale ringrazia il presule dopo revoca del parroco prescritto per pedofilia: &quot;Tutti insieme a tutela dell&#039;infanzia&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/03\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-03T07:30:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/01\/Duomo-Reggio-Calabria.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"851\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sebastiano Plutino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastiano Plutino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/03\\\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/03\\\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\\\/\"},\"author\":{\"name\":\"Sebastiano Plutino\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\"},\"headline\":\"Prete prescritto per pedofilia: Arcivescovo Morrone revoca nomina a don Perrello\",\"datePublished\":\"2024-07-03T07:30:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/03\\\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\\\/\"},\"wordCount\":311,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/03\\\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/01\\\/Duomo-Reggio-Calabria.jpg\",\"keywords\":[\"Antonio Marziale\",\"Arcivescovo Morrone\",\"reato di pedofilia prescritto\",\"revoca nomina a Don Perrello\"],\"articleSection\":[\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/03\\\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/03\\\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\\\/\",\"name\":\"Arcivescovo Morrone revoca nomina don Perrello. Plauso Marziale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/03\\\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/03\\\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/01\\\/Duomo-Reggio-Calabria.jpg\",\"datePublished\":\"2024-07-03T07:30:31+00:00\",\"description\":\"Marziale ringrazia il presule dopo revoca del parroco prescritto per pedofilia: \\\"Tutti insieme a tutela dell'infanzia\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/03\\\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/03\\\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/03\\\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/01\\\/Duomo-Reggio-Calabria.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/01\\\/Duomo-Reggio-Calabria.jpg\",\"width\":851,\"height\":315},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/03\\\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prete prescritto per pedofilia: Arcivescovo Morrone revoca nomina a don Perrello\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\",\"name\":\"Sebastiano Plutino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"caption\":\"Sebastiano Plutino\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/sebastiano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arcivescovo Morrone revoca nomina don Perrello. Plauso Marziale","description":"Marziale ringrazia il presule dopo revoca del parroco prescritto per pedofilia: \"Tutti insieme a tutela dell'infanzia\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/03\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\/","og_locale":"it_IT","og_type":"article","og_title":"Arcivescovo Morrone revoca nomina don Perrello. Plauso Marziale","og_description":"Marziale ringrazia il presule dopo revoca del parroco prescritto per pedofilia: \"Tutti insieme a tutela dell'infanzia\"","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/03\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\/","og_site_name":"Radio Touring 104","article_published_time":"2024-07-03T07:30:31+00:00","og_image":[{"width":851,"height":315,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/01\/Duomo-Reggio-Calabria.jpg","type":"image\/jpeg"}],"author":"Sebastiano Plutino","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Sebastiano Plutino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/03\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/03\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\/"},"author":{"name":"Sebastiano Plutino","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e"},"headline":"Prete prescritto per pedofilia: Arcivescovo Morrone revoca nomina a don Perrello","datePublished":"2024-07-03T07:30:31+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/03\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\/"},"wordCount":311,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/03\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/01\/Duomo-Reggio-Calabria.jpg","keywords":["Antonio Marziale","Arcivescovo Morrone","reato di pedofilia prescritto","revoca nomina a Don Perrello"],"articleSection":["Home","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/03\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/03\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\/","name":"Arcivescovo Morrone revoca nomina don Perrello. Plauso Marziale","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/03\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/03\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/01\/Duomo-Reggio-Calabria.jpg","datePublished":"2024-07-03T07:30:31+00:00","description":"Marziale ringrazia il presule dopo revoca del parroco prescritto per pedofilia: \"Tutti insieme a tutela dell'infanzia\"","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/03\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/03\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/03\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/01\/Duomo-Reggio-Calabria.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/01\/Duomo-Reggio-Calabria.jpg","width":851,"height":315},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/03\/prete-prescritto-per-pedofilia-arcivescovo-morrone-revoca-nomina-a-don-perrello\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Prete prescritto per pedofilia: Arcivescovo Morrone revoca nomina a don Perrello"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e","name":"Sebastiano Plutino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","caption":"Sebastiano Plutino"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/sebastiano\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/01\/Duomo-Reggio-Calabria.jpg","_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/54351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=54351"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/54351\/revisions"}],"predecessor-version":[{"id":54352,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/54351\/revisions\/54352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/43695"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=54351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=54351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=54351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}