{"id":54904,"date":"2024-07-13T09:36:23","date_gmt":"2024-07-13T07:36:23","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=54904"},"modified":"2024-07-13T09:36:23","modified_gmt":"2024-07-13T07:36:23","slug":"la-fidapa-dedica-un-evento-a-michele-affidato","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/la-fidapa-dedica-un-evento-a-michele-affidato\/","title":{"rendered":"La FIDAPA dedica un evento a Michele Affidato"},"content":{"rendered":"<p style=\"text-align: justify\">La FIDAPA (Federazione Italiana Donne Arti Professioni Affari), Sezione di Melito Porto Salvo, ha dato vita a un evento dedicato all\u2019arte e alla maestria di Michele Affidato, dal titolo: \u201cFIDAPA celebra l\u2019arte del maestro Michele Affidato &#8211; l\u2019orafo della Magna Grecia\u201d, tenutosi all\u2019interno del Centro Polifunzionale \u201cPaolo Flachi\u201d. L\u2019evento ha visto una partecipazione entusiasta e numerosa di ospiti, i quali hanno avuto l\u2019opportunit\u00e0 di ammirare alcune delle opere pi\u00f9 emblematiche e raffinate del maestro orafo, che hanno incantato il pubblico con la loro bellezza e unicit\u00e0. Michele Affidato, riconosciuto a livello internazionale, orafo della Santa Sede, nelle sue creazioni riesce a fondere, tradizione e innovazione, riflettendo l\u2019antica arte orafa della Magna Grecia, attualizzandola con canoni moderni. La serata \u00e8 stata ulteriormente impreziosita dagli interventi istituzionali della dott.ssa Anna Rita Foti, Presidente della FIDAPA BPW Italy sezione di Melito di Porto Salvo, e del vice Sindaco Daniela Demetrio, la conduzione e la direzione artistica dell\u2019evento \u00e8 stata curata da Tosca Pizzi. Un momento particolarmente emozionante \u00e8 stato poi l\u2019intervento artistico \u201cStorie dal mare\u201d, a cura di Maria Gurnari, che ha aggiunto un tocco di magia alla serata. Michele Affidato ha affascinato il pubblico raccontando la sua storia. Una sintesi di passione, estro e realt\u00e0 preziose. Gli ospiti hanno potuto osservare dal vivo alcune delle sue creazioni, realizzate interamente a mano, esibite in una sfilata ed indossate dalle socie della FIDAPA. La partecipazione di Affidato ha offerto un&#8217;opportunit\u00e0 unica per ascoltare la testimonianza di un uomo che, sin dall\u2019inizio del suo lavoro, ha creduto e investito nella sua terra natia, portando in alto il nome della Calabria. Questo evento, rappresenta un&#8217;altra tappa importante per la FIDAPA sezione di Melito Porto Salvo &#8211; Distretto Sud-Ovest, che ha scelto di celebrare l&#8217;arte e la storia locale. L\u2019evento \u00e8 stato un\u2019occasione unica, non solo per celebrare il talento, la creativit\u00e0 e l\u2019estro di Affidato, ma anche per promuovere l\u2019importanza dell\u2019artigianato artistico calabrese. La FIDAPA, da sempre impegnata nella valorizzazione delle eccellenze femminili e nella promozione della cultura e delle arti, si \u00e8 detta orgogliosa di aver potuto ospitare questa manifestazione. <em>&#8220;\u00c8 stato un vero onore per me essere celebrato dalla FIDAPA, un&#8217;associazione che da sempre valorizza le eccellenze artistiche e culturali &#8211; <\/em>ha spiegato Michele Affidato &#8211;<em> Questo evento ha rappresentato un&#8217;importante occasione per mostrare al pubblico l&#8217;arte orafa della Magna Grecia, un patrimonio che porto con orgoglio nelle mie creazioni <\/em>&#8211; ha aggiunto il maestro orafo &#8211;<em> ringrazio tutti coloro che hanno partecipato e contribuito a rendere questa serata speciale, dimostrando quanto sia forte il legame tra tradizione e innovazione nella nostra amata Calabria.&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La FIDAPA (Federazione Italiana Donne Arti Professioni Affari), Sezione di Melito Porto Salvo, ha dato vita a un evento dedicato all\u2019arte e alla maestria di Michele Affidato, dal titolo: \u201cFIDAPA&hellip;<\/p>\n","protected":false},"author":8,"featured_media":54905,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[921,196,140],"tags":[13726,339,673],"class_list":["post-54904","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-news","category-reggio-calabria","tag-fidapa","tag-melito-di-porto-salvo","tag-michele-affidato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La FIDAPA dedica un evento a Michele Affidato - Radio Touring 104<\/title>\n<meta name=\"description\" content=\"La FIDAPA, Sezione di Melito Porto Salvo, ha dato vita a un evento dedicato all\u2019arte e alla maestria di Michele Affidato\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/la-fidapa-dedica-un-evento-a-michele-affidato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La FIDAPA dedica un evento a Michele Affidato - Radio Touring 104\" \/>\n<meta property=\"og:description\" content=\"La FIDAPA, Sezione di Melito Porto Salvo, ha dato vita a un evento dedicato all\u2019arte e alla maestria di Michele Affidato\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/la-fidapa-dedica-un-evento-a-michele-affidato\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-13T07:36:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/07\/Michele-Affidato.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1468\" \/>\n\t<meta property=\"og:image:height\" content=\"1048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Filippo Francesco Idone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Filippo Francesco Idone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/13\\\/la-fidapa-dedica-un-evento-a-michele-affidato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/13\\\/la-fidapa-dedica-un-evento-a-michele-affidato\\\/\"},\"author\":{\"name\":\"Filippo Francesco Idone\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\"},\"headline\":\"La FIDAPA dedica un evento a Michele Affidato\",\"datePublished\":\"2024-07-13T07:36:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/13\\\/la-fidapa-dedica-un-evento-a-michele-affidato\\\/\"},\"wordCount\":448,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/13\\\/la-fidapa-dedica-un-evento-a-michele-affidato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/07\\\/Michele-Affidato.jpg\",\"keywords\":[\"Fidapa\",\"Melito di Porto Salvo\",\"Michele Affidato\"],\"articleSection\":[\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/13\\\/la-fidapa-dedica-un-evento-a-michele-affidato\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/13\\\/la-fidapa-dedica-un-evento-a-michele-affidato\\\/\",\"name\":\"La FIDAPA dedica un evento a Michele Affidato - Radio Touring 104\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/13\\\/la-fidapa-dedica-un-evento-a-michele-affidato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/13\\\/la-fidapa-dedica-un-evento-a-michele-affidato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/07\\\/Michele-Affidato.jpg\",\"datePublished\":\"2024-07-13T07:36:23+00:00\",\"description\":\"La FIDAPA, Sezione di Melito Porto Salvo, ha dato vita a un evento dedicato all\u2019arte e alla maestria di Michele Affidato\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/13\\\/la-fidapa-dedica-un-evento-a-michele-affidato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/13\\\/la-fidapa-dedica-un-evento-a-michele-affidato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/13\\\/la-fidapa-dedica-un-evento-a-michele-affidato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/07\\\/Michele-Affidato.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/07\\\/Michele-Affidato.jpg\",\"width\":1468,\"height\":1048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/13\\\/la-fidapa-dedica-un-evento-a-michele-affidato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La FIDAPA dedica un evento a Michele Affidato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\",\"name\":\"Filippo Francesco Idone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"caption\":\"Filippo Francesco Idone\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/filippoidone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La FIDAPA dedica un evento a Michele Affidato - Radio Touring 104","description":"La FIDAPA, Sezione di Melito Porto Salvo, ha dato vita a un evento dedicato all\u2019arte e alla maestria di Michele Affidato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/la-fidapa-dedica-un-evento-a-michele-affidato\/","og_locale":"it_IT","og_type":"article","og_title":"La FIDAPA dedica un evento a Michele Affidato - Radio Touring 104","og_description":"La FIDAPA, Sezione di Melito Porto Salvo, ha dato vita a un evento dedicato all\u2019arte e alla maestria di Michele Affidato","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/la-fidapa-dedica-un-evento-a-michele-affidato\/","og_site_name":"Radio Touring 104","article_published_time":"2024-07-13T07:36:23+00:00","og_image":[{"width":1468,"height":1048,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/07\/Michele-Affidato.jpg","type":"image\/jpeg"}],"author":"Filippo Francesco Idone","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Filippo Francesco Idone","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/la-fidapa-dedica-un-evento-a-michele-affidato\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/la-fidapa-dedica-un-evento-a-michele-affidato\/"},"author":{"name":"Filippo Francesco Idone","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b"},"headline":"La FIDAPA dedica un evento a Michele Affidato","datePublished":"2024-07-13T07:36:23+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/la-fidapa-dedica-un-evento-a-michele-affidato\/"},"wordCount":448,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/la-fidapa-dedica-un-evento-a-michele-affidato\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/07\/Michele-Affidato.jpg","keywords":["Fidapa","Melito di Porto Salvo","Michele Affidato"],"articleSection":["Home","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/la-fidapa-dedica-un-evento-a-michele-affidato\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/la-fidapa-dedica-un-evento-a-michele-affidato\/","name":"La FIDAPA dedica un evento a Michele Affidato - Radio Touring 104","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/la-fidapa-dedica-un-evento-a-michele-affidato\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/la-fidapa-dedica-un-evento-a-michele-affidato\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/07\/Michele-Affidato.jpg","datePublished":"2024-07-13T07:36:23+00:00","description":"La FIDAPA, Sezione di Melito Porto Salvo, ha dato vita a un evento dedicato all\u2019arte e alla maestria di Michele Affidato","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/la-fidapa-dedica-un-evento-a-michele-affidato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/la-fidapa-dedica-un-evento-a-michele-affidato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/la-fidapa-dedica-un-evento-a-michele-affidato\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/07\/Michele-Affidato.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/07\/Michele-Affidato.jpg","width":1468,"height":1048},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/la-fidapa-dedica-un-evento-a-michele-affidato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"La FIDAPA dedica un evento a Michele Affidato"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b","name":"Filippo Francesco Idone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","caption":"Filippo Francesco Idone"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/filippoidone\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/07\/Michele-Affidato.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/54904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=54904"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/54904\/revisions"}],"predecessor-version":[{"id":54906,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/54904\/revisions\/54906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/54905"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=54904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=54904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=54904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}