{"id":54932,"date":"2024-07-13T16:05:51","date_gmt":"2024-07-13T14:05:51","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=54932"},"modified":"2024-07-13T16:05:51","modified_gmt":"2024-07-13T14:05:51","slug":"enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\/","title":{"rendered":"Enrico Lazzaretto passa alla Domotek Volley Reggio Calabria"},"content":{"rendered":"<p style=\"text-align: justify\">Freme. Nell&#8217;attesa di conoscere <strong>Reggio Calabria Enrico Lazzaretto<\/strong> freme. Ormai non manca molto, complice una vacanza in Calabria gi\u00e0 programmata, come fosse una mossa molto ben congegnata dal destino, lo schiacciatore padovano sar\u00e0 in riva allo Stretto, insieme alla compagna Livia che per la prima volta si trasferir\u00e0 con lui, gi\u00e0 alla vigilia di Ferragosto. Fa rumore, tanto rumore, il passo di partenza sul mercato della <strong>Domotek Volley Reggio Calabria<\/strong> che, per salutare la serie A3 stretta a s\u00e9 la sera dell&#8217;8 giugno, ha acceso la miccia con un giocatore esaltante in campo e messaggero di gioia contagiosa nella vita. La scintilla \u00e8 scoccata in fretta tra societ\u00e0 e giocatore, le sensazioni reciproche subito positive e l&#8217;unione si \u00e8 concretizzata favorevolmente. Enrico, 29enne di 1,98 centimetri, riesce a far andare d&#8217;amore e d&#8217;accordo la maturit\u00e0 immagazzinata in nove anni di Serie A con una vivace freschezza, atletica ed emotiva:<em> &#8220;Mi sento meglio rispetto a quando avevo 24 anni. Sono migliorato anche fisicamente. Il bagaglio di esperienza, sicuramente ricco, \u00e8 una risorsa che mi avvantaggia perch\u00e9, a certi livelli, essere pratici di situazioni gi\u00e0 ben conosciute aiuta tanto, ma la voglia di vincere e la fame di risultati importanti sono rimaste intatte, sempre al top&#8221;. <\/em><\/p>\n<p style=\"text-align: justify\">Delle sue qualit\u00e0 tecniche, del suo stile coinvolgente, ha offerto saggi ovunque si sia fermato per martellare palloni sul taraflex. Il contatto con <strong>l&#8217;A1<\/strong> nella sua Padova, dove ha modellato, gi\u00e0 da adolescente, i fondamentali rivelatisi determinanti nel corso della carriera. Potenza Picena ed Alessano in A2, poi di nuovo Padova, di nuovo A1. Due stagioni a Porto Viro, prima di trasferirsi a Macerata dove \u00e8 rimasto complessivamente tre anni. E da Macerata <strong>Enrico<\/strong> <strong>Lazzaretto<\/strong> viaggia spedito con la mente, nell&#8217;attesa di farlo anche nella realt\u00e0, verso Reggio Calabria, prima esperienza al sud dopo quella vissuta nel 2017\/2018 ad Alissano, in Puglia:<em><strong> &#8220;Trover\u00f2 una societ\u00e0 che,<\/strong> come una famiglia, riempir\u00e0 di attenzione ed affetto, i suoi figli e trover\u00f2 il calore dei tifosi che ci spingeranno verso traguardi ambiziosi&#8221;. Coltiva una fede inattaccabile nella coesione del gruppo: &#8220;L&#8217;unione di uno spogliatoio formato da giocatori che si divertono a giocare insieme \u00e8 la chiave di volta per superare qualsiasi ostacolo, rende molto pi\u00f9 facile vincere perch\u00e9 si gioca con spensieratezza&#8221;<\/em>.<\/p>\n<p style=\"text-align: justify\"><strong>Lazzaretto<\/strong>, pur essendo un attaccante puro in grado di aprire in due le retroguardie al di l\u00e0 della rete, \u00e8 fortemente orientato a migliorare a muro e a dare continuit\u00e0 ai suoi progressi enormi in ricezione: <em>&#8220;Mai si smette di imparare, mai si smette quel lavoro di perfezionamento dei fondamentali che completa un giocatore&#8221;.<\/em> \u00c8 cosciente del ruolo centrale che, nelle tracce di gioco di mister Polimeni, dovr\u00e0 rivestire e questo, per un amante delle sfide come lui, non fa altro che elevare l&#8217;intensit\u00e0 dell&#8217;adrenalina di cui si nutre: &#8220;<em>Mi gasa parecchio prendermi responsabilit\u00e0, se sotto pressione riesco a dare il meglio e sapere che mi saranno assegnati compiti di massima responsabilit\u00e0 \u00e8 benzina nel motore delle mie aspirazioni. Voglio fare un ulteriore salto di qualit\u00e0 e sono prontissimo a dare tutto quello che \u00e8 nelle mie potenzialit\u00e0 per dare alla squadra ci\u00f2 che serve per arrivare il pi\u00f9 in alto possibile&#8221;.<\/em> Lo show pu\u00f2 cominciare, con Lazzaretto in campo non \u00e8 una promessa: \u00e8 una certezza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Freme. Nell&#8217;attesa di conoscere Reggio Calabria Enrico Lazzaretto freme. Ormai non manca molto, complice una vacanza in Calabria gi\u00e0 programmata, come fosse una mossa molto ben congegnata dal destino, lo&hellip;<\/p>\n","protected":false},"author":8,"featured_media":54933,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[196,140,144],"tags":[26780,33758,236],"class_list":["post-54932","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-reggio-calabria","category-sport","tag-domotek-volley-reggio-calabria","tag-enrico-lazzaretto","tag-reggio-calabria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Enrico Lazzaretto passa alla Domotek Volley Reggio Calabria - Radio Touring 104<\/title>\n<meta name=\"description\" content=\"Esplode il mercato della Domotek Volley Reggio Calabria: Enrico Lazzaretto \u00e8 il nuovo schiacciatore della squadra reggina\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enrico Lazzaretto passa alla Domotek Volley Reggio Calabria - Radio Touring 104\" \/>\n<meta property=\"og:description\" content=\"Esplode il mercato della Domotek Volley Reggio Calabria: Enrico Lazzaretto \u00e8 il nuovo schiacciatore della squadra reggina\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-13T14:05:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/07\/Enrico-Lazzaretto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"526\" \/>\n\t<meta property=\"og:image:height\" content=\"526\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Filippo Francesco Idone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Filippo Francesco Idone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/13\\\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/13\\\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\\\/\"},\"author\":{\"name\":\"Filippo Francesco Idone\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\"},\"headline\":\"Enrico Lazzaretto passa alla Domotek Volley Reggio Calabria\",\"datePublished\":\"2024-07-13T14:05:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/13\\\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\\\/\"},\"wordCount\":534,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/13\\\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/07\\\/Enrico-Lazzaretto.jpg\",\"keywords\":[\"Domotek Volley Reggio Calabria\",\"Enrico Lazzaretto\",\"reggio calabria\"],\"articleSection\":[\"News\",\"Reggio Calabria\",\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/13\\\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/13\\\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\\\/\",\"name\":\"Enrico Lazzaretto passa alla Domotek Volley Reggio Calabria - Radio Touring 104\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/13\\\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/13\\\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/07\\\/Enrico-Lazzaretto.jpg\",\"datePublished\":\"2024-07-13T14:05:51+00:00\",\"description\":\"Esplode il mercato della Domotek Volley Reggio Calabria: Enrico Lazzaretto \u00e8 il nuovo schiacciatore della squadra reggina\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/13\\\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/13\\\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/13\\\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/07\\\/Enrico-Lazzaretto.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/07\\\/Enrico-Lazzaretto.jpg\",\"width\":526,\"height\":526},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/07\\\/13\\\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enrico Lazzaretto passa alla Domotek Volley Reggio Calabria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/4a82259ca52ac8702ad1a8f9e5a3120b\",\"name\":\"Filippo Francesco Idone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g\",\"caption\":\"Filippo Francesco Idone\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/filippoidone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enrico Lazzaretto passa alla Domotek Volley Reggio Calabria - Radio Touring 104","description":"Esplode il mercato della Domotek Volley Reggio Calabria: Enrico Lazzaretto \u00e8 il nuovo schiacciatore della squadra reggina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\/","og_locale":"it_IT","og_type":"article","og_title":"Enrico Lazzaretto passa alla Domotek Volley Reggio Calabria - Radio Touring 104","og_description":"Esplode il mercato della Domotek Volley Reggio Calabria: Enrico Lazzaretto \u00e8 il nuovo schiacciatore della squadra reggina","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\/","og_site_name":"Radio Touring 104","article_published_time":"2024-07-13T14:05:51+00:00","og_image":[{"width":526,"height":526,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/07\/Enrico-Lazzaretto.jpg","type":"image\/jpeg"}],"author":"Filippo Francesco Idone","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Filippo Francesco Idone","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\/"},"author":{"name":"Filippo Francesco Idone","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b"},"headline":"Enrico Lazzaretto passa alla Domotek Volley Reggio Calabria","datePublished":"2024-07-13T14:05:51+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\/"},"wordCount":534,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/07\/Enrico-Lazzaretto.jpg","keywords":["Domotek Volley Reggio Calabria","Enrico Lazzaretto","reggio calabria"],"articleSection":["News","Reggio Calabria","Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\/","name":"Enrico Lazzaretto passa alla Domotek Volley Reggio Calabria - Radio Touring 104","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/07\/Enrico-Lazzaretto.jpg","datePublished":"2024-07-13T14:05:51+00:00","description":"Esplode il mercato della Domotek Volley Reggio Calabria: Enrico Lazzaretto \u00e8 il nuovo schiacciatore della squadra reggina","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/07\/Enrico-Lazzaretto.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/07\/Enrico-Lazzaretto.jpg","width":526,"height":526},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/07\/13\/enrico-lazzaretto-passa-alla-domotek-volley-reggio-calabria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Enrico Lazzaretto passa alla Domotek Volley Reggio Calabria"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/4a82259ca52ac8702ad1a8f9e5a3120b","name":"Filippo Francesco Idone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7268715d2366395c3dd314385670e6484117d44f5c442e61e230f7008b7b62d3?s=96&d=mm&r=g","caption":"Filippo Francesco Idone"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/filippoidone\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/07\/Enrico-Lazzaretto.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/54932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=54932"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/54932\/revisions"}],"predecessor-version":[{"id":54934,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/54932\/revisions\/54934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/54933"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=54932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=54932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=54932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}