{"id":56315,"date":"2024-08-02T12:46:12","date_gmt":"2024-08-02T10:46:12","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=56315"},"modified":"2024-08-02T12:46:56","modified_gmt":"2024-08-02T10:46:56","slug":"carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2024\/08\/02\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\/","title":{"rendered":"Carceri Calabresi: presentata la relazione semestrale del Garante dei detenuti, Luca Muglia"},"content":{"rendered":"<p style=\"text-align: justify\">Gioved\u00ec<strong> 1 agosto 2024 la Cittadella regionale ha ospitato<\/strong> la conferenza stampa di presentazione del<strong>la Relazione semestrale del Garante<\/strong> regionale dei diritti delle persone detenute o private della libert\u00e0 personale, <strong>avvocato Luca Muglia,<\/strong> il quale <strong>ha illustrato le condizioni di detenzione<\/strong> e lo stato dei diritti umani negli istituti penitenziari e negli altri luoghi di privazione della libert\u00e0 personale ubicati in Calabria. La Relazione semestrale del Garante regionale ha analizzato svariati aspetti, evidenziando un peggioramento ed aggravamento del quadro generale.<\/p>\n<p style=\"text-align: justify\"><strong>GRAVI LACUNE DI SISTEMA<\/strong><\/p>\n<p style=\"text-align: justify\">Le criticit\u00e0 del sistema penitenziario calabrese rilevate riguardano: il sovraffollamento (10 istituti su 12, con picchi elevati su Locri, Castrovillari, Cosenza, Crotone, Reggio San Pietro); le condizioni strutturali delle carceri, datate nel tempo, umide e prive di manutenzione; l\u2019inadeguatezza di diverse camere detentive (talune con schermature opache in plexiglass alle finestre o prive di docce); le gravi carenze di organico. La Relazione dedica un focus alle sezioni femminili del carcere di Castrovillari e di Reggio Calabria, analizzandone caratteristiche e peculiarit\u00e0, all\u2019esecuzione penale esterna e alla detenzione minorile (Istituto Penale Minorile, Comunit\u00e0 ministeriali di Catanzaro e Reggio Calabria). Con riferimento a quest\u2019ultima si conferma la presenza di giovani multiproblematici, dediti all\u2019assunzione di sostanze stupefacenti e farmacologiche, con problemi di controllo o regolazione di emozioni, impulsi e comportamenti. Quanto agli ingressi in IPM si rileva gi\u00e0 un + 26,3 % rispetto all\u2019anno precedente, con prevalenza di detenuti (minori e giovani adulti) giudicabili e non definitivi.<\/p>\n<p style=\"text-align: justify\"><strong>DIRITTI UMANI FONDAMENTALI <\/strong><\/p>\n<p style=\"text-align: justify\">A proposito dello stato dei diritti umani fondamentali l\u2019indagine del Garante ha accertato svariate lacune in Calabria: la mancata approvazione o possibilit\u00e0 di consultazione del Regolamento d\u2019istituto; l\u2019omessa consegna o disponibilit\u00e0 della Carta dei diritti e dei doveri dei detenuti (quasi mai tradotta in altre lingue); l\u2019esigua presenza di camere detentive per persone disabili; l\u2019utilizzo improprio della sezione riservata ai nuovi giunti.<\/p>\n<p style=\"text-align: justify\"><strong>REPORT DEGLI EVENTI CRITICI<\/strong><\/p>\n<p style=\"text-align: justify\">La relazione contiene il report degli eventi critici registrati presso gli istituti penitenziari calabresi nel periodo compreso tra i1 gennaio e il 12 giugno 2024, acquisiti grazie alla collaborazione del Garante nazionale dei diritti delle persone private della libert\u00e0 personale. Le informazioni (decessi, suicidi, tentati suicidi, atti di autolesionismo, manifestazioni di protesta, aggressioni, isolamento, infrazioni disciplinari, perquisizioni, etc) mettono in risalto due aspetti: 1) le forme di vulnerabilit\u00e0 delle persone detenute; 2) la natura dei conflitti che vengono ad instaurarsi negli istituti penitenziari. Dalla comparazione con i dati degli eventi critici registrati nel 2023 si evince che la percentuale media \u00e8 rimasta inalterata, che in alcuni istituti si \u00e8 rilevato un incremento e che nelle sezioni a custodia attenuata gli eventi critici sono sostanzialmente assenti. In Calabria nel 2024, in meno di sei mesi si sono registrati 5.306 eventi critici tra i quali 2 suicidi, 80 tentati suicidi, 225 atti di autolesionismo e 2 75 aggressioni fisiche alla Polizia penitenziaria. Si consideri che, nelle more, si \u00e8 verificato presso la Casa circondariale di Paola il terzo decesso per suicidio dall\u2019inizio dell\u2019anno. PERCENTUALE DI DETENUTI DEFINITIVI O GIUDICABILI A fronte di una popolazione detenuta che in Calabria raggiunge le 2.998 unit\u00e0, i detenuti definitivi sono 1.677. La parte residua, il 40% circa, \u00e8 costituita da detenuti giudicabili (in attesa di primo giudizio, appellanti, ricorrenti) ovvero con posizione mista. Il dato \u00e8 estremamente significativo.<\/p>\n<p style=\"text-align: justify\"><strong>REMS &#8211; RESIDENZE PER L\u2019ESECUZIONE DELLE MISURE DI SICUREZZA<\/strong><\/p>\n<p style=\"text-align: justify\">Le strutture di Santa Sofia d\u2019Epiro e Girifalco sono a pieno regime e ospitano 20 pazienti ciascuna. Allo stato non vi sono persone detenute in carcere, sine titulo, in attesa di una collocazione in REMS, mentre sono 27 le persone in stato di libert\u00e0 che attendono di essere collocate in una REMS. Il dato pi\u00f9 preoccupante \u00e8 che in Calabria il tempo medio di permanenza delle persone in lista di attesa per l\u2019ingresso in REMS supera 2 anni. L\u2019auspicio \u00e8 che, a breve, possa essere attivato il secondo modulo della REMS di Girifalco che consentirebbe di ospitare altri 20 pazienti. RACCOLTA DATI CARITAS DIOCESANE A seguito dell\u2019audizione dinanzi alla Conferenza Episcopale Calabra il Garante Muglia ha partecipato all\u2019incontro regionale delle delegazioni Caritas Diocesane svoltosi a Lamezia Terme, concordando in tale occasione con il responsabile regionale, Don Bruno Di Domenico, l\u2019acquisizione di tutte le informazioni utili. L\u2019obiettivo era quello di accertare quali fossero in Calabria i progetti di giustizia riparativa e di inclusione sociale destinati alle persone detenute, private della libert\u00e0 personale o in esecuzione penale esterna. Nella Relazione semestrale \u00e8 inserita una nutrita raccolta dati riguardanti i progetti delle Caritas Diocesane calabresi.<\/p>\n<p style=\"text-align: justify\"><strong>RACCOMADAZIONI, PROTOCOLLI E LINEE GUIDA DEL GARANTE REGIONALE PROTOCOLLI SERVIZI DEMOGRAFICI (ANAGRAFE E STATO CIVILE) <\/strong><\/p>\n<p style=\"text-align: justify\">Il Garante regionale ha sollecitato tutti i Comuni delle citt\u00e0 calabresi in cui sono ubicati gli Istituti penitenziari a sottoscrivere Protocolli di intesa con gli Istituti penitenziari volti ad individuare soluzioni operative circa i problemi legati all\u2019identificazione, al rilascio dei documenti, alla residenza dei detenuti senza fissa dimora (italiani e stranieri) e alle questioni riguardanti i detenuti richiedenti asilo e titolari di protezione, nonch\u00e9 al riconoscimento dei figli. L\u2019Ufficio del Garante regionale ha indicato ai Comuni interessati l\u2019adozione di alcune prassi virtuose recepite nelle altre regioni, fornendo il proprio supporto e allegando la documentazione utile. Il primo ad essere sottoscritto \u00e8 il Protocollo di intesa tra il Comune di Vibo Valentia e la Casa circondariale di Vibo Valentia, definito grazie alla collaborazione del Sindaco Maria Limardo, dell\u2019Assessore alle Politiche Sociali Arcangelo Scionti, del Responsabile dei Servizi demografici Domenico Scuglia Libero e del Direttore della Casa circondariale Angela Marcello. Allo stato attuale \u00e8 in corso la definizione di analoghi protocolli presso la citt\u00e0 di Locri e di Castrovillari.<\/p>\n<p style=\"text-align: justify\"><strong>LINEE GUIDA CARCERE, GENITORIALITA\u2019 E INCONTRI CON I FIGLI MINORI <\/strong><\/p>\n<p style=\"text-align: justify\">Le Linee guida del Garante regionale contengono le Raccomandazioni in ordine ai procedimenti di limitazione della responsabilit\u00e0 genitoriale che riguardano persone detenute, nonch\u00e9 la tutela del diritto dei figli minori d\u2019et\u00e0 al legame continuativo ed affettivo con il genitore detenuto. La finalit\u00e0 primaria \u00e8 quella di contemperare le esigenze di tutela della persona detenuta, avuto riguardo all\u2019esercizio delle funzioni genitoriali e alle garanzie procedurali in ambito giudiziario, con le esigenze di tutela dei figli minori d\u2019et\u00e0 e l\u2019esercizio del diritto alla bigenitorialit\u00e0 nei casi in cui il genitore sia ristretto in un luogo di detenzione. Le Linee guida sono state precedute da importanti interlocuzioni istituzionali e sono state giudicate favorevolmente dagli addetti ai lavori quali direttive estensibili all\u2019intero territorio nazionale.<\/p>\n<p style=\"text-align: justify\"><strong>DICHIARAZIONI CONCLUSIVE<\/strong><\/p>\n<p style=\"text-align: justify\"><em>\u201cL\u2019auspicio\u201d \u2013<\/em><strong> ha dichiarato il Garante Muglia<\/strong> \u2013<em> \u201c\u00e8 che i dati acquisiti e le indagini effettuate a cura del mio Ufficio possano contribuire alla promozione ed attuazione dei diritti fondamentali a tutela delle persone detenute o private della libert\u00e0 personale. Risulta evidente che occorre una maggiore e pi\u00f9 puntuale attenzione alle problematiche penitenziarie rilevate in Calabria e che necessitano, altres\u00ec, provvedimenti legislativi ed organizzativi indifferibili ed urgenti. Non c\u2019\u00e8 pi\u00f9 tempo!\u201d<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gioved\u00ec 1 agosto 2024 la Cittadella regionale ha ospitato la conferenza stampa di presentazione della Relazione semestrale del Garante regionale dei diritti delle persone detenute o private della libert\u00e0 personale,&hellip;<\/p>\n","protected":false},"author":12,"featured_media":56318,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[142,921,150,196],"tags":[34568,5375,17282,34567],"class_list":["post-56315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-home","category-in-primo-piano","category-news","tag-necessitano-dei-provvedimenti-legislativi-urgenti","tag-cittadella-regionale","tag-garante-muglia","tag-presentata-la-relazione-semestrale-del-garante-dei-detenuti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carceri Calabresi: presentata la relazione semestrale del Garante dei detenuti, Luca Muglia - Radio Touring 104<\/title>\n<meta name=\"description\" content=\"&quot;Necessitano dei provvedimenti legislativi ed organizzativi urgenti, non c&#039;\u00e8 pi\u00f9 tempo&quot;, tuona il Garante dei detenuti calabrese, Luca Muglia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/08\/02\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carceri Calabresi: presentata la relazione semestrale del Garante dei detenuti, Luca Muglia - Radio Touring 104\" \/>\n<meta property=\"og:description\" content=\"&quot;Necessitano dei provvedimenti legislativi ed organizzativi urgenti, non c&#039;\u00e8 pi\u00f9 tempo&quot;, tuona il Garante dei detenuti calabrese, Luca Muglia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/08\/02\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-02T10:46:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-02T10:46:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/08\/Luca-Muglia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1306\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sebastiano Plutino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastiano Plutino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/08\\\/02\\\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/08\\\/02\\\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\\\/\"},\"author\":{\"name\":\"Sebastiano Plutino\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\"},\"headline\":\"Carceri Calabresi: presentata la relazione semestrale del Garante dei detenuti, Luca Muglia\",\"datePublished\":\"2024-08-02T10:46:12+00:00\",\"dateModified\":\"2024-08-02T10:46:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/08\\\/02\\\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\\\/\"},\"wordCount\":1127,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/08\\\/02\\\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/08\\\/Luca-Muglia.jpg\",\"keywords\":[\"\\\"Necessitano dei provvedimenti legislativi urgenti\",\"Cittadella Regionale\",\"Garante Muglia\",\"presentata la relazione semestrale del Garante dei detenuti\"],\"articleSection\":[\"Calabria\",\"Home\",\"In primo piano\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/08\\\/02\\\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/08\\\/02\\\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\\\/\",\"name\":\"Carceri Calabresi: presentata la relazione semestrale del Garante dei detenuti, Luca Muglia - Radio Touring 104\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/08\\\/02\\\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/08\\\/02\\\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/08\\\/Luca-Muglia.jpg\",\"datePublished\":\"2024-08-02T10:46:12+00:00\",\"dateModified\":\"2024-08-02T10:46:56+00:00\",\"description\":\"\\\"Necessitano dei provvedimenti legislativi ed organizzativi urgenti, non c'\u00e8 pi\u00f9 tempo\\\", tuona il Garante dei detenuti calabrese, Luca Muglia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/08\\\/02\\\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/08\\\/02\\\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/08\\\/02\\\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/08\\\/Luca-Muglia.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/08\\\/Luca-Muglia.jpg\",\"width\":1536,\"height\":1306},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/08\\\/02\\\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carceri Calabresi: presentata la relazione semestrale del Garante dei detenuti, Luca Muglia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\",\"name\":\"Sebastiano Plutino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"caption\":\"Sebastiano Plutino\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/sebastiano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carceri Calabresi: presentata la relazione semestrale del Garante dei detenuti, Luca Muglia - Radio Touring 104","description":"\"Necessitano dei provvedimenti legislativi ed organizzativi urgenti, non c'\u00e8 pi\u00f9 tempo\", tuona il Garante dei detenuti calabrese, Luca Muglia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2024\/08\/02\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\/","og_locale":"it_IT","og_type":"article","og_title":"Carceri Calabresi: presentata la relazione semestrale del Garante dei detenuti, Luca Muglia - Radio Touring 104","og_description":"\"Necessitano dei provvedimenti legislativi ed organizzativi urgenti, non c'\u00e8 pi\u00f9 tempo\", tuona il Garante dei detenuti calabrese, Luca Muglia","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/08\/02\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\/","og_site_name":"Radio Touring 104","article_published_time":"2024-08-02T10:46:12+00:00","article_modified_time":"2024-08-02T10:46:56+00:00","og_image":[{"width":1536,"height":1306,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/08\/Luca-Muglia.jpg","type":"image\/jpeg"}],"author":"Sebastiano Plutino","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Sebastiano Plutino","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/08\/02\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/08\/02\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\/"},"author":{"name":"Sebastiano Plutino","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e"},"headline":"Carceri Calabresi: presentata la relazione semestrale del Garante dei detenuti, Luca Muglia","datePublished":"2024-08-02T10:46:12+00:00","dateModified":"2024-08-02T10:46:56+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/08\/02\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\/"},"wordCount":1127,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/08\/02\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/08\/Luca-Muglia.jpg","keywords":["\"Necessitano dei provvedimenti legislativi urgenti","Cittadella Regionale","Garante Muglia","presentata la relazione semestrale del Garante dei detenuti"],"articleSection":["Calabria","Home","In primo piano","News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/08\/02\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/08\/02\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\/","name":"Carceri Calabresi: presentata la relazione semestrale del Garante dei detenuti, Luca Muglia - Radio Touring 104","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/08\/02\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/08\/02\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/08\/Luca-Muglia.jpg","datePublished":"2024-08-02T10:46:12+00:00","dateModified":"2024-08-02T10:46:56+00:00","description":"\"Necessitano dei provvedimenti legislativi ed organizzativi urgenti, non c'\u00e8 pi\u00f9 tempo\", tuona il Garante dei detenuti calabrese, Luca Muglia","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/08\/02\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2024\/08\/02\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/08\/02\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/08\/Luca-Muglia.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/08\/Luca-Muglia.jpg","width":1536,"height":1306},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/08\/02\/carceri-calabresi-presentata-la-relazione-semestrale-del-garante-dei-detenuti-luca-muglia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Carceri Calabresi: presentata la relazione semestrale del Garante dei detenuti, Luca Muglia"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e","name":"Sebastiano Plutino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","caption":"Sebastiano Plutino"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/sebastiano\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/08\/Luca-Muglia.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/56315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=56315"}],"version-history":[{"count":2,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/56315\/revisions"}],"predecessor-version":[{"id":56321,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/56315\/revisions\/56321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/56318"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=56315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=56315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=56315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}