{"id":58306,"date":"2024-09-24T12:17:41","date_gmt":"2024-09-24T10:17:41","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=58306"},"modified":"2024-09-24T12:17:41","modified_gmt":"2024-09-24T10:17:41","slug":"milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2024\/09\/24\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\/","title":{"rendered":"Milia, FI \u201cDalla Biennale dello Stretto la forte consapevolezza che il rilancio del Mediterraneo \u00e8 possibile\u201d"},"content":{"rendered":"<p style=\"text-align: justify\"><em>\u201cUn laboratorio di idee declinate in varie forme, <\/em><strong><em>dall\u2019architettura<\/em><\/strong><strong><em>, <\/em><\/strong><strong><em>all\u2019arte, al cinema, alla fotografia<\/em><\/strong><strong><em>, alla narrativa: <\/em><\/strong><em>l&#8217;esposizione delle installazioni artistiche e le mostre fotografiche<\/em><em> degli artisti intervenuti alla Biennale dello stretto ci mostrano le potenzialit\u00e0 enormi delle citt\u00e0 del Mediterraneo.<\/em><\/p>\n<p style=\"text-align: justify\"><em>Attraverso l\u2019elemento dell\u2019acqua, \u00e8 possibile concretizzare una nuova idea di sviluppo di un\u2019intera area, che nasce dalla coesione di citt\u00e0 apparentemente divise, ma al contempo unite dal mare\u201d<\/em>.<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">Cos\u00ec il capogruppo di Forza Italia in consiglio comunale, Federico Milia, commenta la seconda edizione della Biennale dello stretto, l&#8217;evento culturale con la direzione di\u00a0Mariangela Cama, Alfonso Femia e Francesca Moraci in mostra al Forte Batteria Siacci di Campo Calabro: \u201c<em>che merita di essere istituzionalizzato e di diventare un appuntamento fisso in citt\u00e0\u201d.<\/em><\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">\u201c<em>L\u2019ambientazione del forte e lo spettacolo mozzafiato dello stretto rafforzano ancor di pi\u00f9 quest\u2019idea: il nostro compito \u00e8 che queste nuove prospettive diventino punto di partenza per azioni concrete a beneficio del territorio<\/em>\u201d dichiara Milia.<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">\u201c<em>Come ha ricordato, in occasione della sua visita alla presentazione della Biennale la nostra eurodeputata On. Giusi Princi, che presto incontrer\u00e0 la neonominata commissaria UE del Mediterraneo, <\/em><strong><em>Dubravka \u0160uica<\/em><\/strong><strong><em>, assieme al Presidente Occhiuto, serve un\u2019attenzione strategica per quest\u2019area dalle enormi potenzialit\u00e0: azioni sinergiche che possano incidere direttamente sui territori e che possano favorire la crescita di tutte le citt\u00e0 del Mediterraneo<\/em><\/strong><strong>\u201d conclude Milia.<\/strong><\/p>\n<p style=\"text-align: justify\">\n","protected":false},"excerpt":{"rendered":"<p>\u201cUn laboratorio di idee declinate in varie forme, dall\u2019architettura, all\u2019arte, al cinema, alla fotografia, alla narrativa: l&#8217;esposizione delle installazioni artistiche e le mostre fotografiche degli artisti intervenuti alla Biennale dello&hellip;<\/p>\n","protected":false},"author":12,"featured_media":58307,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[921,140],"tags":[4415,3231,35654,35655],"class_list":["post-58306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-reggio-calabria","tag-biennale-dello-stretto","tag-federico-milia","tag-rilancio-mediterraneo","tag-rilancio-reggio-calabria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Milia: &quot;Biennale risultato che rilancio Mediterraneo \u00e8 possibile&quot;<\/title>\n<meta name=\"description\" content=\"\u201cLe idee e progetti esposti siano fonte di ispirazione per ripensare alle citt\u00e0 come traino per lo sviluppo di tutto il Sud\u201d, dichiara Milia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/09\/24\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Milia: &quot;Biennale risultato che rilancio Mediterraneo \u00e8 possibile&quot;\" \/>\n<meta property=\"og:description\" content=\"\u201cLe idee e progetti esposti siano fonte di ispirazione per ripensare alle citt\u00e0 come traino per lo sviluppo di tutto il Sud\u201d, dichiara Milia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/09\/24\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-24T10:17:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/09\/MILIA-Biennale-Stretto-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1895\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sebastiano Plutino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastiano Plutino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/09\\\/24\\\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/09\\\/24\\\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\\\/\"},\"author\":{\"name\":\"Sebastiano Plutino\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\"},\"headline\":\"Milia, FI \u201cDalla Biennale dello Stretto la forte consapevolezza che il rilancio del Mediterraneo \u00e8 possibile\u201d\",\"datePublished\":\"2024-09-24T10:17:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/09\\\/24\\\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\\\/\"},\"wordCount\":242,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/09\\\/24\\\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/09\\\/MILIA-Biennale-Stretto-scaled.jpg\",\"keywords\":[\"Biennale dello Stretto\",\"Federico Milia\",\"rilancio Mediterraneo\",\"rilancio Reggio Calabria\"],\"articleSection\":[\"Home\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/09\\\/24\\\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/09\\\/24\\\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\\\/\",\"name\":\"Milia: \\\"Biennale risultato che rilancio Mediterraneo \u00e8 possibile\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/09\\\/24\\\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/09\\\/24\\\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/09\\\/MILIA-Biennale-Stretto-scaled.jpg\",\"datePublished\":\"2024-09-24T10:17:41+00:00\",\"description\":\"\u201cLe idee e progetti esposti siano fonte di ispirazione per ripensare alle citt\u00e0 come traino per lo sviluppo di tutto il Sud\u201d, dichiara Milia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/09\\\/24\\\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/09\\\/24\\\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/09\\\/24\\\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/09\\\/MILIA-Biennale-Stretto-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/09\\\/MILIA-Biennale-Stretto-scaled.jpg\",\"width\":2560,\"height\":1895},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/09\\\/24\\\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Milia, FI \u201cDalla Biennale dello Stretto la forte consapevolezza che il rilancio del Mediterraneo \u00e8 possibile\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\",\"name\":\"Sebastiano Plutino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"caption\":\"Sebastiano Plutino\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/sebastiano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Milia: \"Biennale risultato che rilancio Mediterraneo \u00e8 possibile\"","description":"\u201cLe idee e progetti esposti siano fonte di ispirazione per ripensare alle citt\u00e0 come traino per lo sviluppo di tutto il Sud\u201d, dichiara Milia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2024\/09\/24\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\/","og_locale":"it_IT","og_type":"article","og_title":"Milia: \"Biennale risultato che rilancio Mediterraneo \u00e8 possibile\"","og_description":"\u201cLe idee e progetti esposti siano fonte di ispirazione per ripensare alle citt\u00e0 come traino per lo sviluppo di tutto il Sud\u201d, dichiara Milia","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/09\/24\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\/","og_site_name":"Radio Touring 104","article_published_time":"2024-09-24T10:17:41+00:00","og_image":[{"width":2560,"height":1895,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/09\/MILIA-Biennale-Stretto-scaled.jpg","type":"image\/jpeg"}],"author":"Sebastiano Plutino","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Sebastiano Plutino","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/09\/24\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/09\/24\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\/"},"author":{"name":"Sebastiano Plutino","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e"},"headline":"Milia, FI \u201cDalla Biennale dello Stretto la forte consapevolezza che il rilancio del Mediterraneo \u00e8 possibile\u201d","datePublished":"2024-09-24T10:17:41+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/09\/24\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\/"},"wordCount":242,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/09\/24\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/09\/MILIA-Biennale-Stretto-scaled.jpg","keywords":["Biennale dello Stretto","Federico Milia","rilancio Mediterraneo","rilancio Reggio Calabria"],"articleSection":["Home","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/09\/24\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/09\/24\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\/","name":"Milia: \"Biennale risultato che rilancio Mediterraneo \u00e8 possibile\"","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/09\/24\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/09\/24\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/09\/MILIA-Biennale-Stretto-scaled.jpg","datePublished":"2024-09-24T10:17:41+00:00","description":"\u201cLe idee e progetti esposti siano fonte di ispirazione per ripensare alle citt\u00e0 come traino per lo sviluppo di tutto il Sud\u201d, dichiara Milia","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/09\/24\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2024\/09\/24\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/09\/24\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/09\/MILIA-Biennale-Stretto-scaled.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/09\/MILIA-Biennale-Stretto-scaled.jpg","width":2560,"height":1895},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/09\/24\/milia-fi-dalla-biennale-dello-stretto-la-forte-consapevolezza-che-il-rilancio-del-mediterraneo-e-possibile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Milia, FI \u201cDalla Biennale dello Stretto la forte consapevolezza che il rilancio del Mediterraneo \u00e8 possibile\u201d"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e","name":"Sebastiano Plutino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","caption":"Sebastiano Plutino"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/sebastiano\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/09\/MILIA-Biennale-Stretto-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/58306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=58306"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/58306\/revisions"}],"predecessor-version":[{"id":58308,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/58306\/revisions\/58308"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/58307"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=58306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=58306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=58306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}