{"id":60818,"date":"2024-11-04T12:02:19","date_gmt":"2024-11-04T11:02:19","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=60818"},"modified":"2024-11-04T12:02:19","modified_gmt":"2024-11-04T11:02:19","slug":"reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/04\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\/","title":{"rendered":"Reggio, Truffe: Corte d&#8217;Appello assolve Santo Alfonso Martorano"},"content":{"rendered":"<p style=\"text-align: justify\">Sono<strong> cadute in Appello tutte le accuse a carico di Santo Alfonso Martorano,<\/strong> di 67 anni, titolare della &#8220;M3&#8221;,<strong> societ\u00e0 di intermediazione finanziaria<\/strong> al centro di un&#8217;inchiesta coordinata dalla Procura della Repubblica di Reggio Calabria.<\/p>\n<p style=\"text-align: justify\">La Corte d&#8217;Appello, presieduta da Alfredo Sicuro,<strong>\u00a0ha assolto<\/strong>, <em>&#8220;perch\u00e9 il fatto non sussiste&#8221;<\/em>, <strong>Martorano,<\/strong> che <strong>in primo grado era stato condannato a 4 anni e 8 mesi di reclusione con l&#8217;accusa di associazione per delinquer<\/strong>e finalizzata alla commissione di una serie di truffe ai danni di alcuni istituti bancari.<\/p>\n<p style=\"text-align: justify\"><strong>L&#8217;impianto accusatorio \u00e8 stato contestato,<\/strong> nel processo d&#8217;appello, dai difensori di Martorano e dei suoi familiari, gli avvocati Mario Antinucci, Mario Mazza, Roberto Zanotti e Sabrina Tirabassi, le tesi dei quali sono state accolte dal collegio giudicante.<strong> I giudici<\/strong> di secondo grado, inoltre,<strong> hanno revocato la confisca dei beni disposta a suo tempo a carico di Martorano.<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>In un una nota l&#8217;avvocato Antinucci sottolinea<\/strong> <em>&#8220;la gogna mediatico-giudiziaria&#8221; subita dai suoi clienti per accuse &#8220;risultate<\/em> &#8211; scrive il legale &#8211;<em> totalmente infondate. La famiglia Martorano ha sempre proclamato a gran voce la totale estraneit\u00e0 ai fatti contestati alle persone fisiche ed alle aziende del gruppo, senza mai perdere la fiducia nella cultura della legalit\u00e0 e nel rispetto delle decisioni della magistratura, ma soprattutto senza mai perdere la dignit\u00e0 delle persone oneste, nella fondamentale coerenza a quei principi di legalit\u00e0 economica che hanno da sempre costitutito la spina dorsale e le fondamenta del gruppo finanziario Martorano&#8221;.<\/em><\/p>\n<p style=\"text-align: justify\">Assolte anche la moglie e la figlia di Martorano, <strong>Antonina Maesano e Carmen Miriam Martorano<\/strong>, di 66 e 35 anni, che gestivano insieme a lui la societ\u00e0 di intermediazione finanziaria e che, in primo grado,<strong> erano state condannate, rispettivamente, a 4 anni e 6 mesi e ad un anno e 6 mesi di reclusione.<\/strong>\n<\/p>\n<p style=\"text-align: justify\">Secondo la Procura reggina, Martoran<strong>o avrebbe sfruttato apposite convenzioni sottoscritte con alcuni istituti bancari appropriandosi indebitamente<\/strong>, con artifizi e raggiri, di ingenti somme di denaro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono cadute in Appello tutte le accuse a carico di Santo Alfonso Martorano, di 67 anni, titolare della &#8220;M3&#8221;, societ\u00e0 di intermediazione finanziaria al centro di un&#8217;inchiesta coordinata dalla Procura&hellip;<\/p>\n","protected":false},"author":12,"featured_media":21019,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[921,196,140],"tags":[37116,37115,10414],"class_list":["post-60818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-news","category-reggio-calabria","tag-associazione-per-delinquere-finalizzata-alla-truffa","tag-assolto-santo-alfonso-martorano","tag-corte-dappello-di-reggio-calabria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reggio, Truffe: Corte d&#039;Appello assolve Santo Alfonso Martorano<\/title>\n<meta name=\"description\" content=\"La Corte d&#039;Appello di Reggio ha assolto l&#039;intermediatore finanziario, dall&#039;accusa di associazione a delinquere, finalizzata alla truffa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/04\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reggio, Truffe: Corte d&#039;Appello assolve Santo Alfonso Martorano\" \/>\n<meta property=\"og:description\" content=\"La Corte d&#039;Appello di Reggio ha assolto l&#039;intermediatore finanziario, dall&#039;accusa di associazione a delinquere, finalizzata alla truffa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/04\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-04T11:02:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/Corte-dAppello-rc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sebastiano Plutino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastiano Plutino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/04\\\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/04\\\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\\\/\"},\"author\":{\"name\":\"Sebastiano Plutino\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\"},\"headline\":\"Reggio, Truffe: Corte d&#8217;Appello assolve Santo Alfonso Martorano\",\"datePublished\":\"2024-11-04T11:02:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/04\\\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\\\/\"},\"wordCount\":317,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/04\\\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/03\\\/Corte-dAppello-rc.jpg\",\"keywords\":[\"associazione per delinquere finalizzata alla truffa\",\"assolto Santo Alfonso Martorano\",\"Corte d\u2019Appello di Reggio Calabria\"],\"articleSection\":[\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/04\\\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/04\\\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\\\/\",\"name\":\"Reggio, Truffe: Corte d'Appello assolve Santo Alfonso Martorano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/04\\\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/04\\\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/03\\\/Corte-dAppello-rc.jpg\",\"datePublished\":\"2024-11-04T11:02:19+00:00\",\"description\":\"La Corte d'Appello di Reggio ha assolto l'intermediatore finanziario, dall'accusa di associazione a delinquere, finalizzata alla truffa\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/04\\\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/04\\\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/04\\\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/03\\\/Corte-dAppello-rc.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/03\\\/Corte-dAppello-rc.jpg\",\"width\":640,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/04\\\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reggio, Truffe: Corte d&#8217;Appello assolve Santo Alfonso Martorano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\",\"name\":\"Sebastiano Plutino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"caption\":\"Sebastiano Plutino\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/sebastiano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reggio, Truffe: Corte d'Appello assolve Santo Alfonso Martorano","description":"La Corte d'Appello di Reggio ha assolto l'intermediatore finanziario, dall'accusa di associazione a delinquere, finalizzata alla truffa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/04\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\/","og_locale":"it_IT","og_type":"article","og_title":"Reggio, Truffe: Corte d'Appello assolve Santo Alfonso Martorano","og_description":"La Corte d'Appello di Reggio ha assolto l'intermediatore finanziario, dall'accusa di associazione a delinquere, finalizzata alla truffa","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/04\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\/","og_site_name":"Radio Touring 104","article_published_time":"2024-11-04T11:02:19+00:00","og_image":[{"width":640,"height":640,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/Corte-dAppello-rc.jpg","type":"image\/jpeg"}],"author":"Sebastiano Plutino","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Sebastiano Plutino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/04\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/04\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\/"},"author":{"name":"Sebastiano Plutino","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e"},"headline":"Reggio, Truffe: Corte d&#8217;Appello assolve Santo Alfonso Martorano","datePublished":"2024-11-04T11:02:19+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/04\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\/"},"wordCount":317,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/04\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/Corte-dAppello-rc.jpg","keywords":["associazione per delinquere finalizzata alla truffa","assolto Santo Alfonso Martorano","Corte d\u2019Appello di Reggio Calabria"],"articleSection":["Home","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/04\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/04\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\/","name":"Reggio, Truffe: Corte d'Appello assolve Santo Alfonso Martorano","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/04\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/04\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/Corte-dAppello-rc.jpg","datePublished":"2024-11-04T11:02:19+00:00","description":"La Corte d'Appello di Reggio ha assolto l'intermediatore finanziario, dall'accusa di associazione a delinquere, finalizzata alla truffa","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/04\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/04\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/04\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/Corte-dAppello-rc.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/Corte-dAppello-rc.jpg","width":640,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/04\/reggio-truffe-corte-dappello-assolve-santo-alfonso-martorano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Reggio, Truffe: Corte d&#8217;Appello assolve Santo Alfonso Martorano"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e","name":"Sebastiano Plutino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","caption":"Sebastiano Plutino"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/sebastiano\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/Corte-dAppello-rc.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/60818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=60818"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/60818\/revisions"}],"predecessor-version":[{"id":60819,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/60818\/revisions\/60819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/21019"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=60818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=60818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=60818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}