{"id":60879,"date":"2024-11-05T10:30:15","date_gmt":"2024-11-05T09:30:15","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=60879"},"modified":"2024-11-05T10:31:49","modified_gmt":"2024-11-05T09:31:49","slug":"gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/05\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\/","title":{"rendered":"Gal Terre Locridee organizza l&#8217;evento &#8220;Sapori e Identit\u00e0&#8221; per la valorizzazione dei territori"},"content":{"rendered":"<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><strong>Dall\u20198 all\u201911 novembre, Antonimina, Portigliola, Sant\u2019Ilario dello Ionio e Locri ospiteranno<\/strong> <em>\u201cSapori e identit\u00e0\u201d,<\/em> evento <strong>promosso dal Gal Terre Locridee<\/strong> in collaborazione con le amministrazioni comunali, <strong>dedicato alla valorizzazione dei prodotti tipici del territorio.<\/strong><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><strong>Un programma ricco e vario con incontri, degustazioni<\/strong> e convivialit\u00e0 per una manifestazione che celebra le radici culturali ed enogastronomiche della Calabria, facendo emergere il legame tra tradizione, gusto e benessere. Un\u2019esperienza autentica all\u2019insegna della sostenibilit\u00e0, della cultura e della salute.<\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><strong>Si parte da Antonimina, venerd\u00ec 8 novembre,<\/strong> dove, nell\u2019ambito della III edizione di <em>\u201cSan Martino in paese\u201d<\/em>, a cura dell\u2019associazione Enosis-Comitato Feste Antonimina,<strong> alle ore 17.00,<\/strong> avr\u00e0 luogo l\u2019inaugurazione del Museo dell\u2019Olio, presso <em>\u201cU Trappitedu\u201d,<\/em> dedicato alla storia e alla cultura dell\u2019olio di oliva. Alle 17.30, in Piazza Littorio, si terr\u00e0 il convegno sul tema \u201cAgricoltura di Resilienza &#8211; La Grossa di Gerace e il Suino Nero d\u2019Aspromonte\u201d. <strong>Dopo i saluti del sindaco Giuseppe Murdaca<\/strong> e della presidente di Enosis, <strong>Maria Fazzari,<\/strong> interverranno S.E. <strong>Monsignor Francesco Oliva,<\/strong> il parroco di Antonimina,<strong> Costant Soho<\/strong>; relazioneranno<strong> Renato Carullo,<\/strong> commissario Ente Parco Nazionale dell\u2019Aspromonte,<strong> Marco Poiana<\/strong>, direttore Dipartimento di Agraria dell\u2019Universit\u00e0 Mediterranea, <strong>Francesco Barretta,<\/strong> direttore della Cooperativa \u201cMaiale nero d\u2019Aspromonte\u201d, <strong>Filomena Citarro,<\/strong> direttore A.R.A. Calabria, <strong>Francesco Macr\u00ec,<\/strong> presidente G.A.L. \u201cTerre Locridee,<strong> Guido Mignolli,<\/strong> direttore Gal Terre Locridee. Dopo il convegno, alle ore 19.30, apertura stand espositivi di prodotti tipici e artigianali provenienti dalle aziende locali.<\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><strong>Sabato 9 novembre, a Sant\u2019Ilario dello Ionio, per<\/strong><em> \u201cColori del Sud\u201d<\/em> V edizione<strong>, a partire dalle 16.00, <\/strong>sar\u00e0 possibile visitare il borgo dove si trovano il Museo della Tradizione Contadina, il Laboratorio d\u2019Arte Trifoglio e la Casa degli Artisti,<strong> fondata da Renato Mollica<\/strong> che ha dato la propria disponibilit\u00e0 a fare da guida. Alle 17.30, si terr\u00e0 il convegno \u201cDieta mediterranea e longevit\u00e0\u201d, con gli interventi del <strong>sindaco Pasquale Brizzi,<\/strong> del presidente del Gal Terre Locridee,<strong> Francesco Macr\u00ec,<\/strong> e del direttore del Gal Terre Locridee, <strong>Guido Mignolli; Franco Carnovale<\/strong> testimonier\u00e0 l\u2019esperienza di Bivongi sui centenari. Sul tema <em>\u201cDieta mediterranea, sfida epocale per la sostenibilit\u00e0 e la salute\u201d<\/em> relazioner\u00e0<strong> Mariateresa Russo,<\/strong> presidente Societ\u00e0 italiana di Chimica degli alimenti. <strong>Alle 19.30 apertura stand<\/strong> dedicati alle pietanze della dieta mediterranea e mercatini artigianali. <strong>Alle 21.00 live con Ciccio Sax e Koko De Leo.<\/strong> Nel rispetto dell\u2019ambiente, lo spazio enogastronomico sar\u00e0 privo di materiali in plastica.<\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><strong>Domenica 10 novembre al Museo Nazionale di Locri Epizefiri, alle 17.30, si terr\u00e0 il convegno dal titolo<\/strong> <em>\u201cEx Vite Vita \u2013 Il vino dall\u2019antichit\u00e0 a oggi\u201d<\/em>. Dopo i saluti del presidente Gal Terre Locridee,<strong> Francesco Macr\u00ec,<\/strong> e del sindaco di Portigliola, <strong>Rocco Luglio,<\/strong> introdurr\u00e0 la direttrice del Museo e Parco archeologico nazionale di Locri Epizefiri,<strong> Elena Trunfio,<\/strong> <strong>relazioneranno Sara Balcon,<\/strong> funzionaria archeologa Direzione regionale Musei Calabrese, <strong>sul tema<\/strong>\u00a0<em>\u201cLa bevanda che unisce. Il vino nell\u2019Antica Calabria\u201d,<\/em> <strong>Marco Poiana,<\/strong> direttore Dipartimento Agraria Universit\u00e0 Mediterranea di Reggio Calabria,<em> \u201cConservazione e valorizzazione dei vigneti della Locride\u201d,<\/em> la biologa nutrizionista, <strong>Giovanna Anghelone,<\/strong> su \u201cPropriet\u00e0 e benefici del vino\u201d. <strong>Dopo il convegno,<\/strong> ci si sposter\u00e0 nel centro storico di Portigliola,<strong> alle 20.00,<\/strong> per una degustazione di pietanze preparate con olio e suino nero d\u2019Aspromonte, un vero e proprio viaggio nei sapori locali. La serata si concluder\u00e0 con il concerto live di Kalavria e uno spettacolo di fuochi pirotecnici.<\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><strong>Luned\u00ec 11 novembre, nel Palazzo della Cultura di Locri, alle ore 9.00, si terr\u00e0 il seminario sul tema<\/strong> <strong>\u201cModelli organizzativi della Filiera Olivicola biologica calabrese\u201d.<\/strong> Dopo i saluti del sindaco di Locri, <strong>Giuseppe Fontana,<\/strong> e della dirigente dell\u2019I.C. \u201cDe Amicis-Maresca\u201d di Locri, <strong>Carla Maria Pelagi,<\/strong> <strong>interverranno: Citraro Filomena,<\/strong> sul tema \u201cLe produzioni biologiche calabresi\u201d, <strong>Matteo Lentini su<\/strong> \u201cModello organizzativo di\u00a0 una filiera olivicola biologica\u201d, <strong>Fortunato La Capria<\/strong> su \u201cTecniche di produzione olivicola\u201d, <strong>Vincenzo Triunveri su<\/strong><em> \u201cLa Certificazione biologica nel settore olivicolo\u201d<\/em>. Seguir\u00e0 dibattito. Coordina i lavori il presidente del Gal Terre Locridee,<strong> Francesco Macr\u00ec. <\/strong><\/p>\n<p class=\"xmprfx_MsoNormal\" style=\"text-align: justify\"><strong>Dalle ore 15.00 alle 21.00, in Piazza dei Martiri, si terr\u00e0 l\u2019esposizione di prodotti biologici<\/strong> dei soci Anaprobio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dall\u20198 all\u201911 novembre, Antonimina, Portigliola, Sant\u2019Ilario dello Ionio e Locri ospiteranno \u201cSapori e identit\u00e0\u201d, evento promosso dal Gal Terre Locridee in collaborazione con le amministrazioni comunali, dedicato alla valorizzazione dei&hellip;<\/p>\n","protected":false},"author":12,"featured_media":60880,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[921,196,140],"tags":[2643,37147,3726,338,24344,2995],"class_list":["post-60879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-news","category-reggio-calabria","tag-antonimina","tag-evento-sapori-e-identita","tag-gal-terre-locridee","tag-locri","tag-portigliola","tag-santilario-dello-jonio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gal Terre Locridee :organizza l&#039;evento &quot;Sapori e Identit\u00e0&quot;<\/title>\n<meta name=\"description\" content=\"L&#039;evento, in collaborazione coi Comuni, si svolger\u00e0 dall&#039;8 all&#039;11 novembre a Antonimina, Portigliola, Sant\u2019Ilario dello Ionio e Locri\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/05\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gal Terre Locridee :organizza l&#039;evento &quot;Sapori e Identit\u00e0&quot;\" \/>\n<meta property=\"og:description\" content=\"L&#039;evento, in collaborazione coi Comuni, si svolger\u00e0 dall&#039;8 all&#039;11 novembre a Antonimina, Portigliola, Sant\u2019Ilario dello Ionio e Locri\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/05\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-05T09:30:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-05T09:31:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/11\/Sapori-Identita-GAL-TERRE-LOCRIDEE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1365\" \/>\n\t<meta property=\"og:image:height\" content=\"1838\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sebastiano Plutino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastiano Plutino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/05\\\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/05\\\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\\\/\"},\"author\":{\"name\":\"Sebastiano Plutino\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\"},\"headline\":\"Gal Terre Locridee organizza l&#8217;evento &#8220;Sapori e Identit\u00e0&#8221; per la valorizzazione dei territori\",\"datePublished\":\"2024-11-05T09:30:15+00:00\",\"dateModified\":\"2024-11-05T09:31:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/05\\\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\\\/\"},\"wordCount\":667,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/05\\\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/11\\\/Sapori-Identita-GAL-TERRE-LOCRIDEE.jpg\",\"keywords\":[\"antonimina\",\"evento \\\"Sapori e Identit\u00e0\\\"\",\"Gal Terre Locridee\",\"Locri\",\"Portigliola\",\"Sant'Ilario dello Jonio\"],\"articleSection\":[\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/05\\\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/05\\\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\\\/\",\"name\":\"Gal Terre Locridee :organizza l'evento \\\"Sapori e Identit\u00e0\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/05\\\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/05\\\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/11\\\/Sapori-Identita-GAL-TERRE-LOCRIDEE.jpg\",\"datePublished\":\"2024-11-05T09:30:15+00:00\",\"dateModified\":\"2024-11-05T09:31:49+00:00\",\"description\":\"L'evento, in collaborazione coi Comuni, si svolger\u00e0 dall'8 all'11 novembre a Antonimina, Portigliola, Sant\u2019Ilario dello Ionio e Locri\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/05\\\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/05\\\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/05\\\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/11\\\/Sapori-Identita-GAL-TERRE-LOCRIDEE.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/11\\\/Sapori-Identita-GAL-TERRE-LOCRIDEE.jpg\",\"width\":1365,\"height\":1838},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/05\\\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gal Terre Locridee organizza l&#8217;evento &#8220;Sapori e Identit\u00e0&#8221; per la valorizzazione dei territori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\",\"name\":\"Sebastiano Plutino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"caption\":\"Sebastiano Plutino\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/sebastiano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gal Terre Locridee :organizza l'evento \"Sapori e Identit\u00e0\"","description":"L'evento, in collaborazione coi Comuni, si svolger\u00e0 dall'8 all'11 novembre a Antonimina, Portigliola, Sant\u2019Ilario dello Ionio e Locri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/05\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\/","og_locale":"it_IT","og_type":"article","og_title":"Gal Terre Locridee :organizza l'evento \"Sapori e Identit\u00e0\"","og_description":"L'evento, in collaborazione coi Comuni, si svolger\u00e0 dall'8 all'11 novembre a Antonimina, Portigliola, Sant\u2019Ilario dello Ionio e Locri","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/05\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\/","og_site_name":"Radio Touring 104","article_published_time":"2024-11-05T09:30:15+00:00","article_modified_time":"2024-11-05T09:31:49+00:00","og_image":[{"width":1365,"height":1838,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/11\/Sapori-Identita-GAL-TERRE-LOCRIDEE.jpg","type":"image\/jpeg"}],"author":"Sebastiano Plutino","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Sebastiano Plutino","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/05\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/05\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\/"},"author":{"name":"Sebastiano Plutino","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e"},"headline":"Gal Terre Locridee organizza l&#8217;evento &#8220;Sapori e Identit\u00e0&#8221; per la valorizzazione dei territori","datePublished":"2024-11-05T09:30:15+00:00","dateModified":"2024-11-05T09:31:49+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/05\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\/"},"wordCount":667,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/05\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/11\/Sapori-Identita-GAL-TERRE-LOCRIDEE.jpg","keywords":["antonimina","evento \"Sapori e Identit\u00e0\"","Gal Terre Locridee","Locri","Portigliola","Sant'Ilario dello Jonio"],"articleSection":["Home","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/05\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/05\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\/","name":"Gal Terre Locridee :organizza l'evento \"Sapori e Identit\u00e0\"","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/05\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/05\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/11\/Sapori-Identita-GAL-TERRE-LOCRIDEE.jpg","datePublished":"2024-11-05T09:30:15+00:00","dateModified":"2024-11-05T09:31:49+00:00","description":"L'evento, in collaborazione coi Comuni, si svolger\u00e0 dall'8 all'11 novembre a Antonimina, Portigliola, Sant\u2019Ilario dello Ionio e Locri","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/05\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/05\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/05\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/11\/Sapori-Identita-GAL-TERRE-LOCRIDEE.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/11\/Sapori-Identita-GAL-TERRE-LOCRIDEE.jpg","width":1365,"height":1838},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/05\/gal-terre-locridee-organizza-levento-sapori-e-identitaper-valorizzare-i-territori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Gal Terre Locridee organizza l&#8217;evento &#8220;Sapori e Identit\u00e0&#8221; per la valorizzazione dei territori"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e","name":"Sebastiano Plutino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","caption":"Sebastiano Plutino"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/sebastiano\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/11\/Sapori-Identita-GAL-TERRE-LOCRIDEE.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/60879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=60879"}],"version-history":[{"count":3,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/60879\/revisions"}],"predecessor-version":[{"id":60883,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/60879\/revisions\/60883"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/60880"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=60879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=60879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=60879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}