{"id":62263,"date":"2024-11-27T11:07:02","date_gmt":"2024-11-27T10:07:02","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=62263"},"modified":"2024-11-27T11:08:07","modified_gmt":"2024-11-27T10:08:07","slug":"convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/27\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\/","title":{"rendered":"Convegno di Fidapa di Cosenza e Paola sulla Violenza di genere"},"content":{"rendered":"<p style=\"text-align: justify\">La violenza di genere \u00e8 una delle sfide sociali pi\u00f9 urgenti del nostro tempo, un fenomeno complesso che richiede interventi incisivi e multidisciplinari per essere affrontato in modo efficace. Domani, 27 novembre, alle ore 17, presso l\u2019Hotel San Francesco di Rende, la Fidapa (Federazione Italiana Donne Arti Professioni Affari), con le sezioni di Cosenza e Paola, promuove il convegno dal titolo \u201cViolenza di genere: la rieducazione \u00e8 possibile\u201d. L\u2019iniziativa, presieduta da Lucia Nicosia, presidente della Fidapa di Cosenza, e Laura Aloise, presidente della sezione di Paola, si pone l\u2019obiettivo di approfondire un tema cruciale e spesso trascurato: la rieducazione degli autori di violenza, una chiave fondamentale per interrompere il ciclo degli abusi e costruire una societ\u00e0 pi\u00f9 equa e sicura.<\/p>\n<p style=\"text-align: justify\">L\u2019evento si colloca in continuit\u00e0 con le numerose iniziative della Fidapa per la difesa delle donne e la promozione della parit\u00e0 di genere. In occasione della Giornata Internazionale contro la Violenza sulle Donne, celebrata il 25 novembre, la Fidapa di Cosenza ha aderito al progetto di Confagricoltura per una raccolta fondi a favore del Centro Antiviolenza Fabiana Luzzi, intitolato alla giovane vittima di un femminicidio che ha scosso profondamente il territorio. Il convegno di domani offrir\u00e0 un\u2019opportunit\u00e0 unica per approfondire il tema della rieducazione degli uomini autori di soprusi, un elemento spesso trascurato nella lotta alla violenza di genere.<\/p>\n<p style=\"text-align: justify\">La presidente della Fidapa di Cosenza, Lucia Nicosia, sottolinea l&#8217;importanza di sensibilizzare la societ\u00e0 civile: \u00ab\u00c8 fondamentale affrontare il problema alla radice. Senza percorsi strutturati di rieducazione per i maltrattanti, si rischia di perpetuare un ciclo di abusi che colpisce le vittime e, spesso, intere famiglie. L\u2019obiettivo deve essere quello di prevenire la recidiva e costruire una societ\u00e0 in cui il rispetto e l\u2019uguaglianza siano valori condivisi\u00bb.<\/p>\n<p style=\"text-align: justify\">Tra i relatori spiccano figure di rilievo come Giuseppe Zanfini, 1\u00b0 Dirigente della Polizia di Stato (delegato dal Questore Giuseppe Cannizzaro), e professioniste del settore che operano quotidianamente in ambiti di mediazione e prevenzione come Sara Serafini (socia e referente Fidapa sezione di Cosenza per Le donne nella Storia e nella Cultura), \u00a0Maria Esposito (socia e referente Fidapa sezione di Cosenza contro la Violenza sulle donne), Maria Cristina Ciambrone, (socia della sezione di Paola e presidente dell&#8217;associazione AIMEPE &#8211; Associazione Italiana Mediatori Penali).<\/p>\n<p style=\"text-align: justify\">Il focus sar\u00e0 sui percorsi psicoeducativi, che mirano non solo a ridurre il rischio di recidiva, ma anche a intervenire sulle radici culturali e psicologiche della violenza. Modificare le convinzioni tossiche e i comportamenti aggressivi degli autori di violenza \u00e8 essenziale per spezzare il ciclo degli abusi e garantire un futuro sicuro alle vittime. Questo approccio integrato, che combina protezione delle vittime e intervento sugli aggressori, \u00e8 considerato dalla Fidapa e dai suoi partner strategico per affrontare il fenomeno nella sua complessit\u00e0.<\/p>\n<p style=\"text-align: justify\">Il convegno si concluder\u00e0 con un appello a tutte le istituzioni, le associazioni e i cittadini: solo lavorando insieme \u00e8 possibile combattere la violenza di genere in ogni sua forma. La Fidapa, con il suo impegno costante e la collaborazione con altre realt\u00e0 come la Confagricoltura e i Centri Antiviolenza, continua a portare avanti progetti di sensibilizzazione, prevenzione e sostegno alle vittime.<\/p>\n<p style=\"text-align: justify\">\u00abNon \u00e8 solo un dovere morale \u2013 dichiara la presidente Lucia Nicosia \u2013 ma una responsabilit\u00e0 collettiva. Dobbiamo costruire una societ\u00e0 in cui ogni donna possa sentirsi al sicuro e valorizzata\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La violenza di genere \u00e8 una delle sfide sociali pi\u00f9 urgenti del nostro tempo, un fenomeno complesso che richiede interventi incisivi e multidisciplinari per essere affrontato in modo efficace. Domani,&hellip;<\/p>\n","protected":false},"author":12,"featured_media":13773,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[142,921,196],"tags":[38027,38028,38029],"class_list":["post-62263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-home","category-news","tag-hotel-san-francesco-di-rende","tag-convegno-violenza-di-genere-la-rieducazione-e-possibile","tag-fidapa-cosenza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Convegno di Fidapa di Cosenza e Paola sulla Violenza di genere - Radio Touring 104<\/title>\n<meta name=\"description\" content=\"Il convegno \u201cViolenza di genere: la rieducazione \u00e8 possibile\u201d si terr\u00e0 oggi, alle ore 17, presso l\u2019Hotel San Francesco di Rende\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/27\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Convegno di Fidapa di Cosenza e Paola sulla Violenza di genere - Radio Touring 104\" \/>\n<meta property=\"og:description\" content=\"Il convegno \u201cViolenza di genere: la rieducazione \u00e8 possibile\u201d si terr\u00e0 oggi, alle ore 17, presso l\u2019Hotel San Francesco di Rende\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/27\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-27T10:07:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-27T10:08:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/12\/violenza-donne.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"664\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sebastiano Plutino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastiano Plutino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/27\\\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/27\\\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\\\/\"},\"author\":{\"name\":\"Sebastiano Plutino\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\"},\"headline\":\"Convegno di Fidapa di Cosenza e Paola sulla Violenza di genere\",\"datePublished\":\"2024-11-27T10:07:02+00:00\",\"dateModified\":\"2024-11-27T10:08:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/27\\\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\\\/\"},\"wordCount\":549,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/27\\\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/12\\\/violenza-donne.jpg\",\"keywords\":[\"\u2019Hotel San Francesco di Rende\",\"convegno \u201cViolenza di genere: la rieducazione \u00e8 possibile\u201d\",\"Fidapa Cosenza\"],\"articleSection\":[\"Calabria\",\"Home\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/27\\\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/27\\\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\\\/\",\"name\":\"Convegno di Fidapa di Cosenza e Paola sulla Violenza di genere - Radio Touring 104\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/27\\\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/27\\\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/12\\\/violenza-donne.jpg\",\"datePublished\":\"2024-11-27T10:07:02+00:00\",\"dateModified\":\"2024-11-27T10:08:07+00:00\",\"description\":\"Il convegno \u201cViolenza di genere: la rieducazione \u00e8 possibile\u201d si terr\u00e0 oggi, alle ore 17, presso l\u2019Hotel San Francesco di Rende\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/27\\\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/27\\\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/27\\\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/12\\\/violenza-donne.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/12\\\/violenza-donne.jpg\",\"width\":1000,\"height\":664},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/11\\\/27\\\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Convegno di Fidapa di Cosenza e Paola sulla Violenza di genere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\",\"name\":\"Sebastiano Plutino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"caption\":\"Sebastiano Plutino\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/sebastiano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Convegno di Fidapa di Cosenza e Paola sulla Violenza di genere - Radio Touring 104","description":"Il convegno \u201cViolenza di genere: la rieducazione \u00e8 possibile\u201d si terr\u00e0 oggi, alle ore 17, presso l\u2019Hotel San Francesco di Rende","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/27\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\/","og_locale":"it_IT","og_type":"article","og_title":"Convegno di Fidapa di Cosenza e Paola sulla Violenza di genere - Radio Touring 104","og_description":"Il convegno \u201cViolenza di genere: la rieducazione \u00e8 possibile\u201d si terr\u00e0 oggi, alle ore 17, presso l\u2019Hotel San Francesco di Rende","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/27\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\/","og_site_name":"Radio Touring 104","article_published_time":"2024-11-27T10:07:02+00:00","article_modified_time":"2024-11-27T10:08:07+00:00","og_image":[{"width":1000,"height":664,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/12\/violenza-donne.jpg","type":"image\/jpeg"}],"author":"Sebastiano Plutino","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Sebastiano Plutino","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/27\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/27\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\/"},"author":{"name":"Sebastiano Plutino","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e"},"headline":"Convegno di Fidapa di Cosenza e Paola sulla Violenza di genere","datePublished":"2024-11-27T10:07:02+00:00","dateModified":"2024-11-27T10:08:07+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/27\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\/"},"wordCount":549,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/27\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/12\/violenza-donne.jpg","keywords":["\u2019Hotel San Francesco di Rende","convegno \u201cViolenza di genere: la rieducazione \u00e8 possibile\u201d","Fidapa Cosenza"],"articleSection":["Calabria","Home","News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/27\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/27\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\/","name":"Convegno di Fidapa di Cosenza e Paola sulla Violenza di genere - Radio Touring 104","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/27\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/27\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/12\/violenza-donne.jpg","datePublished":"2024-11-27T10:07:02+00:00","dateModified":"2024-11-27T10:08:07+00:00","description":"Il convegno \u201cViolenza di genere: la rieducazione \u00e8 possibile\u201d si terr\u00e0 oggi, alle ore 17, presso l\u2019Hotel San Francesco di Rende","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/27\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/27\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/27\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/12\/violenza-donne.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/12\/violenza-donne.jpg","width":1000,"height":664},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/11\/27\/convegno-di-fidapa-di-cosenza-e-paola-insieme-sulla-violenza-di-genere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Convegno di Fidapa di Cosenza e Paola sulla Violenza di genere"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e","name":"Sebastiano Plutino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","caption":"Sebastiano Plutino"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/sebastiano\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/12\/violenza-donne.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/62263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=62263"}],"version-history":[{"count":2,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/62263\/revisions"}],"predecessor-version":[{"id":62265,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/62263\/revisions\/62265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/13773"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=62263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=62263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=62263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}