{"id":63883,"date":"2024-12-20T12:36:28","date_gmt":"2024-12-20T11:36:28","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=63883"},"modified":"2024-12-20T12:36:28","modified_gmt":"2024-12-20T11:36:28","slug":"mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2024\/12\/20\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\/","title":{"rendered":"Mancuso ricorda la tragedia del viadotto della Fiumarella"},"content":{"rendered":"<p style=\"text-align: justify\">Non potendo partecipare all&#8217;evento, in quanto impegnato nella seduta odierna del Consiglio regionale, il presidente Filippo Mancuso ha inviato un messaggio per ricordare la strage del 23 dicembre 1961, avvenuta sul viadotto della Fiumarella di Catanzaro.<\/p>\n<p style=\"text-align: justify\">&#8220;La perdita di 71 vite, in gran parte giovani che affrontavano quel viaggio con la speranza di un futuro migliore, rimane una ferita incancellabile per le famiglie, le comunit\u00e0 e tutti noi che, ancora oggi, ne custodiamo il ricordo. La memoria di quelle vite spezzate deve essere per noi un monito costante, un richiamo alla responsabilit\u00e0 e all\u2019impegno per garantire sicurezza ed efficienza nei servizi pubblici, ma anche per costruire un futuro pi\u00f9 giusto per la nostra regione.<\/p>\n<p style=\"text-align: justify\">Il ricordo di quel dramma ci unisce, al di l\u00e0 di ogni differenza politica e culturale, nella convinzione che la memoria non \u00e8 solo un valore ma anche una responsabilit\u00e0. \u00c8 nostro dovere fare in modo che il sacrificio di quelle vite innocenti non sia stato vano e che il futuro delle nuove generazioni sia costruito su basi solide di sicurezza, equit\u00e0 e progresso.<\/p>\n<p style=\"text-align: justify\">Con profonda commozione, rinnovo il mio pensiero alle famiglie colpite da quella tragedia e a tutte le comunit\u00e0 che ne portano ancora oggi il peso. A loro va il mio pi\u00f9 sentito abbraccio e l\u2019impegno a non dimenticare mai\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Non potendo partecipare all&#8217;evento, in quanto impegnato nella seduta odierna del Consiglio regionale, il presidente Filippo Mancuso ha inviato un messaggio per ricordare la strage del 23 dicembre 1961, avvenuta&hellip;<\/p>\n","protected":false},"author":12,"featured_media":20319,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[142,921,196],"tags":[1604,594,35236,38882],"class_list":["post-63883","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-home","category-news","tag-anniversario","tag-filippo-mancuso","tag-ricordo","tag-strage-fiumarella"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mancuso ricorda la tragedia del viadotto della Fiumarella - Radio Touring 104<\/title>\n<meta name=\"description\" content=\"Nota stampa del Presidente del Consiglio Regionale, in occasione dell&#039;anniversario della tragedia che, nel &#039;61, cost\u00f2 la vita a 71 persone\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/12\/20\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mancuso ricorda la tragedia del viadotto della Fiumarella - Radio Touring 104\" \/>\n<meta property=\"og:description\" content=\"Nota stampa del Presidente del Consiglio Regionale, in occasione dell&#039;anniversario della tragedia che, nel &#039;61, cost\u00f2 la vita a 71 persone\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2024\/12\/20\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-20T11:36:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/Mancuso-Derby-Cutro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"684\" \/>\n\t<meta property=\"og:image:height\" content=\"642\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sebastiano Plutino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastiano Plutino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/12\\\/20\\\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/12\\\/20\\\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\\\/\"},\"author\":{\"name\":\"Sebastiano Plutino\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\"},\"headline\":\"Mancuso ricorda la tragedia del viadotto della Fiumarella\",\"datePublished\":\"2024-12-20T11:36:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/12\\\/20\\\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\\\/\"},\"wordCount\":224,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/12\\\/20\\\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/03\\\/Mancuso-Derby-Cutro.jpg\",\"keywords\":[\"anniversario\",\"Filippo Mancuso\",\"ricordo\",\"strage fiumarella\"],\"articleSection\":[\"Calabria\",\"Home\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/12\\\/20\\\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/12\\\/20\\\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\\\/\",\"name\":\"Mancuso ricorda la tragedia del viadotto della Fiumarella - Radio Touring 104\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/12\\\/20\\\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/12\\\/20\\\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/03\\\/Mancuso-Derby-Cutro.jpg\",\"datePublished\":\"2024-12-20T11:36:28+00:00\",\"description\":\"Nota stampa del Presidente del Consiglio Regionale, in occasione dell'anniversario della tragedia che, nel '61, cost\u00f2 la vita a 71 persone\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/12\\\/20\\\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/12\\\/20\\\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/12\\\/20\\\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/03\\\/Mancuso-Derby-Cutro.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/03\\\/Mancuso-Derby-Cutro.jpg\",\"width\":684,\"height\":642},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2024\\\/12\\\/20\\\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mancuso ricorda la tragedia del viadotto della Fiumarella\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\",\"name\":\"Sebastiano Plutino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"caption\":\"Sebastiano Plutino\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/sebastiano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mancuso ricorda la tragedia del viadotto della Fiumarella - Radio Touring 104","description":"Nota stampa del Presidente del Consiglio Regionale, in occasione dell'anniversario della tragedia che, nel '61, cost\u00f2 la vita a 71 persone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2024\/12\/20\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\/","og_locale":"it_IT","og_type":"article","og_title":"Mancuso ricorda la tragedia del viadotto della Fiumarella - Radio Touring 104","og_description":"Nota stampa del Presidente del Consiglio Regionale, in occasione dell'anniversario della tragedia che, nel '61, cost\u00f2 la vita a 71 persone","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/12\/20\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\/","og_site_name":"Radio Touring 104","article_published_time":"2024-12-20T11:36:28+00:00","og_image":[{"width":684,"height":642,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/Mancuso-Derby-Cutro.jpg","type":"image\/jpeg"}],"author":"Sebastiano Plutino","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Sebastiano Plutino","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/12\/20\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/12\/20\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\/"},"author":{"name":"Sebastiano Plutino","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e"},"headline":"Mancuso ricorda la tragedia del viadotto della Fiumarella","datePublished":"2024-12-20T11:36:28+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/12\/20\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\/"},"wordCount":224,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/12\/20\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/Mancuso-Derby-Cutro.jpg","keywords":["anniversario","Filippo Mancuso","ricordo","strage fiumarella"],"articleSection":["Calabria","Home","News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/12\/20\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2024\/12\/20\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\/","name":"Mancuso ricorda la tragedia del viadotto della Fiumarella - Radio Touring 104","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/12\/20\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/12\/20\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/Mancuso-Derby-Cutro.jpg","datePublished":"2024-12-20T11:36:28+00:00","description":"Nota stampa del Presidente del Consiglio Regionale, in occasione dell'anniversario della tragedia che, nel '61, cost\u00f2 la vita a 71 persone","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/12\/20\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2024\/12\/20\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/12\/20\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/Mancuso-Derby-Cutro.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/Mancuso-Derby-Cutro.jpg","width":684,"height":642},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2024\/12\/20\/mancuso-ricorda-la-tragedia-del-viadotto-della-fiumarella\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Mancuso ricorda la tragedia del viadotto della Fiumarella"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e","name":"Sebastiano Plutino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","caption":"Sebastiano Plutino"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/sebastiano\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2023\/03\/Mancuso-Derby-Cutro.jpg","_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/63883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=63883"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/63883\/revisions"}],"predecessor-version":[{"id":63884,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/63883\/revisions\/63884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/20319"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=63883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=63883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=63883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}