{"id":69394,"date":"2025-03-22T20:43:31","date_gmt":"2025-03-22T19:43:31","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=69394"},"modified":"2025-03-22T20:43:31","modified_gmt":"2025-03-22T19:43:31","slug":"giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2025\/03\/22\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\/","title":{"rendered":"Giornata Mondiale della Poesia: Le Muse e l\u2019Archivio di Stato insieme con la manifestazione \u201cLa Poesia costruisce ponti di pace\u201d"},"content":{"rendered":"<p>L\u2019associazione culturale Le Muse \u2013 Laboratorio delle Arti e delle Lettere di Reggio Calabria, continua le sue attivit\u00e0 domenicali con nuovi importantissimi momenti di questa nuova programmazione del venticinquennale.<\/p>\n<p>Anche in questo anno sociale \u201cLe Muse\u201d rinnovano il loro protocollo d\u2019intesa con l\u2019Archivio di Stato di Reggio Calabria in occasione della Giornata Mondiale della Poesia.<\/p>\n<p>&#8220;Abbiamo pensato &#8211; dichiara Giuseppe Livoti, presidente Muse-\u00a0 di dedicare due momenti ben precisi per questa importante giornata: uno per il mese di marzo ed uno in occasione del \u201cMaggio dei libri\u201d grazie all\u2019attenzione e cooperazione della dott.ssa Angela Puleio che ancora una volta crea rete con il nostro sodalizio culturale.<\/p>\n<p>Domenica 23 marzo, alle ore 17,30,\u00a0 presso la sala conferenze dell\u2019Archivio di Stato di via Casalotto si terr\u00e0 la manifestazione \u201cLa Poesia costruisce ponti di pace\u201d presentazione della silloge \u201cElogio dell\u2019attesa\u201d di Anna Lauria con la sua Po.etica attraverso la parola, video\u00a0 ed opere visive.<\/p>\n<p>La Lauria \u00e8 poetessa, organizzatrice di eventi e conduttrice di programmi culturali radiofonici e televisivi.<\/p>\n<p>Collabora alla Cattedra di Etica e Deontologia presso la Facolt\u00e0 di Scienze della Comunicazione dell\u2019Universit\u00e0 di Bari.<\/p>\n<p>Domenica, inoltre, si terr\u00e0 la premiazione del Primo Concorso Segnalibro D\u2019Artista 2025 che ha visto, tra artisti di chiara fama e giovani promesse provenienti dal mondo della scuola, la partecipazione di ben 75 partecipanti.<\/p>\n<p>Gli Artisti hanno partecipato con la realizzazione di un segnalibro, esemplare unico prodotto con materiali diversi e liberamente scelte.<\/p>\n<p>Il concorso \u00e8 stato aperto a tutti gli artisti (senza limiti d\u2019et\u00e0) operanti nel campo delle arti visive: pittura, fotografia, scultura, decorazione con la consegna solo di un&#8217; opera. Le opere saranno giudicate, dopo una presentazione critica, dal pubblico in sala che ricever\u00e0 una scheda con tutti i codici dei Segnalibri e potr\u00e0 esprimere una sola preferenza. A fine serata verranno consegnati 3 Premi per la Sezione Artisti e 3 Premi per la Sezione Giovani Promesse. Le creazioni saranno esposte nelle sale dell\u2019Archivio di Stato per i prossimi giorni in un grande momento collettivo. Nel mese di maggio invece ritorner\u00e0 la rassegna \u2013 concorso \u201dSegrete sillabe\u201d poich\u00e8 \u00e8 nelle intenzioni del prof. Giuseppe Livoti e della dott.ssa Angela Puleio di condividere con scrittori e poeti un evento pubblico per celebrare la poesia. L<\/p>\n<p>a Giornata Mondiale della Poesia \u00e8 stata istituita nel 1999 dall\u2019Unesco proprio con l\u2019intento di valorizzare questa forma di comunicazione cos\u00ec universale e per riconoscere nell\u2019espressione poetica un qualcosa di privilegiato necessario a promuovere il dialogo interculturale tra popoli. L\u2019obiettivo \u00e8 di andare oltre i confini, le lingue e le differenze, portando con s\u00e9 un ideale di bellezza che diventa globale.<\/p>\n<p>&#8220;La poesia \u2013 secondo Audrey Azoulay, direttore generale dell\u2019Unesco \u2013 \u00e8, senza dubbio, la forma migliore per esprimere questo desiderio, poich\u00e9 ci tocca nell\u2019intimo e permette ogni forma di libert\u00e0.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019associazione culturale Le Muse \u2013 Laboratorio delle Arti e delle Lettere di Reggio Calabria, continua le sue attivit\u00e0 domenicali con nuovi importantissimi momenti di questa nuova programmazione del venticinquennale. Anche&hellip;<\/p>\n","protected":false},"author":19,"featured_media":69395,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[145,921,196,140],"tags":[],"class_list":["post-69394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-home","category-news","category-reggio-calabria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giornata Mondiale della Poesia: Le Muse e l\u2019Archivio di Stato insieme con la manifestazione \u201cLa Poesia costruisce ponti di pace\u201d - Radio Touring 104<\/title>\n<meta name=\"description\" content=\"Domenica 23 marzo con la Po.etica di Anna Lauria e la premiazione del Segnalibro d\u2019artista 2025\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2025\/03\/22\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giornata Mondiale della Poesia: Le Muse e l\u2019Archivio di Stato insieme con la manifestazione \u201cLa Poesia costruisce ponti di pace\u201d - Radio Touring 104\" \/>\n<meta property=\"og:description\" content=\"Domenica 23 marzo con la Po.etica di Anna Lauria e la premiazione del Segnalibro d\u2019artista 2025\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2025\/03\/22\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-22T19:43:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/03\/485763417_10235858254506376_167519588465022692_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"456\" \/>\n\t<meta property=\"og:image:height\" content=\"392\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"S L\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"S L\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/03\\\/22\\\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/03\\\/22\\\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\\\/\"},\"author\":{\"name\":\"S L\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/b9f9c3730b0a78814c9b9f3bfc52c619\"},\"headline\":\"Giornata Mondiale della Poesia: Le Muse e l\u2019Archivio di Stato insieme con la manifestazione \u201cLa Poesia costruisce ponti di pace\u201d\",\"datePublished\":\"2025-03-22T19:43:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/03\\\/22\\\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\\\/\"},\"wordCount\":484,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/03\\\/22\\\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/03\\\/485763417_10235858254506376_167519588465022692_n.jpg\",\"articleSection\":[\"Cultura\",\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/03\\\/22\\\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/03\\\/22\\\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\\\/\",\"name\":\"Giornata Mondiale della Poesia: Le Muse e l\u2019Archivio di Stato insieme con la manifestazione \u201cLa Poesia costruisce ponti di pace\u201d - Radio Touring 104\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/03\\\/22\\\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/03\\\/22\\\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/03\\\/485763417_10235858254506376_167519588465022692_n.jpg\",\"datePublished\":\"2025-03-22T19:43:31+00:00\",\"description\":\"Domenica 23 marzo con la Po.etica di Anna Lauria e la premiazione del Segnalibro d\u2019artista 2025\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/03\\\/22\\\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/03\\\/22\\\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/03\\\/22\\\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/03\\\/485763417_10235858254506376_167519588465022692_n.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/03\\\/485763417_10235858254506376_167519588465022692_n.jpg\",\"width\":456,\"height\":392},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/03\\\/22\\\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giornata Mondiale della Poesia: Le Muse e l\u2019Archivio di Stato insieme con la manifestazione \u201cLa Poesia costruisce ponti di pace\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/b9f9c3730b0a78814c9b9f3bfc52c619\",\"name\":\"S L\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/652c51789d7030aaed9ff828331360502a68204fe6fb0831bc280515210e16d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/652c51789d7030aaed9ff828331360502a68204fe6fb0831bc280515210e16d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/652c51789d7030aaed9ff828331360502a68204fe6fb0831bc280515210e16d2?s=96&d=mm&r=g\",\"caption\":\"S L\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/slibri\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giornata Mondiale della Poesia: Le Muse e l\u2019Archivio di Stato insieme con la manifestazione \u201cLa Poesia costruisce ponti di pace\u201d - Radio Touring 104","description":"Domenica 23 marzo con la Po.etica di Anna Lauria e la premiazione del Segnalibro d\u2019artista 2025","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2025\/03\/22\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\/","og_locale":"it_IT","og_type":"article","og_title":"Giornata Mondiale della Poesia: Le Muse e l\u2019Archivio di Stato insieme con la manifestazione \u201cLa Poesia costruisce ponti di pace\u201d - Radio Touring 104","og_description":"Domenica 23 marzo con la Po.etica di Anna Lauria e la premiazione del Segnalibro d\u2019artista 2025","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2025\/03\/22\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\/","og_site_name":"Radio Touring 104","article_published_time":"2025-03-22T19:43:31+00:00","og_image":[{"width":456,"height":392,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/03\/485763417_10235858254506376_167519588465022692_n.jpg","type":"image\/jpeg"}],"author":"S L","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"S L","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/03\/22\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/03\/22\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\/"},"author":{"name":"S L","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/b9f9c3730b0a78814c9b9f3bfc52c619"},"headline":"Giornata Mondiale della Poesia: Le Muse e l\u2019Archivio di Stato insieme con la manifestazione \u201cLa Poesia costruisce ponti di pace\u201d","datePublished":"2025-03-22T19:43:31+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/03\/22\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\/"},"wordCount":484,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/03\/22\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/03\/485763417_10235858254506376_167519588465022692_n.jpg","articleSection":["Cultura","Home","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/03\/22\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2025\/03\/22\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\/","name":"Giornata Mondiale della Poesia: Le Muse e l\u2019Archivio di Stato insieme con la manifestazione \u201cLa Poesia costruisce ponti di pace\u201d - Radio Touring 104","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/03\/22\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/03\/22\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/03\/485763417_10235858254506376_167519588465022692_n.jpg","datePublished":"2025-03-22T19:43:31+00:00","description":"Domenica 23 marzo con la Po.etica di Anna Lauria e la premiazione del Segnalibro d\u2019artista 2025","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/03\/22\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2025\/03\/22\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/03\/22\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/03\/485763417_10235858254506376_167519588465022692_n.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/03\/485763417_10235858254506376_167519588465022692_n.jpg","width":456,"height":392},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/03\/22\/giornata-mondiale-della-poesia-le-muse-e-larchivio-di-stato-insieme-con-la-manifestazione-la-poesia-costruisce-ponti-di-pace\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Giornata Mondiale della Poesia: Le Muse e l\u2019Archivio di Stato insieme con la manifestazione \u201cLa Poesia costruisce ponti di pace\u201d"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/b9f9c3730b0a78814c9b9f3bfc52c619","name":"S L","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/652c51789d7030aaed9ff828331360502a68204fe6fb0831bc280515210e16d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/652c51789d7030aaed9ff828331360502a68204fe6fb0831bc280515210e16d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/652c51789d7030aaed9ff828331360502a68204fe6fb0831bc280515210e16d2?s=96&d=mm&r=g","caption":"S L"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/slibri\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/03\/485763417_10235858254506376_167519588465022692_n.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/69394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=69394"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/69394\/revisions"}],"predecessor-version":[{"id":69396,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/69394\/revisions\/69396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/69395"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=69394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=69394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=69394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}