{"id":70596,"date":"2025-04-07T12:02:57","date_gmt":"2025-04-07T10:02:57","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=70596"},"modified":"2025-04-07T12:02:57","modified_gmt":"2025-04-07T10:02:57","slug":"a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/07\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\/","title":{"rendered":"A Villa San Giovanni il salotto culturale &#8220;Le donne nell\u2019Architettura&#8221;"},"content":{"rendered":"<p style=\"text-align: justify\">In un mondo afflitto da persistenti divari, raggiungere l\u2019uguaglianza per tutte le donne e le ragazze rimane una convinzione fondamentale e una sfida duratura.<\/p>\n<p style=\"text-align: justify\">A sostegno di questo presupposto, durante il salotto culturale \u201cLe donne nell\u2019Architettura\u201d, organizzato dall\u2019arch. <strong>Cinzia Basile<\/strong> referente della Task Force \u201cArte e Cultura\u201d &#8211; Sezione FIDAPA-BPW di Villa San Giovanni, in collaborazione con l\u2019OAPPC di Reggio Calabria, si \u00e8 avviata una riflessione sulle donne che hanno fatto la storia dell\u2019Architettura, evidenziando le sfide ancora esistenti e promuovendo azioni concrete per la parit\u00e0 di genere.<\/p>\n<p style=\"text-align: justify\">L\u2019iniziativa, patrocinata della Sezione reggina di A.I.D.I.A. &#8211; Associazione Italiana Donne Ingegneri e Architetti &#8211; ha consegnato valore simbolico all\u2019importante lavoro svolto dalle donne architetto e al contributo da queste offerto, in modo sostanziale, allo sviluppo dell\u2019architettura.<\/p>\n<p style=\"text-align: justify\">L\u2019evento, ospitato presso l\u2019Auditorium \u201cEmanuela Loi\u201d dell\u2019IPALB TUR \u201cGiovanni Trecroci\u201d, le cui attivit\u00e0 di regia sono state curate dalle stesse organizzatrici coadiuvate dal tecnico <strong>Saverio Verduci<\/strong>, \u00e8 stato moderato dall\u2019avv. <strong>Carmela Infortuna<\/strong>, Segretaria della Sezione FIDAPA-BPW, che ha aperto il dibattito sulla necessit\u00e0 di una narrazione storica, accendendo i riflettori sul rapporto tra donne e architettura in diversi contesti sociali e culturali.<\/p>\n<p style=\"text-align: justify\">A ricevere in sala le relatrici, e gli ospiti tutti, sono stati gli studenti del corso serale di \u201cAccoglienza Turistica, Sala e Pasticceria\u201d dell\u2019IPALB TUR, diretto dal prof. Pontieri, accompagnati dalla prof.ssa Camilla Alampi.<\/p>\n<p style=\"text-align: justify\">Nel porgere i saluti l\u2019avv. <strong>Michela Catanese<\/strong>, Presidente della Sezione villese FIDAPA-BPW, ha rimarcato \u201c<em>Non si possono certo dimenticare le difficolt\u00e0 affrontate dal genere femminile in questo ambito professionale, nonostante la naturale propensione delle donne per il senso del bello e dell\u2019estetica in genere\u2026 ed \u00e8 proprio alla forza, alla tenacia di queste donne che hanno combattuto l\u2019arcaismo dei due sessi forte\/debole che ci siamo ispirati proponendo questo evento\u201d.<\/em><\/p>\n<p style=\"text-align: justify\">La padrona di casa prof.ssa<strong> Enza Loiero,<\/strong> DS dell\u2019istituto, sottolinea <em>\u201cLe donne grazie alla loro resilienza sono capaci di realizzare tantissime cose eleganti anche in circostanze poco favorevoli proprio per la loro propensione alla vita. Siamo in un auditorium intitolato ad Emanuela Loi che ha dato la vita per difendere i valori di giustizia e legalit\u00e0\u201d.<\/em><\/p>\n<p style=\"text-align: justify\">Nel suo intervento l\u2019ing.<strong> Margherita Tripodi<\/strong>, Presidente di AIDIA, specificando il ruolo dell\u2019associazione ha riportato il pensiero di Oriana Fallaci, abbinando alla figura della donna le tre parole<em>: <\/em>avventura, coraggio e sfida<em> \u201cTutti concetti che le donne architetto di un tempo, di oggi e di domani, abbracciano pienamente\u201d.<\/em><\/p>\n<p style=\"text-align: justify\">L\u2019arch.<strong> Cinzia Basile<\/strong>, nell\u2019esporre un\u2019approfondita ricerca da lei stessa curata e nel dettaglio espletata con la proiezione di un documentario, ha spiegato che <em>\u201cP<\/em><em>er molti secoli l\u2019architettura e l\u2019ingegneria sono rimaste strettamente legate al mondo maschile, resistendo all\u2019avanzata delle donne e alla loro progressiva conquista. Dopo qualche tentativo pionieristico nella prima met\u00e0 del Novecento, oggi le donne architetto sono molte e negli ultimi anni hanno cominciato finalmente a veder riconosciuto il proprio lavoro. <\/em><em>Il genere femminile, nella pratica dell\u2019architettura, di cui ad oggi possiamo vantare eccellenti esponenti, non ha certo avuto vita facile, come in tutti i campi professionali tecnici. <\/em><em>Esplorando i risultati ottenuti dalle donne architetto, possiamo comprendere meglio il loro impatto sul settore e ispirare le generazioni future a intraprendere una carriera in architettura\u201d.<\/em><\/p>\n<p style=\"text-align: justify\"><em>\u00a0<\/em>Con il suo intervento la Basile ha reso protagoniste del salotto alcune tra le maggiori esponenti che hanno segnato la storia dell\u2019architettura, dalle archistar alle architette, urbaniste, designer, docenti e ricercatrici.<\/p>\n<p style=\"text-align: justify\">Promotrice del cambiamento \u00e8 <strong>Plautilla Bricci<\/strong>, la prima a affermarsi in Italia, nel \u2018600 barocco di Bernini e Borromini. La Bricci venne definita \u201cl\u2019architettrice\u201d, in mancanza, prima di allora, di un nome femminile che potesse definire una donna architetto.<\/p>\n<p style=\"text-align: justify\">Sar\u00e0 tra la fine dell\u2019800 e tutto il \u2018900, con l\u2019avvento delle nuove tecnologie, le avanguardie e le nuove contaminazioni, che la figura della donna \u201carchitetto\u201d prender\u00e0 forma. Pioniera dell\u2019estetica dell\u2019<em>International Style<\/em>, l\u2019irlandese <strong>Eileen Grey<\/strong>, rimasta folgorata dall\u2019esposizione Universale di Parigi, nel primo dopoguerra decise di specializzarsi in architettura d\u2019interni e design, affiancando colleghi come Le Corbusier. Parliamo di tempi in cui alla donna non \u00e8 ancora dato ricoprire ruoli tipicamente maschili, basti ricordare che lo stesso Le Corbusier quando buss\u00f2 alla porta del suo studio la giovane <strong>Charlotte Perriand<\/strong>, sorridendo le disse \u201c<em>Qui non ricamiamo cuscini<\/em>\u201d, ma nonostante tutto nel 1927 con lei avvi\u00f2 una collaborazione per l\u2019arredamento di interni con pezzi moderni. Indicata fra i fondatori del design contemporaneo, le creazioni della Perriand sono tuttora in produzione da Cassina.<\/p>\n<p style=\"text-align: justify\">Nel 1991 sar\u00e0 grazie all\u2019architetto e urbanista statunitense<strong> Denise Scott Brown<\/strong>, coautrice della bibbia del Post Modern \u201cLearning from Las Vegas\u201d, se il premio Pritzker, il pi\u00f9 alto riconoscimento mondiale in architettura, pu\u00f2 essere oggi assegnato anche alle donne.<\/p>\n<p style=\"text-align: justify\">Alla carrellata di fautrici del cambiamento non pu\u00f2 mancare l\u2019italiana<strong> Gae Aulenti<\/strong>, classe \u201827. A sua firma sono pezzi iconici come la lampada da tavolo \u201cPipistrello\u201d, disegnata per gli <em>showroom<\/em> di Olivetti a Parigi e Buenos Aires, successivamente prodotta in serie e oggi esposta al MoMA di New York.<\/p>\n<p style=\"text-align: justify\">Negli stessi anni <strong>Lina Bo Bardi<\/strong>, una delle figure pi\u00f9 rivoluzionarie nell\u2019architettura del \u2018900, oltre a collaborare con lo studio di Gio Ponti, assunse la vicedirezione della rivista Domus e fond\u00f2 il magazine Habitat.\u00a0 Grazie a edifici come \u201cLa Casa de Vidro\u201d, oggi sede della fondazione a lei dedicata, l\u2019apporto di Bo Bardi sar\u00e0 fondamentale allo sviluppo dell\u2019architettura brasiliana.<\/p>\n<p style=\"text-align: justify\">Sulla scia delle donne che l\u2019hanno preceduta, l\u2019architetto e designer irachena di<strong> Zaha Hadid<\/strong> \u00e8 la prima donna nella storia a vincere il Premio Pritzker 2004 e la medaglia d\u2019oro del Royal Institute of British Architects 2016. Lo stile inconfondibile, basato su prospettive ardite e forme sinuose, \u00e8 riconoscibile nel Museo Nazionale delle Arti del XXI secolo di Roma, nella Stazione Marittima di Salerno e nel costruendo Museo del Mediterraneo nel Waterfront di Reggio Calabria.<\/p>\n<p style=\"text-align: justify\">Nello stesso scenario le irlandesi <strong>Shelley McNamara<\/strong> e <strong>Yvonne Farrel<\/strong>, attive fin dagli anni \u201970, hanno vinto il World Building of the Year 2008 per l\u2019estensione dell\u2019Universit\u00e0 Bocconi e il Leone d\u2019Argento alla Biennale 2012 con il progetto del campus UTEC per l\u2019Universit\u00e0 di Lima. Nel 2018 curano la Biennale di Archittetura a Venezia nel 2018.<\/p>\n<p style=\"text-align: justify\">A soli 21 anni, nel 1981, \u00e8 ancora una studentessa universitaria,<strong> Maya Lin<\/strong>, americana di origini cinesi, quando esordisce con il progetto vincitore al concorso di idee del Vietnam Veterans Memorial a Washington, monumento dedicato ai 58.000 soldati americani caduti durante la guerra del Vietnam eretto al Cimitero di Arlington.<\/p>\n<p style=\"text-align: justify\">Infine, ma non ultima, tra le pioniere dell\u2019architettura del passato e del presente, l\u2019italiana<strong> Jolanda Milano<\/strong>, special guest all\u2019evento. La Milano oltre a essere una delle prime tre donne iscritte all\u2019Ordine di Reggio Calabria, ha lasciato alla citt\u00e0, con le sue progettazioni che spaziano dall\u2019architettura al design, traccia tangibile del suo stile ricercato, visibile nei dettagli come nelle balaustre della fossa orchestrale del Teatro Francesco Cilea del quale ne ha curato il restauro.<\/p>\n<p style=\"text-align: justify\">Sulla figura di <strong>Jolanda Milano<\/strong> \u00e8 intervenuta l\u2019arch.<strong> Sabrina Prestipino<\/strong>. Il suo contributo ha ripercorso, attraverso le emozioni, il lavoro della madre architetta e gli effetti prodotti indirettamente nella formazione della figlia.<\/p>\n<p style=\"text-align: justify\">La Milano visibilmente emozionata, nel ricevere la targa in riconoscimento della sua carriera, ha ringraziato tutti i presenti.<\/p>\n<p style=\"text-align: justify\">Nel corso della cerimonia di premiazione \u00e8 intervenuta l\u2019avv.<strong> Giusy Caminiti<\/strong>, Sindaco della Citt\u00e0 di Villa San Giovanni, esprimendo grande soddisfazione per il taglio dato all\u2019evento e per la testimonianza di Jolanda Milano.<\/p>\n<p style=\"text-align: justify\">Il dibattito \u00e8 proseguito con l\u2019arch.<strong> Giovanna Caminiti<\/strong>, Presidente della Commissione \u201cPari Opportunit\u00e0\u201d dell\u2019OAPPC di Reggio Calabria, con una dedica alla Bricci <em>\u201cPalutilla non \u00e8 solo un esempio per le donne che voglio diventare architetto e che da lei raccolgono questa preziosa eredit\u00e0, ma un modello per chiunque, donna o uomo, volesse intraprendere il percorso per diventare ci\u00f2 che desidera, credendo nel proprio talento, forte del proprio coraggio\u201d. <\/em><\/p>\n<p style=\"text-align: justify\">Ha chiuso gli interventi l\u2019arch.<strong> Silvia Lottero<\/strong> che, tracciando vecchie e nuove sfide, dichiara <em>\u201cOgni giorno siamo impegnate ad affrontare sfide nella nostra professione che si occupa di architettura e non solo, essa \u00e8 al confine tra l&#8217;arte e la scienza, tra la cultura e la tecnica.<\/em> <em>A cento anni dalla fondazione degli ordini professionali per la tutela del titolo e dell\u2019esercizio professionale degli Ingegneri e Architetti, i numeri restituiscono una situazione incoraggiante in quanto evidenziano una crescita costante sia di iscrizioni che di partecipazione all\u2019interno dei Consigli dell\u2019Ordine, tuttavia nell\u2019immaginario collettivo quello dell\u2019architetto \u00e8 ancora considerato un lavoro maschile. Le donne architetto, a fronte di un divario retributivo di genere che resiste ma che si sta man mano riducendo, non demordono e da sempre instillano nuova linfa nella rivoluzione silenziosa iniziata da Plautilla Bricci. La storia \u00e8 certamente corredata di esempi di donne illustri che sono riuscite a distinguersi ma accanto a queste eccellenze vi sono tante professioniste derubate dei loro meriti\u201d. <\/em><\/p>\n<p style=\"text-align: justify\">Il salotto culturale \u201cLe donne nell\u2019Architettura\u201d \u00e8 stato arricchito dagli eleganti intermezzi di danza eseguiti delle giovani allieve della scuola ASD Divina, dirette da <strong>Mariarosa Verduci<\/strong> in collaborazione con la maestra del corso di danza classica <strong>Fatima Ranieri<\/strong>.<\/p>\n<p style=\"text-align: justify\">Nel corso dell\u2019evento gli ospiti hanno potuto gustare le pietanze preparate dallo Chef <strong>Francesco Figliomeni.<\/strong><\/p>\n<p style=\"text-align: justify\">L\u2019evento curato dalla Task Force \u201cArte e Cultura\u201d, composta anche da <strong>Rina Morabito, Maria Cantarella, Nuccia Cardile, Isabella Irac\u00e0, Silvia Lottero, Anna Stajano, Rosy Ussia, Nuccia Ferrante e Tiziana Pansera<\/strong>, ha contribuito a far riflettere sul contributo che ogni donna pu\u00f2 offrire alla societ\u00e0. Le socie, coadiuvate dalle allieve della \u201cScuola Divina\u201d, hanno consegnato gli attestati e omaggi floreali realizzati da \u201cRiviera dei fiori\u201d di Francesco Giuffr\u00e8.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In un mondo afflitto da persistenti divari, raggiungere l\u2019uguaglianza per tutte le donne e le ragazze rimane una convinzione fondamentale e una sfida duratura. A sostegno di questo presupposto, durante&hellip;<\/p>\n","protected":false},"author":12,"featured_media":70597,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[921,196,140],"tags":[42227,42225,42228,13726,42229,42226,10298,1323,364],"class_list":["post-70596","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-news","category-reggio-calabria","tag-le-donne-nellarchitettura","tag-arch-cinzia-basile","tag-carmela-infortuna","tag-fidapa","tag-ispirazione","tag-salotto-culturale","tag-saverio-verduci","tag-storia","tag-villa-san-giovanni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Villa San Giovanni il salotto culturale &quot;Le donne nell\u2019Architettura&quot; - Radio Touring 104<\/title>\n<meta name=\"description\" content=\"Svolto a Villa San Giovanni, Il salotto culturale FIDAPA, organizzato dall\u2019arch. Cinzia Basile, tra storia, talento e ispirazione\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/07\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Villa San Giovanni il salotto culturale &quot;Le donne nell\u2019Architettura&quot; - Radio Touring 104\" \/>\n<meta property=\"og:description\" content=\"Svolto a Villa San Giovanni, Il salotto culturale FIDAPA, organizzato dall\u2019arch. Cinzia Basile, tra storia, talento e ispirazione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/07\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-07T10:02:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/04\/Jolanda-Milano-con-le-donne-del-salotto.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sebastiano Plutino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastiano Plutino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/07\\\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/07\\\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\\\/\"},\"author\":{\"name\":\"Sebastiano Plutino\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\"},\"headline\":\"A Villa San Giovanni il salotto culturale &#8220;Le donne nell\u2019Architettura&#8221;\",\"datePublished\":\"2025-04-07T10:02:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/07\\\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\\\/\"},\"wordCount\":1612,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/07\\\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/04\\\/Jolanda-Milano-con-le-donne-del-salotto.jpeg\",\"keywords\":[\"\\\"Le donne nell\u2019Architettura\\\"\",\"arch. Cinzia Basile\",\"Carmela infortuna\",\"Fidapa\",\"ispirazione\",\"Salotto culturale\",\"Saverio Verduci\",\"storia\",\"villa san giovanni\"],\"articleSection\":[\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/07\\\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/07\\\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\\\/\",\"name\":\"A Villa San Giovanni il salotto culturale \\\"Le donne nell\u2019Architettura\\\" - Radio Touring 104\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/07\\\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/07\\\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/04\\\/Jolanda-Milano-con-le-donne-del-salotto.jpeg\",\"datePublished\":\"2025-04-07T10:02:57+00:00\",\"description\":\"Svolto a Villa San Giovanni, Il salotto culturale FIDAPA, organizzato dall\u2019arch. Cinzia Basile, tra storia, talento e ispirazione\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/07\\\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/07\\\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/07\\\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/04\\\/Jolanda-Milano-con-le-donne-del-salotto.jpeg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/04\\\/Jolanda-Milano-con-le-donne-del-salotto.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/07\\\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Villa San Giovanni il salotto culturale &#8220;Le donne nell\u2019Architettura&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\",\"name\":\"Sebastiano Plutino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"caption\":\"Sebastiano Plutino\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/sebastiano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Villa San Giovanni il salotto culturale \"Le donne nell\u2019Architettura\" - Radio Touring 104","description":"Svolto a Villa San Giovanni, Il salotto culturale FIDAPA, organizzato dall\u2019arch. Cinzia Basile, tra storia, talento e ispirazione","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/07\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\/","og_locale":"it_IT","og_type":"article","og_title":"A Villa San Giovanni il salotto culturale \"Le donne nell\u2019Architettura\" - Radio Touring 104","og_description":"Svolto a Villa San Giovanni, Il salotto culturale FIDAPA, organizzato dall\u2019arch. Cinzia Basile, tra storia, talento e ispirazione","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/07\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\/","og_site_name":"Radio Touring 104","article_published_time":"2025-04-07T10:02:57+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/04\/Jolanda-Milano-con-le-donne-del-salotto.jpeg","type":"image\/jpeg"}],"author":"Sebastiano Plutino","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Sebastiano Plutino","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/07\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/07\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\/"},"author":{"name":"Sebastiano Plutino","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e"},"headline":"A Villa San Giovanni il salotto culturale &#8220;Le donne nell\u2019Architettura&#8221;","datePublished":"2025-04-07T10:02:57+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/07\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\/"},"wordCount":1612,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/07\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/04\/Jolanda-Milano-con-le-donne-del-salotto.jpeg","keywords":["\"Le donne nell\u2019Architettura\"","arch. Cinzia Basile","Carmela infortuna","Fidapa","ispirazione","Salotto culturale","Saverio Verduci","storia","villa san giovanni"],"articleSection":["Home","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/07\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/07\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\/","name":"A Villa San Giovanni il salotto culturale \"Le donne nell\u2019Architettura\" - Radio Touring 104","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/07\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/07\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/04\/Jolanda-Milano-con-le-donne-del-salotto.jpeg","datePublished":"2025-04-07T10:02:57+00:00","description":"Svolto a Villa San Giovanni, Il salotto culturale FIDAPA, organizzato dall\u2019arch. Cinzia Basile, tra storia, talento e ispirazione","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/07\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/07\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/07\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/04\/Jolanda-Milano-con-le-donne-del-salotto.jpeg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/04\/Jolanda-Milano-con-le-donne-del-salotto.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/07\/a-villa-san-giovanni-il-salotto-culturale-le-donne-nellarchitettura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"A Villa San Giovanni il salotto culturale &#8220;Le donne nell\u2019Architettura&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e","name":"Sebastiano Plutino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","caption":"Sebastiano Plutino"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/sebastiano\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/04\/Jolanda-Milano-con-le-donne-del-salotto.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/70596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=70596"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/70596\/revisions"}],"predecessor-version":[{"id":70598,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/70596\/revisions\/70598"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/70597"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=70596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=70596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=70596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}