{"id":72245,"date":"2025-04-28T10:37:09","date_gmt":"2025-04-28T08:37:09","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=72245"},"modified":"2025-04-28T10:37:09","modified_gmt":"2025-04-28T08:37:09","slug":"marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\/","title":{"rendered":"Marina di Gioiosa, Agostino (&#8220;Cuore e Futuro&#8221;): &#8220;Movimento nasce per colmare vuoto politico della cittadina&#8221;"},"content":{"rendered":"<p style=\"text-align: justify\">\u201cCon emozione e grande orgoglio,\u00a0 abbiamo presentato ufficialmente la lista \u201cMarina di Gioiosa, Cuore e Futuro\u201d, una squadra straordinaria che si candida a guidare il nostro paese verso una nuova stagione di crescita, partecipazione e rinascita. Accanto a me ci sono donne e uomini che rappresentano la vera forza di Marina di Gioiosa, persone competenti, oneste, appassionate e unite da un unico grande obiettivo: mettere il cuore al servizio del futuro della nostra comunit\u00e0\u201d. Queste le parole del candidato a Sindaco Rocco Femia che in questi giorni ha potuto percepire in prima persona il crescente entusiasmo per la sua ricandidatura a primo cittadino.<\/p>\n<p style=\"text-align: justify\">\u00a0\u201cAbbiamo costruito \u2013 prosegue Femia &#8211; \u00a0questa lista, rappresentativa di tutte le anime della nostra comunit\u00e0, ascoltando i bisogni reali della gente, raccogliendo sogni, proposte e idee. Oggi siamo qui, pi\u00f9 forti che mai, spinti dall\u2019entusiasmo e dall\u2019affetto che i cittadini ci stanno dimostrando giorno dopo giorno.\u00a0 I nomi che compongono questa squadra \u2013 Rocco Agostino, Danilo Barba, Nicola Catalano, Salvatore Catalano, Barbara Costa, Carmela Femia, Matteo Femia, Rossella Logozzo, Domenico Lupis, Vincenzo Misserianni, Alessia Ursino, Domenico Zavaglia \u2013 sono garanzia di seriet\u00e0, competenza e radicamento nel territorio. Siamo una squadra fatta di esperienze diverse che si completano e si rafforzano reciprocamente. Un team pronto a lavorare da subito per ridare a Marina di Gioiosa il ruolo che merita: una comunit\u00e0 viva, orgogliosa, capace di guardare avanti senza dimenticare le proprie radici\u201d.<\/p>\n<p style=\"text-align: justify\">Il consenso crescente che circonda il progetto trasmette anche un senso di forte responsabilit\u00e0. Ecco perch\u00e9 \u201cMarina di Gioiosa, Cuore e Futuro\u201d promette di portare avanti una precisa idea politica che punta, tra l\u2019altro, a rilanciare l\u2019economia locale, valorizzare le realt\u00e0 locali, curare\u00a0 il verde pubblico, rinnovare la macchina amministrativa e rafforzare i servizi sociali. Particolare attenzione sar\u00e0 rivolta al miglioramento di settori come sport e scuola, che consideriamo fondamentali per la crescita del territorio\u201d.<\/p>\n<p style=\"text-align: justify\">\u201cSiamo a un mese dal voto \u2013 sottolinea l\u2019ex Sindaco &#8211; e continueremo ad incontrare le persone, raccontare il nostro progetto e costruire, passo dopo passo, il cambiamento che Marina di Gioiosa merita. Chiedo a tutti i cittadini di darci fiducia: siamo pronti. La nostra campagna sar\u00e0 fatta di incontri veri, di proposte reali e di tanto entusiasmo. Un ringraziamento particolare a tutti coloro che avevano dato la propria disponibilit\u00e0 alla candidatura, ma non sono stati inseriti per questioni esclusivamente numeriche, continueranno ad essere parte attiva del nostro movimento e sono sicuro che il loro contributo sar\u00e0 fondamentale\u201d.<\/p>\n<p style=\"text-align: justify\">Femia conclude ribadendo che \u201cIncontrer\u00f2 ogni cittadino che vorr\u00e0 ascoltarmi e discuter\u00f2 ogni idea. Chiedo fiducia, ma soprattutto chiedo partecipazione. Marina di Gioiosa Ionica ha bisogno di tutti noi, di gruppi di lavoro disposti a lavorare per il bene della citt\u00e0. Siamo pronti a costruire insieme una nuova stagione di crescita, inclusione e futuro. Saremo disponibili ad ascoltare i nostri concittadini per aiutarli a risolvere i loro problemi\u201d.<\/p>\n<p style=\"text-align: justify\">Il programma elettorale sar\u00e0 presentato nel dettaglio nei prossimi giorni attraverso incontri pubblici per garantire la massima trasparenza e partecipazione.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cCon emozione e grande orgoglio,\u00a0 abbiamo presentato ufficialmente la lista \u201cMarina di Gioiosa, Cuore e Futuro\u201d, una squadra straordinaria che si candida a guidare il nostro paese verso una nuova&hellip;<\/p>\n","protected":false},"author":12,"featured_media":72246,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[921,196,140],"tags":[42177,42897,42520,30223,42896,41487],"class_list":["post-72245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-news","category-reggio-calabria","tag-cuore-e-futuro","tag-fondamentale-ascoltare-i-cittadini","tag-imprenditore-rocco-agostino","tag-marina-di-gioiosa-jonica","tag-movimento-nasce-per-colmare-vuoto-politico-della-cittadina","tag-rocco-femia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marina di Gioiosa, Agostino (&quot;Cuore e Futuro&quot;): &quot;Movimento nasce per colmare vuoto politico della cittadina&quot; - Radio Touring 104<\/title>\n<meta name=\"description\" content=\"Secondo l\u2019imprenditore, candidato alle comunali con il Sindaco Femia, \u00e8 \u201cfondamentale ascoltare i cittadini ed intervenire ove possibile\u201d\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marina di Gioiosa, Agostino (&quot;Cuore e Futuro&quot;): &quot;Movimento nasce per colmare vuoto politico della cittadina&quot; - Radio Touring 104\" \/>\n<meta property=\"og:description\" content=\"Secondo l\u2019imprenditore, candidato alle comunali con il Sindaco Femia, \u00e8 \u201cfondamentale ascoltare i cittadini ed intervenire ove possibile\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-28T08:37:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/04\/Rocco-Agostino-Marina-di-Gioiosa.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1147\" \/>\n\t<meta property=\"og:image:height\" content=\"860\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sebastiano Plutino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastiano Plutino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/28\\\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/28\\\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\\\/\"},\"author\":{\"name\":\"Sebastiano Plutino\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\"},\"headline\":\"Marina di Gioiosa, Agostino (&#8220;Cuore e Futuro&#8221;): &#8220;Movimento nasce per colmare vuoto politico della cittadina&#8221;\",\"datePublished\":\"2025-04-28T08:37:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/28\\\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\\\/\"},\"wordCount\":514,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/28\\\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/04\\\/Rocco-Agostino-Marina-di-Gioiosa.jpeg\",\"keywords\":[\"Cuore e futuro\",\"fondamentale ascoltare i cittadini\",\"imprenditore Rocco Agostino\",\"Marina di Gioiosa Jonica\",\"Movimento nasce per colmare vuoto politico della cittadina\",\"Rocco Femia\"],\"articleSection\":[\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/28\\\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/28\\\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\\\/\",\"name\":\"Marina di Gioiosa, Agostino (\\\"Cuore e Futuro\\\"): \\\"Movimento nasce per colmare vuoto politico della cittadina\\\" - Radio Touring 104\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/28\\\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/28\\\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/04\\\/Rocco-Agostino-Marina-di-Gioiosa.jpeg\",\"datePublished\":\"2025-04-28T08:37:09+00:00\",\"description\":\"Secondo l\u2019imprenditore, candidato alle comunali con il Sindaco Femia, \u00e8 \u201cfondamentale ascoltare i cittadini ed intervenire ove possibile\u201d\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/28\\\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/28\\\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/28\\\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/04\\\/Rocco-Agostino-Marina-di-Gioiosa.jpeg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/04\\\/Rocco-Agostino-Marina-di-Gioiosa.jpeg\",\"width\":1147,\"height\":860},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/28\\\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marina di Gioiosa, Agostino (&#8220;Cuore e Futuro&#8221;): &#8220;Movimento nasce per colmare vuoto politico della cittadina&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\",\"name\":\"Sebastiano Plutino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"caption\":\"Sebastiano Plutino\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/sebastiano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marina di Gioiosa, Agostino (\"Cuore e Futuro\"): \"Movimento nasce per colmare vuoto politico della cittadina\" - Radio Touring 104","description":"Secondo l\u2019imprenditore, candidato alle comunali con il Sindaco Femia, \u00e8 \u201cfondamentale ascoltare i cittadini ed intervenire ove possibile\u201d","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\/","og_locale":"it_IT","og_type":"article","og_title":"Marina di Gioiosa, Agostino (\"Cuore e Futuro\"): \"Movimento nasce per colmare vuoto politico della cittadina\" - Radio Touring 104","og_description":"Secondo l\u2019imprenditore, candidato alle comunali con il Sindaco Femia, \u00e8 \u201cfondamentale ascoltare i cittadini ed intervenire ove possibile\u201d","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\/","og_site_name":"Radio Touring 104","article_published_time":"2025-04-28T08:37:09+00:00","og_image":[{"width":1147,"height":860,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/04\/Rocco-Agostino-Marina-di-Gioiosa.jpeg","type":"image\/jpeg"}],"author":"Sebastiano Plutino","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Sebastiano Plutino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\/"},"author":{"name":"Sebastiano Plutino","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e"},"headline":"Marina di Gioiosa, Agostino (&#8220;Cuore e Futuro&#8221;): &#8220;Movimento nasce per colmare vuoto politico della cittadina&#8221;","datePublished":"2025-04-28T08:37:09+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\/"},"wordCount":514,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/04\/Rocco-Agostino-Marina-di-Gioiosa.jpeg","keywords":["Cuore e futuro","fondamentale ascoltare i cittadini","imprenditore Rocco Agostino","Marina di Gioiosa Jonica","Movimento nasce per colmare vuoto politico della cittadina","Rocco Femia"],"articleSection":["Home","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\/","name":"Marina di Gioiosa, Agostino (\"Cuore e Futuro\"): \"Movimento nasce per colmare vuoto politico della cittadina\" - Radio Touring 104","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/04\/Rocco-Agostino-Marina-di-Gioiosa.jpeg","datePublished":"2025-04-28T08:37:09+00:00","description":"Secondo l\u2019imprenditore, candidato alle comunali con il Sindaco Femia, \u00e8 \u201cfondamentale ascoltare i cittadini ed intervenire ove possibile\u201d","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/04\/Rocco-Agostino-Marina-di-Gioiosa.jpeg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/04\/Rocco-Agostino-Marina-di-Gioiosa.jpeg","width":1147,"height":860},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/marina-di-gioiosa-agostino-cuore-e-futuro-movimento-nasce-per-colmare-vuoto-politico-della-cittadina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Marina di Gioiosa, Agostino (&#8220;Cuore e Futuro&#8221;): &#8220;Movimento nasce per colmare vuoto politico della cittadina&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e","name":"Sebastiano Plutino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","caption":"Sebastiano Plutino"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/sebastiano\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/04\/Rocco-Agostino-Marina-di-Gioiosa.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/72245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=72245"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/72245\/revisions"}],"predecessor-version":[{"id":72247,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/72245\/revisions\/72247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/72246"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=72245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=72245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=72245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}