{"id":72248,"date":"2025-04-28T10:50:44","date_gmt":"2025-04-28T08:50:44","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=72248"},"modified":"2025-04-28T12:48:31","modified_gmt":"2025-04-28T10:48:31","slug":"reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\/","title":{"rendered":"Reggio: incontro a Palazzo Alvaro tra il Garante Metropolitano per l&#8217;infanzia ed una delegazione dell&#8217;Associazione &#8220;Il Volo delle Farfalle&#8221;"},"content":{"rendered":"<div class=\"application-pane\">\n<div class=\"main-pane\">\n<div id=\"application-stack\" class=\"dijitContainer dijitStackContainer dijitLayoutContainer\" dir=\"ltr\" role=\"tabpanel\">\n<div id=\"webmail-page\" class=\"main-page dijitContentPane dijitStackContainer-child dijitStackContainer-dijitContentPane dijitVisible menu-not-pinned is-next main-menu-collapsed\" role=\"group\">\n<div class=\"main-page-center-pane\">\n<div class=\"main-page-pane-with-toolbar\">\n<div class=\"main-content\">\n<div id=\"uiLogic_util_StackContainer_0\" class=\"content-stack-container dijitContainer dijitStackContainer dijitLayoutContainer leading-active componentVisible\" dir=\"ltr\" role=\"tabpanel\">\n<div id=\"uiLogic_webmail_WebmailFoldersManager_0\" class=\"webmailfoldersmanager messages-compose-compofeedback-stack dijitContainer dijitStackContainer dijitLayoutContainer dijitStackContainer-child dijitStackContainer-dijitStackContainer dijitVisible componentVisible\" dir=\"ltr\" role=\"tabpanel\">\n<div id=\"dijit_layout_BorderContainer_0\" class=\"trailing-1 messages-container dijitContainer dijitBorderContainer dijitStackContainer-child dijitStackContainer-dijitBorderContainer dijitVisible componentVisible center-active trailing-active\" dir=\"ltr\" lang=\"\">\n<div id=\"dijit_layout_ContentPane_0\" class=\"dijitContentPane dijitBorderContainer-child dijitBorderContainer-dijitContentPane dijitBorderContainerPane dijitContentPaneSingleChild\" dir=\"ltr\" lang=\"\" role=\"group\">\n<div id=\"xandmail_widget_layout_RelativeBorderContainer_0\" class=\"dijitContainer dijitBorderContainer\" dir=\"ltr\" lang=\"\">\n<div id=\"dijit_layout_StackContainer_0\" class=\"dijitContainer dijitStackContainer dijitLayoutContainer dijitBorderContainer-child dijitBorderContainer-dijitStackContainer dijitBorderContainerPane\" dir=\"ltr\" lang=\"\" role=\"tabpanel\">\n<div id=\"dijit_layout_ContentPane_4\" class=\"component-page item-view webmail-view trailing-1 webmail-view-page dijitContentPane dijitStackContainer-child dijitStackContainer-dijitContentPane dijitVisible dijitContentPaneSingleChild\" dir=\"ltr\" lang=\"\" role=\"group\">\n<div id=\"dijit_layout_BorderContainer_4\" class=\"message dijitContainer dijitBorderContainer\" dir=\"ltr\">\n<div id=\"dijit_layout_ContentPane_15\" class=\"content dijitContentPane dijitBorderContainer-child dijitBorderContainer-dijitContentPane dijitBorderContainerPane\" dir=\"ltr\" role=\"group\">\n<div class=\"message-section\">\n<div class=\"content-message\">\n<div class=\"text msg-view-text\" role=\"text\">\n<div class=\"msg-view-text-cnt\">\n<div class=\"xam_msg_class\">\n<div dir=\"auto\">\n<div dir=\"auto\" style=\"text-align: justify\"><strong>L\u2019Ufficio del Garante Metropolitano<\/strong> per l\u2019Infanzia e l\u2019Adolescenza<strong> ha ricevuto a Palazzo Alvaro una delegazione dell\u2019Associazione<\/strong> &#8220;Il Volo delle Farfalle&#8221;, a seguito della pubblicazione di un articolo che denunciava<strong> gravi pregiudizi nei confronti dei minori affetti da sindrome dello spettro autistico.<\/strong><\/div>\n<div dir=\"auto\" style=\"text-align: justify\"><\/div>\n<div dir=\"auto\" style=\"text-align: justify\">L\u2019incontro ha rappresentato un momento di confronto partecipato e costruttivo.<strong> Il Garante ha espresso l\u2019intenzione di coinvolgere tutte le associazioni del territorio che operano nel settore,<\/strong> al fine di analizzare in modo approfondito le problematiche emerse e proporre contributi migliorativi al Decreto ministeriale del 23 giugno 2023, recante la \u201cDefinizione delle tariffe dell\u2019assistenza specialistica ambulatoriale e protesica\u201d.<\/div>\n<div dir=\"auto\" style=\"text-align: justify\"><\/div>\n<div dir=\"auto\" style=\"text-align: justify\"><strong>Particolare preoccupazione \u00e8 stata manifestata in merito all\u2019esclusione,<\/strong> nel nuovo documento, delle terapie psico-educative basate sull\u2019Analisi Applicata del Comportamento (ABA), non pi\u00f9 ricomprese nella specialistica ambulatoriale prevista dai Livelli Essenziali di Assistenza (LEA).<\/div>\n<div dir=\"auto\" style=\"text-align: justify\"><\/div>\n<div dir=\"auto\" style=\"text-align: justify\">L\u2019articolo 60 dei LEA del 2017 \u2013 in attuazione della Legge 134\/2015 \u2013 riconosceva il diritto a prestazioni diagnostiche precoci, cure e trattamenti individualizzati fondati sulle pi\u00f9 avanzate evidenze scientifiche. Tuttavia, oggi tali diritti sembrano lasciati a un\u2019interpretazione incerta e non uniforme.<\/div>\n<div dir=\"auto\" style=\"text-align: justify\"><\/div>\n<div dir=\"auto\" style=\"text-align: justify\"><em>\u201c\u00c8 fondamentale interrogarsi con esperti e operatori del settore <strong>\u2013<\/strong><\/em><strong> ha dichiarato il Garante <\/strong><em><strong>\u2013<\/strong> per contribuire concretamente a garantire i diritti dei minori con disturbi dello spettro autistico. Non basta colorare di azzurro le citt\u00e0 per un giorno: serve un impegno costante per affrontare, insieme alle famiglie, le difficolt\u00e0 quotidiane.\u201d<\/em><\/div>\n<div dir=\"auto\" style=\"text-align: justify\"><\/div>\n<div dir=\"auto\" style=\"text-align: justify\">Il Garante ha infine ringraziato tutte le associazioni, le fondazioni e soprattutto le famiglie per il loro prezioso contributo. L\u2019Ufficio resta disponibile all\u2019ascolto e aperto a ricevere tutte le realt\u00e0 associative che vorranno offrire il proprio apporto in un\u2019ottica di collaborazione e condivisione degli intenti.<\/div>\n<div dir=\"auto\" style=\"text-align: justify\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"msg-view-attach-preview\" style=\"text-align: justify\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"uiLogic_webmail__view_ListReceipt_0\" class=\"pec-receipts-section light-list spaced-view webmail-inbox-list\" dir=\"ltr\">\n<div><\/div>\n<\/div>\n<\/div>\n<div id=\"dijit_layout_ContentPane_15_splitter\" class=\"dijitGutter dijitGutterV\" role=\"presentation\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"dijit_layout_StackContainer_0_splitter\" class=\"dijitSplitter dijitSplitterV\" role=\"separator\">\n<div class=\"dijitSplitterThumb\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"dijit_layout_ContentPane_0_splitter\" class=\"dijitGutter dijitGutterV\" role=\"presentation\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"xamGlobalDock\" class=\"xamDock\" dir=\"ltr\">\n<div class=\"docking-pane-container\"><\/div>\n<div class=\"summary-pane-container\"><\/div>\n<\/div>\n<\/div>\n<div class=\"dijitPopup\" role=\"presentation\">\n<div id=\"dijit_TooltipDialog_0\" class=\"user-ffn-tooltip-dialog dijitTooltipABRight dijitTooltipDialog\" dir=\"ltr\" lang=\"\" role=\"presentation\">\n<div class=\"dijitTooltipContainer\" role=\"presentation\">\n<div class=\"dijitTooltipContents dijitTooltipFocusNode\" role=\"dialog\">\n<div class=\"user-menu\">\n<div class=\"user-menu-title\">\n<div id=\"uiLogic_util_UserAvatarPicker_0\" class=\"avatar-picker-cnt avatar-picker default-avatar avatar-picker-text\" dir=\"ltr\" lang=\"\">\n<div class=\"avatar-picker-photo-cnt\">\n<div class=\"avatar-picker-photo\">\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"user-menu-title-cnt flex-column\">\n<div class=\"flex\">\n<div class=\"user-menu-emailffn-cnt flex-column\">\n<div class=\"user-menu-ffn\"><\/div>\n<div class=\"user-menu-email-cnt\">\n<div class=\"user-menu-email\"><\/div>\n<div class=\"user-pecplus\"><\/div>\n<\/div>\n<\/div>\n<div class=\"user-menu-link link\" data-monitoring-name=\"pe_profile_logout\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"dijitPopup\" role=\"presentation\">\n<table id=\"uiLogic_webmail_selection_MessageMenu_0\" class=\"dijit dijitMenu dijitMenuPassive dijitReset dijitMenuTable\" role=\"menu\" cellspacing=\"0\">\n<tbody class=\"dijitReset\">\n<tr id=\"dijit_MenuItem_37\" class=\"dijitReset dijitMenuItem\" role=\"menuitem\" aria-labelledby=\"dijit_MenuItem_37_text dijit_MenuItem_37_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_MenuItem_37_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuItem_38\" class=\"dijitReset dijitMenuItem\" role=\"menuitem\" aria-labelledby=\"dijit_MenuItem_38_text dijit_MenuItem_38_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_MenuItem_38_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuItem_39\" class=\"dijitReset dijitMenuItem\" role=\"menuitem\" aria-labelledby=\"dijit_MenuItem_39_text dijit_MenuItem_39_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_MenuItem_39_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuItem_40\" class=\"dijitReset dijitMenuItem\" role=\"menuitem\" aria-labelledby=\"dijit_MenuItem_40_text dijit_MenuItem_40_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_MenuItem_40_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuSeparator_5\" class=\"dijitMenuSeparator\">\n<td class=\"dijitMenuSeparatorIconCell\">\n<div class=\"dijitMenuSeparatorTop\"><\/div>\n<div class=\"dijitMenuSeparatorBottom\"><\/div>\n<\/td>\n<td class=\"dijitMenuSeparatorLabelCell\" colspan=\"3\">\n<div class=\"dijitMenuSeparatorTop dijitMenuSeparatorLabel\"><\/div>\n<div class=\"dijitMenuSeparatorBottom\"><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuItem_41\" class=\"dijitReset dijitMenuItem\" role=\"menuitem\" aria-labelledby=\"dijit_MenuItem_41_text dijit_MenuItem_41_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_MenuItem_41_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_PopupMenuItem_1\" class=\"dijitReset dijitMenuItem\" role=\"menuitem\" aria-labelledby=\"dijit_PopupMenuItem_1_text dijit_PopupMenuItem_1_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_PopupMenuItem_1_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuItem_48\" class=\"dijitReset dijitMenuItem\" role=\"menuitem\" aria-labelledby=\"dijit_MenuItem_48_text dijit_MenuItem_48_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_MenuItem_48_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuItem_49\" class=\"dijitReset dijitMenuItem\" role=\"menuitem\" aria-labelledby=\"dijit_MenuItem_49_text dijit_MenuItem_49_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_MenuItem_49_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuItem_50\" class=\"dijitReset dijitMenuItem\" role=\"menuitem\" aria-labelledby=\"dijit_MenuItem_50_text dijit_MenuItem_50_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_MenuItem_50_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuItem_51\" class=\"dijitReset dijitMenuItem\" role=\"menuitem\" aria-labelledby=\"dijit_MenuItem_51_text dijit_MenuItem_51_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_MenuItem_51_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuSeparator_7\" class=\"dijitMenuSeparator\">\n<td class=\"dijitMenuSeparatorIconCell\">\n<div class=\"dijitMenuSeparatorTop\"><\/div>\n<div class=\"dijitMenuSeparatorBottom\"><\/div>\n<\/td>\n<td class=\"dijitMenuSeparatorLabelCell\" colspan=\"3\">\n<div class=\"dijitMenuSeparatorTop dijitMenuSeparatorLabel\"><\/div>\n<div class=\"dijitMenuSeparatorBottom\"><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_PopupMenuItem_2\" class=\"dijitReset dijitMenuItem\" role=\"menuitem\" aria-labelledby=\"dijit_PopupMenuItem_2_text dijit_PopupMenuItem_2_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_PopupMenuItem_2_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuItem_56\" class=\"dijitReset dijitMenuItem\" role=\"menuitem\" aria-labelledby=\"dijit_MenuItem_56_text dijit_MenuItem_56_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_MenuItem_56_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuSeparator_8\" class=\"dijitMenuSeparator\">\n<td class=\"dijitMenuSeparatorIconCell\">\n<div class=\"dijitMenuSeparatorTop\"><\/div>\n<div class=\"dijitMenuSeparatorBottom\"><\/div>\n<\/td>\n<td class=\"dijitMenuSeparatorLabelCell\" colspan=\"3\">\n<div class=\"dijitMenuSeparatorTop dijitMenuSeparatorLabel\"><\/div>\n<div class=\"dijitMenuSeparatorBottom\"><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuItem_57\" class=\"dijitReset dijitMenuItem\" role=\"menuitem\" aria-labelledby=\"dijit_MenuItem_57_text dijit_MenuItem_57_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_MenuItem_57_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuItem_58\" class=\"dijitReset dijitMenuItem\" role=\"menuitem\" aria-labelledby=\"dijit_MenuItem_58_text dijit_MenuItem_58_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_MenuItem_58_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div id=\"usabilla_live_button_container_701406579\" class=\"usabilla_live_button_container\" role=\"button\" aria-label=\"Usabilla Feedback Button\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Ufficio del Garante Metropolitano per l\u2019Infanzia e l\u2019Adolescenza ha ricevuto a Palazzo Alvaro una delegazione dell\u2019Associazione &#8220;Il Volo delle Farfalle&#8221;, a seguito della pubblicazione di un articolo che denunciava gravi&hellip;<\/p>\n","protected":false},"author":12,"featured_media":5666,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[921,150,196,140],"tags":[42151,5698,42899,739,42898],"class_list":["post-72248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-in-primo-piano","category-news","category-reggio-calabria","tag-associazione-il-volo-delle-farfalle-evoluzione-autismo","tag-incontro","tag-minori-affetti-da-sindrome-dello-spettro-autistico","tag-palazzo-alvaro","tag-ufficio-del-garante-metropolitano-per-linfanzia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reggio: incontro a Palazzo Alvaro tra il Garante Metropolitano per l&#039;infanzia ed una delegazione dell&#039;Associazione &quot;Il Volo delle Farfalle&quot; - Radio Touring 104<\/title>\n<meta name=\"description\" content=\"Ricevuta a Palazzo Alvaro delegazione dell&#039;associazione, dopo la denuncia di pregiudizi verso i minori affetti da sindrome spettro autistico\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reggio: incontro a Palazzo Alvaro tra il Garante Metropolitano per l&#039;infanzia ed una delegazione dell&#039;Associazione &quot;Il Volo delle Farfalle&quot; - Radio Touring 104\" \/>\n<meta property=\"og:description\" content=\"Ricevuta a Palazzo Alvaro delegazione dell&#039;associazione, dopo la denuncia di pregiudizi verso i minori affetti da sindrome spettro autistico\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-28T08:50:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-28T10:48:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/05\/san-giorgio-comune.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sebastiano Plutino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastiano Plutino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/28\\\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/28\\\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\\\/\"},\"author\":{\"name\":\"Sebastiano Plutino\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\"},\"headline\":\"Reggio: incontro a Palazzo Alvaro tra il Garante Metropolitano per l&#8217;infanzia ed una delegazione dell&#8217;Associazione &#8220;Il Volo delle Farfalle&#8221;\",\"datePublished\":\"2025-04-28T08:50:44+00:00\",\"dateModified\":\"2025-04-28T10:48:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/28\\\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\\\/\"},\"wordCount\":291,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/28\\\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/05\\\/san-giorgio-comune.jpg\",\"keywords\":[\"Associazione \\\"Il volo delle farfalle evoluzione autismo\\\"\",\"incontro\",\"minori affetti da sindrome dello spettro autistico.\",\"Palazzo Alvaro\",\"Ufficio del Garante Metropolitano per l\u2019Infanzia\"],\"articleSection\":[\"Home\",\"In primo piano\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/28\\\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/28\\\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\\\/\",\"name\":\"Reggio: incontro a Palazzo Alvaro tra il Garante Metropolitano per l'infanzia ed una delegazione dell'Associazione \\\"Il Volo delle Farfalle\\\" - Radio Touring 104\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/28\\\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/28\\\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/05\\\/san-giorgio-comune.jpg\",\"datePublished\":\"2025-04-28T08:50:44+00:00\",\"dateModified\":\"2025-04-28T10:48:31+00:00\",\"description\":\"Ricevuta a Palazzo Alvaro delegazione dell'associazione, dopo la denuncia di pregiudizi verso i minori affetti da sindrome spettro autistico\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/28\\\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/28\\\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/28\\\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/05\\\/san-giorgio-comune.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/05\\\/san-giorgio-comune.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/04\\\/28\\\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reggio: incontro a Palazzo Alvaro tra il Garante Metropolitano per l&#8217;infanzia ed una delegazione dell&#8217;Associazione &#8220;Il Volo delle Farfalle&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\",\"name\":\"Sebastiano Plutino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"caption\":\"Sebastiano Plutino\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/sebastiano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reggio: incontro a Palazzo Alvaro tra il Garante Metropolitano per l'infanzia ed una delegazione dell'Associazione \"Il Volo delle Farfalle\" - Radio Touring 104","description":"Ricevuta a Palazzo Alvaro delegazione dell'associazione, dopo la denuncia di pregiudizi verso i minori affetti da sindrome spettro autistico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\/","og_locale":"it_IT","og_type":"article","og_title":"Reggio: incontro a Palazzo Alvaro tra il Garante Metropolitano per l'infanzia ed una delegazione dell'Associazione \"Il Volo delle Farfalle\" - Radio Touring 104","og_description":"Ricevuta a Palazzo Alvaro delegazione dell'associazione, dopo la denuncia di pregiudizi verso i minori affetti da sindrome spettro autistico","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\/","og_site_name":"Radio Touring 104","article_published_time":"2025-04-28T08:50:44+00:00","article_modified_time":"2025-04-28T10:48:31+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/05\/san-giorgio-comune.jpg","type":"image\/jpeg"}],"author":"Sebastiano Plutino","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Sebastiano Plutino","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\/"},"author":{"name":"Sebastiano Plutino","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e"},"headline":"Reggio: incontro a Palazzo Alvaro tra il Garante Metropolitano per l&#8217;infanzia ed una delegazione dell&#8217;Associazione &#8220;Il Volo delle Farfalle&#8221;","datePublished":"2025-04-28T08:50:44+00:00","dateModified":"2025-04-28T10:48:31+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\/"},"wordCount":291,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/05\/san-giorgio-comune.jpg","keywords":["Associazione \"Il volo delle farfalle evoluzione autismo\"","incontro","minori affetti da sindrome dello spettro autistico.","Palazzo Alvaro","Ufficio del Garante Metropolitano per l\u2019Infanzia"],"articleSection":["Home","In primo piano","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\/","name":"Reggio: incontro a Palazzo Alvaro tra il Garante Metropolitano per l'infanzia ed una delegazione dell'Associazione \"Il Volo delle Farfalle\" - Radio Touring 104","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/05\/san-giorgio-comune.jpg","datePublished":"2025-04-28T08:50:44+00:00","dateModified":"2025-04-28T10:48:31+00:00","description":"Ricevuta a Palazzo Alvaro delegazione dell'associazione, dopo la denuncia di pregiudizi verso i minori affetti da sindrome spettro autistico","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/05\/san-giorgio-comune.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/05\/san-giorgio-comune.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/04\/28\/reggio-incontro-a-palazzo-alvaro-tra-il-garante-metropolitano-per-linfanzia-ed-una-delegazione-dellassociazione-il-volo-delle-farfalle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Reggio: incontro a Palazzo Alvaro tra il Garante Metropolitano per l&#8217;infanzia ed una delegazione dell&#8217;Associazione &#8220;Il Volo delle Farfalle&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e","name":"Sebastiano Plutino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","caption":"Sebastiano Plutino"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/sebastiano\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/05\/san-giorgio-comune.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/72248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=72248"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/72248\/revisions"}],"predecessor-version":[{"id":72250,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/72248\/revisions\/72250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/5666"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=72248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=72248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=72248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}