{"id":75394,"date":"2025-06-06T18:54:56","date_gmt":"2025-06-06T16:54:56","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=75394"},"modified":"2025-06-06T18:54:56","modified_gmt":"2025-06-06T16:54:56","slug":"palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/06\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\/","title":{"rendered":"Palazzo San Giorgio: la Giunta approva interventi sulla viabilit\u00e0 per Podargoni"},"content":{"rendered":"<p class=\"xmprfx_MsoNormal\">La Giunta comunale di Reggio Calabria, su proposta del settore Lavori Pubblici, ha approvato in una recente seduta i progetti di fattibilit\u00e0 tecnico-economica degli interventi di manutenzione straordinaria e messa in sicurezza della viabilit\u00e0 di accesso a Podargoni e della viabilit\u00e0 di collegamento del borgo con Cerasi, Schindilif\u00e0 e con gli altri centri nel versante sinistro del torrente Gallico. Le opere, che rispettivamente hanno un importo complessivo di 2,5 milioni e 3,5 milioni di euro, rientrano nell\u2019ambito del progetto unitario \u201cRecupero e valorizzazione del borgo di Podargoni e del territorio circostante\u201d che comprende i due interventi mirati, oltre che al miglioramento del livello di sicurezza e la salvaguardia della pubblica incolumit\u00e0, alla riduzione della condizione di isolamento e marginalit\u00e0 delle aree pi\u00f9 interne dell\u2019Aspromonte, incrementando i livelli di connessione e accessibilit\u00e0 fisica.<\/p>\n<p class=\"xmprfx_MsoNormal\">Il progetto dal titolo \u201cRecupero e valorizzazione del borgo di Podargoni e del territorio circostante\u201d \u00e8 finanziato nell\u2019ambito del \u201cProgramma straordinario per la riqualificazione urbana e la sicurezza delle periferie delle citt\u00e0 metropolitane e dei comuni capoluogo di provincia\u201d predisposto dalla Presidenza del Consiglio dei Ministri e, inoltre, \u00e8 assunto come progetto pilota\u00a0 &#8211; azione strategica Rigenerazione della memoria dei Borghi di Reggio Calabria\u00a0 &#8211; nell\u2019ambito del Masterplan di Reggio Calabria.<\/p>\n<p class=\"xmprfx_MsoNormal\">La Giunta, sempre su proposta del settore Lavori Pubblici, ha inoltre approvato il progetto di fattibilit\u00e0 tecnico-economica relativa all\u2019intervento di completamento dei rioni Guarna e Caridi e alla creazione di aree ludiche e verdi. L\u2019importo complessivo dell\u2019intervento, a valere sulle risorse del Piano di Sviluppo e Coesione della Citt\u00e0 Metropolitana di Reggio Calabria, \u00e8 in questo caso di circa 862 mila euro.<\/p>\n<p class=\"xmprfx_MsoNormal\"><em>\u00abI due ulteriori interventi per migliorare l\u2019accessibilit\u00e0 a Podargoni e mettere in rete i tre centri di Schindilif\u00e0, Cerasi e Podargoni<\/em> \u2013 ha commentato l\u2019assessore alla \u201cCitt\u00e0 sostenibile e accessibile\u201d, Paolo Malara \u2013 <em>rappresentano un altro tassello del programma pi\u00f9 generale di rigenerazione e valorizzazione dei borghi e delle aree interne attraverso le relazioni di comunit\u00e0, la qualit\u00e0 dell\u2019abitare, il turismo, le tradizioni e la cultura\u00bb.<\/em><\/p>\n<p class=\"xmprfx_MsoNormal\">Il vicesindaco Paolo Brunetti, che detiene la delega ai Lavori pubblici, ha aggiunto: <em>\u00abConcretizziamo l\u2019opportunit\u00e0 di riqualificare un borgo che senza dubbio merita di essere valorizzato per le sue caratteristiche peculiari e che, tra l&#8217;altro, si trova a ridosso del Parco Nazionale dell\u2019Aspromonte. Nella stessa ottica rientra il completamento degli interventi nei rioni Guarna e Caridi: un parco in un\u2019area densamente abitata della zona Sud della citt\u00e0 diventer\u00e0 realt\u00e0 sulla scia di altre esperienze positive come quella dell\u2019area del Tempietto. \u00c8 la dimostrazione<\/em> \u2013 ha concluso Brunetti \u2013 <em>che questa Amministrazione inizia le opere e nella stessa consiliatura riesce anche a portarle a compimento\u00bb.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Giunta comunale di Reggio Calabria, su proposta del settore Lavori Pubblici, ha approvato in una recente seduta i progetti di fattibilit\u00e0 tecnico-economica degli interventi di manutenzione straordinaria e messa&hellip;<\/p>\n","protected":false},"author":19,"featured_media":9490,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[921,196,140],"tags":[],"class_list":["post-75394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-news","category-reggio-calabria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Palazzo San Giorgio: la Giunta approva interventi sulla viabilit\u00e0 per Podargoni - Radio Touring 104<\/title>\n<meta name=\"description\" content=\"Interessati da opere di miglioramento anche i rioni Guarna e Caridi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/06\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palazzo San Giorgio: la Giunta approva interventi sulla viabilit\u00e0 per Podargoni - Radio Touring 104\" \/>\n<meta property=\"og:description\" content=\"Interessati da opere di miglioramento anche i rioni Guarna e Caridi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/06\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-06T16:54:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/09\/Palazzo-San-Giorgio-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"S L\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"S L\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/06\\\/06\\\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/06\\\/06\\\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\\\/\"},\"author\":{\"name\":\"S L\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/b9f9c3730b0a78814c9b9f3bfc52c619\"},\"headline\":\"Palazzo San Giorgio: la Giunta approva interventi sulla viabilit\u00e0 per Podargoni\",\"datePublished\":\"2025-06-06T16:54:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/06\\\/06\\\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\\\/\"},\"wordCount\":449,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/06\\\/06\\\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/09\\\/Palazzo-San-Giorgio-3.jpg\",\"articleSection\":[\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/06\\\/06\\\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/06\\\/06\\\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\\\/\",\"name\":\"Palazzo San Giorgio: la Giunta approva interventi sulla viabilit\u00e0 per Podargoni - Radio Touring 104\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/06\\\/06\\\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/06\\\/06\\\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/09\\\/Palazzo-San-Giorgio-3.jpg\",\"datePublished\":\"2025-06-06T16:54:56+00:00\",\"description\":\"Interessati da opere di miglioramento anche i rioni Guarna e Caridi\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/06\\\/06\\\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/06\\\/06\\\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/06\\\/06\\\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/09\\\/Palazzo-San-Giorgio-3.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/09\\\/Palazzo-San-Giorgio-3.jpg\",\"width\":1000,\"height\":563},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/06\\\/06\\\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Palazzo San Giorgio: la Giunta approva interventi sulla viabilit\u00e0 per Podargoni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/b9f9c3730b0a78814c9b9f3bfc52c619\",\"name\":\"S L\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/652c51789d7030aaed9ff828331360502a68204fe6fb0831bc280515210e16d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/652c51789d7030aaed9ff828331360502a68204fe6fb0831bc280515210e16d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/652c51789d7030aaed9ff828331360502a68204fe6fb0831bc280515210e16d2?s=96&d=mm&r=g\",\"caption\":\"S L\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/slibri\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Palazzo San Giorgio: la Giunta approva interventi sulla viabilit\u00e0 per Podargoni - Radio Touring 104","description":"Interessati da opere di miglioramento anche i rioni Guarna e Caridi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/06\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\/","og_locale":"it_IT","og_type":"article","og_title":"Palazzo San Giorgio: la Giunta approva interventi sulla viabilit\u00e0 per Podargoni - Radio Touring 104","og_description":"Interessati da opere di miglioramento anche i rioni Guarna e Caridi","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/06\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\/","og_site_name":"Radio Touring 104","article_published_time":"2025-06-06T16:54:56+00:00","og_image":[{"width":1000,"height":563,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/09\/Palazzo-San-Giorgio-3.jpg","type":"image\/jpeg"}],"author":"S L","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"S L","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/06\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/06\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\/"},"author":{"name":"S L","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/b9f9c3730b0a78814c9b9f3bfc52c619"},"headline":"Palazzo San Giorgio: la Giunta approva interventi sulla viabilit\u00e0 per Podargoni","datePublished":"2025-06-06T16:54:56+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/06\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\/"},"wordCount":449,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/06\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/09\/Palazzo-San-Giorgio-3.jpg","articleSection":["Home","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/06\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/06\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\/","name":"Palazzo San Giorgio: la Giunta approva interventi sulla viabilit\u00e0 per Podargoni - Radio Touring 104","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/06\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/06\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/09\/Palazzo-San-Giorgio-3.jpg","datePublished":"2025-06-06T16:54:56+00:00","description":"Interessati da opere di miglioramento anche i rioni Guarna e Caridi","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/06\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/06\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/06\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/09\/Palazzo-San-Giorgio-3.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/09\/Palazzo-San-Giorgio-3.jpg","width":1000,"height":563},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/06\/palazzo-san-giorgio-la-giunta-approva-interventi-sulla-viabilita-per-podargoni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Palazzo San Giorgio: la Giunta approva interventi sulla viabilit\u00e0 per Podargoni"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/b9f9c3730b0a78814c9b9f3bfc52c619","name":"S L","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/652c51789d7030aaed9ff828331360502a68204fe6fb0831bc280515210e16d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/652c51789d7030aaed9ff828331360502a68204fe6fb0831bc280515210e16d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/652c51789d7030aaed9ff828331360502a68204fe6fb0831bc280515210e16d2?s=96&d=mm&r=g","caption":"S L"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/slibri\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/09\/Palazzo-San-Giorgio-3.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/75394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=75394"}],"version-history":[{"count":2,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/75394\/revisions"}],"predecessor-version":[{"id":75396,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/75394\/revisions\/75396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/9490"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=75394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=75394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=75394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}