{"id":76738,"date":"2025-06-26T09:04:05","date_gmt":"2025-06-26T07:04:05","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=76738"},"modified":"2025-06-26T09:04:05","modified_gmt":"2025-06-26T07:04:05","slug":"la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/26\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\/","title":{"rendered":"La Senatrice Minasi presenta un disegno di legge su manipolazione mentale e sette"},"content":{"rendered":"<p class=\"xmprfx_gmail-CorpoA\">E&#8217; stato presentato al Senato, su iniziativa della senatrice Tilde Minasi e il convinto sostegno delle colleghe Giulia Bongiorno ed Erika Stefani (la prima Presidente e la seconda componente della Commissione Giustizia del Senato), un disegno di legge volto a introdurre nel codice penale una nuova fattispecie autonoma: il reato di \u201cmanipolazione mentale\u201d.<span class=\"xmprfx_gmail-Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"xmprfx_gmail-CorpoA\">L&#8217;obiettivo \u00e8 colmare \u2013 come auspicano la dottrina penalistica e la giurisprudenza di merito \u2013 un vuoto normativo che, da oltre quarant&#8217;anni, priva l&#8217;ordinamento italiano di uno strumento idoneo a contrastare gravi forme di condizionamento psicologico esercitato in modo sistematico, reiterato e organizzato.<\/p>\n<p class=\"xmprfx_gmail-CorpoA\">Dal 1981, cio\u00e8 da quando la Corte Costituzionale si pronunci\u00f2 per l\u2019incostituzionalit\u00e0 del reato di plagio, previsto allora dall\u2019art. 603 c.p., non esiste una tutela per le vittime di manipolazione mentale. La Consulta non neg\u00f2 in quel momento l&#8217;esistenza del fenomeno della soggezione psichica n<span lang=\"FR\">\u00e9<span class=\"xmprfx_gmail-Apple-converted-space\">\u00a0<\/span><\/span>la sua lesivit\u00e0 per l&#8217;autonomia personale, ma ritenne carente di determinatezza la norma in vigore, rendendola dunque inapplicabile, e, da allora, il legislatore non \u00e8 pi\u00f9 intervenuto per reintegrare l&#8217;area di tutela rimasta scoperta, nonostante i numerosi casi documentati di condotte manipolatorie in grado di soggiogare le persone fino all&#8217;annullamento dell&#8217;identit\u00e0 e del pensiero critico.<\/p>\n<p class=\"xmprfx_gmail-CorpoA\">\u00abHo ritenuto di dover presentare questo DDL \u2013 spiega la Senatrice Minasi \u2013 perch\u00e9 ci troviamo ormai di fronte a un fenomeno dilagante. Non possiamo pi\u00f9 rimanere inerti di fronte alla necessit\u00e0 di tutelare i tantissimi soggetti fragili caduti nella trappola di santoni, truffatori, persone senza scrupoli che, usando violenze psichiche e fisiche, riescono ad annullarne la personalit\u00e0, arrivando a distruggere le vittime e le loro famiglie. E\u2019 indispensabile, perci\u00f2, ripristinare prima possibile una soglia di difesa adeguata, definendo con chiarezza gli elementi costitutivi della nuova fattispecie\u00bb.<\/p>\n<p class=\"xmprfx_MsoNormal\">La proposta a prima firma Minasi, che ha lavorato a stretto contatto con la collega Stefani, prevede che sia punito con la reclusione da tre a otto anni \u201cchiunque, nell\u2019ambito di un gruppo che promuove o pratica attivit\u00e0 finalizzate a creare o sfruttare la dipendenza psicologica o fisica delle persone che vi partecipano, pone taluno in un perdurante stato di soggezione tale da escludere o da limitare grandemente la libert\u00e0 di autodeterminazione o la capacit\u00e0 di discernimento\u201d. E se<span class=\"xmprfx_gmail-Apple-converted-space\">\u00a0<\/span>la vittima \u00e8 minorenne,<span class=\"xmprfx_gmail-Apple-converted-space\">\u00a0<\/span>\u201cla pena non pu\u00f2 essere inferiore a sei anni di reclusione\u201d.<\/p>\n<p class=\"xmprfx_gmail-CorpoA\"><span lang=\"FR\">\u00ab<\/span>Si tratta \u2013 continua la Senatrice \u2013 di una risposta meditata e tecnicamente solida a un fenomeno che, pur non nuovo, ha assunto negli ultimi decenni connotazioni sempre pi\u00f9 sofisticate e difficilmente perseguibili con gli strumenti oggi disponibili. Basti pensare alle cosiddette &#8216;psico-sette&#8217;, comunit\u00e0 apparentemente legittime che, come ci racconta l\u2019esperienza clinica e investigativa, celano strutture di dominio fondate sull&#8217;isolamento relazionale, l&#8217;indottrinamento ideologico, l&#8217;alterazione dei ritmi sonno-veglia, l&#8217;induzione di stati di trance ipnotica e, non di rado, la manipolazione sessuale e lo sfruttamento economico. Spesso \u2013 come riportiamo nella relazione allegata al DDL \u2013 vengono addirittura usate tecniche psicologiche avanzate, in parte derivate dalla psicoterapia, in modo distorto, per destrutturare appunto progressivamente la personalit\u00e0 dell&#8217;adepto.<span class=\"xmprfx_gmail-Apple-converted-space\">\u00a0<\/span>La descrizione che ci \u00e8 stata fatta dagli esperti della materia \u2013 prosegue Minasi \u2013 \u00e8 impressionante: parliamo del cosiddetto \u201clove bombing\u201d, di isolamento sociale, di uso di falsi ricordi indotti, di deprivazione sensoriale, di riprogrammazione mentale. Cio\u00e8 di un vero e proprio \u201clavaggio del cervello\u201d che arriva a far dissociare le vittime dalla realt\u00e0, talvolta fino a indurle alla follia. Per tutte queste ragioni abbiamo ritenuto che non sia pi\u00f9 possibile ritardare oltre un intervento da parte di chi ha la responsabilit\u00e0 di legiferare per tutelare i cittadini\u00bb.<\/p>\n<p class=\"xmprfx_gmail-CorpoA\">Ad aggiungere altri dettagli \u00e8 la Senatrice Stefani:<span class=\"xmprfx_gmail-Apple-converted-space\">\u00a0<\/span>\u00abIl testo normativo prevede anche l&#8217;istituzione di un&#8217;unit\u00e0 investigativa interforze a livello centrale, con articolazioni regionali, e un archivio informatizzato contenente informazioni sulle organizzazioni settarie, i loro leader, le modalit\u00e0 operative, la geolocalizzazione delle sedi e i profili delle vittime, fondamentali per aiutare chi \u00e8 appunto chiamato a investigare, ma anche per diffondere consapevolezza tra la popolazione. Solo attraverso un approccio integrato e un\u2019efficace intelligence preventiva sar\u00e0, infatti, possibile contrastare una rete che, per sua natura, opera in modo nascosto, anche con tecnologie non tracciabili e circuiti chiusi come il dark web\u00bb, afferma Stefani, che poi commenta ancora:<span class=\"xmprfx_gmail-Apple-converted-space\">\u00a0<\/span>\u00abPer noi \u00e8 fondamentale che finalmente la manipolazione mentale venga riconosciuta come reato. Significa, infatti, dar voce a chi ha subito l&#8217;invisibile violenza del controllo psicologico, e offrire uno strumento concreto di tutela alle vittime e alle loro famiglie. Nessuno deve essere lasciato solo davanti a un abuso che distrugge identit\u00e0, legami e futuro. Bisogna prevenire queste situazioni drammatiche e, insieme, sostenere chi purtroppo ci finisce dentro\u00bb.<\/p>\n<p class=\"xmprfx_gmail-CorpoA\">Il DDL si allinea alle raccomandazioni di organismi internazionali, come il Consiglio d&#8217;Europa, che da tempo esortano gli Stati membri ad adottare strumenti giuridici adeguati per fronteggiare i cosiddetti \u201cculti distruttivi\u201d.<\/p>\n<p class=\"xmprfx_gmail-CorpoA\">\u00abQuesta proposta rappresenta un passo decisivo nella tutela della persona nella sua integralit\u00e0 \u2013 dicono le Senatrici \u2013 Riconosciamo che l&#8217;aggressione alla psiche, se condotta con sistematicit\u00e0 e intenzionalit\u00e0, costituisce una forma intollerabile di violenza. Lo Stato deve presidiare anche lo spazio interiore dell&#8217;individuo, garantendo che la libert\u00e0 di credere, scegliere e pensare non venga mai piegata a logiche di potere occulto\u00bb.<\/p>\n<p class=\"xmprfx_gmail-CorpoA\">Un contributo fondamentale \u00e8 arrivato, alla stesura del DDL, dall\u2019Associazione Manisco World e da due professionisti che da tempo seguono da vicino la problematica, l\u2019avvocato Vincenzo Dionisi e il criminologo Sergio Caruso.<\/p>\n<p class=\"xmprfx_gmail-CorpoA\">\u00abDesidero rivolgere un sentito ringraziamento \u2013 sottolinea infine Minasi \u2013 all&#8217;Associazione Manisco World, e in particolare alla sua presidente Virginia Melissa Adamo, all&#8217;avvocato Dionisi e al dott. Caruso, per il contributo fondamentale nel portare alla luce la natura pervasiva e distruttiva dei meccanismi settari. La loro esperienza sul campo, a diretto contatto con vittime e famiglie, ha permesso di trasformare il dolore in consapevolezza e la denuncia in proposta concreta. \u00c8 proprio a figure come loro che ogni giorno affrontano l&#8217;invisibile \u2013 conclude \u2013 che la politica deve dare ascolto e seguito se vuole davvero colmare un vuoto e offrire risposte all&#8217;altezza della sofferenza vissuta da tante persone\u00bb.<\/p>\n<p class=\"xmprfx_gmail-CorpoA\">\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; stato presentato al Senato, su iniziativa della senatrice Tilde Minasi e il convinto sostegno delle colleghe Giulia Bongiorno ed Erika Stefani (la prima Presidente e la seconda componente della&hellip;<\/p>\n","protected":false},"author":12,"featured_media":76739,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[142,921,196],"tags":[45255,45257,45258,45256,31925],"class_list":["post-76738","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-home","category-news","tag-disegno-di-legge","tag-manipolazione-mentale","tag-senatrice-stefani","tag-sette","tag-tide-minasi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Minasi presenta un Dl su manipolazione mentale e sette<\/title>\n<meta name=\"description\" content=\"&quot;Vuoto legislativo di oltre 40 anni, non possiamo pi\u00f9 rinviare&quot;, dichiara la Senatrice della Lega, Tilde Minasi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/26\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Minasi presenta un Dl su manipolazione mentale e sette\" \/>\n<meta property=\"og:description\" content=\"&quot;Vuoto legislativo di oltre 40 anni, non possiamo pi\u00f9 rinviare&quot;, dichiara la Senatrice della Lega, Tilde Minasi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/26\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-26T07:04:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/06\/MINASI-E-STEFANI.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"668\" \/>\n\t<meta property=\"og:image:height\" content=\"692\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sebastiano Plutino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastiano Plutino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/06\\\/26\\\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/06\\\/26\\\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\\\/\"},\"author\":{\"name\":\"Sebastiano Plutino\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\"},\"headline\":\"La Senatrice Minasi presenta un disegno di legge su manipolazione mentale e sette\",\"datePublished\":\"2025-06-26T07:04:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/06\\\/26\\\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\\\/\"},\"wordCount\":980,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/06\\\/26\\\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/06\\\/MINASI-E-STEFANI.jpg\",\"keywords\":[\"disegno di legge\",\"manipolazione mentale\",\"Senatrice Stefani\",\"sette\",\"Tide Minasi\"],\"articleSection\":[\"Calabria\",\"Home\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/06\\\/26\\\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/06\\\/26\\\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\\\/\",\"name\":\"Minasi presenta un Dl su manipolazione mentale e sette\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/06\\\/26\\\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/06\\\/26\\\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/06\\\/MINASI-E-STEFANI.jpg\",\"datePublished\":\"2025-06-26T07:04:05+00:00\",\"description\":\"\\\"Vuoto legislativo di oltre 40 anni, non possiamo pi\u00f9 rinviare\\\", dichiara la Senatrice della Lega, Tilde Minasi\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/06\\\/26\\\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/06\\\/26\\\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/06\\\/26\\\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/06\\\/MINASI-E-STEFANI.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/06\\\/MINASI-E-STEFANI.jpg\",\"width\":668,\"height\":692},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/06\\\/26\\\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Senatrice Minasi presenta un disegno di legge su manipolazione mentale e sette\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/78613917f1851f041f7483f5af1d422e\",\"name\":\"Sebastiano Plutino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g\",\"caption\":\"Sebastiano Plutino\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/sebastiano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Minasi presenta un Dl su manipolazione mentale e sette","description":"\"Vuoto legislativo di oltre 40 anni, non possiamo pi\u00f9 rinviare\", dichiara la Senatrice della Lega, Tilde Minasi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/26\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\/","og_locale":"it_IT","og_type":"article","og_title":"Minasi presenta un Dl su manipolazione mentale e sette","og_description":"\"Vuoto legislativo di oltre 40 anni, non possiamo pi\u00f9 rinviare\", dichiara la Senatrice della Lega, Tilde Minasi","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/26\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\/","og_site_name":"Radio Touring 104","article_published_time":"2025-06-26T07:04:05+00:00","og_image":[{"width":668,"height":692,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/06\/MINASI-E-STEFANI.jpg","type":"image\/jpeg"}],"author":"Sebastiano Plutino","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Sebastiano Plutino","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/26\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/26\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\/"},"author":{"name":"Sebastiano Plutino","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e"},"headline":"La Senatrice Minasi presenta un disegno di legge su manipolazione mentale e sette","datePublished":"2025-06-26T07:04:05+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/26\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\/"},"wordCount":980,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/26\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/06\/MINASI-E-STEFANI.jpg","keywords":["disegno di legge","manipolazione mentale","Senatrice Stefani","sette","Tide Minasi"],"articleSection":["Calabria","Home","News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/26\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/26\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\/","name":"Minasi presenta un Dl su manipolazione mentale e sette","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/26\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/26\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/06\/MINASI-E-STEFANI.jpg","datePublished":"2025-06-26T07:04:05+00:00","description":"\"Vuoto legislativo di oltre 40 anni, non possiamo pi\u00f9 rinviare\", dichiara la Senatrice della Lega, Tilde Minasi","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/26\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/26\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/26\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/06\/MINASI-E-STEFANI.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/06\/MINASI-E-STEFANI.jpg","width":668,"height":692},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/06\/26\/la-senatrice-minasi-presenta-un-disegno-di-legge-su-manipolazione-mentale-e-sette\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"La Senatrice Minasi presenta un disegno di legge su manipolazione mentale e sette"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/78613917f1851f041f7483f5af1d422e","name":"Sebastiano Plutino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0546ffaa9b79224faf9f2a156b67a529ae861d3287c66c1d8ccfdf909bcba78d?s=96&d=mm&r=g","caption":"Sebastiano Plutino"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/sebastiano\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/06\/MINASI-E-STEFANI.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/76738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=76738"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/76738\/revisions"}],"predecessor-version":[{"id":76740,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/76738\/revisions\/76740"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/76739"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=76738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=76738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=76738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}