{"id":77931,"date":"2025-07-18T12:50:11","date_gmt":"2025-07-18T10:50:11","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=77931"},"modified":"2025-07-18T12:50:51","modified_gmt":"2025-07-18T10:50:51","slug":"calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2025\/07\/18\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\/","title":{"rendered":"Calabria: la Rete dei Borghi parteciper\u00e0 all&#8217;Assemblea Regionale e all&#8217; &#8220;ABT Festival&#8221;"},"content":{"rendered":"<p class=\"xmprfx_MsoNormal\">L\u2019Associazione Borghi Autentici d\u2019Italia annuncia con grande soddisfazione due importanti appuntamenti previsti in Calabria che coinvolgeranno la rete regionale dei Borghi Autentici e rafforzeranno il percorso di cooperazione territoriale tra le comunit\u00e0.<\/p>\n<p class=\"xmprfx_MsoNormal\">l\u2019Associazione sar\u00e0 presente alla tappa calabrese\u00a0<b>dell\u2019ABT Festival,\u00a0<\/b>il tour che attraversa l\u2019Italia per promuovere l\u2019Appennino e accendere i riflettori sullo sviluppo di queste aree con l\u2019organizzazione di un evento nazionale in ognuna delle regioni appenniniche,\u00a0<b>in programma il 19 luglio in localit\u00e0 Silvana Mansio<\/b>\u00a0a Casali del Manco. Un evento dedicato al turismo lento, alle tradizioni locali e alla promozione culturale dei territori, ma anche un\u2019occasione per raccontare la mission dei Borghi Autentici d\u2019Italia, incontrare il pubblico e ribadire l\u2019importanza del protagonismo delle comunit\u00e0 locali nel disegno del futuro dei borghi.<\/p>\n<p class=\"xmprfx_MsoNormal\">Nel Villaggio Appennino Bike Tour si alterneranno eventi ed iniziative con l\u2019organizzazione di talk, convegni, degustazioni e attivit\u00e0 di avviamento alla bicicletta per i pi\u00f9 piccoli. In questa cornice si terr\u00e0 il\u00a0<b>Forum Regionale sullo Sviluppo Sostenibile dell\u2019Appennino<\/b>\u00a0in programma alle ore 15.00, rappresenta un momento di riflessione e confronto sulle progettualit\u00e0 in corso e sulle sfide future, coinvolgendo sindaci, istituzioni, associazioni ed enti impegnati nello sviluppo sostenibile dell\u2019Appennino.<\/p>\n<p class=\"xmprfx_MsoNormal\">A questo importante momento di confronto parteciperanno:\u00a0<b>Francesca Pisani<\/b>, Sindaca di Casali del Manco;\u00a0<b>Enrico Della Torre<\/b>, Direttore Generale Vivi Appennino;\u00a0<b>Saverio Bianco<\/b>, Guida Ufficiale del Parco Nazionale della Sila;\u00a0<b>Rosaria Succurro<\/b>, Presidente ANCI Calabria;\u00a0<b>Rosanna Mazzia<\/b>\u00a0&#8211; Presidente Associazione Borghi Autentici d&#8217;italia;\u00a0<b>Liborio Bloise<\/b>, Commissario del Parco Nazionale della Sila;\u00a0<b>Fulvia Caligiuri<\/b>, Direttore Generale ARSAC Calabria;\u00a0<b>Antonio Candalise<\/b>, Presidente GAL Sila;\u00a0<b>Antonio Nicoletti<\/b>, Presidente Legambiente Cosenza;\u00a0<b>Giuseppe Guzzo<\/b>, Presidente Sila Tre Vette;\u00a0<b>On.le Giovanni Calabrese<\/b>, Assessore al Turismo e all&#8217;Ambiente della Regione Calabria.<br \/><b>Sabato 20 luglio<\/b>\u00a0alle ore 10:00, nella splendida cornice di Lorica, nel cuore della Sila, si terr\u00e0\u00a0<b>l\u2019Assemblea Regionale dei Borghi Autentici della Calabria,<\/b>\u00a0un momento di confronto tra amministratori, referenti territoriali, cittadini attivi e rappresentanti dell\u2019Associazione nazionale per condividere esperienze, visioni e strategie comuni per la valorizzazione dei borghi calabresi.\u00a0<b>L\u2019incontro rappresenta un\u2019occasione fondamentale per consolidare il legame tra i comuni aderenti alla rete<\/b>\u00a0e per definire nuove azioni condivise di sviluppo locale sostenibile.<\/p>\n<p class=\"xmprfx_MsoNormal\">I lavori dell\u2019Assemblea Regionale BAI vedranno la partecipazione della Sindaca di casa e Componente del Consiglio Direttivo dell\u2019Associazione,\u00a0<b>Francesca Pisani,<\/b>\u00a0dei Sindaci e dei rappresentanti dei Comuni della Rete BAI Calabria e dell\u2019intero territorio, della Segreteria Tecnica e della Presidente Nazionale, Rosanna Mazzia.<\/p>\n<p class=\"xmprfx_MsoNormal\">\u201cQuesti due appuntamenti \u2013 sottolinea la Presidente dell\u2019Associazione Borghi Autentici d\u2019Italia,\u00a0<b>Rosanna Mazzia<\/b>\u00a0\u2013 confermano il fermento e l\u2019energia dei territori calabresi. Attraverso queste iniziative vogliamo costruire una rete regionale sempre pi\u00f9 attiva, consapevole e unita nel perseguire un modello di sviluppo che mette al centro le persone, la vitalit\u00e0 dei territori e la coesione sociale.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Associazione Borghi Autentici d\u2019Italia annuncia con grande soddisfazione due importanti appuntamenti previsti in Calabria che coinvolgeranno la rete regionale dei Borghi Autentici e rafforzeranno il percorso di cooperazione territoriale tra&hellip;<\/p>\n","protected":false},"author":5,"featured_media":77932,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[142,921,196],"tags":[45837,10929,45836,11280],"class_list":["post-77931","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-home","category-news","tag-abt-festival","tag-assemblea-regionale","tag-rete-dei-borghi","tag-rosanna-mazzia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Rete dei Borghi parteciper\u00e0 a due eventi in Calabria<\/title>\n<meta name=\"description\" content=\"L\u2019Associazione annuncia con grande soddisfazione due importanti appuntamenti previsti in Calabria. Ecco tutte le info\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2025\/07\/18\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Rete dei Borghi parteciper\u00e0 a due eventi in Calabria\" \/>\n<meta property=\"og:description\" content=\"L\u2019Associazione annuncia con grande soddisfazione due importanti appuntamenti previsti in Calabria. Ecco tutte le info\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2025\/07\/18\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-18T10:50:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-18T10:50:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/07\/Rete-dei-Borghi.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1131\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/07\\\/18\\\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/07\\\/18\\\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\\\/\"},\"author\":{\"name\":\"redazione\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/1b3eb3c07c47136bc44c785c543e635f\"},\"headline\":\"Calabria: la Rete dei Borghi parteciper\u00e0 all&#8217;Assemblea Regionale e all&#8217; &#8220;ABT Festival&#8221;\",\"datePublished\":\"2025-07-18T10:50:11+00:00\",\"dateModified\":\"2025-07-18T10:50:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/07\\\/18\\\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\\\/\"},\"wordCount\":481,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/07\\\/18\\\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/07\\\/Rete-dei-Borghi.jpeg\",\"keywords\":[\"\\\"ABT Festival\\\"\",\"Assemblea regionale\",\"Rete dei Borghi\",\"Rosanna Mazzia\"],\"articleSection\":[\"Calabria\",\"Home\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/07\\\/18\\\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/07\\\/18\\\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\\\/\",\"name\":\"La Rete dei Borghi parteciper\u00e0 a due eventi in Calabria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/07\\\/18\\\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/07\\\/18\\\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/07\\\/Rete-dei-Borghi.jpeg\",\"datePublished\":\"2025-07-18T10:50:11+00:00\",\"dateModified\":\"2025-07-18T10:50:51+00:00\",\"description\":\"L\u2019Associazione annuncia con grande soddisfazione due importanti appuntamenti previsti in Calabria. Ecco tutte le info\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/07\\\/18\\\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/07\\\/18\\\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/07\\\/18\\\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/07\\\/Rete-dei-Borghi.jpeg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/07\\\/Rete-dei-Borghi.jpeg\",\"width\":1131,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/07\\\/18\\\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calabria: la Rete dei Borghi parteciper\u00e0 all&#8217;Assemblea Regionale e all&#8217; &#8220;ABT Festival&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/1b3eb3c07c47136bc44c785c543e635f\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Rete dei Borghi parteciper\u00e0 a due eventi in Calabria","description":"L\u2019Associazione annuncia con grande soddisfazione due importanti appuntamenti previsti in Calabria. Ecco tutte le info","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2025\/07\/18\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\/","og_locale":"it_IT","og_type":"article","og_title":"La Rete dei Borghi parteciper\u00e0 a due eventi in Calabria","og_description":"L\u2019Associazione annuncia con grande soddisfazione due importanti appuntamenti previsti in Calabria. Ecco tutte le info","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2025\/07\/18\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\/","og_site_name":"Radio Touring 104","article_published_time":"2025-07-18T10:50:11+00:00","article_modified_time":"2025-07-18T10:50:51+00:00","og_image":[{"width":1131,"height":1600,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/07\/Rete-dei-Borghi.jpeg","type":"image\/jpeg"}],"author":"redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/07\/18\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/07\/18\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\/"},"author":{"name":"redazione","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/1b3eb3c07c47136bc44c785c543e635f"},"headline":"Calabria: la Rete dei Borghi parteciper\u00e0 all&#8217;Assemblea Regionale e all&#8217; &#8220;ABT Festival&#8221;","datePublished":"2025-07-18T10:50:11+00:00","dateModified":"2025-07-18T10:50:51+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/07\/18\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\/"},"wordCount":481,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/07\/18\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/07\/Rete-dei-Borghi.jpeg","keywords":["\"ABT Festival\"","Assemblea regionale","Rete dei Borghi","Rosanna Mazzia"],"articleSection":["Calabria","Home","News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/07\/18\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2025\/07\/18\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\/","name":"La Rete dei Borghi parteciper\u00e0 a due eventi in Calabria","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/07\/18\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/07\/18\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/07\/Rete-dei-Borghi.jpeg","datePublished":"2025-07-18T10:50:11+00:00","dateModified":"2025-07-18T10:50:51+00:00","description":"L\u2019Associazione annuncia con grande soddisfazione due importanti appuntamenti previsti in Calabria. Ecco tutte le info","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/07\/18\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2025\/07\/18\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/07\/18\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/07\/Rete-dei-Borghi.jpeg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/07\/Rete-dei-Borghi.jpeg","width":1131,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/07\/18\/calabria-la-rete-dei-borghi-partecipera-allassemblea-regionale-e-all-abt-festival\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Calabria: la Rete dei Borghi parteciper\u00e0 all&#8217;Assemblea Regionale e all&#8217; &#8220;ABT Festival&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/1b3eb3c07c47136bc44c785c543e635f","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g","caption":"redazione"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/redazione\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/07\/Rete-dei-Borghi.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/77931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=77931"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/77931\/revisions"}],"predecessor-version":[{"id":77933,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/77931\/revisions\/77933"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/77932"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=77931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=77931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=77931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}