{"id":83683,"date":"2025-10-10T11:04:04","date_gmt":"2025-10-10T09:04:04","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=83683"},"modified":"2025-10-10T12:50:23","modified_gmt":"2025-10-10T10:50:23","slug":"reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/10\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\/","title":{"rendered":"Reggio: firmato il protocollo di intesa fra la\u00a0Capitaneria di Porto \u2013 Guardia Costiera\u00a0e l\u2019Accademia di Belle Arti"},"content":{"rendered":"<p style=\"font-weight: 400\">Nella Sala dello Stretto della Direzione marittima, ieri mattina, \u00e8 stato firmato il protocollo di intesa fra la\u00a0<strong>Capitaneria di Porto \u2013 Guardia Costiera<\/strong>\u00a0e l\u2019<strong>Accademia di Belle Arti di Reggio Calabria<\/strong>. A siglare l\u2019intesa,\u00a0il\u00a0<strong>Direttore\u00a0<\/strong>dell\u2019Accademia di Belle Arti, professor Piero\u00a0<strong>Sacchetti\u00a0<\/strong>e il\u00a0<strong>Contrammiraglio<\/strong>\u00a0Giuseppe\u00a0<strong>Sciarrone<\/strong>.<\/p>\n<p style=\"font-weight: 400\">L\u2019accordo formalizza la comunione di intenti e di\u00a0<strong>valori\u00a0<\/strong>tra le parti, nello sviluppo di nuove sinergie finalizzate alla realizzazione di attivit\u00e0 atte alla promozione e valorizzazione della cultura marinara e del territorio.<\/p>\n<p style=\"font-weight: 400\">&#8220;Con la firma dell&#8217;odierno Protocollo d&#8217;intesa con l\u2019Accademia delle Belle Arti si consolida ulteriormente la sinergia che ha visto di recente collaborare l\u2019importante Ateneo reggino con la Direzione marittima, in attivit\u00e0 culturali quali la predisposizione della\u00a0<strong>mostra fotografica\u00a0<\/strong>dal titolo \u201cancorati al passato, con rotta verso il futuro\u201d, con il sincero e convinto auspicio che, con tali premesse, il protocollo si traduca presto in concreti ulteriori progetti di ricerca e collaborazione&#8221; .<\/p>\n<p style=\"font-weight: 400\">Il\u00a0Direttore dell\u2019Accademia delle Belle Arti, Sacchetti ha espresso l&#8217;orgoglio di tutto l&#8217;Ateneo per l&#8217;inizio di un\u00a0<strong>percorso condiviso<\/strong>\u00a0che, con questo importante accordo, avvier\u00e0 un&#8217;attivit\u00e0 di\u00a0<strong>formazione\u00a0<\/strong>e di avvicinamento\u00a0dell&#8217;Accademia\u00a0ad una realt\u00e0 strategica\u00a0come quella del Corpo delle Capitanerie di\u00a0Porto &#8211; Guardia Costiera.\u00a0Il Protocollo d&#8217;intesa ben si inserisce \u2013 ha proseguito \u2013 nei percorsi di apprendimento che il nostro Ateneo propone ai suoi\u00a0<strong>studenti<\/strong>, con esperienze fattive che necessariamente vanno a completare un percorso di studio e formazione come quello da sempre proposto&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella Sala dello Stretto della Direzione marittima, ieri mattina, \u00e8 stato firmato il protocollo di intesa fra la\u00a0Capitaneria di Porto \u2013 Guardia Costiera\u00a0e l\u2019Accademia di Belle Arti di Reggio Calabria.&hellip;<\/p>\n","protected":false},"author":5,"featured_media":83684,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[921,196,140],"tags":[1437,48220,48222,19649,47394,48221],"class_list":["post-83683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-news","category-reggio-calabria","tag-accademia-di-belle-arti","tag-capitaneria-di-porto-guardia-costiera","tag-contrammiraglio-giuseppe-sciarrone","tag-piero-sacchetti","tag-valorizzazione-del-territorio","tag-valorizzazione-della-cultura-marinara"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reggio: firmato il Protocollo tra Capitaneria ed Accademia Belle Arti<\/title>\n<meta name=\"description\" content=\"L\u2019accordo formalizza lw sinergie finalizzate alla realizzazione di attivit\u00e0 atte alla valorizzazione della cultura marinara e del territorio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/10\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reggio: firmato il Protocollo tra Capitaneria ed Accademia Belle Arti\" \/>\n<meta property=\"og:description\" content=\"L\u2019accordo formalizza lw sinergie finalizzate alla realizzazione di attivit\u00e0 atte alla valorizzazione della cultura marinara e del territorio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/10\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-10T09:04:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-10T10:50:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/10\/Contrammiraglio-Sciarrone-Piero-Sacchetti.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"1073\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/10\\\/10\\\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/10\\\/10\\\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\\\/\"},\"author\":{\"name\":\"redazione\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/1b3eb3c07c47136bc44c785c543e635f\"},\"headline\":\"Reggio: firmato il protocollo di intesa fra la\u00a0Capitaneria di Porto \u2013 Guardia Costiera\u00a0e l\u2019Accademia di Belle Arti\",\"datePublished\":\"2025-10-10T09:04:04+00:00\",\"dateModified\":\"2025-10-10T10:50:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/10\\\/10\\\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\\\/\"},\"wordCount\":263,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/10\\\/10\\\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/10\\\/Contrammiraglio-Sciarrone-Piero-Sacchetti.gif\",\"keywords\":[\"accademia di belle arti\",\"Capitaneria di Porto \u2013 Guardia Costiera\",\"Contrammiraglio\u00a0Giuseppe\u00a0Sciarrone.\",\"Piero Sacchetti.\",\"valorizzazione del territorio.\",\"valorizzazione della cultura marinara\"],\"articleSection\":[\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/10\\\/10\\\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/10\\\/10\\\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\\\/\",\"name\":\"Reggio: firmato il Protocollo tra Capitaneria ed Accademia Belle Arti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/10\\\/10\\\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/10\\\/10\\\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/10\\\/Contrammiraglio-Sciarrone-Piero-Sacchetti.gif\",\"datePublished\":\"2025-10-10T09:04:04+00:00\",\"dateModified\":\"2025-10-10T10:50:23+00:00\",\"description\":\"L\u2019accordo formalizza lw sinergie finalizzate alla realizzazione di attivit\u00e0 atte alla valorizzazione della cultura marinara e del territorio\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/10\\\/10\\\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/10\\\/10\\\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/10\\\/10\\\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/10\\\/Contrammiraglio-Sciarrone-Piero-Sacchetti.gif\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/10\\\/Contrammiraglio-Sciarrone-Piero-Sacchetti.gif\",\"width\":1073,\"height\":534},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/10\\\/10\\\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reggio: firmato il protocollo di intesa fra la\u00a0Capitaneria di Porto \u2013 Guardia Costiera\u00a0e l\u2019Accademia di Belle Arti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/1b3eb3c07c47136bc44c785c543e635f\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reggio: firmato il Protocollo tra Capitaneria ed Accademia Belle Arti","description":"L\u2019accordo formalizza lw sinergie finalizzate alla realizzazione di attivit\u00e0 atte alla valorizzazione della cultura marinara e del territorio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/10\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\/","og_locale":"it_IT","og_type":"article","og_title":"Reggio: firmato il Protocollo tra Capitaneria ed Accademia Belle Arti","og_description":"L\u2019accordo formalizza lw sinergie finalizzate alla realizzazione di attivit\u00e0 atte alla valorizzazione della cultura marinara e del territorio","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/10\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\/","og_site_name":"Radio Touring 104","article_published_time":"2025-10-10T09:04:04+00:00","article_modified_time":"2025-10-10T10:50:23+00:00","og_image":[{"width":1073,"height":534,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/10\/Contrammiraglio-Sciarrone-Piero-Sacchetti.gif","type":"image\/gif"}],"author":"redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/10\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/10\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\/"},"author":{"name":"redazione","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/1b3eb3c07c47136bc44c785c543e635f"},"headline":"Reggio: firmato il protocollo di intesa fra la\u00a0Capitaneria di Porto \u2013 Guardia Costiera\u00a0e l\u2019Accademia di Belle Arti","datePublished":"2025-10-10T09:04:04+00:00","dateModified":"2025-10-10T10:50:23+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/10\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\/"},"wordCount":263,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/10\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/10\/Contrammiraglio-Sciarrone-Piero-Sacchetti.gif","keywords":["accademia di belle arti","Capitaneria di Porto \u2013 Guardia Costiera","Contrammiraglio\u00a0Giuseppe\u00a0Sciarrone.","Piero Sacchetti.","valorizzazione del territorio.","valorizzazione della cultura marinara"],"articleSection":["Home","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/10\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/10\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\/","name":"Reggio: firmato il Protocollo tra Capitaneria ed Accademia Belle Arti","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/10\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/10\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/10\/Contrammiraglio-Sciarrone-Piero-Sacchetti.gif","datePublished":"2025-10-10T09:04:04+00:00","dateModified":"2025-10-10T10:50:23+00:00","description":"L\u2019accordo formalizza lw sinergie finalizzate alla realizzazione di attivit\u00e0 atte alla valorizzazione della cultura marinara e del territorio","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/10\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/10\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/10\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/10\/Contrammiraglio-Sciarrone-Piero-Sacchetti.gif","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/10\/Contrammiraglio-Sciarrone-Piero-Sacchetti.gif","width":1073,"height":534},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/10\/reggio-firmato-il-protocollo-di-intesa-fra-la-capitaneria-di-porto-guardia-costiera-e-laccademia-di-belle-arti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Reggio: firmato il protocollo di intesa fra la\u00a0Capitaneria di Porto \u2013 Guardia Costiera\u00a0e l\u2019Accademia di Belle Arti"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/1b3eb3c07c47136bc44c785c543e635f","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g","caption":"redazione"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/redazione\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/10\/Contrammiraglio-Sciarrone-Piero-Sacchetti.gif","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/83683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=83683"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/83683\/revisions"}],"predecessor-version":[{"id":83685,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/83683\/revisions\/83685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/83684"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=83683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=83683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=83683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}