{"id":85105,"date":"2025-10-31T12:21:37","date_gmt":"2025-10-31T11:21:37","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=85105"},"modified":"2025-10-31T12:38:24","modified_gmt":"2025-10-31T11:38:24","slug":"lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/31\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\/","title":{"rendered":"Lamezia: domani l&#8217;evento &#8220;Per te\u2026Sissy\u201d, in ricordo di Sissy Trovato Mazza"},"content":{"rendered":"<p>Una serata per celebrare il ricordo di Sissy Trovato Mazza nella ricorrenza del giorno in cui fu trovata agonizzante in una pozza di sangue, ma anche per approfondire e scandagliare il suo caso giudiziario a poca distanza dalla quarta richiesta di archiviazione come suicidio. L\u2019associazione contro la violenza di genere \u201cPer Te\u201d, guidata da Katya Nero, promuove sabato 1 novembre alle ore 19 presso il Teatro Costabile l\u2019evento \u201cPer te\u2026Sissy\u201d.<\/p>\n<p>La giovane agente di polizia penitenzia originaria di Taurianova in servizio nel carcere di Venezia, venne ritrovata nel 2016 all\u2019interno del vano ascensore dell\u2019ospedale civile in cui si era recata per un servizio esterno. Ferita da un colpo di pistola alla testa, Sissy rimase in coma fino al 12 gennaio 2019.<\/p>\n<p>Per la Procura si tratta di suicidio. Una versione a cui i familiari e gli affetti di Sissy non credono e che li porta da anni a spendersi per una riapertura delle indagini.<\/p>\n<p>Nella serata, condotta dalla regista teatrale Tiziana De Matteo con la giornalista Tiziana Bagnato, verr\u00e0 ricordata Sissy e rianalizzato il caso con i contributi dei familiari, del giornalista Rai Edoardo Lucarelli, della parlamentare Stefania Ascari ( entrambi in remoto), del presidente Adicosp &#8211; Associazione Direttori e Collaboratori Sportivi Calcio Alfonso Morrone.<\/p>\n<p>Durante la serata, patrocinata dal Comune di Lamezia Terme, \u00a0si esibiranno gli studenti della Scuola di Canto e Arti Sceniche A Regola d\u2019Arte e verr\u00e0 interpretato il monologo dedicato a Sissy di Mafalda Mele.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una serata per celebrare il ricordo di Sissy Trovato Mazza nella ricorrenza del giorno in cui fu trovata agonizzante in una pozza di sangue, ma anche per approfondire e scandagliare&hellip;<\/p>\n","protected":false},"author":5,"featured_media":85106,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[142,921,196,140],"tags":[48839,48840,48838,1705,48837,43734],"class_list":["post-85105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-home","category-news","category-reggio-calabria","tag-per-tesissy","tag-associazione-per-te","tag-evento-in-ricordo","tag-lamezia-terme","tag-sissy-trovato-mazza","tag-teatro-costabile"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lamezia: &quot;Per te\u2026Sissy\u201d, evento in ricordo di Sissy Trovato Mazza<\/title>\n<meta name=\"description\" content=\"L&#039;evento, promosso dall&#039;Associazione \u201cPer Te\u201d, si svolger\u00e0 doman, alle 19:00, presso il &quot;Teatro Costabile&quot; di Lamezia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/31\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lamezia: &quot;Per te\u2026Sissy\u201d, evento in ricordo di Sissy Trovato Mazza\" \/>\n<meta property=\"og:description\" content=\"L&#039;evento, promosso dall&#039;Associazione \u201cPer Te\u201d, si svolger\u00e0 doman, alle 19:00, presso il &quot;Teatro Costabile&quot; di Lamezia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/31\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-31T11:21:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-31T11:38:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/10\/Sissi-Trovato-Mazza.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1131\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/10\\\/31\\\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/10\\\/31\\\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\\\/\"},\"author\":{\"name\":\"redazione\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/1b3eb3c07c47136bc44c785c543e635f\"},\"headline\":\"Lamezia: domani l&#8217;evento &#8220;Per te\u2026Sissy\u201d, in ricordo di Sissy Trovato Mazza\",\"datePublished\":\"2025-10-31T11:21:37+00:00\",\"dateModified\":\"2025-10-31T11:38:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/10\\\/31\\\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\\\/\"},\"wordCount\":251,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/10\\\/31\\\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/10\\\/Sissi-Trovato-Mazza.jpeg\",\"keywords\":[\"\\\"Per te\u2026Sissy\u201d\",\"Associazione \u201cPer Te\u201d\",\"evento in ricordo\",\"Lamezia Terme\",\"Sissy Trovato Mazza\",\"teatro costabile\"],\"articleSection\":[\"Calabria\",\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/10\\\/31\\\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/10\\\/31\\\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\\\/\",\"name\":\"Lamezia: \\\"Per te\u2026Sissy\u201d, evento in ricordo di Sissy Trovato Mazza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/10\\\/31\\\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/10\\\/31\\\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/10\\\/Sissi-Trovato-Mazza.jpeg\",\"datePublished\":\"2025-10-31T11:21:37+00:00\",\"dateModified\":\"2025-10-31T11:38:24+00:00\",\"description\":\"L'evento, promosso dall'Associazione \u201cPer Te\u201d, si svolger\u00e0 doman, alle 19:00, presso il \\\"Teatro Costabile\\\" di Lamezia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/10\\\/31\\\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/10\\\/31\\\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/10\\\/31\\\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/10\\\/Sissi-Trovato-Mazza.jpeg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/10\\\/Sissi-Trovato-Mazza.jpeg\",\"width\":1131,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2025\\\/10\\\/31\\\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lamezia: domani l&#8217;evento &#8220;Per te\u2026Sissy\u201d, in ricordo di Sissy Trovato Mazza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/1b3eb3c07c47136bc44c785c543e635f\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lamezia: \"Per te\u2026Sissy\u201d, evento in ricordo di Sissy Trovato Mazza","description":"L'evento, promosso dall'Associazione \u201cPer Te\u201d, si svolger\u00e0 doman, alle 19:00, presso il \"Teatro Costabile\" di Lamezia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/31\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\/","og_locale":"it_IT","og_type":"article","og_title":"Lamezia: \"Per te\u2026Sissy\u201d, evento in ricordo di Sissy Trovato Mazza","og_description":"L'evento, promosso dall'Associazione \u201cPer Te\u201d, si svolger\u00e0 doman, alle 19:00, presso il \"Teatro Costabile\" di Lamezia","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/31\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\/","og_site_name":"Radio Touring 104","article_published_time":"2025-10-31T11:21:37+00:00","article_modified_time":"2025-10-31T11:38:24+00:00","og_image":[{"width":1131,"height":1600,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/10\/Sissi-Trovato-Mazza.jpeg","type":"image\/jpeg"}],"author":"redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/31\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/31\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\/"},"author":{"name":"redazione","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/1b3eb3c07c47136bc44c785c543e635f"},"headline":"Lamezia: domani l&#8217;evento &#8220;Per te\u2026Sissy\u201d, in ricordo di Sissy Trovato Mazza","datePublished":"2025-10-31T11:21:37+00:00","dateModified":"2025-10-31T11:38:24+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/31\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\/"},"wordCount":251,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/31\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/10\/Sissi-Trovato-Mazza.jpeg","keywords":["\"Per te\u2026Sissy\u201d","Associazione \u201cPer Te\u201d","evento in ricordo","Lamezia Terme","Sissy Trovato Mazza","teatro costabile"],"articleSection":["Calabria","Home","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/31\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/31\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\/","name":"Lamezia: \"Per te\u2026Sissy\u201d, evento in ricordo di Sissy Trovato Mazza","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/31\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/31\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/10\/Sissi-Trovato-Mazza.jpeg","datePublished":"2025-10-31T11:21:37+00:00","dateModified":"2025-10-31T11:38:24+00:00","description":"L'evento, promosso dall'Associazione \u201cPer Te\u201d, si svolger\u00e0 doman, alle 19:00, presso il \"Teatro Costabile\" di Lamezia","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/31\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/31\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/31\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/10\/Sissi-Trovato-Mazza.jpeg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/10\/Sissi-Trovato-Mazza.jpeg","width":1131,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2025\/10\/31\/lamezia-domani-levento-per-tesissy-in-ricordo-di-sissy-trovato-mazza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Lamezia: domani l&#8217;evento &#8220;Per te\u2026Sissy\u201d, in ricordo di Sissy Trovato Mazza"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/1b3eb3c07c47136bc44c785c543e635f","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g","caption":"redazione"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/redazione\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2025\/10\/Sissi-Trovato-Mazza.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/85105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=85105"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/85105\/revisions"}],"predecessor-version":[{"id":85107,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/85105\/revisions\/85107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/85106"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=85105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=85105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=85105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}