{"id":92719,"date":"2026-03-27T10:04:46","date_gmt":"2026-03-27T09:04:46","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=92719"},"modified":"2026-03-27T12:38:47","modified_gmt":"2026-03-27T11:38:47","slug":"ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2026\/03\/27\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\/","title":{"rendered":"Ponte sullo Stretto, Caminiti: &#8220;Stop annunci sui cantieri. Urge chiarezza su VIA e alternative all&#8217;Opera&#8221;"},"content":{"rendered":"<p>La Sindaca di Villa San Giovanni, Giusy Caminiti, interviene in modo netto e deciso sulle vicessitudini legate alla realizzazione del Ponte sullo Stretto. La prima cittadina di Villa S,G. sull&#8217;ennesimo rinvio dell&#8217;apertura dei cantieri, ora spostato all&#8217;ultimo trimestre del 2026, rammenta, tramite un comunicato tutti i rinvii, arrivati a quota 7, che hanno preceduto quest&#8217;ultimo.<\/p>\n<p>&#8220;A nulla \u00e8 servita la prudenza che abbiamo chiesto in commissione al Senato marted\u00ec scorso: non sorprende che per la settima volta si annunci l\u2019apertura dei cantieri nella nostra citt\u00e0 per l\u2019ultimo trimestre del 2026.<\/p>\n<p>Ricordiamole tutte quelle date: estate 2024, estate 2025, settembre 2025, ottobre 2025, febbraio 2026. Adesso sarebbe\u00a0l\u2019ultimo trimestre 2026. Anche la ragionevolezza del ministro Salvini nel non voler pi\u00f9 dare date \u00e8 durata davvero poco!<\/p>\n<p>Tanto lontano da qui a chi vuoi che importi di una comunit\u00e0 che si ritrova, suo malgrado, di fronte ad una incertezza perenne ed imminente?<\/p>\n<p>Non potr\u00f2 che dire questo al dottor Ciucci che incontrer\u00f2, il 27 marzo, prima della sua conferenza stampa qui a Villa, ribadendo ci\u00f2 che alle commissioni del Senato abbiamo detto chiaramente: non si perda l\u2019occasione di prevedere nella nuova legge una VIA integrale e complessiva; non si faccia come \u00e8 successo con la Corte dei Conti i cui rilievi oggi sono in quel disegno di legge, quando sarebbe bastato ascoltare i rilievi posti dalle amministrazioni e seguire un iter adeguato e non frettoloso.<\/p>\n<p>La stessa fretta che oggi constatiamo nell\u2019annuncio fatto dalla Stretto di Messina dopo che, in commissione, le amministrazioni territoriali hanno chiesto di valutare e approfondire.<\/p>\n<p>Cosa ha chiesto Villa San Giovanni: l\u2019aggiornamento dello studio di impatto ambientale perch\u00e9 c\u2019\u00e8 una \u201csignificativa modificazione dell\u2019impatto globale del progetto sull\u2019ambiente\u201c dovuta, nel caso specifico, al fatto che sono cambiati gli stessi fattori presi in esame 20 anni or sono; ha chiesto che venga rinnovata integralmente la valutazione di impatto ambientale per superare una \u201cmini via\u201d e per arrivare ad una VIA complessiva; ha chiesto che le prescrizioni relative agli studi vadano verificate (per come peraltro chiaramente evidenziato dallo stesso Tar Lazio) non con un semplice giudizio di ottemperanza ma con una nuova VIA; ha chiesto che tutto questo venga valutato dalle camere ed inserito nel disegno di legge in esame, senza trincerarsi dietro la solita decretazione d\u2019urgenza.<\/p>\n<p>\u00c8 chiaro che indietro non si torna! Se \u00e8 vero che il diritto comunitario non impone che la compatibilit\u00e0 ambientale sia condizionata inderogabilmente dall\u2019esito dell\u2019istruttoria tecnica, il CIPESS nel contemperare tra le esigenze di tutela ambientale e lo sviluppo economico non pu\u00f2 prescindere da due condizioni: che non vi siano soluzioni alternative (e quelle soluzioni ci sono e sono depositate al MIT) e che non sia percorribile l\u2019alternativa zero.<\/p>\n<p>Per la citt\u00e0 di Villa San Giovanni vedere nel disegno di legge finalmente l\u2019indicazione precisa del \u201ctenuto conto delle soluzioni alternative, inclusa quella di non intervento\u201c \u00e8 la prima vittoria, perch\u00e9 quest\u2019Amministrazione in commissione VIA VAS e in conferenza istruttoria al MIT ha sempre sostenuto che non si potesse prescindere da tali valutazioni comparative. Ed allora, se veramente si vuole affrontare sul serio il seguito di questi iter procedurale si pongano a fondamento del disegno di legge tutte le prescrizioni ed i rilievi della Corte Dei Conti e del Tar Lazio. Continueremo a vigilare con una precipua azione di controllo su tutti gli atti che saranno posti in essere dal governo e dai ministeri competenti, senza per\u00f2 permettere ad alcuno di poter nuovamente generare paure nella nostra comunit\u00e0. Lo stop alla pianificazione dal l 2023, la perdita di alcuni finanziamenti, il danno economico ai villesi sui cui beni grava il vincolo da esproprio, non consentono ad alcuno di continuare ad ingenerare ansie e preoccupazioni.<\/p>\n<p>Non c\u2019\u00e8 una prossima data per l\u2019apertura dei cantieri. Continuare a dirlo, rende tutti noi assolutamente non credibili.&#8221;, scrive la Sindaca di Villa San Giovanni, Giusy Caminitit, nel comunicato,<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Sindaca di Villa San Giovanni, Giusy Caminiti, interviene in modo netto e deciso sulle vicessitudini legate alla realizzazione del Ponte sullo Stretto. La prima cittadina di Villa S,G. sull&#8217;ennesimo&hellip;<\/p>\n","protected":false},"author":5,"featured_media":43160,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[921,196,140],"tags":[52232,52229,3568,4355,52230,52231],"class_list":["post-92719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-news","category-reggio-calabria","tag-alternaative-al-ponte-sullo-stretto","tag-basta-annuncic-sui-cantieri","tag-giusy-caminiti","tag-ponte-sullo-stretto","tag-serve-chiarezza","tag-via"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ponte sullo Stretto, Caminiti: &quot;Stop annunci sui cantieri. Urge chiarezza su VIA e alternative all&#039;Opera&quot; - Radio Touring 104<\/title>\n<meta name=\"description\" content=\"&quot;Non sorprende che per la 7\u00b0 volta si annunci l\u2019apertura dei cantieri nella nostra citt\u00e0 per l\u2019ultimo trimestre del 2026&quot;, tuona la Sindaca\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2026\/03\/27\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ponte sullo Stretto, Caminiti: &quot;Stop annunci sui cantieri. Urge chiarezza su VIA e alternative all&#039;Opera&quot; - Radio Touring 104\" \/>\n<meta property=\"og:description\" content=\"&quot;Non sorprende che per la 7\u00b0 volta si annunci l\u2019apertura dei cantieri nella nostra citt\u00e0 per l\u2019ultimo trimestre del 2026&quot;, tuona la Sindaca\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2026\/03\/27\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-27T09:04:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-27T11:38:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/01\/Ponte-sullo-Stretto-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"667\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/03\\\/27\\\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/03\\\/27\\\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\\\/\"},\"author\":{\"name\":\"redazione\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/1b3eb3c07c47136bc44c785c543e635f\"},\"headline\":\"Ponte sullo Stretto, Caminiti: &#8220;Stop annunci sui cantieri. Urge chiarezza su VIA e alternative all&#8217;Opera&#8221;\",\"datePublished\":\"2026-03-27T09:04:46+00:00\",\"dateModified\":\"2026-03-27T11:38:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/03\\\/27\\\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\\\/\"},\"wordCount\":653,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/03\\\/27\\\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/01\\\/Ponte-sullo-Stretto-1.jpg\",\"keywords\":[\"alternaative al ponte sullo stretto\",\"basta annuncic sui cantieri\",\"Giusy Caminiti\",\"Ponte sullo stretto\",\"serve chiarezza\",\"VIA\"],\"articleSection\":[\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/03\\\/27\\\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/03\\\/27\\\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\\\/\",\"name\":\"Ponte sullo Stretto, Caminiti: \\\"Stop annunci sui cantieri. Urge chiarezza su VIA e alternative all'Opera\\\" - Radio Touring 104\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/03\\\/27\\\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/03\\\/27\\\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/01\\\/Ponte-sullo-Stretto-1.jpg\",\"datePublished\":\"2026-03-27T09:04:46+00:00\",\"dateModified\":\"2026-03-27T11:38:47+00:00\",\"description\":\"\\\"Non sorprende che per la 7\u00b0 volta si annunci l\u2019apertura dei cantieri nella nostra citt\u00e0 per l\u2019ultimo trimestre del 2026\\\", tuona la Sindaca\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/03\\\/27\\\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/03\\\/27\\\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/03\\\/27\\\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/01\\\/Ponte-sullo-Stretto-1.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/01\\\/Ponte-sullo-Stretto-1.jpg\",\"width\":667,\"height\":432},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/03\\\/27\\\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ponte sullo Stretto, Caminiti: &#8220;Stop annunci sui cantieri. Urge chiarezza su VIA e alternative all&#8217;Opera&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/1b3eb3c07c47136bc44c785c543e635f\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ponte sullo Stretto, Caminiti: \"Stop annunci sui cantieri. Urge chiarezza su VIA e alternative all'Opera\" - Radio Touring 104","description":"\"Non sorprende che per la 7\u00b0 volta si annunci l\u2019apertura dei cantieri nella nostra citt\u00e0 per l\u2019ultimo trimestre del 2026\", tuona la Sindaca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2026\/03\/27\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\/","og_locale":"it_IT","og_type":"article","og_title":"Ponte sullo Stretto, Caminiti: \"Stop annunci sui cantieri. Urge chiarezza su VIA e alternative all'Opera\" - Radio Touring 104","og_description":"\"Non sorprende che per la 7\u00b0 volta si annunci l\u2019apertura dei cantieri nella nostra citt\u00e0 per l\u2019ultimo trimestre del 2026\", tuona la Sindaca","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2026\/03\/27\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\/","og_site_name":"Radio Touring 104","article_published_time":"2026-03-27T09:04:46+00:00","article_modified_time":"2026-03-27T11:38:47+00:00","og_image":[{"width":667,"height":432,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/01\/Ponte-sullo-Stretto-1.jpg","type":"image\/jpeg"}],"author":"redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/03\/27\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/03\/27\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\/"},"author":{"name":"redazione","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/1b3eb3c07c47136bc44c785c543e635f"},"headline":"Ponte sullo Stretto, Caminiti: &#8220;Stop annunci sui cantieri. Urge chiarezza su VIA e alternative all&#8217;Opera&#8221;","datePublished":"2026-03-27T09:04:46+00:00","dateModified":"2026-03-27T11:38:47+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/03\/27\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\/"},"wordCount":653,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/03\/27\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/01\/Ponte-sullo-Stretto-1.jpg","keywords":["alternaative al ponte sullo stretto","basta annuncic sui cantieri","Giusy Caminiti","Ponte sullo stretto","serve chiarezza","VIA"],"articleSection":["Home","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/03\/27\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2026\/03\/27\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\/","name":"Ponte sullo Stretto, Caminiti: \"Stop annunci sui cantieri. Urge chiarezza su VIA e alternative all'Opera\" - Radio Touring 104","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/03\/27\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/03\/27\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/01\/Ponte-sullo-Stretto-1.jpg","datePublished":"2026-03-27T09:04:46+00:00","dateModified":"2026-03-27T11:38:47+00:00","description":"\"Non sorprende che per la 7\u00b0 volta si annunci l\u2019apertura dei cantieri nella nostra citt\u00e0 per l\u2019ultimo trimestre del 2026\", tuona la Sindaca","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/03\/27\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2026\/03\/27\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/03\/27\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/01\/Ponte-sullo-Stretto-1.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/01\/Ponte-sullo-Stretto-1.jpg","width":667,"height":432},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/03\/27\/ponte-sullo-stretto-caminiti-stop-annunci-sui-cantieri-urge-chiarezza-su-via-e-alternative-allopera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Ponte sullo Stretto, Caminiti: &#8220;Stop annunci sui cantieri. Urge chiarezza su VIA e alternative all&#8217;Opera&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/1b3eb3c07c47136bc44c785c543e635f","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g","caption":"redazione"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/redazione\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2024\/01\/Ponte-sullo-Stretto-1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/92719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=92719"}],"version-history":[{"count":1,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/92719\/revisions"}],"predecessor-version":[{"id":92720,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/92719\/revisions\/92720"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/43160"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=92719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=92719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=92719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}