{"id":95069,"date":"2026-05-11T11:47:10","date_gmt":"2026-05-11T09:47:10","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=95069"},"modified":"2026-05-11T16:31:00","modified_gmt":"2026-05-11T14:31:00","slug":"reggio-successo-per-levento-gran-gala-di-primavera-al-cilea","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2026\/05\/11\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\/","title":{"rendered":"Reggio: successo per l&#8217;evento &#8220;Gran Gal\u00e0 di Primavera&#8221; al &#8220;Cilea&#8221;"},"content":{"rendered":"<p>Un Foyer del Teatro Francesco Cilea gremito e vibrante di emozione ha fatto da cornice al Gran Gal\u00e0 di Primavera, l&#8217;evento dell\u20198 maggio al Foyer del Teatro F. Cilea di Reggio Calabria, promosso dall\u2019Associazione Artemide, con la direzione artistica di Mario Vitolo, ha saputo fondere l\u2019eleganza della moda con l\u2019alto valore civile. Una serata &#8220;sold out&#8221; patrocinata dalla Presidenza del Consiglio regionale della Calabria, dal comune di Reggio Calabria e dal GOM , a ridosso della Festa della Mamma, ha celebrato la vita e la storia della medicina reggina.<\/p>\n<p>Il culmine della serata \u00e8 stato il conferimento del <strong>Premio Artemide Lucina 2026<\/strong> alla Dott.ssa <strong>Isabella Mondello<\/strong>, attuale Direttore dell\u2019U.O.C. Neonatologia \u2013 TIN \u2013 Nido del Grande Ospedale Metropolitano (GOM) di Reggio Calabria. Gi\u00e0 Presidente della Societ\u00e0 Italiana di Neonatologia (sezione Calabria), la Dottoressa \u00e8 stata omaggiata per la sua straordinaria carriera e per la guida sicura di un reparto che \u00e8 punto di riferimento per l&#8217;intero territorio.<\/p>\n<p>Il nome del premio racchiude un simbolismo profondo: unisce <strong>Artemide<\/strong> protettrice delle donne e del parto a<strong> Lucina<\/strong>, la divinit\u00e0 che \u201cporta alla luce\u201d simboleggiando perfettamente la missione della terapia intensiva neonatale nel guidare i piccoli guerrieri verso la vita.<\/p>\n<p>&#8220;Abbiamo voluto premiare non solo un\u2019eccellenza scientifica, ma una donna che incarna il valore della cura come missione di vita&#8221;, ha dichiarato visibilmente emozionata la Presidente di Artemide, Valeria Pellegrino. &#8220;La partecipazione della citt\u00e0 \u00e8 stata straordinaria, a dimostrazione che Reggio Calabria, sa stringersi attorno alle proprie eccellenze e ai valori della maternit\u00e0 e della rinascita.&#8221;<\/p>\n<p>La serata ha vissuto momenti di grande intensit\u00e0 istituzionale grazie al contributo video dell\u2019On. Giusy Princi in onore alla Dott.ssa Mondello e al tema del Gran Gal\u00e0, \u00a0e all\u2019intervento dell\u2019avv. Ernesto Siclari, Garante regionale delle persone con disabilit\u00e0, che ha sottolineato l\u2019importanza della rete tra sanit\u00e0 e istituzioni per la tutela dei pi\u00f9 fragili.<\/p>\n<p>Significativa la partecipazione istituzionale del GOM, rappresentato dal Direttore Amministrativo, dott. Francesco Araniti, a testimonianza del forte legame tra l&#8217;ospedale e il tessuto sociale cittadino.<\/p>\n<p>Un momento di profonda commozione \u00e8 stato dedicato da parte della dott.ssa Mondello alla memoria storica della neonatologia reggina, con la presenza di ospiti illustri che hanno segnato le tappe di questo reparto d&#8217;eccellenza: il dott. Giuseppe Serrao, figlio dell&#8217;indimenticato dott. Pasquale Serrao che fond\u00f2 la Neonatologia a Reggio negli anni &#8217;70, e la signora Maria Nicol\u00f2, moglie del compianto dott. Nicol\u00f2, il primario che raccolse l&#8217;eredit\u00e0 di Serrao guidando il reparto con sapienza prima dell&#8217;attuale direzione della dott.ssa Mondello.<\/p>\n<p>L&#8217;impegno sociale \u00e8 stato ulteriormente celebrato con la consegna dei Riconoscimenti al Merito Sociale all\u2019Associazione Eracle ODV, da anni al fianco delle famiglie dei neonati pretermine, e con un \u201cRiconoscimento Speciale Artemide\u201d dedicato a tutto il reparto di Neonatologia e Terapia Intensiva Neonatale del GOM. Un tributo doveroso a quell&#8217; &#8220;esercito silenzioso&#8221; di medici e infermieri che ogni giorno opera con professionalit\u00e0 e amore estremo.<\/p>\n<p>Lo spettacolo ha visto un\u2019alternanza di momenti di alta moda, un susseguirsi di quadri stilistici che hanno incantato il pubblico, fino al momento di altissimo prestigio con le creazioni dell\u2019arte orafa del <strong>maestro Gerardo Sacco<\/strong>, che ha voluto <strong>omaggiare la dott.ssa Mondello con un gioiello esclusivo simbolo di luce e rinascita.<\/strong><\/p>\n<p>Ad arricchire la scena, la grazia e il talento dei campioni italiani Mattia Pio Luppino e Benedetta Leonello, della scuola ADS Olympus di Sant\u2019Eufemia D\u2019Aspromonte, diretti dai maestri Saverio Carbone e Federica Scappatura.<\/p>\n<p>Un Gran Gal\u00e0 che ha raccontato come la primavera di ogni bambino salvato, di ogni sfida vinta \u00e8 l\u2019inizio di una storia bellissima che merita di essere vissuta.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un Foyer del Teatro Francesco Cilea gremito e vibrante di emozione ha fatto da cornice al Gran Gal\u00e0 di Primavera, l&#8217;evento dell\u20198 maggio al Foyer del Teatro F. Cilea di&hellip;<\/p>\n","protected":false},"author":5,"featured_media":95070,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[921,196,140],"tags":[28656,53537,30689,53536,9874,28655],"class_list":["post-95069","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-news","category-reggio-calabria","tag-associazione-artemide","tag-dott-ssa-isabella-mondello","tag-gran-gala-di-primavera","tag-premio-artemide-lucina","tag-teatro-cilea-reggio-calabria","tag-valeria-pellegrino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reggio: successo al Teatro Cilea per il &quot;Gran Gal\u00e0 di Primavera&quot;<\/title>\n<meta name=\"description\" content=\"Consegnato il Premio \u201cArtemide Lucina\u201d alla Dott.ssa Isabella Mondello. Evento promosso dall\u2019Associazione &quot;Artemide&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2026\/05\/11\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reggio: successo al Teatro Cilea per il &quot;Gran Gal\u00e0 di Primavera&quot;\" \/>\n<meta property=\"og:description\" content=\"Consegnato il Premio \u201cArtemide Lucina\u201d alla Dott.ssa Isabella Mondello. Evento promosso dall\u2019Associazione &quot;Artemide&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2026\/05\/11\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T09:47:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T14:31:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2026\/05\/Gran-Gala-di-Primavera-Teatro-Cilea.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"621\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/05\\\/11\\\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/05\\\/11\\\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\\\/\"},\"author\":{\"name\":\"redazione\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/1b3eb3c07c47136bc44c785c543e635f\"},\"headline\":\"Reggio: successo per l&#8217;evento &#8220;Gran Gal\u00e0 di Primavera&#8221; al &#8220;Cilea&#8221;\",\"datePublished\":\"2026-05-11T09:47:10+00:00\",\"dateModified\":\"2026-05-11T14:31:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/05\\\/11\\\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\\\/\"},\"wordCount\":611,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/05\\\/11\\\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/05\\\/Gran-Gala-di-Primavera-Teatro-Cilea.jpg\",\"keywords\":[\"Associazione Artemide\",\"Dott.ssa Isabella Mondello\",\"Gran Gal\u00e0 di primavera\",\"Premio \u201cArtemide Lucina\u201d\",\"Teatro Cilea Reggio Calabria\",\"Valeria Pellegrino\"],\"articleSection\":[\"Home\",\"News\",\"Reggio Calabria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/05\\\/11\\\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/05\\\/11\\\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\\\/\",\"name\":\"Reggio: successo al Teatro Cilea per il \\\"Gran Gal\u00e0 di Primavera\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/05\\\/11\\\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/05\\\/11\\\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/05\\\/Gran-Gala-di-Primavera-Teatro-Cilea.jpg\",\"datePublished\":\"2026-05-11T09:47:10+00:00\",\"dateModified\":\"2026-05-11T14:31:00+00:00\",\"description\":\"Consegnato il Premio \u201cArtemide Lucina\u201d alla Dott.ssa Isabella Mondello. Evento promosso dall\u2019Associazione \\\"Artemide\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/05\\\/11\\\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/05\\\/11\\\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/05\\\/11\\\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/05\\\/Gran-Gala-di-Primavera-Teatro-Cilea.jpg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/05\\\/Gran-Gala-di-Primavera-Teatro-Cilea.jpg\",\"width\":621,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/05\\\/11\\\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reggio: successo per l&#8217;evento &#8220;Gran Gal\u00e0 di Primavera&#8221; al &#8220;Cilea&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/1b3eb3c07c47136bc44c785c543e635f\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reggio: successo al Teatro Cilea per il \"Gran Gal\u00e0 di Primavera\"","description":"Consegnato il Premio \u201cArtemide Lucina\u201d alla Dott.ssa Isabella Mondello. Evento promosso dall\u2019Associazione \"Artemide\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2026\/05\/11\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\/","og_locale":"it_IT","og_type":"article","og_title":"Reggio: successo al Teatro Cilea per il \"Gran Gal\u00e0 di Primavera\"","og_description":"Consegnato il Premio \u201cArtemide Lucina\u201d alla Dott.ssa Isabella Mondello. Evento promosso dall\u2019Associazione \"Artemide\"","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2026\/05\/11\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\/","og_site_name":"Radio Touring 104","article_published_time":"2026-05-11T09:47:10+00:00","article_modified_time":"2026-05-11T14:31:00+00:00","og_image":[{"width":621,"height":420,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2026\/05\/Gran-Gala-di-Primavera-Teatro-Cilea.jpg","type":"image\/jpeg"}],"author":"redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/05\/11\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/05\/11\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\/"},"author":{"name":"redazione","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/1b3eb3c07c47136bc44c785c543e635f"},"headline":"Reggio: successo per l&#8217;evento &#8220;Gran Gal\u00e0 di Primavera&#8221; al &#8220;Cilea&#8221;","datePublished":"2026-05-11T09:47:10+00:00","dateModified":"2026-05-11T14:31:00+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/05\/11\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\/"},"wordCount":611,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/05\/11\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2026\/05\/Gran-Gala-di-Primavera-Teatro-Cilea.jpg","keywords":["Associazione Artemide","Dott.ssa Isabella Mondello","Gran Gal\u00e0 di primavera","Premio \u201cArtemide Lucina\u201d","Teatro Cilea Reggio Calabria","Valeria Pellegrino"],"articleSection":["Home","News","Reggio Calabria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/05\/11\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2026\/05\/11\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\/","name":"Reggio: successo al Teatro Cilea per il \"Gran Gal\u00e0 di Primavera\"","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/05\/11\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/05\/11\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2026\/05\/Gran-Gala-di-Primavera-Teatro-Cilea.jpg","datePublished":"2026-05-11T09:47:10+00:00","dateModified":"2026-05-11T14:31:00+00:00","description":"Consegnato il Premio \u201cArtemide Lucina\u201d alla Dott.ssa Isabella Mondello. Evento promosso dall\u2019Associazione \"Artemide\"","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/05\/11\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2026\/05\/11\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/05\/11\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2026\/05\/Gran-Gala-di-Primavera-Teatro-Cilea.jpg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2026\/05\/Gran-Gala-di-Primavera-Teatro-Cilea.jpg","width":621,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/05\/11\/reggio-successo-per-levento-gran-gala-di-primavera-al-cilea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Reggio: successo per l&#8217;evento &#8220;Gran Gal\u00e0 di Primavera&#8221; al &#8220;Cilea&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/1b3eb3c07c47136bc44c785c543e635f","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g","caption":"redazione"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/redazione\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2026\/05\/Gran-Gala-di-Primavera-Teatro-Cilea.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/95069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=95069"}],"version-history":[{"count":2,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/95069\/revisions"}],"predecessor-version":[{"id":95101,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/95069\/revisions\/95101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/95070"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=95069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=95069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=95069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}