{"id":99651,"date":"2026-09-02T11:46:45","date_gmt":"2026-09-02T09:46:45","guid":{"rendered":"https:\/\/progettotouring.it\/radiotouring104\/?p=99651"},"modified":"2026-09-02T12:32:15","modified_gmt":"2026-09-02T10:32:15","slug":"reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza","status":"publish","type":"post","link":"https:\/\/progettotouring.it\/radiotouring104\/2026\/09\/02\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\/","title":{"rendered":"Reggio Bic: ingaggiato Marco Guidotto: &#8220;Un sogno che si realizza&#8221;"},"content":{"rendered":"<p>La Reggio BIC accoglie il talento del CUS Catania. La sua storia parte dalla diagnosi di sclerosi multipla e arriva fino al massimo campionato italiano: \u00abDove non arrivo con il corpo o con la testa, compenso con la voglia di migliorare, con il cuore e con l\u2019amore per il basket\u00bb.<\/p>\n<p>Ci sono storie che raccontano un trasferimento. E poi ci sono storie che raccontano una rinascita.<\/p>\n<p>Quella di Marco Guidotto, nuovo giocatore della Reggio BIC, appartiene decisamente alla seconda categoria.<\/p>\n<p>Il suo arrivo in riva allo Stretto non \u00e8 soltanto un nuovo tassello per il roster di coach Antonio Cugliandro. \u00c8 il punto pi\u00f9 alto, almeno finora, di un percorso iniziato nel momento pi\u00f9 difficile della sua vita.<\/p>\n<p>Marco ha sempre giocato a basket. Poi \u00e8 arrivata la diagnosi di sclerosi multipla e tutto \u00e8 cambiato.<\/p>\n<p>\u00abLa mia vita \u00e8 cambiata radicalmente. Ero una persona molto dinamica e la malattia mi ha isolato. Ho attraversato anni bui\u00bb.<\/p>\n<p>La svolta arriva quasi per caso, durante un ricovero per un\u2019intensa ricaduta. Nel corso della riabilitazione presso l\u2019Unit\u00e0 Spinale dell\u2019ospedale Cannizzaro, qualcuno gli mostra una possibilit\u00e0 che fino a quel momento sembrava impensabile: continuare a fare sport, nonostante le limitazioni.<\/p>\n<p>\u00c8 da l\u00ec che nasce una nuova strada.<\/p>\n<p>Nel 2019 comincia il percorso con il CUS Catania. Ma \u00e8 il 2020 a cambiare ulteriormente il significato di quella sfida.<\/p>\n<p>Nasce sua figlia.<\/p>\n<p>\u00abLei mi ha dato una ragione in pi\u00f9 per metterci ogni singola risorsa e tutto l\u2019impegno possibile\u00bb.<\/p>\n<p>Anche il numero di maglia diventa cos\u00ec una promessa, un simbolo, un legame indissolubile.<\/p>\n<p>Il 3, il giorno della nascita di sua figlia.<\/p>\n<p>\u00abSpero davvero che sia orgogliosa del suo pap\u00e0\u00bb.<\/p>\n<p>IMPARARE DI NUOVO A GIOCARE<\/p>\n<p>Passare dal basket in piedi alla carrozzina non \u00e8 stato semplice.<\/p>\n<p>\u00abAll\u2019inizio \u00e8 stata dura abituarmi alla carrozzina, perch\u00e9 \u00e8 un gioco totalmente diverso rispetto al basket in piedi\u00bb.<\/p>\n<p>A Catania, per\u00f2, Marco trova compagni pronti ad accompagnarlo e una guida fondamentale in coach Gabriella.<\/p>\n<p>\u00abDevo un ringraziamento enorme ai miei compagni di squadra e alla pazienza di coach Gabriella, che mi hanno dato il tempo necessario per comprendere le nuove dinamiche\u00bb.<\/p>\n<p>E nel suo percorso ci sono due nomi ai quali Guidotto riconosce un ruolo speciale: Ivan Messina e Giuseppe Garaffo, i suoi mentori al CUS Catania.<\/p>\n<p>\u00abDevo proprio a loro la crescita personale in questo sport\u00bb.<\/p>\n<p>Una crescita che, secondo Marco, segue una regola semplice ma potentissima:<\/p>\n<p>\u00abPi\u00f9 diventi bravo, pi\u00f9 ti piace e pi\u00f9 ti innamori di quello che fai\u00bb.<\/p>\n<p>E lui del basket si \u00e8 innamorato ancora una volta.<\/p>\n<p>UNA SECONDA OPPORTUNIT\u00c0<\/p>\n<p>Guidotto non nasconde le difficolt\u00e0 legate alla propria patologia.<\/p>\n<p>La sclerosi multipla incide sulla forza, sull\u2019equilibrio, sulla memoria, sulla vista e sui movimenti. Ma nella sua storia la malattia non \u00e8 diventata il punto finale.<\/p>\n<p>\u00c8 diventata una parte della strada.<\/p>\n<p>\u00abRingrazio immensamente questo sport per avermi dato una seconda opportunit\u00e0\u00bb.<\/p>\n<p>Poi una frase che racconta meglio di qualsiasi altra cosa il suo modo di vivere questa sfida:<\/p>\n<p>\u00abDove non arrivo con il corpo o con la testa, compenso con la voglia di migliorare, con il cuore e con l\u2019amore per il basket\u00bb.<\/p>\n<p>QUELLA MAGLIA CHE SEMBRAVA IMPOSSIBILE<\/p>\n<p>La Serie A, fino a qualche tempo fa, sembrava un traguardo troppo lontano.<\/p>\n<p>Poi arriva la chiamata della Reggio BIC.<\/p>\n<p>\u00abLa mia reazione \u00e8 stata un misto di sorpresa, pura felicit\u00e0 e anche un pizzico di paura\u00bb.<\/p>\n<p>Perch\u00e9 Marco conosce perfettamente la difficolt\u00e0 della sfida che lo attende.<\/p>\n<p>\u00abCon la mia patologia, non avrei mai creduto di potermi spingere fino alla Serie A\u00bb.<\/p>\n<p>Eppure ci \u00e8 arrivato.<\/p>\n<p>Un piccolo anticipo di quello che sarebbe successo era gi\u00e0 arrivato un paio di mesi fa, quando Guidotto aveva avuto la possibilit\u00e0 di allenarsi con la Reggio BIC insieme al compagno di squadra Massimo Chillemi.<\/p>\n<p>\u00ab\u00c8 stata una bella esperienza, ma non avrei mai pensato di poter giocare insieme a loro\u00bb.<\/p>\n<p>Adesso non sar\u00e0 pi\u00f9 soltanto un allenamento.<\/p>\n<p>Sar\u00e0 la sua squadra.<\/p>\n<p>\u00abUn sogno che si realizza\u00bb.<\/p>\n<p>CUGLIANDRO E LA SCELTA DI INVESTIRE SUL TALENTO ITALIANO<\/p>\n<p>Con l\u2019arrivo di Guidotto, la Reggio BIC porta a cinque gli italiani presenti nel roster.<\/p>\n<p>Un dato che racconta una precisa direzione tecnica.<\/p>\n<p>Coach Antonio Cugliandro continua infatti a costruire una squadra capace di unire esperienza e talento internazionale alla valorizzazione dei giocatori italiani, offrendo loro spazio, responsabilit\u00e0 e soprattutto la possibilit\u00e0 di crescere.<\/p>\n<p>\u201cIl sogno di tanti ragazzi e\u2019 poter arrivare a giocare in serie A, e noi come unica squadra di serie A del sud Italia, siamo considerati spesso da loro come punto di riferimento. Ma questa nostra scelta di ricadere su atleti del nostro territorio evidenzia anche una barriera geografica e logistica strutturale: la forte difficolt\u00e0 per una societ\u00e0 del Sud come la nostra, di attrarre giocatori italiani stabilmente residenti nel Centro o nel Nord Italia, costringendo di fatto a fare di necessit\u00e0 virt\u00f9 e sono davvero felice per l&#8217;innesto di Marco poich\u00e9 non \u00e8 solo una scelta territoriale, ma il giusto riconoscimento a un atleta che grazie a una forza di volont\u00e0 straordinaria e a un desiderio profondo, incarna perfettamente lo spirito di rivalsa della nostra squadra che ci ha da sempre contraddistinto\u201d.<\/p>\n<p>Non soltanto nomi gi\u00e0 affermati, dunque, ma anche atleti da accompagnare nel proprio percorso di maturazione.<\/p>\n<p>Ed \u00e8 proprio qui che l\u2019arrivo di Guidotto assume un significato particolare.<\/p>\n<p>La Reggio BIC non sceglie soltanto un giocatore.<\/p>\n<p>Sceglie una storia.<\/p>\n<p>Sceglie un atleta che ha gi\u00e0 dimostrato di saper trasformare gli ostacoli in motivazioni.<\/p>\n<p>E adesso gli consegna una nuova sfida.<\/p>\n<p>\u00abVoglio ringraziare di cuore la societ\u00e0 per avermi dato questa incredibile occasione\u00bb.<\/p>\n<p>La paura c\u2019\u00e8. Le difficolt\u00e0 ci saranno.<\/p>\n<p>Ma anche la voglia di provarci.<\/p>\n<p>\u00ab\u00c8 un\u2019opportunit\u00e0 che voglio cogliere con tutto il cuore\u00bb.<\/p>\n<p>Perch\u00e9 questa volta Marco Guidotto non deve semplicemente tornare a giocare a basket.<\/p>\n<p>Deve giocare in Serie A.<\/p>\n<p>E lo far\u00e0 con il numero 3 sulla schiena.<\/p>\n<p>Per sua figlia.<\/p>\n<p>Per chi ha creduto in lui.<\/p>\n<p>E, soprattutto, per ricordare a s\u00e9 stesso che a volte il traguardo pi\u00f9 bello arriva proprio dopo la strada pi\u00f9 difficile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Reggio BIC accoglie il talento del CUS Catania. La sua storia parte dalla diagnosi di sclerosi multipla e arriva fino al massimo campionato italiano: \u00abDove non arrivo con il&hellip;<\/p>\n","protected":false},"author":5,"featured_media":99652,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[196,140,144],"tags":[56222,56221,56220,20339,20937],"class_list":["post-99651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-reggio-calabria","category-sport","tag-un-sogno-che-si-realizza","tag-giocatore-proveniente-dal-cus-catania","tag-ingaggiato-marco-guidotto","tag-reggio-bic","tag-sclerosi-multipla"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reggio Bic: ingaggiato Marco Guidotto<\/title>\n<meta name=\"description\" content=\"La Societ\u00e0 ufficializza l&#039;arrivo del giocatore, proveniente dal Cus Catania, che \u00e8 riuscito a trasformare gli ostacoli in motivazioni\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progettotouring.it\/radiotouring104\/2026\/09\/02\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reggio Bic: ingaggiato Marco Guidotto\" \/>\n<meta property=\"og:description\" content=\"La Societ\u00e0 ufficializza l&#039;arrivo del giocatore, proveniente dal Cus Catania, che \u00e8 riuscito a trasformare gli ostacoli in motivazioni\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progettotouring.it\/radiotouring104\/2026\/09\/02\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Touring 104\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T09:46:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T10:32:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2026\/09\/Marco-Guidotto-Reggio-BIc.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/09\\\/02\\\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/09\\\/02\\\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\\\/\"},\"author\":{\"name\":\"redazione\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/1b3eb3c07c47136bc44c785c543e635f\"},\"headline\":\"Reggio Bic: ingaggiato Marco Guidotto: &#8220;Un sogno che si realizza&#8221;\",\"datePublished\":\"2026-09-02T09:46:45+00:00\",\"dateModified\":\"2026-09-02T10:32:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/09\\\/02\\\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\\\/\"},\"wordCount\":1005,\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/09\\\/02\\\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/09\\\/Marco-Guidotto-Reggio-BIc.jpeg\",\"keywords\":[\"\\\"Un sogno che si realizza\\\"\",\"giocatore proveniente dal Cus Catania\",\"ingaggiato Marco Guidotto\",\"Reggio Bic\",\"Sclerosi Multipla\"],\"articleSection\":[\"News\",\"Reggio Calabria\",\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/09\\\/02\\\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/09\\\/02\\\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\\\/\",\"name\":\"Reggio Bic: ingaggiato Marco Guidotto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/09\\\/02\\\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/09\\\/02\\\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/09\\\/Marco-Guidotto-Reggio-BIc.jpeg\",\"datePublished\":\"2026-09-02T09:46:45+00:00\",\"dateModified\":\"2026-09-02T10:32:15+00:00\",\"description\":\"La Societ\u00e0 ufficializza l'arrivo del giocatore, proveniente dal Cus Catania, che \u00e8 riuscito a trasformare gli ostacoli in motivazioni\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/09\\\/02\\\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/09\\\/02\\\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/09\\\/02\\\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/09\\\/Marco-Guidotto-Reggio-BIc.jpeg\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/09\\\/Marco-Guidotto-Reggio-BIc.jpeg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/2026\\\/09\\\/02\\\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reggio Bic: ingaggiato Marco Guidotto: &#8220;Un sogno che si realizza&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#website\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"name\":\"Radio Touring 104\",\"description\":\"La prima radio Reggina\",\"publisher\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#organization\",\"name\":\"Radio Touring 104\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"contentUrl\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/02\\\/cropped-logo-radio-touring-104.png\",\"width\":377,\"height\":182,\"caption\":\"Radio Touring 104\"},\"image\":{\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/#\\\/schema\\\/person\\\/1b3eb3c07c47136bc44c785c543e635f\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"url\":\"https:\\\/\\\/progettotouring.it\\\/radiotouring104\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reggio Bic: ingaggiato Marco Guidotto","description":"La Societ\u00e0 ufficializza l'arrivo del giocatore, proveniente dal Cus Catania, che \u00e8 riuscito a trasformare gli ostacoli in motivazioni","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progettotouring.it\/radiotouring104\/2026\/09\/02\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\/","og_locale":"it_IT","og_type":"article","og_title":"Reggio Bic: ingaggiato Marco Guidotto","og_description":"La Societ\u00e0 ufficializza l'arrivo del giocatore, proveniente dal Cus Catania, che \u00e8 riuscito a trasformare gli ostacoli in motivazioni","og_url":"https:\/\/progettotouring.it\/radiotouring104\/2026\/09\/02\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\/","og_site_name":"Radio Touring 104","article_published_time":"2026-09-02T09:46:45+00:00","article_modified_time":"2026-09-02T10:32:15+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2026\/09\/Marco-Guidotto-Reggio-BIc.jpeg","type":"image\/jpeg"}],"author":"redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/09\/02\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\/#article","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/09\/02\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\/"},"author":{"name":"redazione","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/1b3eb3c07c47136bc44c785c543e635f"},"headline":"Reggio Bic: ingaggiato Marco Guidotto: &#8220;Un sogno che si realizza&#8221;","datePublished":"2026-09-02T09:46:45+00:00","dateModified":"2026-09-02T10:32:15+00:00","mainEntityOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/09\/02\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\/"},"wordCount":1005,"publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/09\/02\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2026\/09\/Marco-Guidotto-Reggio-BIc.jpeg","keywords":["\"Un sogno che si realizza\"","giocatore proveniente dal Cus Catania","ingaggiato Marco Guidotto","Reggio Bic","Sclerosi Multipla"],"articleSection":["News","Reggio Calabria","Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/09\/02\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\/","url":"https:\/\/progettotouring.it\/radiotouring104\/2026\/09\/02\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\/","name":"Reggio Bic: ingaggiato Marco Guidotto","isPartOf":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/09\/02\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\/#primaryimage"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/09\/02\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\/#primaryimage"},"thumbnailUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2026\/09\/Marco-Guidotto-Reggio-BIc.jpeg","datePublished":"2026-09-02T09:46:45+00:00","dateModified":"2026-09-02T10:32:15+00:00","description":"La Societ\u00e0 ufficializza l'arrivo del giocatore, proveniente dal Cus Catania, che \u00e8 riuscito a trasformare gli ostacoli in motivazioni","breadcrumb":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/09\/02\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progettotouring.it\/radiotouring104\/2026\/09\/02\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/09\/02\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\/#primaryimage","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2026\/09\/Marco-Guidotto-Reggio-BIc.jpeg","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2026\/09\/Marco-Guidotto-Reggio-BIc.jpeg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/progettotouring.it\/radiotouring104\/2026\/09\/02\/reggio-bic-ingaggiato-marco-guidotto-un-sogno-che-si-realizza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/progettotouring.it\/radiotouring104\/"},{"@type":"ListItem","position":2,"name":"Reggio Bic: ingaggiato Marco Guidotto: &#8220;Un sogno che si realizza&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/progettotouring.it\/radiotouring104\/#website","url":"https:\/\/progettotouring.it\/radiotouring104\/","name":"Radio Touring 104","description":"La prima radio Reggina","publisher":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progettotouring.it\/radiotouring104\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/progettotouring.it\/radiotouring104\/#organization","name":"Radio Touring 104","url":"https:\/\/progettotouring.it\/radiotouring104\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/","url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","contentUrl":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2022\/02\/cropped-logo-radio-touring-104.png","width":377,"height":182,"caption":"Radio Touring 104"},"image":{"@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/progettotouring.it\/radiotouring104\/#\/schema\/person\/1b3eb3c07c47136bc44c785c543e635f","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b31605b49f100769e8b624b3e05de1b73e1692e9568a352f60f53fd072e6e11?s=96&d=mm&r=g","caption":"redazione"},"url":"https:\/\/progettotouring.it\/radiotouring104\/author\/redazione\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/progettotouring.it\/radiotouring104\/wp-content\/uploads\/sites\/6\/2026\/09\/Marco-Guidotto-Reggio-BIc.jpeg","_links":{"self":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/99651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/comments?post=99651"}],"version-history":[{"count":2,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/99651\/revisions"}],"predecessor-version":[{"id":99654,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/posts\/99651\/revisions\/99654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media\/99652"}],"wp:attachment":[{"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/media?parent=99651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/categories?post=99651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progettotouring.it\/radiotouring104\/wp-json\/wp\/v2\/tags?post=99651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}